{"id":377,"name":"Charlotte Dietrich","url":"","description":"Im Sommer 2016 war ich das erste Mal in Zentralasien im Rahmen eines Praktikums in Astana. Begeistert von dieser Region, ihrer je nach Land sehr unterschiedlichen Kultur und der Offenheit und Gastfreundlichkeit der Menschen, habe ich nach Abschluss meines Bachelors an der Sciences Po Paris Praktika in Moskau, Bishkek und Dushanbe gemacht. Zu Novastan bin ich im Januar 2017 gesto\u00dfen und bin Teil der deutschen Redaktionsleitung.","link":"https:\/\/novastan.org\/fr\/author\/charlottedietrich\/","slug":"charlottedietrich","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b50a7c82cb10ab7b98197a313abc817761f1b63409bdbb96b6b47b957afefebc?s=24&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b50a7c82cb10ab7b98197a313abc817761f1b63409bdbb96b6b47b957afefebc?s=48&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b50a7c82cb10ab7b98197a313abc817761f1b63409bdbb96b6b47b957afefebc?s=96&r=g"},"meta":{"lw_harbor_dismissed_notices":[]},"acf":[],"user_switching_url":null,"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users"}]}}