{"id":57343,"date":"2023-03-16T17:23:13","date_gmt":"2023-03-16T16:23:13","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=57343"},"modified":"2023-03-31T13:43:14","modified_gmt":"2023-03-31T11:43:14","slug":"a-bichkek-la-semaine-de-la-francophonie-celebre-le-voyage","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kirghizstan\/a-bichkek-la-semaine-de-la-francophonie-celebre-le-voyage\/","title":{"rendered":"A Bichkek, la semaine de la francophonie c\u00e9l\u00e8bre le voyage"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Au Kirghizstan, la francophonie \u00e9tait c\u00e9l\u00e9br\u00e9e dans la capitale kirghize le temps d\u2019une semaine. Retour sur les nombreux \u00e9v\u00e9nements qui mettaient en avant la langue fran\u00e7aise sous toutes ses formes, mais aussi sa culture et ses apprenants.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la nouvelle \u00e9dition de <a href=\"https:\/\/kg.ambafrance.org\/Programme-de-la-Semaine-de-la-Francophonie-2023\">la semaine de la francophonie \u00e0 Bichkek<\/a>, le th\u00e8me choisi \u00e9tait le voyage. Un sujet qui colle bien au Kirghizstan, connu par <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/les-vacances-au-kirghizstan-de-plus-en-plus-populaires\/\">ses nombreux touristes fran\u00e7ais et europ\u00e9ens<\/a>, enthousiastes de d\u00e9couvrir chaque ann\u00e9e les montagnes et les steppes kirghizes. Mais du 9 au 18 mars 2023, c\u2019est cette fois-ci \u00e0 la capitale kirghize Bichkek de d\u00e9couvrir la langue fran\u00e7aise, sa culture, mais aussi celle des pays francophones du monde, \u00e0 travers de nombreuses activit\u00e9s culturelles organis\u00e9es par l\u2019Alliance fran\u00e7aise de Bichkek. <\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nAu programme, une vingtaine d\u2019\u00e9v\u00e9nements ouverts \u00e0 toutes et \u00e0 tous promouvant la culture fran\u00e7aise, comme une d\u00e9gustation au bar \u00e0 vin Chapoutier, ou encore une exposition Jules Verne tenue \u00e0 l\u2019Alliance fran\u00e7aise. Mais la culture de l\u2019Hexagone n\u2019\u00e9tait pas la seule \u00e0 \u00eatre mise \u00e0 l\u2019honneur, tant l\u2019espace francophone mondial est vari\u00e9.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La francophonie encore active<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Lors de l\u2019inauguration de la semaine de la francophonie, l\u2019ambassadeur de France au Kirghizstan, <a href=\"https:\/\/kg.ambafrance.org\/Biographie-de-M-Francois-DELAHOUSSE-Charge-d-affaires-de-France-au-Kirghizstan\">Fran\u00e7ois Delahousse<\/a>, \u00e9tait pr\u00e9sent aux c\u00f4t\u00e9s de Bega\u00efm Isra\u00eflova, directrice de l\u2019Alliance fran\u00e7aise \u00e0 Bichkek, pour d\u00e9clarer la semaine de la langue fran\u00e7aise ouverte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/decryptage\/le-francais-a-t-il-encore-un-avenir-en-asie-centrale\/\">Le fran\u00e7ais a-t-il encore un avenir en Asie centrale ?<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce dernier a rappel\u00e9 qu\u2019il y a environ 4 700 apprenants du fran\u00e7ais au Kirghizstan, en comptant les \u00e9coliers et les \u00e9tudiants \u00e0 l\u2019universit\u00e9. Un chiffre qui montre que <em>\u00ab\u00a0la francophonie n\u2019est pas morte<\/em> \u00bb au Kirghizstan aux yeux de l\u2019ambassadeur fran\u00e7ais. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les institutions fran\u00e7aises de Bichkek mobilis\u00e9es&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Pour animer cette semaine de la francophonie, plusieurs organismes fran\u00e7ais se sont joints \u00e0 l\u2019Alliance fran\u00e7aise pour organiser des \u00e9v\u00e9nements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/les-relations-franco-kirghizes-se-resserrent-discretement-mais-surement\/\">Les relations franco-kirghizes se resserrent discr\u00e8tement mais s\u00fbrement<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La boutique l\u2019Occitane par exemple, implant\u00e9e dans une art\u00e8re passante du centre-ville de Bichkek, a tenu une pr\u00e9sentation des sp\u00e9cificit\u00e9s des cosm\u00e9tiques fran\u00e7aises. Un <em>\u00ab concours de parfums \u00bb<\/em> a \u00e9t\u00e9 organis\u00e9, lors duquel les participants devaient deviner les composantes des parfums. Un \u00e9v\u00e9nements qui r\u00e9unissaient les int\u00e9ress\u00e9s et curieux du charme \u00e0 la fran\u00e7aise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019<a href=\"https:\/\/novastan.org\/fr\/europe-et-asie-centrale\/recherche-lifeac-en-route-vers-un-rayonnement-regional\/\">Institut fran\u00e7ais d&rsquo;\u00e9tudes sur l\u2019Asie centrale<\/a> (IFEAC), implant\u00e9 \u00e0 Bichkek, a \u00e9galement mobilis\u00e9 ses chercheurs, dont le pal\u00e9ontologue fran\u00e7ais William Rendu, pour animer une conf\u00e9rence sur la pal\u00e9ontologie pr\u00e9historique et l&rsquo;importance fondamentale des fouilles en Asie centrale. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La francophonie au-del\u00e0 de la France <\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\nLes artistes de langue fran\u00e7aise ont \u00e9t\u00e9 mis \u00e0 l\u2019honneur. Apr\u00e8s la projection du documentaire c\u00e9saris\u00e9 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/La_Panth%C3%A8re_des_neiges_(film)\"><em>La panth\u00e8re des neiges<\/em><\/a> r\u00e9alis\u00e9 par Marie Amiguet et Vincent Munier en 2021, un film canadien, <a href=\"https:\/\/www.filmsquebec.com\/films\/gang-des-hors-la-loi-jean-beaudry\/\"><em>La gang des hors-la-loi<\/em><\/a>, de Jean Baudry, a \u00e9t\u00e9 projet\u00e9 \u00e0 l\u2019acad\u00e9mie du tourisme de Bichkek.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nL&rsquo;Alliance fran\u00e7aise de Bichkek a activement travaill\u00e9 avec ses partenaires francophones via les ambassades et consulats. Le lendemain au m\u00eame endroit, c\u2019\u00e9tait au tour du cin\u00e9ma belge d\u2019\u00eatre mis \u00e0 l\u2019honneur, avec le film <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Continuer_(film)\"><em>Continuer<\/em><\/a> de Joachim Lafosse, mettant en sc\u00e8ne notamment l\u2019actrice Virginie Effira. Enfin, l&rsquo;exploratrice suisse <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ella_Maillart\">Ella Maillart<\/a>, connue pour avoir travers\u00e9 l\u2019Asie centrale en sac \u00e0 dos du temps de l\u2019Union sovi\u00e9tique, dans les ann\u00e9es 1930, a vu son parcours d\u00e9voil\u00e9 lors de la projection du film documentaire de Rapha\u00ebl Blanc, <em>Les voyages extraordinaires d&rsquo;Ella Maillart<\/em>, au mus\u00e9e national d&rsquo;Histoire de la capitale.\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Emma Collet<\/strong><br><strong>R\u00e9dactrice pour Novastan<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Emma Jerome<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Merci d&rsquo;avoir lu cet article jusqu&rsquo;au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez&nbsp;<a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a>&nbsp;ou nous envoyer un email \u00e0&nbsp;<a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au Kirghizstan, la francophonie \u00e9tait c\u00e9l\u00e9br\u00e9e dans la capitale kirghize le temps d\u2019une semaine. Retour sur les nombreux \u00e9v\u00e9nements qui mettaient en avant la langue fran\u00e7aise sous toutes ses formes, mais aussi sa culture et ses apprenants. Pour la nouvelle \u00e9dition de la semaine de la francophonie \u00e0 Bichkek, le th\u00e8me choisi \u00e9tait le voyage. [&hellip;]<\/p>\n","protected":false},"author":751,"featured_media":57346,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,3986],"tags":[433,513,1365,458,466,4263,588,521],"coauthors":[3664,5049],"class_list":["post-57343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kirghizstan","category-societe-et-culture","tag-bichkek","tag-culture","tag-francais","tag-france","tag-kirghizstan","tag-leurope-et-lasie-centrale","tag-semaine-de-la-francophonie","tag-societe"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/57343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/751"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=57343"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/57343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/57346"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=57343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=57343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=57343"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=57343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}