{"id":56142,"date":"2022-10-27T09:16:51","date_gmt":"2022-10-27T07:16:51","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=56142"},"modified":"2023-03-31T19:51:22","modified_gmt":"2023-03-31T17:51:22","slug":"le-kazakhstan-cible-par-une-campagne-de-desinformation-russe","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kazakhstan\/le-kazakhstan-cible-par-une-campagne-de-desinformation-russe\/","title":{"rendered":"Le Kazakhstan cibl\u00e9 par une campagne de d\u00e9sinformation russe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Depuis le d\u00e9but de la guerre en Ukraine, une campagne massive de d\u00e9sinformation a lieu au Kazakhstan. Des m\u00e9dias et des cha\u00eenes Telegram russes v\u00e9hiculent notamment l&rsquo;id\u00e9e d&rsquo;une soci\u00e9t\u00e9 kazakhe russophobe.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Novastan reprend et traduit ici un article publi\u00e9 le 20 ao\u00fbt 2022 par le m\u00e9dia russe sp\u00e9cialis\u00e9 sur l&rsquo;Asie centrale <a href=\"https:\/\/fergana.news\/articles\/127337\/\">Fergana News<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Kazakhstan est au c\u0153ur d\u2019une guerre de l\u2019information. Apr\u00e8s le d\u00e9but de la guerre en Ukraine, le Kazakhstan, o\u00f9 un contingent russe de l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Organisation_du_trait%C3%A9_de_s%C3%A9curit%C3%A9_collective\">Organisation du trait\u00e9 de s\u00e9curit\u00e9 collective<\/a> (OTSC) a aid\u00e9 \u00e0 <a href=\"https:\/\/fergana.media\/stories\/gazovye_protesty\/\">r\u00e9primer<\/a> les <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/manifestations-au-kazakhstan-accalmie-intrigues-de-palais-et-inegalites-sociales\/\">troubles<\/a> d\u00e9but janvier 2022, aurait pu rendre la pareille \u00e0 la Russie en soutenant l\u2019op\u00e9ration, ce qu&rsquo;il n\u2019a pas fait. <\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nOfficiellement, Astana a pris ses distances avec le conflit. Mais l\u2019\u00c9tat n\u2019a pas emp\u00each\u00e9 des volontaires d\u2019envoyer de l\u2019aide humanitaire en Ukraine. Les remarques indign\u00e9es de la Russie \u00e0 ce sujet ont fini par se transformer en une campagne d\u2019information cibl\u00e9e \u00e0 laquelle ont particip\u00e9 des journalistes.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des ambulances kazakhes livr\u00e9es en Ukraine<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> En ao\u00fbt dernier, trois ambulances kazakhes <a href=\"https:\/\/www.facebook.com\/photo\/?fbid=374984481473571&amp;set=a.187048716933816\">sont arriv\u00e9es<\/a> en Ukraine. La cha\u00eene Telegram Ateo Breaking a rapport\u00e9 que les autorit\u00e9s de la r\u00e9publique d\u2019Asie centrale avaient envoy\u00e9 ces v\u00e9hicules, d\u00e9cidant d\u2019aider le pays. Cependant, Astana n\u2019a rien \u00e0 voir avec cette action. Les voitures ont \u00e9t\u00e9 achet\u00e9es avec des fonds fournis par des hommes d\u2019affaires kazakhs, comme l\u2019a indiqu\u00e9 le minist\u00e8re ukrainien de la Sant\u00e9 et l\u2019ambassade d\u2019Ukraine au Kazakhstan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019<a href=\"https:\/\/uahouse.org\/ukraine-relief\">Ukrainian American House<\/a>, l\u2019<a href=\"https:\/\/www.facebook.com\/helpEplus\">Initiative E+<\/a> et la <a href=\"https:\/\/pinchukartcentre.org\/en\/about_us\/Victor_Pinchuk_Foundation\">Fondation Victor Pintchouk<\/a><a href=\"https:\/\/moz.gov.ua\/article\/news\/tri-shvidki-dlja-ukrainskih-medikiv-\u2013-vid-posolstva-ukraini-v-kazahstani-ta-kazahstanskogo-biznesu?__cf_chl_tk=39_3pWKod6RsPlKK1K7b2LkByr8tR05PbnU6Bvt2FlY-1666098568-0-gaNycGzNCNE\">ont aid\u00e9<\/a> \u00e0 faire passer les v\u00e9hicules en Ukraine. D\u00e8s le d\u00e9but de l\u2019op\u00e9ration sp\u00e9ciale, les autorit\u00e9s kazakhes ont pris leurs distances avec les participants au conflit. Le vice-ministre de la d\u00e9fense, Soultan Kamaletdinov, <a href=\"https:\/\/tengrinews.kz\/kazakhstan_news\/ne-podderjivaem-ni-odnu-storon-zamministra-oboronyi-463416\/\">a \u00e9t\u00e9 tr\u00e8s clair<\/a> \u00e0 ce sujet :\u00a0<em>\u00ab\u00a0Nous ne soutenons aucun des deux camps. Il ne peut y avoir aucun doute \u00e0 cet \u00e9gard. \u00bb<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des points de collecte b\u00e9n\u00e9voles<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Cependant, tous les Kazakhs ne partagent pas ce point de vue. Depuis le d\u00e9but de l\u2019op\u00e9ration militaire, des centaines de b\u00e9n\u00e9voles ont envoy\u00e9 de l\u2019aide humanitaire et collect\u00e9 de l\u2019argent pour les victimes par l\u2019interm\u00e9diaire de l\u2019ambassade d\u2019Ukraine au Kazakhstan. Il est important de souligner qu\u2019il s\u2019agit d\u2019une initiative citoyenne et non d\u2019un ordre des autorit\u00e9s. Des points de collecte fonctionnent dans onze r\u00e9gions du Kazakhstan : <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Karaganda\">Karaganda<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oural_(Kazakhstan)\">Oural<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Seme%C3%AF\">Seme\u00ef<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/%C3%96skemen\">Oust-Kamenogorsk<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Aktaou\">Aktaou<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Atyraou\">Atyraou<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ekibastouz\">Ekibastouz<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Aktioub%C3%A9\">Aktioub\u00e9<\/a>, <a href=\"https:\/\/www.novastan.org\/fr\/kazakhstan\/almaty-la-ville-aux-1000-couleurs-et-aux-1001-annees\/\">Almaty<\/a> et Astana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9but juin, les Kazakhs avaient d\u00e9j\u00e0 envoy\u00e9 plusieurs avions et onze convois d\u2019aide humanitaire en Ukraine, pour un poids total de plus de 200 tonnes. Il s\u2019agit d\u2019articles d\u2019hygi\u00e8ne personnelle, de nourriture, de m\u00e9dicaments et divers autres. Dans la r\u00e9publique, des concerts en soutien \u00e0 l\u2019Ukraine sont organis\u00e9s, rendant les autorit\u00e9s locales <a href=\"https:\/\/www.the-village-kz.com\/village\/city\/news-city\/24351-na-kontsert-v-podderzhku-ukrainy-v-almaty-ne-razreshali-pronosit-ukrainskie-flagi\">nerveuses<\/a>. Divers \u00e9v\u00e9nements ont lieu, comme par exemple une course de charit\u00e9 en <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Vychyvanka\">vychyvankas<\/a>, dont l\u2019argent collect\u00e9 est destin\u00e9 \u00e0 la reconstruction des \u00e9coles de la r\u00e9gion de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oblast_de_Tchernihiv\">Tchernihiv<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Une neutralit\u00e9 difficile \u00e0 conserver<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Officiellement, Astana n\u2019interf\u00e8re pas particuli\u00e8rement dans ces activit\u00e9s. Les autorit\u00e9s elles-m\u00eames ont envoy\u00e9 trois vols sp\u00e9ciaux de fournitures m\u00e9dicales, de nourriture et de literie en Ukraine au printemps dernier. Au quotidien, les dirigeants de la r\u00e9publique tentent de maintenir un \u00e9quilibre d\u00e9licat : d\u2019un c\u00f4t\u00e9, ils <a href=\"https:\/\/esquire.kz\/antivoennyj-miting-v-podderzhku-ukrainy-zapretili-v-almaty\/\">interdisent<\/a> les rassemblements en soutien \u00e0 l\u2019Ukraine, tandis que de l\u2019autre, les personnes affichant les lettres Z et V, symboles utilis\u00e9s par les partisans de l\u2019op\u00e9ration sp\u00e9ciale, sont passibles de poursuite. Cependant, plus la guerre dure, plus la neutralit\u00e9 devient compliqu\u00e9 \u00e0 conserver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/economie\/limpact-de-la-guerre-en-ukraine-sur-lasie-centrale-vers-la-fin-dune-politique-multidirectionnelle\/\">L\u2019impact de la guerre en Ukraine sur l\u2019Asie centrale\u00a0: vers la fin d\u2019une \u00ab\u00a0politique multidirectionnelle\u00a0\u00bb\u00a0?<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au printemps, des personnalit\u00e9s m\u00e9diatiques c\u00e9l\u00e8bres ont \u00e9t\u00e9 utilis\u00e9es pour pousser le Kazakhstan \u00e0 soutenir la Russie, accusant Astana de politique russophobe et de trahison. Des dizaines de cha\u00eenes Telegram ont rejoint la campagne de d\u00e9sinformation, publiant presque quotidiennement des fakes news ou des nouvelles non confirm\u00e9es tir\u00e9es des m\u00e9dias russes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des fakes news largement partag\u00e9es<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Le m\u00e9dia d\u2019\u00c9tat <a href=\"https:\/\/www.gazeta.ru\/\">Gazeta.ru<\/a> a par exemple parl\u00e9 dans son fil Twitter des ambulances envoy\u00e9es par les hommes d\u2019affaires kazakhs. Selon le site, les ambulances ont \u00e9t\u00e9 envoy\u00e9es par les autorit\u00e9s kazakhes et \u00e9taient destin\u00e9es aux forces arm\u00e9es ukrainiennes. Une autre information curieuse du m\u00eame genre est apparue sur les r\u00e9seaux\u00a0: le Kazakhstan vendrait des armes au Royaume-Uni, et celles-ci seraient ensuite livr\u00e9es \u00e0 l\u2019Ukraine. Les <a href=\"https:\/\/telegra.ph\/Velikobritaniya-pokupaet-oruzhie-v-Kazahstane-dlya-Ukrainy-dokumenty-08-09\">documents<\/a> en question ont \u00e9t\u00e9 publi\u00e9s d\u00e9but ao\u00fbt par le groupe de pirates informatiques pro-russe Beregini. L\u2019accord aurait \u00e9t\u00e9 n\u00e9goci\u00e9 par Technoexport.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/decryptage\/pour-les-medias-centrasiatiques-les-pressions-de-la-russie-saccentuent\/\">Pour les m\u00e9dias centrasiatiques, les pressions de la Russie s\u2019accentuent<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans un premier temps, la nouvelle s\u2019est activement r\u00e9pandue sur les cha\u00eenes Telegram russes, avant d&rsquo;attirer l\u2019attention des m\u00e9dias. Le minist\u00e8re de l\u2019Industrie et du D\u00e9veloppement des infrastructures du Kazakhstan a rapidement <a href=\"https:\/\/fergana.media\/news\/127299\/?country=kz\">d\u00e9menti<\/a> l\u2019information, d\u00e9clarant que les autorit\u00e9s n\u2019avaient pas d\u00e9livr\u00e9, ni \u00e0 Technoexport ni \u00e0 aucune autre soci\u00e9t\u00e9, de licence pour exporter des armes vers le Royaume-Uni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le minist\u00e8re n\u2019a pas non plus d\u00e9livr\u00e9 le permis n\u00e9cessaire, dans un tel cas, \u00e0 la r\u00e9exportation d\u2019armes. La cha\u00eene Telegram Rybar, sp\u00e9cialis\u00e9e notamment dans la couverture de la guerre, a cependant qualifi\u00e9 la d\u00e9claration du ministre d\u2019 <em>\u00ab infond\u00e9e \u00bb<\/em> et a indiqu\u00e9 que la documentation de Technoexport comprenait bel et bien les licences et permis n\u00e9cessaires. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des cha\u00eenes Telegram tr\u00e8s suivies<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab Ainsi, quoi que les repr\u00e9sentants officiels du gouvernement kazakh puissent dire en pr\u00e9textant qu\u2019ils ne peuvent pas exporter d\u2019armes sovi\u00e9tiques sans l\u2019autorisation du fabricant, c\u2019est-\u00e0-dire la Russie, ils le font \u00e0 huis clos \u00bb<\/em>, <a href=\"https:\/\/t.me\/rybar\/37231\">ont conclu<\/a> les auteurs de la cha\u00eene devant un public de plus d\u2019un demi-million de personnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En d\u2019autres termes, ce ne sont pas les forces de l\u2019ordre russes, ni la pr\u00e9sidence ou les structures sp\u00e9cialis\u00e9es, ni m\u00eame le comit\u00e9 de r\u00e9daction d\u2019un quelconque m\u00e9dia, mais une cha\u00eene Telegram anonyme qui a directement accus\u00e9 l\u2019\u00c9tat kazakh de mentir, sachant que, ce faisant, elle ne risquait rien. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des faits divers repris et d\u00e9form\u00e9s<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Une histoire de maltraitance d\u2019enfants \u2013 un sujet tr\u00e8s sensible au Kazakhstan \u2013 a suivi un sch\u00e9ma similaire fin ao\u00fbt. Un groupe d\u2019adolescents d\u2019Almaty a abus\u00e9 de deux fr\u00e8res, \u00e2g\u00e9s de quatre et neuf ans, en essayant de les forcer \u00e0 se faire des fellations. La m\u00e8re des gar\u00e7ons a <a href=\"https:\/\/orda.kz\/zastavljal-sovat-v-rot-podrostki-v-almaty-izdevalis-nad-detmi-na-detskoj-ploshhadke\/?utm_source=fergana.news&amp;utm_medium=referral&amp;utm_campaign=fergana.news&amp;utm_referrer=fergana.news\">lanc\u00e9<\/a> un appel \u00e0 l\u2019aide aupr\u00e8s de la fondation publique Nemoltchi.kz et de journalistes. Elle s\u2019est \u00e9galement adress\u00e9e \u00e0 la police.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, une vid\u00e9o d\u2019elle <a href=\"https:\/\/t.me\/mnogonazi\/8564\">est apparue<\/a> plus tard sur la cha\u00eene Telegram Mnogonatsional, sous le titre\u00a0: <em>\u00ab\u00a0Au Kazakhstan, des musulmans sans foi ni loi ont forc\u00e9 deux petits enfants russes, des fr\u00e8res, \u00e0 pratiquer le sexe oral sur une aire de jeu et ont tout film\u00e9.\u00a0\u00bb<\/em> Tsargrad, une cha\u00eene russe, a repris l\u2019histoire et a <a href=\"https:\/\/spb.tsargrad.tv\/news\/v-kazahstane-russkih-detej-unizili-v-izvrashhjonnoj-forme_605817\">rapport\u00e9<\/a><em>\u00ab\u00a0un autre cas de russophobie explicite au Kazakhstan.\u00a0\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/politique\/comment-la-russie-recrute-des-citoyens-centrasiatiques-pour-la-guerre-en-ukraine\/\">Comment la Russie recrute des citoyens centrasiatiques pour la guerre en Ukraine<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab\u00a0Cette fois, ceux qui d\u00e9testent la Russie se sont abaiss\u00e9s aux actes les plus ignobles\u00a0: ce sont des enfants russes qui en ont souffert \u00bb<\/em>, a d\u00e9clar\u00e9 la cha\u00eene dans son reportage, qui a \u00e9t\u00e9 ensuite cit\u00e9 par d\u2019autres m\u00e9dias russes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Une pol\u00e9mique qui continue malgr\u00e9 un d\u00e9menti<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> La m\u00e8re des victimes a ensuite publi\u00e9 une r\u00e9futation. La femme a qualifi\u00e9 les publications de provocation. <em>\u00ab Tous les enfants impliqu\u00e9s dans l\u2019incident sont ethniquement europ\u00e9ens, et il ne faut pas donner aux faits une tournure interethnique. Je vis au Kazakhstan depuis ma naissance et j\u2019ai de nombreux amis d\u2019autres minorit\u00e9s ethniques. Nous vivons tous en paix \u00bb<\/em>, a-t-elle soulign\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simultan\u00e9ment, la police d\u2019Almaty a ouvert une proc\u00e9dure p\u00e9nale pour incitation \u00e0 la haine ethnique. La question est de savoir qui sera tenu pour responsable de cette provocation. La cha\u00eene Telegram Mnogonatsional, qui a \u00e9t\u00e9 la premi\u00e8re \u00e0 parler de <em>\u00ab musulmans sans foi ni loi\u00a0\u00bb<\/em>, est \u00e9galement anonyme. De plus, m\u00eame apr\u00e8s la r\u00e9futation, les auteurs de la cha\u00eene, croyant en leur impunit\u00e9, ont affirm\u00e9 que la m\u00e8re avait \u00e9t\u00e9 contrainte d\u2019enregistrer sa d\u00e9claration par la force. Ils n\u2019ont, bien s\u00fbr, fourni aucune preuve de cette affirmation. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La question linguistique<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Il y a une autre question que les r\u00e9seaux sociaux russes pro-gouvernementaux n\u2019ont pas laiss\u00e9e \u00e9chapper dans les relations entre les deux pays : la question linguistique. Dans un premier temps, l\u2019information selon laquelle les cours de langue russe dispara\u00eetraient dans les six ou sept prochaines ann\u00e9es a commenc\u00e9 \u00e0 circuler activement sur les r\u00e9seaux sociaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les m\u00e9dias <a href=\"https:\/\/glas.ru\/society\/646806-v-shkolax-kazaxstana-xotyat-uprazdnit-russkoyazychnye-klassy-dlya-pervoklassnikov-un10338\/\">Glas.ru<\/a> et <a href=\"https:\/\/kz.tsargrad.tv\/news\/v-shkolah-kazahstana-gotovjatsja-zakryt-vse-russkojazychnye-klassy_604453\">Tsargrad.tv<\/a>. notamment ont rapport\u00e9 cette information. Il s\u2019est av\u00e9r\u00e9 qu\u2019ils faisaient r\u00e9f\u00e9rence \u00e0 un reportage diffus\u00e9 deux ans auparavant sur la cha\u00eene 31 du Kazakhstan, tout en d\u00e9formant les faits. Le minist\u00e8re kazakh de l\u2019\u00c9ducation a d\u00e9menti, mais quelques jours plus tard, la question de la langue russe a refait surface.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/decryptage\/le-divorce-progressif-du-kazakhstan-avec-la-russie\/\">Le divorce progressif du Kazakhstan avec la Russie<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 16 ao\u00fbt dernier, apr\u00e8s la d\u00e9claration du ministre de l\u2019\u00c9ducation, Askhat A\u00efmagambetov, une rumeur a commenc\u00e9 \u00e0 circuler sur les r\u00e9seaux sociaux : les \u00e9coliers de premi\u00e8re ann\u00e9e (l&rsquo;\u00e9quivalent du CP) n\u2019apprendraient plus la langue russe au Kazakhstan, et ce d\u00e8s la rentr\u00e9e 2022. Seule la langue kazakhe resterait obligatoire pour les \u00e9l\u00e8ves de premi\u00e8re ann\u00e9e. En r\u00e9alit\u00e9, le ministre ne parlait que des \u00e9coles o\u00f9 l\u2019enseignement est dispens\u00e9 dans la langue d\u2019\u00c9tat, le kazakh, ce qu\u2019un certain nombre de publications a d\u00e9lib\u00e9r\u00e9ment <a href=\"https:\/\/ok.ru\/tsargradtv\/topic\/154451874882944\">omis de mentionner<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>L\u2019omission d\u2019informations<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Les agences f\u00e9d\u00e9rales, notamment <a href=\"https:\/\/tass.ru\/obschestvo\/15491101\">TASS<\/a>, et les principaux m\u00e9dias russes, ont cependant donn\u00e9 une version correcte des faits. Au d\u00e9but du mois de juin dernier, le ministre Askhat A\u00efmagambetov, dans une interview accord\u00e9e \u00e0 <a href=\"https:\/\/www.nur.kz\/politics\/kazakhstan\/1972720-v-pervom-klasse-tolko-rodnoy-yazyk-glava-mon-zayavil-ob-izmeneniyah-v-trehyazychii\/\">nur.kz<\/a>, a par exemple d\u00e9clar\u00e9 qu\u2019il \u00e9tait difficile pour les enfants d\u2019avoir une \u00e9ducation trilingue d\u00e8s la premi\u00e8re ann\u00e9e, et qu\u2019il avait donc \u00e9t\u00e9 d\u00e9cid\u00e9 d\u2019introduire les langues pour les classes primaires par \u00e9tapes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0<\/em><\/strong><em>Nous avons pris une d\u00e9cision sur cette question. Nous travaillons d\u00e9j\u00e0 pour que dans les \u00e9coles o\u00f9 l\u2019enseignement est dispens\u00e9 en kazakh, l\u2019enfant n\u2019apprenne qu\u2019une seule langue en premi\u00e8re ann\u00e9e\u00a0: le kazakh, c\u2019est-\u00e0-dire qu\u2019il apprenne d\u2019abord \u00e0 lire et \u00e0 \u00e9crire dans sa langue maternelle. En deuxi\u00e8me ann\u00e9e, le russe est ajout\u00e9 dans le programme et en troisi\u00e8me ann\u00e9e, l\u2019anglais\u00a0\u00bb<\/em>, avait-il d\u00e9clar\u00e9. Les m\u00e9dias russes ne se sont pas int\u00e9ress\u00e9s \u00e0 cette d\u00e9claration. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un post rapidement supprim\u00e9 de Dmitri Medvedev<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Ce ne sont que quelques exemples parmi tant d\u2019autres. Le post supprim\u00e9 sur Vkontakte de l\u2019ancien pr\u00e9sident Dmitri Medvedev, vice-pr\u00e9sident du Conseil de s\u00e9curit\u00e9 de la F\u00e9d\u00e9ration de Russie, a aussi eu une r\u00e9sonance particuli\u00e8re. Selon lui, le Kazakhstan est un <em>\u00ab \u00c9tat artificiel\u00a0\u00bb<\/em> o\u00f9 les autorit\u00e9s m\u00e8nent une politique de <em>\u00ab\u00a0g\u00e9nocide des Russes.\u00a0\u00bb<\/em> Le poste a \u00e9t\u00e9 supprim\u00e9 dix minutes apr\u00e8s sa publication.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dmitri Medvedev lui-m\u00eame a justifi\u00e9 cette publication par un piratage. En outre, un grand nombre de faux ont commenc\u00e9 \u00e0 circuler via les cha\u00eenes Telegram et les r\u00e9seaux, comme le fait que des enfants kazakhs auraient <a href=\"https:\/\/t.me\/zvoinaukraina\/16560\">tu\u00e9<\/a> un gar\u00e7on russe \u00e0 Astana. L\u2019information \u00e9tait justifi\u00e9e par la vid\u00e9o d\u2019un combat de l\u2019ann\u00e9e pr\u00e9c\u00e9dente, au cours duquel personne n\u2019avait \u00e9t\u00e9 tu\u00e9. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Une campagne planifi\u00e9e<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\nLe nombre de cas similaires a tellement augment\u00e9 qu\u2019il s\u2019agit sans aucun doute d\u2019une campagne de d\u00e9sinformation planifi\u00e9e.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"> Les officiels russes nient avec v\u00e9h\u00e9mence. Le pr\u00e9sident russe Vladimir Poutine a qualifi\u00e9 \u00e0 plusieurs reprises le Kazakhstan de partenaire strat\u00e9gique, tandis que son porte-parole l\u2019a d\u00e9crit comme un \u00c9tat ami. Le 19 ao\u00fbt 2022, le dirigeant kazakh, <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kassym-jomart-tokaiev-le-diplomate-devenu-president\/\">Kassym-Jomart Toka\u00efev<\/a>, est arriv\u00e9 \u00e0 Sotchi pour rencontrer Vladimir Poutine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kassym-Jomart Toka\u00efev a ensuite d\u00e9clar\u00e9 \u00eatre satisfait de l\u2019\u00e9volution de la coop\u00e9ration entre les deux pays. <em>\u00ab\u00a0Nous sommes unis par une fronti\u00e8re commune, la plus longue fronti\u00e8re terrestre du monde, qui est enti\u00e8rement d\u00e9limit\u00e9e. Il n\u2019y a certainement aucune raison de faire des pr\u00e9dictions pessimistes sur l\u2019avenir de notre coop\u00e9ration\u00a0! Personnellement, en tant que pr\u00e9sident de la R\u00e9publique du Kazakhstan, je suis d\u00e9termin\u00e9 \u00e0 donner un nouvel \u00e9lan \u00e0 notre coop\u00e9ration bilat\u00e9rale dans tous les domaines\u00a0\u00bb<\/em>, a <a href=\"https:\/\/www.akorda.kz\/ru\/prezident-kazahstana-provel-peregovory-s-prezidentom-rossii-1975333\">d\u00e9clar\u00e9<\/a> Kassym-Jomart Toka\u00efev.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>La r\u00e9daction de Fergana News<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Traduit du <a href=\"https:\/\/fergana.news\/articles\/127337\/\">russe<\/a> par Alexei Vasselin<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>\u00c9dit\u00e9 par Judith Robert<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par \u00c9lise Piedfort<\/strong>*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Merci d&rsquo;avoir lu cet article jusqu&rsquo;au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez&nbsp;<a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a>&nbsp;ou nous envoyer un email \u00e0&nbsp;<a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but de la guerre en Ukraine, une campagne massive de d\u00e9sinformation a lieu au Kazakhstan. Des m\u00e9dias et des cha\u00eenes Telegram russes v\u00e9hiculent notamment l&rsquo;id\u00e9e d&rsquo;une soci\u00e9t\u00e9 kazakhe russophobe. Novastan reprend et traduit ici un article publi\u00e9 le 20 ao\u00fbt 2022 par le m\u00e9dia russe sp\u00e9cialis\u00e9 sur l&rsquo;Asie centrale Fergana News. Le Kazakhstan [&hellip;]<\/p>\n","protected":false},"author":1589,"featured_media":56161,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,3984],"tags":[3666,2995,470,1698,488,1956],"coauthors":[5128],"class_list":["post-56142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kazakhstan","category-politique","tag-fake-news","tag-information","tag-kazakhstan","tag-medias","tag-politique","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/56142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1589"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=56142"}],"version-history":[{"count":1,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/56142\/revisions"}],"predecessor-version":[{"id":69362,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/56142\/revisions\/69362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/56161"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=56142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=56142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=56142"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=56142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}