{"id":54979,"date":"2022-06-10T08:12:44","date_gmt":"2022-06-10T06:12:44","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=54979"},"modified":"2023-03-30T10:04:05","modified_gmt":"2023-03-30T08:04:05","slug":"lagrotourisme-se-developpe-au-kazakhstan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kazakhstan\/lagrotourisme-se-developpe-au-kazakhstan\/","title":{"rendered":"L&rsquo;agrotourisme se d\u00e9veloppe au Kazakhstan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L\u2019id\u00e9e de d\u00e9velopper l\u2019agrotourisme dans la r\u00e9gion du Turkestan flotte dans l\u2019air depuis d\u00e9j\u00e0 de nombreuses ann\u00e9es. La r\u00e9gion dispose d\u2019un fort potentiel dans ce domaine, avec des centaines de rivi\u00e8res et de lacs purs, des monuments historiques et culturels, des parcs nationaux. Et plus important encore, cette province, forte d\u2019une population accueillante et hospitali\u00e8re, est parsem\u00e9e de villages, plus commun\u00e9ment appel\u00e9s aouls, charg\u00e9s de traditions et o\u00f9 la vie est paisible.<\/strong><strong>Novastan reprend et traduit ici un article publi\u00e9 le 16 f\u00e9vrier 2022 par le m\u00e9dia kazakh <\/strong><a href=\"https:\/\/livingasia.online\/2022\/02\/16\/agroturizm-razvivaetsya\/\"><strong>LivingAsia<\/strong><\/a><strong>.<\/strong>\n\nGr\u00e2ce \u00e0 l&rsquo;association publique UGAM, une des organisations non gouvernementales (ONG) les plus anciennes et exp\u00e9riment\u00e9es de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oblys_du_Turkestan\">l&rsquo;oblast de Turkestan<\/a>, et avec le soutien du programme de <a href=\"https:\/\/www.thegef.org\/projects-operations\/projects\/9205\">microfinancement du Fond pour l\u2019environnement mondial (FEM)<\/a>, l\u2019agrotourisme est d\u00e9sormais possible dans cette r\u00e9gion. L\u2019agrotourisme, qu\u2019est-ce que c\u2019est&nbsp;? Secteur de l\u2019industrie touristique, l\u2019agrotourisme permet aux touristes de s&rsquo;immerger dans le mode de vie rural, de se familiariser avec le travail des artisans, des agriculteurs, et de d\u00e9couvrir la culture et les coutumes locales.\n\n<\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nCe genre d\u2019activit\u00e9 est d\u00e9j\u00e0 pratiqu\u00e9 depuis longtemps en Europe, plus particuli\u00e8rement en France et en Espagne. Des villages entiers y ont \u00e9t\u00e9 cr\u00e9\u00e9s, offrant aux visiteurs la possibilit\u00e9 de s\u2019\u00e9loigner de l&rsquo;agitation de la ville, de d\u00e9couvrir des produits plus respectueux de l\u2019environnement, de respirer l\u2019air pur et de s\u2019essayer aux travaux agricoles.\n\n<strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/au-kazakhstan-deux-eco-activistes-de-bestobe-juges-pour-incitation-a-la-discorde-sociale\/\">Au Kazakhstan, deux \u00e9co-activistes de Bestob\u00e9 jug\u00e9s pour \u00ab&nbsp;incitation \u00e0 la discorde sociale&nbsp;\u00bb<\/a><\/strong>\n\nL\u2019agrotourisme a plusieurs avantages. Il favorise le d\u00e9veloppement de petites entreprises tout en ne n\u00e9cessitant pas d\u2019importants investissements et constitue une source de revenus pour la population rurale.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>L\u2019importance de l\u2019agrotourisme dans la r\u00e9habilitation des terres<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nLa majorit\u00e9 des terres arables et des p\u00e2tures de la province de Turkestan sont sujettes \u00e0 la d\u00e9gradation. Cela est en grande partie d\u00fb \u00e0 la mani\u00e8re dont sont men\u00e9es les activit\u00e9s agricoles sur ces sols.\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-54987\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan.jpg\" alt=\"Agrotourisme Turkestan\" class=\"wp-image-54987\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan.jpg 1170w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan-300x200.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan-1024x683.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan-768x512.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan-128x86.jpg 128w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\">Les touristes rencontrent les traditions kazakhes.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nDe ce fait, le rendement des champs diminue, jusqu&rsquo;\u00e0 les rendre compl\u00e8tement inexploitables, affectant ainsi le niveau de vie des communaut\u00e9s locales. Les populations locales doivent \u00eatre, par cons\u00e9quent, en premier lieu impliqu\u00e9es dans les activit\u00e9s de r\u00e9habilitation des terres. Il est n\u00e9cessaire de travailler directement avec les acteurs de l&rsquo;agriculture : agriculteurs et propri\u00e9taires d&rsquo;exploitations, jeunes entrepreneurs ruraux. Les agriculteurs pourront alors apprendre \u00e0 ma\u00eetriser de nouvelles m\u00e9thodes d&rsquo;agriculture progressives, s&rsquo;\u00e9loignant des techniques agricoles plus anciennes, utilis\u00e9es jusqu\u2019\u00e0 pr\u00e9sent. Ainsi, l\u2019agrotourisme contribuera \u00e0 sensibiliser \u00e0 la protection de la nature et de l\u2019environnement.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Un secteur prometteur<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab L\u2019agrotourisme demeure le moyen le plus prometteur pour aider les populations locales des aouls \u00e0 vivre confortablement \u00bb,<\/em> selon Alikhane Abdechevitch Abdechev, pr\u00e9sident de l&rsquo;ONG UGAM. \u00ab <em>L\u2019arriv\u00e9e de seulement quelques touristes permettrait d\u2019employer trois ou quatre habitants locaux. La propri\u00e9taire de la maison d&rsquo;h\u00f4tes accueillera les touristes, pr\u00e9parera les repas, leur montrera comment elle s&rsquo;occupe des animaux et comment elle effectue les t\u00e2ches m\u00e9nag\u00e8res. L&rsquo;h\u00f4te les guidera \u00e0 travers les sentiers, et son fils les accompagnera lors d\u2019une randonn\u00e9e \u00e0 cheval de longue distance \u00bb, <\/em>explique-t-il.\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-54986\"><img loading=\"lazy\" decoding=\"async\" width=\"1672\" height=\"1254\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1.jpg\" alt=\"Agrotourisme Turkestan\" class=\"wp-image-54986\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1.jpg 1672w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1-300x225.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1-1024x768.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1-768x576.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1-1536x1152.jpg 1536w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1-800x600.jpg 800w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/06\/agrotourisme-turkestan1-1300x975.jpg 1300w\" sizes=\"auto, (max-width: 1672px) 100vw, 1672px\" \/><figcaption class=\"wp-element-caption\">L&rsquo;agrotourisme permet aux familles de recevoir un revenu suppl\u00e9mentaire (illustration).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab Les touristes \u00e9trangers sont tr\u00e8s curieux et s\u2019int\u00e9ressent \u00e0 tout. Ils cherchent \u00e0 comprendre notre mentalit\u00e9 kazakhe, ils veulent participer \u00e0 tout et manger avec nous. Nous avons essay\u00e9 d&rsquo;organiser un repas europ\u00e9en pour eux, mais ils le refusent. Ils observent notre mani\u00e8re d\u2019\u00e9lever nos animaux. Ils assistent \u00e0 la traite des vaches et des juments et y participent \u00e9galement \u00bb<\/em>, ajoute-t-il.\n\n<strong>Lire aussi sur Novastan :<\/strong><strong> <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-ce-qui-bloque-lessor-du-tourisme-rural\/\">Tadjikistan : ce qui bloque l\u2019essor du tourisme rural<\/a><\/strong>\n\n59 familles d\u2019agriculteurs et d\u2019entrepreneurs individuels ont particip\u00e9 aux activit\u00e9s du projet UGAM. Ils ont am\u00e9nag\u00e9 des parcelles de d\u00e9monstration sur leurs terres arables et ont adopt\u00e9 des m\u00e9thodes \u00e9cologiques. L&rsquo;initiative d\u00e9montre d\u00e9sormais les avantages environnementaux et socio-\u00e9conomiques des technologies agricoles durables.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Partenariat avec l\u2019Universit\u00e9 agricole de Turkestan<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nL&rsquo;ONG UGAM a cr\u00e9\u00e9 un centre de formation permanent, AgroEcoCenter, en collaboration avec l\u2019<a href=\"https:\/\/turkistan-agro.kz\/en\/home\/\">Universit\u00e9 agricole de Turkestan<\/a> et la facult\u00e9 d&rsquo;agriculture de l&rsquo;<a href=\"https:\/\/en.wikipedia.org\/wiki\/Shymkent_University\">Universit\u00e9 de Chymkent<\/a>. L&rsquo;AgroEcoCenter a form\u00e9 160 agriculteurs aux panneaux et capteurs solaires, \u00e0 la gestion des serres, \u00e0 l&rsquo;irrigation au goutte-\u00e0-goutte, aux technologies permettant d&rsquo;\u00e9conomiser l&rsquo;eau ainsi qu&rsquo;\u00e0 bien d&rsquo;autres techniques. La formation dispens\u00e9e sur le site de l&rsquo;Universit\u00e9 agricole ne concerne pas seulement les agriculteurs. Les \u00e9tudiants ont d\u00e9sormais la possibilit\u00e9 de se familiariser avec les nouvelles technologies, pratiques et m\u00e9thodes de production v\u00e9g\u00e9tale.\n\n<strong>Lire aussi sur Novastan : <\/strong><strong><a href=\"https:\/\/novastan.org\/fr\/environnement\/louzbekistan-et-le-turkmenistan-surconsomment-leurs-ressources-en-eau\/\">L\u2019Ouzb\u00e9kistan et le Turkm\u00e9nistan surconsomment leurs ressources en eau<\/a><\/strong><em>\u00ab La coop\u00e9ration entre notre \u00e9tablissement et l&rsquo;ONG UGAM est tr\u00e8s fructueuse et b\u00e9n\u00e9fique \u00bb,<\/em> constate Timour Ormantchine, directeur adjoint de l\u2019Universit\u00e9 agricole de Turkestan. \u00ab <em>Notre universit\u00e9 comporte deux objectifs. Le premier est d&rsquo;am\u00e9liorer la qualit\u00e9 de l&rsquo;enseignement, car aujourd&rsquo;hui la r\u00e9gion du sud est l&rsquo;une des plus chaudes, et les agronomes de notre r\u00e9gion ont d&rsquo;\u00e9normes perspectives en termes de d\u00e9veloppement. Le second est de produire des produits \u00e9cologiques propres et de haute qualit\u00e9. Pour cela, nous avons \u00e9t\u00e9 grandement aid\u00e9s par l\u2019UGAM avec le soutien du programme de microfinancement du FEM \u00bb<\/em>, ajoute-t-il.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nDes sites de d\u00e9monstration ont \u00e9t\u00e9, par cons\u00e9quent, mis en place dans six exploitations agricoles de trois districts de l&rsquo;oblast de Turkestan. Des plantes fourrag\u00e8res et ol\u00e9agineuses y sont cultiv\u00e9es dans le but d\u2019am\u00e9liorer la fertilit\u00e9 des sols. Les agrotouristes qui s\u00e9journent dans ces fermes sont form\u00e9s aux meilleures pratiques pour lutter contre la d\u00e9gradation des sols. Plus de 200 visiteurs ont appris en pratique ce qu&rsquo;\u00e9tait l&rsquo;agrotourisme en participant aux activit\u00e9s sur ces sites. Le premier catalogue d&rsquo;agrotourisme dans la r\u00e9gion de Turkestan a \u00e9t\u00e9 publi\u00e9 dans le cadre de ce projet.\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Oksana Tarnetska\u00efa\n<\/strong><strong>Auteur pour LivingAsia<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Traduit du <a href=\"https:\/\/livingasia.online\/2022\/02\/16\/agroturizm-razvivaetsya\/\">russe<\/a> par Alexandra B\u00e9roujon<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>\u00c9dit\u00e9 par Anthony Vial<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Emma Jerome<\/strong>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019id\u00e9e de d\u00e9velopper l\u2019agrotourisme dans la r\u00e9gion du Turkestan flotte dans l\u2019air depuis d\u00e9j\u00e0 de nombreuses ann\u00e9es. La r\u00e9gion dispose d\u2019un fort potentiel dans ce domaine, avec des centaines de rivi\u00e8res et de lacs purs, des monuments historiques et culturels, des parcs nationaux. Et plus important encore, cette province, forte d\u2019une population accueillante et hospitali\u00e8re, [&hellip;]<\/p>\n","protected":false},"author":1595,"featured_media":54985,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3981,4],"tags":[416,571,1138,428,4597,1956,999],"coauthors":[5127,3688,5049],"class_list":["post-54979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-environnement","category-kazakhstan","tag-agriculture","tag-economie","tag-ecotourisme","tag-environnement","tag-kazahkstan","tag-traduction","tag-turkestan"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1595"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=54979"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/54985"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=54979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=54979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=54979"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=54979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}