{"id":54764,"date":"2022-06-04T09:44:34","date_gmt":"2022-06-04T07:44:34","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=54764"},"modified":"2026-03-31T14:32:27","modified_gmt":"2026-03-31T12:32:27","slug":"entretien-avec-lartiste-goulnour-moukajanova-sur-la-sauvegarde-de-la-culture-kazakhe-dans-lart-contemporain","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kazakhstan\/entretien-avec-lartiste-goulnour-moukajanova-sur-la-sauvegarde-de-la-culture-kazakhe-dans-lart-contemporain\/","title":{"rendered":"Entretien avec l\u2019artiste Goulnour Moukajanova sur la sauvegarde de la culture kazakhe dans l&rsquo;art contemporain"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>La galerie Aspan \u00e0 Almaty a inaugur\u00e9 l\u2019exposition personnelle de la jeune artiste Goulnour Moukajanova. Le m\u00e9dia Vlast a discut\u00e9 avec l\u2019artiste de ses objectifs artistiques et de son attitude vis-\u00e0-vis de l\u2019environnement socioculturel qui l\u2019entoure.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Novastan reprend et traduit ici un article publie\u0301 le 23 juillet 2021 par le me\u0301dia kazakh <\/b><a href=\"https:\/\/vlast.kz\/life\/45975-gulnur-mukazanova-hudoznica-kogda-byla-vozmoznost-postroit-nase-obsestvo-svobodnym-my-soorudili-svoego-roda-kapkan.html\"><b>Vlast<\/b><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/gulnurmukazhanova.com\/\"><span style=\"font-weight: 400\">Goulnour Moukajanova<\/span><\/a><span style=\"font-weight: 400\">travaille avec des mat\u00e9riaux sp\u00e9cifiques, en particulier le feutre. Dans ses projets photo et ses vid\u00e9os, l\u2019attention est port\u00e9e sur le mat\u00e9riau lui-m\u00eame, notamment sur son aspect performatif. Le processus de fabrication du feutre devient tout aussi important que le r\u00e9sultat.\u00a0L&rsquo;artiste est n\u00e9e en 1984 \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Seme%C3%AF\">Seme\u00ef<\/a>, au Kazakhstan. Elle vit et travaille \u00e0 Berlin.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Ses expositions r\u00e9centes sont Bread &amp; Roses au <a href=\"https:\/\/momentum.berlin\/\">Momentum<\/a> de Berlin (2018) et Post Nomadic Mind au <a href=\"https:\/\/thewappingproject.org\/about\/\">Wapping Project<\/a> \u00e0 Londres (2018). L&rsquo;artiste a expos\u00e9 \u00e0 la 4\u00e8me <a href=\"https:\/\/www.routard.com\/guide_agenda_detail\/18698\/biennale_internationale_de_moscou_pour_l_art_jeune.htm\">Biennale internationale de Moscou pour l\u2019art jeune<\/a> (2014) et au Central Asia Pavilion \u00e0 la 52\u00e8me <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Biennale_de_Venise\">biennale de Venise<\/a> (2007).<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Vlast : Quelles sont les \u0153uvres centrales de votre exposition ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\"><strong>Goulnour Moukajanova :<\/strong> L\u2019exposition se compose de trois parties diff\u00e9rentes : une s\u00e9rie d\u2019\u0153uvres en feutres, une autre de photographies et une derni\u00e8re compos\u00e9e de vid\u00e9os. La partie principale est le travail du feutre. Les photos et vid\u00e9os sont compl\u00e9mentaires et contrast\u00e9es. Elles permettent d\u2019approfondir un peu le sens du travail.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u00c0 l\u2019aide d\u2019\u0153uvres en feutre, j\u2019essaie de transmettre l\u2019\u00e9tat g\u00e9n\u00e9ral, un aper\u00e7u de la soci\u00e9t\u00e9. Tout mon travail concerne la culture kazakhe, les questions identitaires, les valeurs culturelles, morales et ce qui se passe aujourd\u2019hui.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Comment en \u00eates-vous venue \u00e0 utiliser le feutre dans vos \u0153uvres ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Lorsque j\u2019\u00e9tais \u00e0 l\u2019<a href=\"https:\/\/en.wikipedia.org\/wiki\/Kazakh_National_Academy_of_Arts\">Acad\u00e9mie Jourgenov<\/a>, j\u2019ai \u00e9tudi\u00e9 \u00e0 la facult\u00e9 des arts appliqu\u00e9s, du tissage de tapis et des textiles. J\u2019ai appris de nombreuses techniques diff\u00e9rentes, mais mon choix s\u2019est affin\u00e9 \u00e0 la fin de mes \u00e9tudes \u00e0 Berlin.<\/span><\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Je suis partie apr\u00e8s avoir obtenu mon dipl\u00f4me. J\u2019ai r\u00e9alis\u00e9 que nous \u00e9tions tr\u00e8s proches du feutre, comme s\u2019il \u00e9tait dans notre sang. \u00c0 la fin de mes \u00e9tudes \u00e0 Berlin, toutes mes \u0153uvres \u00e9taient faites en feutre. Par la suite, il est devenu clair que je devais approfondir les techniques de travail de ce mat\u00e9riau. Il y a beaucoup de possibilit\u00e9s \u00e0 exploiter. En effet, j\u2019ai vu une sorte de perspective \u00e0 travers cette mati\u00e8re.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Le th\u00e8me central de votre exposition est la perte d\u2019identit\u00e9 due \u00e0 la mondialisation. Comment avez-vous d\u00e9couvert ce sujet ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Tout cela est arriv\u00e9 quand je suis venue \u00e9tudier en Allemagne. J\u2019ai eu un choc culturel. J\u2019ai commenc\u00e9 \u00e0 comparer l\u2019Allemagne et le Kazakhstan. Par la suite, j\u2019ai juste continu\u00e9 \u00e0 m\u2019ouvrir et \u00e0 travailler sur ce sujet. Cela m\u2019inqui\u00e9tait beaucoup et m\u2019inqui\u00e8te toujours. <\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-54768\"><img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"787\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Global-society-.jpeg\" alt=\"Global society\" class=\"wp-image-54768\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Global-society-.jpeg 1181w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Global-society--300x200.jpeg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Global-society--1024x682.jpeg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Global-society--768x512.jpeg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Global-society--128x86.jpeg 128w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/><figcaption class=\"wp-element-caption\">Photo appartenant \u00e0 la s\u00e9rie Global society.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il y a beaucoup de facteurs qui me sont incompr\u00e9hensibles. Il faut les \u00e9tudier, \u00e9tudier sa propre histoire et celle des nomades. En fait, nous avons tr\u00e8s peu de contenu \u00e0 ce sujet. J\u2019ai commenc\u00e9 \u00e0 regarder mon pays de l\u2019ext\u00e9rieur, et c\u2019est pourquoi j\u2019ai abord\u00e9 ce sujet.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>En parlant de choc culturel, y a-t-il quelque chose de pr\u00e9cis qui vous a incit\u00e9 \u00e0 explorer davantage ce sujet ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">D\u2019abord, c\u2019est la vie sociale et quotidienne. Au cours des deux premi\u00e8res ann\u00e9es de mon s\u00e9jour en Allemagne, j\u2019ai remarqu\u00e9 \u00e0 quel point la qualit\u00e9 de vie est diff\u00e9rente. Malgr\u00e9 le fait que le Kazakhstan est l\u2019un des pays les plus riches en termes de ressources. Cependant, les habitants ordinaires ne pensent qu&rsquo;en termes de survie. Chaque fois que je viens au Kazakhstan, je constate que rien n\u2019a chang\u00e9. S\u2019il y a des changements, alors ils sont tous tr\u00e8s superficiels.En v\u00e9rit\u00e9, chaque famille est endett\u00e9e de deux ou trois pr\u00eats financiers. De plus, les gens ont la possibilit\u00e9 d\u2019acheter une propri\u00e9t\u00e9 uniquement gr\u00e2ce \u00e0 des cr\u00e9dits.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">C\u2019est la m\u00eame chose avec la vie culturelle, la compr\u00e9hension de la culture et l\u2019art. Les gens ici disent souvent que l\u2019art contemporain est quelque chose d\u2019\u00e9trange. C\u2019est simplement qu&rsquo;ils ne le comprennent pas parce qu\u2019ils ne peuvent pas en voir. Au final, nous ne montrons rien, ou tr\u00e8s peu. Au Kazakhstan, il n\u2019y a que deux ou trois galeries d\u2019art contemporain qui font des expositions, cela gr\u00e2ce \u00e0 leurs propres efforts.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>En regardant votre travail, les toiles de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Mark_Rothko\">Mark Rothko<\/a> viennent \u00e0 l\u2019esprit. N\u00e9anmoins vos \u0153uvres, en raison des mat\u00e9riaux utilis\u00e9s, diff\u00e8rent par leur texture. Effacer l\u2019ornementation des tapis peut aussi \u00eatre un symbole de perte de culture, car c\u2019est un syst\u00e8me s\u00e9miotique complexe. Comment votre interpr\u00e9tation des tapis nomades s\u2019est-elle d\u00e9velopp\u00e9e dans cette s\u00e9rie d\u2019\u0153uvres ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">J\u2019ai commenc\u00e9 la s\u00e9rie<i>\u00a0<\/i><em>Post-nomadic Reality <\/em>en 2013 et depuis je la continue sans cesse. Ces \u0153uvres sont inspir\u00e9es des touskiiz, des tapis muraux suspendus dans des yourtes au-dessus du lit au Kazakhstan. La signification symbolique de ce mot est tr\u00e8s importante : <em>\u00ab tous \u00bb<\/em> signifie r\u00eave. La forme du tapis lui-m\u00eame ressemble \u00e0 une porte ou un portail vers un autre espace. Je vois cet espace comme quelque chose d\u2019inconscient.\u00a0<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-54767\"><img loading=\"lazy\" decoding=\"async\" width=\"1909\" height=\"2560\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-scaled.jpeg\" alt=\"Post-nomadic Reality.\" class=\"wp-image-54767\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-scaled.jpeg 1909w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-224x300.jpeg 224w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-763x1024.jpeg 763w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-768x1030.jpeg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-1145x1536.jpeg 1145w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-1527x2048.jpeg 1527w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Postnomadic-Reality-1300x1744.jpeg 1300w\" sizes=\"auto, (max-width: 1909px) 100vw, 1909px\" \/><figcaption class=\"wp-element-caption\">Tableau de la s\u00e9rie <em>Post-nomadic Reality<\/em>.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Lorsque nous nous endormons, nous entrons dans cet espace inconscient. C\u2019est ce qu\u2019on retrouve dans mes travaux. Ces \u0153uvres continuent de conserver la forme rectangulaire des tapis, mais la partie inf\u00e9rieure est ferm\u00e9e. Ainsi, il est possible de montrer le temps et l\u2019\u00e9tat dans lequel nous sommes enferm\u00e9s. Notre soci\u00e9t\u00e9 ressemble \u00e0 un cadre que nous avons nous-m\u00eames cr\u00e9\u00e9.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Elle est constitu\u00e9e de r\u00e8gles, de fondements, de comportements et de mani\u00e8res de parler. Un ensemble arrang\u00e9 par notre peuple depuis l\u2019ind\u00e9pendance. Nous avons eu l&rsquo;opportunit\u00e9 de construire une soci\u00e9t\u00e9 libre mais c\u2019est devenu une sorte de prison. Aujourd\u2019hui, il est difficile de faire changer les choses ou de les am\u00e9liorer. Tout ce qui est cr\u00e9\u00e9 ne fait que nous tirer vers le bas. Bien s\u00fbr, il y a des individus qui essaient de faire des choses par eux-m\u00eames, mais la majorit\u00e9 n\u2019y arrive pas.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Lire aussi sur Novast<\/b><strong>an :\u00a0<a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/la-peinture-contemporaine-kirghize-exposee-a-paris\/\">La peinture contemporaine kirghize expos\u00e9e \u00e0 Paris<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Dans les formes rectangulaires de ces \u0153uvres, il y a des couleurs tr\u00e8s vives. C\u2019est le point d\u2019attraction pour le public. La couleur a un but, celui d\u2019attirer l\u2019attention, de sorte que les gens commencent \u00e0 poser toutes sortes de questions : Pourquoi en deux couleurs ? Pourquoi la forme est-elle rectangulaire ? Pourquoi les fronti\u00e8res sont-elles floues \u00e0 certains endroits ? Ce flou d\u00e9note simplement le d\u00e9sir d\u2019am\u00e9liorer les choses. Dans tous les cas, c\u2019est notre pays que nous soutenons et que nous voulons am\u00e9liorer. Finalement, la couleur vive est celle de l\u2019espoir.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>L\u2019exposition mentionne que vous n\u2019utilisez pas sp\u00e9cifiquement d\u2019ornements.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Oui, c\u2019est une d\u00e9marche d\u00e9lib\u00e9r\u00e9e. Les ornements des tapis existaient avant, mais aujourd\u2019hui l\u2019interpr\u00e9tation n\u2019est pas la m\u00eame puisque leur lecture n\u2019est plus pratiqu\u00e9e. Auparavant, les nomades les comprenaient, et cela faisait partie de leur vie. Aujourd\u2019hui, les ornements utilis\u00e9s dans la vie quotidienne et dans les traditions sont appliqu\u00e9s au hasard. La soci\u00e9t\u00e9 ne sait pas comment les interpr\u00e9ter. Par cons\u00e9quent, je les supprime. Aujourd\u2019hui, je remets en question les valeurs, qui ont laiss\u00e9 un vide. De ce fait, le nom <em>\u00ab espace de silence \u00bb<\/em> fait r\u00e9f\u00e9rence \u00e0 cela.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Vous avez \u00e9galement utilis\u00e9 le mot<span style=\"font-weight: 400\">\u00ab <\/span>portail <span style=\"font-weight: 400\">\u00bb<\/span>\u00a0pour d\u00e9crire les \u0153uvres. Il y a cette id\u00e9e de liaison aux r\u00eaves \u00e0 travers les touskiiz. Est-ce possible d\u2019en savoir plus sur cette id\u00e9e ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">J\u2019ai \u00e9voqu\u00e9 plus haut l\u2019\u00e9tat de conscience et d\u2019inconscience dans lequel chaque personne se trouve. Certains facteurs externes apparaissent rapidement, par exemple la mondialisation. Je ne suis pas contre la mondialisation puisqu\u2019il faut \u00eatre dans l\u2019air du temps. N\u00e9anmoins, il faut aussi pr\u00e9server les valeurs spirituelles int\u00e9rieures des nomades kazakhs qui sont encore dans notre sang. Pour cela, il faut conna\u00eetre la langue de ses anc\u00eatres.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">M\u00eame en lisant la litt\u00e9rature kazakhe en russe, les diff\u00e9rences avec le texte d&rsquo;origine sont visibles. Pour ce qui est du portail, tout est bien s\u00fbr symbolique. En p\u00e9riode de transition, il est possible de sortir ou de rester dans cet espace d\u2019entre-deux. C\u2019est sur cela qu\u2019il faut travailler. Chaque individu doit travailler sur lui-m\u00eame afin de faire des choix et construire une soci\u00e9t\u00e9 saine.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Vous avez utilis\u00e9 plusieurs fois les expressions <em>\u00ab\u00a0valeurs \u00e9trang\u00e8res\u00a0\u00bb<\/em> et <em>\u00ab\u00a0valeurs substitu\u00e9es\u00a0\u00bb<\/em>. Comment d\u00e9cririez-vous ces valeurs ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">D\u2019abord, par la culture mat\u00e9rielle. La valorisation de l\u2019artisanat, par exemple pour les touskiiztiss\u00e9s. Les m\u00e8res et les filles se pr\u00e9paraient pour le mariage en cousant des touskiiz. Aujourd\u2019hui, personne ne s\u2019y int\u00e9resse puisque les priorit\u00e9s sont compl\u00e8tement diff\u00e9rentes, comme avoir une voiture, un appartement, etc. Maintenant, les gens ne croient plus au sens des choses de la m\u00eame mani\u00e8re qu\u2019auparavant. <\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-54766\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2161\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-scaled.jpeg\" alt=\"Tableau sur le modele des tuskiiz.\" class=\"wp-image-54766\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-scaled.jpeg 2560w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-300x253.jpeg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-1024x864.jpeg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-768x648.jpeg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-1536x1297.jpeg 1536w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-2048x1729.jpeg 2048w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-sur-le-modele-des-tuskiiz-1300x1097.jpeg 1300w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-element-caption\">Tableau sur le mod\u00e8le des touskiiz.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Le sens des motifs \u00e9tait important, ils croyaient que cela pouvait apporter le bonheur ou prot\u00e9ger du mauvais \u0153il. La m\u00eame chose se produit avec la langue. Avant, je n\u2019y pr\u00eatais pas beaucoup d\u2019attention. Je pensais que m\u00eame si on ne la connaissait pas, ce n\u2019\u00e9tait pas grave. Cependant, ayant v\u00e9cu \u00e0 l\u2019\u00e9tranger pendant tant d\u2019ann\u00e9es, je commence \u00e0 comprendre que cela est important. Quand je lis de la litt\u00e9rature kazakhe, c\u2019est tr\u00e8s difficile pour moi. En effet, quand vous lisez, vous sentez l\u2019esprit de la langue. Il y a quelque chose qui commence \u00e0 se stimuler et qui vous pousse \u00e0 la r\u00e9flexion sur notre culture.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Le th\u00e8me de l\u2019effacement se poursuit \u00e9galement dans une s\u00e9rie de photographies pr\u00e9sent\u00e9e \u00e0 l\u2019exposition. Pouvez-vous parler de ces travaux ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Tout d\u2019abord, j\u2019ai fait une sculpture avec des masques. Cette s\u00e9rie s\u2019intitule <em>Soci\u00e9t\u00e9 globale.<\/em>\u00a0J\u2019ai essay\u00e9 de pr\u00e9senter le monde entier comme une seule personne, \u00e0 travers moi-m\u00eame et mon exp\u00e9rience. Tous les masques sont faits sur le mod\u00e8le de mon visage. Apr\u00e8s la sculpture, j\u2019ai d\u00e9cid\u00e9 de faire une s\u00e9rie de photographies dans diff\u00e9rents pays : au Kazakhstan, en Ouzb\u00e9kistan et en Europe. Dans les photographies, l\u2019arri\u00e8re-plan est important. L\u00e0, vous pouvez voir le contexte : l&rsquo;intimit\u00e9 de\u00a0la pi\u00e8ce dans laquelle se trouve la personne masqu\u00e9e. Ainsi, il est possible de lire en partie une identit\u00e9.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Lire aussi sur Novastan :\u00a0<\/b><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/aujourdhui-on-attend-que-les-artistes-soient-davantage-impliques-dans-la-vie-sociale-quil-y-a-30-ans\/\"><strong>\u00ab Aujourd\u2019hui, on attend que les artistes soient davantage impliqu\u00e9s dans la vie sociale qu\u2019il y a 30 ans \u00bb<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">La vid\u00e9o est la prochaine \u00e9tape de la s\u00e9rie. Je l\u2019ai fait en 2016. Je voulais transmettre plus profond\u00e9ment l\u2019id\u00e9e d\u2019une soci\u00e9t\u00e9 mondiale. Bien que les gens essayent d\u2019enlever leur masque, il reste toujours sur leur visage. Il n\u2019est plus possible de s\u2019en d\u00e9barrasser. Puis il y a ceux qui mettent d\u00e9lib\u00e9r\u00e9ment le masque. J\u2019aimerais que le public ait quelque chose \u00e0 penser en sortant de l\u2019exposition.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Pourquoi avez-vous d\u00e9cid\u00e9 d\u2019utiliser votre visage comme base pour le masque ? Pourquoi choisir le feutre blanc ? Allez-vous continuer cette s\u00e9rie plus tard ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Puisque je fais partie de la soci\u00e9t\u00e9, je per\u00e7ois tout \u00e0 travers moi-m\u00eame. Naturellement, j\u2019ai fait le masque \u00e0 mon image. Je pr\u00e9vois de cr\u00e9er plus de sculptures. Le feutre blanc dans ce cas est neutre, \u00e0 la fois il est l\u00e0 et il ne l&rsquo;est pas. D\u2019autres couleurs portent des connotations diff\u00e9rentes du point de vue \u00e9motionnel. Aussi, du c\u00f4t\u00e9 pratique, le volume du visage est plus visible sur du blanc.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Le texte de l\u2019exposition utilise le mot \u00ab <i>mankourt<\/i>\u00bb, qui a une connotation tr\u00e8s n\u00e9gative dans la culture locale. Notamment en ce qui concerne la perte des traditions. Avez-vous d\u00e9lib\u00e9r\u00e9ment choisi cette expression dure ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">J\u2019ai lu le roman de <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Tchinguiz_A%C3%AFtmatov\"><span style=\"font-weight: 400\">Tchinguiz A\u00eftmatov<\/span><\/a><span style=\"font-weight: 400\">\u00a0U<\/span><i><span style=\"font-weight: 400\">ne journ\u00e9e plus longue qu\u2019un si\u00e8cle.<\/span><\/i><span style=\"font-weight: 400\">J&rsquo;ai relu plusieurs fois la fa\u00e7on dont le jeune homme \u00e9tait incapable de reconna\u00eetre sa m\u00e8re, ni sa terre, m\u00eame \u00e0 travers le texte. Cela a provoqu\u00e9 chez moi des associations puissantes avec notre culture, voire m\u00eame avec des origines enracin\u00e9es. Nous, en tant que descendants, ne perdons pas contact avec la terre.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Le mot \u00ab <i>mankourt<\/i>\u00bb est surtout pr\u00e9sent chez la vieille g\u00e9n\u00e9ration pour parler des jeunes, qui ne connaissent pas la tradition. Souvent, ces m\u00eames personnes disent que nous restaurons maintenant nos traditions et notre histoire. Quelle est votre opinion sur de telles d\u00e9clarations ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Quand ils disent que nous restaurons toutes nos traditions, ils omettent que tout cela se passe \u00e0 un niveau tr\u00e8s superficiel. Il n\u2019y a pas de connaissances approfondies, de sources ou encore de compr\u00e9hension. Tout passe par le bouche \u00e0 oreille. Au final, c\u2019est un dialogue obscur qui se transforme en quelque chose d\u2019abstrait. Toutes les traditions et les coutumes qui se d\u00e9roulent chez nous lors des mariages ou des anniversaires s\u2019apparentent juste \u00e0 du show. M\u00eame ce qui est utilis\u00e9 pour les coutumes, que ce soit les ornements, les objets ou autre. <\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-54769\"><img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"787\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-de-la-serie-Postnomadic-Reality.jpeg\" alt=\"Photo de la serie Post nomadic Reality.\" class=\"wp-image-54769\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-de-la-serie-Postnomadic-Reality.jpeg 1181w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-de-la-serie-Postnomadic-Reality-300x200.jpeg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-de-la-serie-Postnomadic-Reality-1024x682.jpeg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-de-la-serie-Postnomadic-Reality-768x512.jpeg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2022\/05\/Tableau-de-la-serie-Postnomadic-Reality-128x86.jpeg 128w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/><figcaption class=\"wp-element-caption\">Photo de la s\u00e9rie <em>Post-nomadic Reality<\/em>.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Les gens ne se soucient pas de la fa\u00e7on dont cela est fait, car ils comprennent parfaitement que tout cela n\u2019est que pour une journ\u00e9e. Mais ils se trompent s\u2019ils pensent qu\u2019ils retrouvent de la connaissance, du savoir. Non seulement les jeunes, mais m\u00eame nos parents, qui vivaient \u00e0 l\u2019\u00e9poque sovi\u00e9tique, ont une compr\u00e9hension tr\u00e8s abstraite des traditions. Nous suivons simplement la messe qui dicte ces traditions et ces coutumes, soi-disant conserv\u00e9es. M\u00eame des \u00e9v\u00e9nements au niveau de l\u2019\u00c9tat comme la f\u00eate de <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Norouz\"><span style=\"font-weight: 400\">Norouz<\/span><\/a><span style=\"font-weight: 400\">semblent n\u2019\u00eatre n\u00e9cessaires que pour une mise en \u0153uvre formelle.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Dans votre texte, avec le <em>\u00ab mankourtisme \u00bb<\/em>, il y a une mention du colonialisme et de la d\u00e9colonisation. Comment vous expliquez-vous ce sujet ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Nous devons absolument \u00e9tudier ce sujet car cela fait partie de notre histoire. L\u2019\u00e9ducation ne nous l\u2019a pas montr\u00e9 et ne nous en a pas parl\u00e9. Ce n\u2019est pas dans le programme scolaire, et on ne parle pas de ce que cet \u00c9tat colonial a laiss\u00e9. Par cons\u00e9quent, beaucoup de gens pensent que tout va bien, et l\u2019\u00e8re sovi\u00e9tique manque \u00e0 certains. Mais en regardant la situation du point de vue culturel, c\u2019est tout simplement horrible.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Le pouvoir sovi\u00e9tique a tu\u00e9 la culture, mais ce qui se passe actuellement \u00e0 la t\u00e9l\u00e9vision kazakhe ne fait qu\u2019empirer les choses. Les programmes actuels ne permettent pas de penser et de r\u00e9fl\u00e9chir par nous-m\u00eame. Maintenant, l\u2019accent est mis sur ce qui emp\u00eache les gens de poser des questions. Nous ne sommes pas stupides. Bien s\u00fbr, quand il n\u2019y a pas de programmes acceptables qui donnent mati\u00e8re \u00e0 penser, les gens n\u2019ont nulle part o\u00f9 obtenir des informations.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Le texte de l\u2019exposition parle aussi du silence. Non seulement comme oppression, mais aussi comme pratique spirituelle. Faisant des parall\u00e8les entre la r\u00e9pression et la spiritualit\u00e9, la po\u00e9tesse <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Adrienne_Rich\">Adrienne Rich<\/a> d\u00e9clarait que <i>\u00ab l\u2019impulsion de cr\u00e9er commence souvent de mani\u00e8re terrible et effrayante, dans un tunnel de silence<\/i><span style=\"font-weight: 400\">. \u00bb<\/span> Comment avez-vous choisi cette citation ?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Je repense \u00e0 tout ce qui arrive \u00e0 chacun de nous, \u00e0 chaque individu. \u00c0 cet \u00e9tat de silence dans la t\u00eate quand on plonge dans l\u2019essence des choses, dans la r\u00e9alit\u00e9. D&rsquo;ailleurs, il y a toujours une issue.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Que comptez-vous faire ensuite ? Avez-vous l\u2019intention de travailler au Kazakhstan ? La question se pose surtout car vous avez d\u00e9velopp\u00e9 une distance critique avec le pays apr\u00e8s avoir d\u00e9m\u00e9nag\u00e9.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Peu importe o\u00f9 je suis. Tout mon travail est consacr\u00e9 \u00e0 la culture et au Kazakhstan, aux probl\u00e8mes du pays. Les sujets qui concernent notre soci\u00e9t\u00e9 sont centraux. Quoi que je fasse, il est avant tout important pour moi de le montrer au Kazakhstan. Par cons\u00e9quent, je suis tr\u00e8s heureuse que l\u2019exposition \u00e0 la galerie Aspan ait eu lieu, malgr\u00e9 les reports dus \u00e0 la pand\u00e9mie. J\u2019esp\u00e8re qu\u2019\u00e0 l\u2019avenir il y aura plus d\u2019opportunit\u00e9s d\u2019exposer dans ce pays. Bien s\u00fbr, j\u2019ai des projets que j\u2019aimerais montrer, tout d\u2019abord au Kazakhstan. Certaines \u0153uvres auront \u00e9galement une suite.<\/span><\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Le fait que je sois \u00e0 l\u2019\u00e9tranger est plut\u00f4t une bonne chose. Je peux regarder certaines choses de mani\u00e8re objective et critique. Ce qui est tr\u00e8s important. Quand il y a des critiques, il y a quelque chose \u00e0 penser et \u00e0 travailler. J\u2019esp\u00e8re que dans notre soci\u00e9t\u00e9 les gens commenceront aussi \u00e0 accepter la critique envers le Kazakhstan, envers tout ce qui concerne notre soci\u00e9t\u00e9. Il n\u2019y a pas d\u2019\u00e9volution sans critique.<\/span><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><b>Kamila Narycheva<\/b><b> pour<\/b> <b>V<\/b><b>last<\/b><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><b>Traduit du <\/b><a href=\"https:\/\/vlast.kz\/life\/45975-gulnur-mukazanova-hudoznica-kogda-byla-vozmoznost-postroit-nase-obsestvo-svobodnym-my-soorudili-svoego-roda-kapkan.html\"><b>russe<\/b><\/a><b> par Amir Ayat<\/b><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><b>\u00c9dit\u00e9 par Johanna Regnaud<\/b> <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Mathilde Garnier<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Merci d&rsquo;avoir lu cet article jusqu&rsquo;au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez&nbsp;<a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a>&nbsp;ou nous envoyer un email \u00e0&nbsp;<a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La galerie Aspan \u00e0 Almaty a inaugur\u00e9 l\u2019exposition personnelle de la jeune artiste Goulnour Moukajanova. Le m\u00e9dia Vlast a discut\u00e9 avec l\u2019artiste de ses objectifs artistiques et de son attitude vis-\u00e0-vis de l\u2019environnement socioculturel qui l\u2019entoure. Novastan reprend et traduit ici un article publie\u0301 le 23 juillet 2021 par le me\u0301dia kazakh Vlast. Goulnour Moukajanovatravaille [&hellip;]<\/p>\n","protected":false},"author":1354,"featured_media":54770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,3986],"tags":[4440,470,4027,1956],"coauthors":[4886,5177],"class_list":["post-54764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kazakhstan","category-societe-et-culture","tag-art-contemporain","tag-kazakhstan","tag-societe-et-culture","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1354"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=54764"}],"version-history":[{"count":2,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54764\/revisions"}],"predecessor-version":[{"id":74566,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54764\/revisions\/74566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/54770"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=54764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=54764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=54764"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=54764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}