{"id":54300,"date":"2022-05-07T13:31:41","date_gmt":"2022-05-07T11:31:41","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=54300"},"modified":"2023-03-30T10:07:14","modified_gmt":"2023-03-30T08:07:14","slug":"lanti-occidentalisme-ciment-des-relations-entre-les-etats-autoritaires","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/europe-et-asie-centrale\/lanti-occidentalisme-ciment-des-relations-entre-les-etats-autoritaires\/","title":{"rendered":"L&rsquo;anti-occidentalisme, ciment des relations entre les \u00c9tats autoritaires"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Si l\u2019anti-occidentalisme est un choix politique conscient pour la Chine et la Russie, la position de l\u2019Asie centrale sur la question reste h\u00e9sitante. Questionn\u00e9 sur ce sujet, Alexander Cooley, professeur de Science politique et directeur de l\u2019institut Harriman de l\u2019Universit\u00e9 de Columbia, livre son \u00e9clairage sur ces enjeux politiques.<\/b><b>Novastan reprend et traduit ici un article publie\u0301 le 19 mai 2021 par le m\u00e9dia <\/b><a href=\"https:\/\/www.caa-network.org\/archives\/21856\/%D0%90%D0%BB%D0%B5%D0%BA%D1%81%D0%B0%D0%BD%D0%B4%D1%80-%D0%9A%D1%83%D0%BB%D0%B8-%D0%B0%D0%BD%D1%82%D0%B8%D0%B7%D0%B0%D0%BF%D0%B0%D0%B4%D0%BD%D0%B8%D1%87%D0%B5%D1%81%D1%82%D0%B2%D0%BE-%D1%8D%D1%82%D0%BE-%D0%BA%D0%BB%D0%B5%D0%B9-%D0%BA%D0%BE%D1%82%D0%BE%D1%80%D1%8B%D0%B9-%D1%83%D0%B4%D0%B5%D1%80%D0%B6%D0%B8%D0%B2%D0%B0%D0%B5%D1%82-%D0%B0%D0%B2%D1%82%D0%BE%D1%80%D0%B8%D1%82%D0%B0%D1%80%D0%BD%D1%8B%D0%B5-%D0%B3%D0%BE%D1%81%D1%83%D0%B4%D0%B0%D1%80%D1%81%D1%82%D0%B2%D0%B0-%D0%B2%D0%BC%D0%B5%D1%81%D1%82%D0%B5\"><b>Central Asian Analytical Network<\/b><\/a><b>.<\/b><span style=\"font-weight: 400\">Au c\u0153ur de la rivalit\u00e9 g\u00e9opolitique entre les \u00c9tats-Unis, la Russie et la Chine, l\u2019Asie centrale peine \u00e0 se situer entre lib\u00e9ralisme et <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Illib%C3%A9ralisme\"><span style=\"font-weight: 400\">illib\u00e9ralisme<\/span><\/a><span style=\"font-weight: 400\">. Quelles influences exercent l\u2019autoritarisme russe et chinois sur les pays d\u2019Asie centrale ? Dans un entretien accord\u00e9 au Central Asian Analytical Network (CAAN), <\/span><a href=\"https:\/\/polisci.barnard.edu\/profiles\/alexander-cooley\"><span style=\"font-weight: 400\">Alexander Cooley<\/span><\/a>, professeur au Barnard College de l&rsquo;Universit\u00e9 de Columbia,<span style=\"font-weight: 400\"> explique l\u2019enjeu de l\u2019Asie centrale pour les diff\u00e9rentes puissances et les influences subies par ces pays.<\/span><span style=\"font-weight: 400\">Les<\/span><span style=\"font-weight: 400\"> recherches d&rsquo;Alexander Cooley portent sur la politique en Asie centrale, en particulier l\u2019analyse de la d\u00e9mocratie et du lib\u00e9ralisme dans ces pays.<\/span><b>CAAN : <\/b><b>La situation internationale est de plus en plus complexe, et il devient difficile pour les pays d\u2019Asie centrale de se positionner entre les \u00c9tats-Unis, la Russie et la Chine. Quels conseils donneriez-vous \u00e0 l\u2019Asie centrale pour la mise en \u0153uvre de sa politique \u00e9trang\u00e8re ?<\/b><b>Alexander Cooley :<\/b><span style=\"font-weight: 400\">Je ne suis pas s\u00fbr de pouvoir donner des conseils aux gouvernements, et en particulier \u00e0 l\u2019Asie centrale. Cependant, il est int\u00e9ressant de noter que les pays d\u2019Asie centrale ont d\u00e9j\u00e0 enseign\u00e9 <\/span><span style=\"font-weight: 400\">un cas int\u00e9ressant en termes de compr\u00e9hension de la politique \u00e9trang\u00e8re : c\u2019est l\u2019id\u00e9e de <\/span><span style=\"font-weight: 400\">multivecteur<\/span><span style=\"font-weight: 400\">.<\/span><span style=\"font-weight: 400\"> Je pense que l\u2019approche multivectorielle a atteint son apog\u00e9e dans les ann\u00e9es 2000, comme je l\u2019ai d\u00e9velopp\u00e9 dans mon livre, <\/span><i><span style=\"font-weight: 400\"><a href=\"https:\/\/oxford.universitypressscholarship.com\/view\/10.1093\/acprof:oso\/9780199929825.001.0001\/acprof-9780199929825\">Le Grand Jeu<\/a><\/span><\/i><span style=\"font-weight: 400\">.<\/span><span style=\"font-weight: 400\">En r\u00e9alit\u00e9, tous les \u00c9tats aspirent \u00e0 une politique multivectorielle, mais elle devient de plus en plus difficile \u00e0 mettre en \u0153uvre pour plusieurs raisons. L\u2019une d\u2019elles, je pense, c\u2019est qu\u2019en 2014, la Chine et la Russie ont commenc\u00e9 \u00e0 s\u2019impliquer activement dans la r\u00e9gion. Comme vous le savez, cela co\u00efncide avec un relatif d\u00e9sengagement des \u00c9tats-Unis dans la r\u00e9gion et notamment la diminution des forces en Afghanistan.&nbsp;<\/span><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/tensions-etats-unis-chine-la-diplomatie-multi-vectorielle-des-pays-dasie-centrale-est-mise-a-lepreuve\/\"><b>Tensions \u00c9tats-Unis \/ Chine : \u00ab La diplomatie multi-vectorielle des pays d\u2019Asie centrale est mise \u00e0 l\u2019\u00e9preuve \u00bb<\/b><\/a><span style=\"font-weight: 400\">M\u00eame si les \u00c9tats-Unis et les pays d\u2019Asie centrale disposent de m\u00e9canismes tels que le <\/span><a href=\"https:\/\/novastan.org\/fr\/politique\/format-c51-evolution-et-perspectives-du-dialogue-regional-en-asie-centrale\/\"><span style=\"font-weight: 400\">C5+1<\/span><\/a><span style=\"font-weight: 400\">, l\u2019Afghanistan \u00e9tait la raison principale de leur implication en Asie centrale. Ainsi, <\/span><span style=\"font-weight: 400\">m\u00eame au plus fort du <\/span><span style=\"font-weight: 400\">multivectorialisme<\/span><span style=\"font-weight: 400\"> dans les ann\u00e9es 2000<\/span><span style=\"font-weight: 400\">, chaque pays d\u2019Asie centrale avait des relations avec les \u00c9tats-Unis en mati\u00e8re de s\u00e9curit\u00e9, ainsi que dans le domaine de la logistique. C\u2019\u00e9tait un levier tr\u00e8s important. L\u2019option id\u00e9ale est une politique dans laquelle toutes les portes restent ouvertes.<\/span><span style=\"font-weight: 400\">Le probl\u00e8me, c\u2019est qu\u2019en pleine rivalit\u00e9 strat\u00e9gique entre les pays, certaines grandes puissances exercent des pressions pour compromettre certains partenariats. Quand la Russie exerce une pression pour fermer une base am\u00e9ricaine, il est alors fondamental, selon moi, d\u2019avoir d\u2019autres ressources.<\/span><\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Par cons\u00e9quent, m\u00eame s\u2019il n\u2019y a pas eu de rupture avec les \u00c9tats-Unis, il reste important de d\u00e9velopper autant que possible les relations ext\u00e9rieures. La Cor\u00e9e du Sud, l\u2019Inde, le Japon, sont tous des partenaires importants. Certains analystes am\u00e9ricains les consid\u00e8rent comme des m\u00e9diateurs occidentaux. Je pense que plus les pays d\u2019Asie centrale d\u00e9veloppent des partenariats et des opportunit\u00e9s, plus ils ont de leviers dans les relations avec les grandes puissances, notamment avec la Russie et la Chine. Mais ces man\u0153uvres entre la Russie et la Chine sont caract\u00e9ristiques de la r\u00e9gion, et cela devrait durer plusieurs ann\u00e9es, peut-\u00eatre m\u00eame des d\u00e9cennies.<\/span><b>Comment l\u2019autoritarisme de la Russie et de la Chine&nbsp;influence-t-il l\u2019Asie centrale ? Les pays adoptent-ils les m\u00eames pratiques&nbsp;?<\/b><span style=\"font-weight: 400\">Dans un sens, oui. Mais je pense que l\u2019influence est aussi plus indirecte. D\u2019abord, beaucoup d\u2019\u00c9tats d\u2019Asie centrale ont eux-m\u00eames invent\u00e9 de nouvelles r\u00e9glementations autoritaires, notamment en lien avec la gestion des <\/span><span style=\"font-weight: 400\">diasporas<\/span><span style=\"font-weight: 400\"> et des r\u00e9fugi\u00e9s politiques. Les services de s\u00e9curit\u00e9 ont fait des progr\u00e8s impressionnants en termes de couverture <\/span><span style=\"font-weight: 400\">transnationale<\/span><span style=\"font-weight: 400\">, dans leur ma\u00eetrise du num\u00e9rique et de la cybern\u00e9tique, dans la capacit\u00e9 \u00e0 s\u2019introduire dans diverses communaut\u00e9s. De nombreux \u00c9tats d\u2019Asie centrale, dont j\u2019ai <a href=\"https:\/\/blogs.lse.ac.uk\/lsereviewofbooks\/2017\/03\/27\/book-review-dictators-without-borders-power-and-money-in-central-asia-by-alexander-cooley-and-john-heathershaw\/\">parl\u00e9<\/a> avec <\/span><a href=\"https:\/\/socialsciences.exeter.ac.uk\/politics\/staff\/heathershaw\/\"><span style=\"font-weight: 400\">John Heathershaw<\/span><\/a><span style=\"font-weight: 400\">, ont coop\u00e9r\u00e9 avec la Russie, la Turquie, et d\u2019autres, afin d\u2019accro\u00eetre la port\u00e9e de leurs op\u00e9rations.&nbsp;<\/span><span style=\"font-weight: 400\">On trouve beaucoup de nouvelles r\u00e9glementations autoritaires dans les \u00c9tats d\u2019Asie centrale. Dans les ann\u00e9es 2000, ce sont les autorit\u00e9s russes qui se sont inspir\u00e9es des \u00e9volutions l\u00e9gislatives et des textes de loi en Asie centrale. Cela tient au m\u00e9canisme de l\u2019Assembl\u00e9e interparlementaire de la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Communaut%C3%A9_des_%C3%89tats_ind%C3%A9pendants\">Communaut\u00e9 des Etats ind\u00e9pendants<\/a> (<\/span><span style=\"font-weight: 400\">CEI<\/span>)<span style=\"font-weight: 400\">, qui con\u00e7oit des textes de loi sur la lutte contre le terrorisme et l\u2019extr\u00e9misme, ainsi que sur les manifestations publiques. Toutes ces lois sont adopt\u00e9es le plus souvent dans des endroits tr\u00e8s d\u00e9pendants de la Russie.<\/span><span style=\"font-weight: 400\">De plus, l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Organisation_du_trait%C3%A9_de_s%C3%A9curit%C3%A9_collective\">Organisation du trait\u00e9 de s\u00e9curit\u00e9 collective<\/a> (<\/span><span style=\"font-weight: 400\">OTSC<\/span><span style=\"font-weight: 400\">) et le minist\u00e8re russe pour la CEI sont des m\u00e9canismes qui, me semble-t-il, propagent activement des normes et des pratiques autoritaires. C\u2019est le cas dans les domaines de la coop\u00e9ration extraterritoriale, de l\u2019<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Extradition\"><span style=\"font-weight: 400\">extradition<\/span><\/a><span style=\"font-weight: 400\">, ainsi que le contournement des proc\u00e9dures et des normes internationales en mati\u00e8re d\u2019asile. Tout cela est, disons, institutionnalis\u00e9, mais d\u2019autres coop\u00e9rations se font de fa\u00e7on plus informelle. C\u2019est la raison pour laquelle je pense que les \u00c9tats d\u2019Asie centrale sont du c\u00f4t\u00e9 de la Chine et de la Russie. Ils mettent en \u0153uvre conjointement et ind\u00e9pendamment des pratiques autoritaires. Mais l\u2019<\/span><span style=\"font-weight: 400\">autoritarisme<\/span><span style=\"font-weight: 400\"> gagne aussi en importance dans le monde entier, et je ne pense pas que ce soit la seule r\u00e9gion o\u00f9 il soit observ\u00e9.&nbsp;<\/span><a href=\"https:\/\/gufaculty360.georgetown.edu\/s\/contact\/00336000014RbrtAAC\/daniel-nexon\"><span style=\"font-weight: 400\">Daniel Nexon<\/span><\/a><span style=\"font-weight: 400\"> et moi-m\u00eame avons r\u00e9cemment publi\u00e9 un <a href=\"https:\/\/www.foreignaffairs.com\/articles\/united-states\/2021-03-26\/illiberal-tide\">article<\/a> sur ce th\u00e8me,<\/span><span style=\"font-weight: 400\">&nbsp;o\u00f9 nous affirmons que le monde d\u2019aujourd\u2019hui est nettement plus <\/span><a href=\"https:\/\/www.cnrtl.fr\/definition\/antilib%C3%A9ral\"><span style=\"font-weight: 400\">antilib\u00e9ral<\/span><\/a><span style=\"font-weight: 400\"> que ne le pensent la majorit\u00e9 des gens. Autrement dit, l\u2019ordre lib\u00e9ral international ne s\u2019est pas effondr\u00e9, mais nous observons dans la gouvernance et dans l\u2019ordre international beaucoup de signes d\u2019antilib\u00e9ralisme.<\/span><span style=\"font-weight: 400\">Je pense que nous commen\u00e7ons progressivement \u00e0 les comprendre, car ils reposent sur des institutions et des pratiques que nous consid\u00e9rions jusqu\u2019\u00e0 pr\u00e9sent comme lib\u00e9rales et accept\u00e9es par des \u00c9tats comme la Chine et la Russie. Ainsi, la collaboration intergouvernementale a pris de nombreuses formes antilib\u00e9rales. L\u2019Organisation de coop\u00e9ration de Shanghai, la Banque asiatique d\u2019investissement pour les infrastructures (<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Banque_asiatique_d%27investissement_pour_les_infrastructures\"><span style=\"font-weight: 400\">AIIB<\/span><\/a><span style=\"font-weight: 400\">), l\u2019OTSC<\/span><span style=\"font-weight: 400\">, ou encore l\u2019Union \u00e9conomique eurasiatique (<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Union_%C3%A9conomique_eurasiatique\"><span style=\"font-weight: 400\">UEEA<\/span><\/a><span style=\"font-weight: 400\">), toutes ces organisations sont fi\u00e8res d\u2019\u00eatre des incubateurs de nouvelles normes.<\/span><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kazakhstan-notre-nationalisme-local-est-vide-de-sens-et-impitoyable\/\"><b>Kazakhstan : \u00ab Notre nationalisme local est vide de sens et impitoyable <\/b><\/a><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kazakhstan-notre-nationalisme-local-est-vide-de-sens-et-impitoyable\/\">\u00bb<\/a><span style=\"font-weight: 400\">Mais dans l\u2019ensemble, il me semble que le d\u00e9clin du lib\u00e9ralisme politique ne s\u2019observe pas qu\u2019en Eurasie, mais aussi dans le reste du monde. Ce n\u2019est pas seulement d\u00fb \u00e0 la mont\u00e9e de l\u2019antilib\u00e9ralisme, mais aussi au fait que le lib\u00e9ralisme soit pr\u00e9sent\u00e9 comme un moyen de d\u00e9stabilisation politique. Il serait responsable des changements de r\u00e9gimes, des r\u00e9volutions de couleurs, ou encore l&rsquo;outil d&rsquo;ONG financ\u00e9es par des gouvernements \u00e9trangers.<\/span><span style=\"font-weight: 400\">Le lib\u00e9ralisme est pass\u00e9 du statut d\u2019irritant politique, pour ainsi dire, \u00e0 celui de menace pour la s\u00e9curit\u00e9 ext\u00e9rieure. Ainsi, certaines manipulations de valeurs ont lieu, comme celles relatives aux questions LGBTQ, qui sont ensuite compar\u00e9es \u00e0 la nationalisation des identit\u00e9s et des pratiques. Je pense donc que c\u2019est une question difficile.<\/span><span style=\"font-weight: 400\">En outre, il y a aussi une partie \u00e9conomique, avec laquelle on retrouve des dynamiques nettement plus<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Personnalisme\"><span style=\"font-weight: 400\"> personnalistes<\/span><\/a><span style=\"font-weight: 400\"> et <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kleptocratie\"><span style=\"font-weight: 400\">kleptocratiques<\/span><\/a><span style=\"font-weight: 400\"> que nous ne le pensons g\u00e9n\u00e9ralement dans l\u2019\u00e9conomie globale. Encore une fois certaines institutions mondiales lib\u00e9rales sont utilis\u00e9es, telles que les soci\u00e9t\u00e9s \u00e9crans, les soci\u00e9t\u00e9s <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Offshore\"><span style=\"font-weight: 400\">offshore<\/span><\/a><span style=\"font-weight: 400\"> et ainsi de suite. En pratique, ce que nous consid\u00e9rions autrefois comme des institutions et architectures lib\u00e9rales fonctionnent de fa\u00e7on plus illib\u00e9rale. Nous devons en avoir conscience.<\/span><b><\/b><b>Dans vos travaux, vous utilisez l\u2019expression \u00ab r\u00e9gionalisme autoritaire \u00bb. Pouvez-vous expliquer ce ph\u00e9nom\u00e8ne ?<\/b><span style=\"font-weight: 400\">Je dirais que le r\u00e9gionalisme autoritaire, ce sont des pratiques autoritaires et antid\u00e9mocratiques qui sont institutionnalis\u00e9es et rendues l\u00e9gitimes au niveau r\u00e9gional, de fa\u00e7on formelle ou informelle. Formellement, cela se fait \u00e0 travers le m\u00e9canisme des organisations r\u00e9gionales, comme la convention de l\u2019Organisation de coop\u00e9ration de Shanghai en 2009 contre le terrorisme. Il institutionnalise un certain nombre de pratiques, notamment le droit de transf\u00e9rer des suspects de terrorisme extr\u00e9miste ou s\u00e9paratiste d\u2019un \u00c9tat vers un autre.<\/span><span style=\"font-weight: 400\">C\u2019est le cas en Chine, par exemple, sur la seule base d\u2019accusations, sans autre approbation ou consid\u00e9ration de la l\u00e9gislation nationale. Il s\u2019agit d\u2019un m\u00e9canisme que certains \u00c9tats d\u2019Asie centrale utilisent pour extrader des prisonniers politiques recherch\u00e9s. Il permet aux dissidents politiques d\u2019un pays d\u2019\u00eatre inclus comme terroristes ou extr\u00e9mistes dans la liste commune des personnes recherch\u00e9es. Il y a aussi des dynamiques interr\u00e9gionales, telles que le<\/span><a href=\"https:\/\/en.wikipedia.org\/wiki\/Logrolling\"><span style=\"font-weight: 400\">logrolling<\/span><\/a><span style=\"font-weight: 400\">. C\u2019est ce genre de listes noires, la coop\u00e9ration des services de s\u00e9curit\u00e9, le contournement des lois sur le droit d\u2019asile, la diffusion d\u2019une l\u00e9gislation commune, qui est autoritaire et s\u2019\u00e9tend au niveau r\u00e9gional.&nbsp;<\/span><span style=\"font-weight: 400\">La th\u00e9orie traditionnelle des relations internationales supposait que la coop\u00e9ration r\u00e9gionale se d\u00e9veloppait pour des raisons \u00e9conomiques fonctionnelles. Lorsqu\u2019il serait logique pour les entreprises d\u2019\u00e9tendre leur march\u00e9, alors des r\u00e8gles commerciales communes seraient cr\u00e9\u00e9es. On a suppos\u00e9 que la politique et la s\u00e9curit\u00e9 seraient des questions plus difficiles pour f\u00e9d\u00e9rer les \u00c9tats. Mais dans un contexte autoritaire, on constate le contraire : les causes politiques sont au premier plan, parce que la survie et la stabilit\u00e9 du r\u00e9gime sont la pr\u00e9occupation num\u00e9ro un.<\/span><span style=\"font-weight: 400\">En fait, certains types d\u2019int\u00e9grations \u00e9conomiques sont tr\u00e8s difficiles \u00e0 r\u00e9aliser, en partie du fait des liens capitalistiques de beaucoup de ces industries privil\u00e9gi\u00e9es. Des industries comme les t\u00e9l\u00e9communications ou l\u2019infrastructure ont g\u00e9n\u00e9ralement des liens avec des gouvernements et r\u00e9gimes au pouvoir, c\u2019est pourquoi il est en pratique tr\u00e8s diffi<\/span><span style=\"font-weight: 400\">cile d\u2019obtenir ou d\u2019octroyer des licences dans un espace commun. C\u2019est une version tr\u00e8s sch\u00e9<\/span><span style=\"font-weight: 400\">matique de l\u2019argumentation, mais ce sont les principales caract\u00e9ristiques.&nbsp;<\/span><b>Quelle est l\u2019influence des r\u00e9gimes politiques sur les organisations r\u00e9gionales internationales, en th\u00e9orie et en pratique&nbsp;? Quels sont les m\u00e9canismes de diffusion de l\u2019<\/b><b>autocratie<\/b><b> par l\u2019interm\u00e9diaire des organisations r\u00e9gionales ? Quelles sont les sp\u00e9cificit\u00e9s propres aux organisations r\u00e9gionales non d\u00e9mocratiques ?<\/b><span style=\"font-weight: 400\">Par d\u00e9finition, les organisations r\u00e9gionales doivent renoncer \u00e0 une partie de leur identit\u00e9 nationale. Elles doivent abandonner leur souverainet\u00e9 et renoncer \u00e0 certains id\u00e9aux, pour instaurer une r\u00e9elle coop\u00e9ration, en b\u00e9n\u00e9ficier et obtenir une v\u00e9ritable int\u00e9gration r\u00e9gionale. Mais \u00e0 c\u00f4t\u00e9 de ces collaborations autour de questions comme internet ou la gouvernance du <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Cyberespace\"><span style=\"font-weight: 400\">cyberespace<\/span><\/a><span style=\"font-weight: 400\">, les \u00c9tats souhaitent conserver un contr\u00f4le souverain.<\/span><span style=\"font-weight: 400\">C\u2019est pourquoi ils s\u2019accordent au niveau r\u00e9gional pour conserver ce contr\u00f4le, ce qui cr\u00e9e une communaut\u00e9 pour adopter et promouvoir des pratiques autoritaires entre les r\u00e9gimes. C\u2019est l\u2019essentiel. Les m\u00e9canismes utilis\u00e9s peuvent \u00eatre tr\u00e8s diff\u00e9rents. Il peut s\u2019agir de trait\u00e9s, de coop\u00e9rations informelles en mati\u00e8re de s\u00e9curit\u00e9, ou encore de m\u00e9canismes de r\u00e9glementation. Le <\/span><span style=\"font-weight: 400\">consensus<\/span><span style=\"font-weight: 400\"> se construit autour d\u2019un rejet de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/George_Soros\">George <\/a><\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/George_Soros\"><span style=\"font-weight: 400\">Soros<\/span><\/a><span style=\"font-weight: 400\"> et du lib\u00e9ralisme occidental.&nbsp;<\/span><b>Les autocraties adoptent-elles de nos jours certaines id\u00e9es ou normes lib\u00e9rales ? Par exemple, les id\u00e9es de libre-\u00e9change ou d\u2019\u00e9conomie ouverte&nbsp;?<\/b><span style=\"font-weight: 400\">Bien s\u00fbr. Elles souhaitent non seulement le libre-\u00e9change, mais aussi la libert\u00e9 des flux financiers. Un kleptocrate autoritaire doit avoir la possibilit\u00e9 de retirer son argent pour le placer dans un endroit s\u00fbr, au cas o\u00f9 il y ait un changement de r\u00e9gime. Par cons\u00e9quent, ils ont besoin de la protection des droits de propri\u00e9t\u00e9 occidentaux.<\/span><span style=\"font-weight: 400\">Ils veulent avoir des comptes dans des banques occidentales, des biens immobiliers occidentaux, des lieux pour conserver leur capital de fa\u00e7on relativement s\u00e9curis\u00e9e. Les pays autoritaires ma\u00eetrisent, et sont m\u00eame pionniers dans l\u2019utilisation de tous les moyens l\u00e9gaux de repr\u00e9sentation, tels que les lobbyistes occidentaux, les juristes, les sp\u00e9cialistes en mati\u00e8re de relations publiques, de m\u00e9dias et de communication. Les pays peuvent, par exemple, \u00e9touffer la couverture m\u00e9diatique occidentale ou les r\u00e9seaux sociaux internationaux, si ce qui est diffus\u00e9 ne leur pla\u00eet pas.<\/span><b>Il y a eu des cas de d\u00e9mocratisation de r\u00e9gimes autoritaires qui ont eu lieu sans intervention significative d\u2019une puissance ext\u00e9rieure, comme en Argentine, en Pologne ou encore en Espagne. Pourrait-on appliquer leurs exp\u00e9riences et leurs outils aux r\u00e9gimes autoritaires contemporains&nbsp;?&nbsp;<\/b><span style=\"font-weight: 400\">La <\/span><a href=\"https:\/\/www.princeton.edu\/~cboix\/endogenous%20democratization%20-%20world%20politics.pdf\"><span style=\"font-weight: 400\">d\u00e9mocratie <\/span><\/a><a href=\"https:\/\/www.cnrtl.fr\/definition\/endog%C3%A8ne\"><span style=\"font-weight: 400\">endog\u00e8ne<\/span><\/a><span style=\"font-weight: 400\"> sans intervention d\u2019une puissance ext\u00e9rieure a un potentiel \u00e9norme. Le cas de l\u2019Argentine est un peu controvers\u00e9. Je pense qu\u2019elle a connu son d\u00e9veloppement propre apr\u00e8s la<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Guerre_des_Malouines\"><span style=\"font-weight: 400\"> guerre des Malouines<\/span><\/a><span style=\"font-weight: 400\"> et la crise qui a suivi. Les organisations de d\u00e9fense des droits de l\u2019Homme, bas\u00e9es aux \u00c9tats-Unis et en Occident, ont coop\u00e9r\u00e9 \u00e9troitement avec les organisations argentines. C\u2019est pourquoi il est difficile de dire la part d\u2019intervention ext\u00e9rieure et interne. Mais l\u2019Argentine est utilis\u00e9e par certains universitaires, comme<\/span><a href=\"https:\/\/en.wikipedia.org\/wiki\/Kathryn_Sikkink\"><span style=\"font-weight: 400\"> Kathryn Sikkink<\/span><\/a><span style=\"font-weight: 400\">, comme un exemple classique de pouvoir des r\u00e9seaux transnationaux de d\u00e9fense des droits de l\u2019Homme et de la propagande lib\u00e9rale.&nbsp;<\/span><span style=\"font-weight: 400\">L\u2019exemple de l\u2019Espagne est int\u00e9ressant. C\u2019est un exemple classique d\u2019une transition de l\u2019int\u00e9rieur. Il y a eu des facteurs ext\u00e9rieurs, mais je ne pense pas qu\u2019ils expliquent le processus de la d\u00e9mocratisation. Je pense que l\u2019Espagne avait un r\u00e9el d\u00e9sir de devenir un pays plus europ\u00e9en, ce qui a men\u00e9 \u00e0 son adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne quelques ann\u00e9es plus tard.<\/span><span style=\"font-weight: 400\">Bien s\u00fbr, il y a eu des tensions du fait de la pr\u00e9sence de bases militaires am\u00e9ricaines, mais le spectre de <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Francisco_Franco\"><span style=\"font-weight: 400\">Francisco Franco<\/span><\/a><span style=\"font-weight: 400\"> \u00e9tait omnipr\u00e9sent. Cela s\u2019est r\u00e9v\u00e9l\u00e9 un moteur important, surtout apr\u00e8s la conclusion d\u2019accords de consensus national, les <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pactes_de_la_Moncloa\"><span style=\"font-weight: 400\">pactes de la Moncloa<\/span><\/a><span style=\"font-weight: 400\">. Incontestablement, les structures sociales, l\u2019Eglise, l\u2019<\/span><span style=\"font-weight: 400\">intelligentsia<\/span><span style=\"font-weight: 400\"> anticommuniste, cela a mobilis\u00e9 tout le monde. Comme on l\u2019a vu, la Pologne est une soci\u00e9t\u00e9 tr\u00e8s divis\u00e9e. Beaucoup de ces groupes, unis contre le communisme, sont aujourd\u2019hui tr\u00e8s divis\u00e9s sur des questions comme les valeurs lib\u00e9rales, les droits en mati\u00e8re de procr\u00e9ation, les LGBTQ et ainsi de suite.<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">C\u2019est pourquoi je pense que les <\/span><span style=\"font-weight: 400\">coalitions<\/span><span style=\"font-weight: 400\">, qui sont utiles pour la mobilisation contre certains r\u00e9gimes autoritaires, ne sont pas n\u00e9cessairement utiles pour d\u2019autres. Il faut prendre en compte le temps et l\u2019\u00e9poque. Il me semble qu\u2019il existe aussi diff\u00e9rents types d\u2019influences. Les pays membres de l\u2019Union europ\u00e9enne sont potentiellement plus vuln\u00e9rables aux sanctions.<\/span><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/des-actions-et-des-affiches-anti-macron-au-kirghizstan\/\"><b>Des actions et des affiches anti-Macron au Kirghizstan<\/b><\/a><span style=\"font-weight: 400\">C\u2019est tr\u00e8s diff\u00e9rent des leviers dont dispose la communaut\u00e9 internationale, par exemple en Ouzb\u00e9kistan ou au Kazakhstan. C\u2019est pourquoi je ne pense pas que la pression internationale soit la m\u00eame pour toutes les \u00e9poques et pour tous les \u00c9tats. Je pense que le contexte international est aujourd\u2019hui moins propice \u00e0 la d\u00e9mocratie qu\u2019auparavant. \u00c0 certains \u00e9gards il est plus autoritaire, mais encore une fois, cela d\u00e9pend de la r\u00e9gion et du pays.&nbsp;<\/span><b>Nous terminons cette interview avec une question d\u2019actualit\u00e9. Comment vont \u00e9voluer, sous l\u2019administration Joe Biden, les relations des \u00c9tats-Unis avec la Russie et avec la Chine ?&nbsp;<\/b><span style=\"font-weight: 400\">En r\u00e9alit\u00e9, je ne pense pas qu\u2019elles vont beaucoup \u00e9voluer. C\u2019est peut-\u00eatre une bonne chose, car il n\u2019y a pas de faux espoirs d\u2019am\u00e9lioration. Dans les relations entre les \u00c9tats-Unis et la Russie, le changement est minime. Je pense que les deux camps s\u2019attendent \u00e0 un parcours sem\u00e9 d\u2019obstacles. On esp\u00e9rait que tout s\u2019am\u00e9liorerait sous l\u2019administration Donald Trump, mais \u00e7a n\u2019a pas \u00e9t\u00e9 le cas, \u00e0 cause de la bureaucratie en place et de certains int\u00e9r\u00eats priv\u00e9s.<\/span><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/politique\/quelle-politique-americaine-en-asie-centrale-sous-ladministration-joe-biden\/\">Quelle politique am\u00e9ricaine en Asie centrale sous l\u2019administration Joe Biden ?<\/a><\/strong><span style=\"font-weight: 400\">Donald Trump avait un projet, la conviction sinc\u00e8re qu\u2019il pourrait attirer la Russie de son c\u00f4t\u00e9, pour s\u2019opposer \u00e0 la Chine. D\u2019autres personnes \u00e0 la Maison Blanche l\u2019esp\u00e9raient aussi, mais c\u2019est en fait tr\u00e8s na\u00eff. Ils oublient que la Russie et la Chine travaillent ensemble contre les int\u00e9r\u00eats des \u00c9tats-Unis. Je ne comprends pas pourquoi tant d\u2019experts am\u00e9ricains n\u00e9gligent ce param\u00e8tre, estimant qu\u2019il n\u2019est pas significatif. Ils pensent que la Russie va se r\u00e9veiller un jour et dire comme par magie : <em>\u00ab Les Chinois patrouillent aux fronti\u00e8res tadjikes, c\u2019est terrible et c\u2019est contre nos int\u00e9r\u00eats. \u00bb<\/em><\/span><span style=\"font-weight: 400\">Non, les Chinois patrouillent et ils le font savoir aux Russes, parce qu\u2019ils savent que les Russes ne feront rien. Cela s\u2019appelle l\u2019anti-occidentalisme, et c\u2019est ce qui cimente les \u00c9tats entre eux, les emp\u00eache de s\u2019affronter et de se concurrencer sur d\u2019autres questions. Ils ne se provoqueront pas. Aucun d\u2019entre eux n\u2019a int\u00e9r\u00eat \u00e0 bouleverser le statu quo. On peut qualifier \u00e7a d\u2019alliance, ou encore de mariage de convenance, peu importe. Mais c\u2019est un espace politique divis\u00e9, qu\u2019ils essayent de se partager en \u00e9loignant les influences et normes occidentales.<\/span><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Elvira A\u00efdarkhanova\nJournaliste pour CAAN<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Traduit du <a href=\"https:\/\/www.caa-network.org\/archives\/21856\/%D0%90%D0%BB%D0%B5%D0%BA%D1%81%D0%B0%D0%BD%D0%B4%D1%80-%D0%9A%D1%83%D0%BB%D0%B8-%D0%B0%D0%BD%D1%82%D0%B8%D0%B7%D0%B0%D0%BF%D0%B0%D0%B4%D0%BD%D0%B8%D1%87%D0%B5%D1%81%D1%82%D0%B2%D0%BE-%D1%8D%D1%82%D0%BE-%D0%BA%D0%BB%D0%B5%D0%B9-%D0%BA%D0%BE%D1%82%D0%BE%D1%80%D1%8B%D0%B9-%D1%83%D0%B4%D0%B5%D1%80%D0%B6%D0%B8%D0%B2%D0%B0%D0%B5%D1%82-%D0%B0%D0%B2%D1%82%D0%BE%D1%80%D0%B8%D1%82%D0%B0%D1%80%D0%BD%D1%8B%D0%B5-%D0%B3%D0%BE%D1%81%D1%83%D0%B4%D0%B0%D1%80%D1%81%D1%82%D0%B2%D0%B0-%D0%B2%D0%BC%D0%B5%D1%81%D1%82%D0%B5\">russe<\/a> par Juliette Amiranoff<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>\u00c9dit\u00e9 par Johanna Regnaud<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Emma Jerome<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b><p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/b><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Si l\u2019anti-occidentalisme est un choix politique conscient pour la Chine et la Russie, la position de l\u2019Asie centrale sur la question reste h\u00e9sitante. Questionn\u00e9 sur ce sujet, Alexander Cooley, professeur de Science politique et directeur de l\u2019institut Harriman de l\u2019Universit\u00e9 de Columbia, livre son \u00e9clairage sur ces enjeux politiques.Novastan reprend et traduit ici un article [&hellip;]<\/p>\n","protected":false},"author":459,"featured_media":54311,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3987,3984],"tags":[493,1120,488,1956],"coauthors":[2155,4242,5177,5049],"class_list":["post-54300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europe-et-asie-centrale","category-politique","tag-asie-centrale","tag-geopolitique","tag-politique","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/459"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=54300"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/54311"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=54300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=54300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=54300"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=54300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}