{"id":54020,"date":"2022-04-12T10:53:22","date_gmt":"2022-04-12T08:53:22","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=54020"},"modified":"2023-10-02T21:13:38","modified_gmt":"2023-10-02T19:13:38","slug":"qui-construit-turkestan-la-capitale-spirituelle-du-kazakhstan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kazakhstan\/qui-construit-turkestan-la-capitale-spirituelle-du-kazakhstan\/","title":{"rendered":"Qui construit Turkestan, la capitale spirituelle du Kazakhstan ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Turkestan, dans le sud du Kazakhstan, est r\u00e9put\u00e9e \u00eatre la capitale spirituelle du pays. La ville essaie d\u2019attirer les visiteurs en s\u2019am\u00e9nageant. Quelles entreprises construisent Turkestan, avec quels projets et quel argent&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Novastan reprend et traduit ici un article publi\u00e9 le 28 janvier 2021 par le m\u00e9dia kazakh <\/strong><a href=\"https:\/\/kz.kursiv.media\/2021-01-28\/kto-stroit-turkestan\/\"><strong>Kursiv<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2020, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Turkestan_(ville)\">Turkestan<\/a> a obtenu un montant d\u2019investissement record&nbsp;: pr\u00e8s de 566 milliards de tengu\u00e9s (1,1 milliard d\u2019euros). C\u2019est presque deux fois plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Environ la moiti\u00e9 de ces fonds sont publics. L\u2019autre moiti\u00e9 est constitu\u00e9e d\u2019investissements priv\u00e9s, attir\u00e9s gr\u00e2ce \u00e0 la cr\u00e9ation des zones \u00e9conomiques sp\u00e9ciales (ZES). Les participants des ZES sont exon\u00e9r\u00e9s d\u2019imp\u00f4ts immobiliers et fonciers ainsi que d\u2019imp\u00f4ts sur la soci\u00e9t\u00e9. Les investisseurs ne payent pas de loyer pour la terre, ni de droits de douane et de TVA sur les marchandises import\u00e9es. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Sur les traces de Tamerlan<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nEn novembre 2020, le gouvernement a approuv\u00e9 le sch\u00e9ma directeur d\u2019am\u00e9nagement de Turkestan, qui divise la ville en plusieurs quartiers.\n\n<\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nEn effet, le centre de la ville a \u00e9t\u00e9 construit par <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Tamerlan\">Tamerlan<\/a>, empereur turco-mongol, \u00e0 la fin du XIV\u00e8me si\u00e8cle, quand il a d\u00e9cid\u00e9 de cr\u00e9er un m\u00e9morial en hommage \u00e0 la victoire sur le khan <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Tokhtamych\">Tokhtamych<\/a>, sur la place du mausol\u00e9e de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ahmed_Yasavi\">Khoja Ahmed Yasavi<\/a>. Po\u00e8te soufi et pr\u00e9dicateur, Khoja Ahmed Yasavi est une personnalit\u00e9 tr\u00e8s importante pour les musulmans. Cependant, Tamerlan n\u2019a pas pris ces d\u00e9cisions seulement pour promouvoir la diffusion de l\u2019islam, mais aussi pour r\u00e9pondre \u00e0 des objectifs politiques. La construction sur une telle place symbolique lui permettait d\u2019affirmer son pouvoir dans ces territoires.\n\nSelon les architectes, une telle structure avec un complexe plurifonctionnel sous un m\u00eame toit n\u2019a pas d\u2019\u00e9quivalent ni en Asie centrale, ni en Iran, ni au Moyen-Orient. De surcro\u00eet, le complexe a \u00e9t\u00e9 conserv\u00e9 jusqu\u2019\u00e0 nos jours.\n\nL\u2019architecte Almas Ordaba\u00efev, qui s\u2019est occup\u00e9 de la restauration du mausol\u00e9e, explique dans une interview accord\u00e9e au m\u00e9dia kazakh <a href=\"https:\/\/vlast.kz\/gorod\/22023-problemy-izucenia-ohrany-i-restavracii-pamatnikov-arhitektury-na-primere-mavzolea-hodzi-ahmeda-asavi.html\">vlast.kz<\/a> que d\u2019autres constructions significatives ex\u00e9cut\u00e9es sur ordre de Tamerlan dans l\u2019actuel Ouzb\u00e9kistan, \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Samarcande\">Samarcande<\/a> et \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Chakhrisabz\">Chakhrisabz<\/a>, sont toutes tomb\u00e9es en ruines. Elles ont \u00e9t\u00e9 construites assez rapidement : comme tout dirigeant totalitaire, Tamerlan voulait voir de ses propres yeux la mise en \u0153uvre de ses ordres.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Un site inscrit sur la liste de l\u2019UNESCO qui attire les touristes<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> Ce site inscrit sur la liste du patrimoine mondial de l\u2019UNESCO devrait attirer les touristes du monde entier. L\u2019Ouzb\u00e9kistan a r\u00e9ussi \u00e0 tirer b\u00e9n\u00e9fice du patrimoine architectural l\u00e9gu\u00e9 par Tamerlan : en 2019, 3,1 millions de touristes ont visit\u00e9 Samarcande, selon les estimations de l\u2019administration locale. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/louzbekistan-reconnu-comme-lun-des-centres-mondiaux-du-tourisme-religieux\/\">L\u2019Ouzb\u00e9kistan reconnu comme l\u2019un des centres mondiaux du tourisme religieux<\/a><\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 Turkestan, entre le centre historique, qui s\u2019\u00e9tend sur 188 hectares, et l&rsquo;a\u00e9roport, un centre administratif et d&rsquo;affaires (CAA) d&rsquo;une superficie de 1 350 hectares est en construction. De m\u00eame, il est pr\u00e9vu de construire un lieu pour accueillir l\u2019administration de la r\u00e9gion de Turkestan, des b\u00e2timents pour les entreprises financi\u00e8res et des installations pour l&rsquo;\u00e9ducation, les loisirs et les activit\u00e9s sportives. Cette zone sera reli\u00e9e au centre historique par une promenade : la route des caravanes. Des quartiers r\u00e9sidentiels se trouvent autour des centres administratifs et historico-culturels. La zone industrielle, deux parcelles d&rsquo;une superficie totale de 400 hectares, est situ\u00e9e \u00e0 la fronti\u00e8re de la ville. Kursiv a constat\u00e9 que les entreprises les plus actives dans le d\u00e9veloppement de Turkestan sont la holding <a href=\"https:\/\/ru.wikipedia.org\/wiki\/BI_Group\">BI Group<\/a> et <a href=\"https:\/\/bazis.kz\/our-projects\/built\">Bazis-A<\/a>, les principales entreprises de construction du pays, ainsi que des entreprises \u00e9trang\u00e8res. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>O\u00f9 BI Group cr\u00e9\u00e9 son bonheur<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nLa plupart des projets de BI Group sont concentr\u00e9s dans le centre administratif et commercial de Turkestan.\n\nL&rsquo;un des projets les plus co\u00fbteux, un complexe de b\u00e2timents administratifs avec une fa\u00e7ade ajour\u00e9e d\u00e9corative, ombrageant les bureaux des fonctionnaires du soleil du sud, a co\u00fbt\u00e9 26,8 milliards de tengu\u00e9s (53,2 millions d\u2019euros). Selon le site des march\u00e9s publics, BI Group a remport\u00e9 ces contrats par l&rsquo;interm\u00e9diaire de sa soci\u00e9t\u00e9 BI Construction Turkestan.\n\nLe boulevard qui m\u00e8ne au b\u00e2timent de l\u2019administration locale est construit par la m\u00eame entreprise. Le co\u00fbt de la construction de la premi\u00e8re phase est de 1,36 milliard de tengu\u00e9s (2,7 millions d\u2019euros).\n\nLa place Nur-Sultan, verdie et avec ses fontaines, est la cr\u00e9ation d\u2019une autre entreprise filiale, BI Urban Construction. Le prix des travaux est mont\u00e9 \u00e0 3,95 milliards de tengu\u00e9s (7,84 millions d\u2019euros) pour la place centrale de la capitale r\u00e9gionale.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des constructions de toutes sortes<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> \u00c0 100 m\u00e8tres de l&rsquo;entr\u00e9e du b\u00e2timent administratif de la ville, BI Urban Construction a construit un centre des m\u00e9dias qui a co\u00fbt\u00e9 5 milliards de tengu\u00e9s (9,9 millions d\u2019euros). Le stade Turkestan Arena, qui est \u00e0 1,5 kilom\u00e8tre de l&rsquo;administration r\u00e9gionale, a \u00e9galement \u00e9t\u00e9 construit par BI Group pour 12,6 milliards de tengu\u00e9s (25 millions d\u2019euros), et financ\u00e9 par le Fonds national d&rsquo;assistance <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Samrouk-Kazyna\">Samrouk-Kazyna<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/bpifrance-et-le-fonds-souverain-kazakh-vont-investir-100-millions-deuros-dans-des-entreprises-francaises-et-kazakhes\/\">Bpifrance et le fonds souverain kazakh vont investir 100 millions d\u2019euros dans des entreprises fran\u00e7aises et kazakhes<\/a><\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus des b\u00e2timents et des installations, BI Group construit des routes dans le centre administratif. Ainsi, huit contrats d&rsquo;\u00c9tat pour un montant total de 9,57 milliards de tengu\u00e9s (19 millions d\u2019euros) ont \u00e9t\u00e9 conclus avec la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e Karatas Mining, une filiale de BI Infra Construction, pour la construction de cinq sections de route. Karatas Mining am\u00e9nage un parc lin\u00e9aire d&rsquo;une superficie de 24 hectares, le long de la rue Sattarkhanov qui m\u00e8ne du centre administratif et des affaires au centre historico-culturel de Turkestan. La holding signale qu&rsquo;elle y construira une route de la Soie et une piste de course \u00e0 pied. Un canal, des fontaines pi\u00e9tonnes, des piscines, un \u00e9tang de n\u00e9nuphars ainsi que des arbustes et des arbres garantiront la fra\u00eecheur et l&rsquo;ombre pour les passants. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Le centre historique<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nDans le centre historique, BI Group a moins de travaux : le complexe culturel et de loisirs Oula Dala Eli et le th\u00e9\u00e2tre dramatique. Ici, le d\u00e9veloppeur a mis en \u0153uvre son propre projet d&rsquo;investissement, d&rsquo;un montant de 3,8 milliards de tengu\u00e9s (7,6 millions d\u2019euros)&nbsp;: l\u2019h\u00f4tel Hampton by Hilton.\n\nEn outre, le gouvernement a charg\u00e9 la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e Karatas Mining de construire un canal navigable avec des complexes sportifs dans le centre administratif et d&rsquo;affaires, partant du fleuve <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Syr-Daria\">Syr-Daria<\/a> pour alimenter le canal principal Arys Turkestan, ainsi que de mener des activit\u00e9s pour relancer le syst\u00e8me de lacs de Chochkakol. 2,18 milliards de tengu\u00e9s (4,34 millions d\u2019euros) seront investis dans le lac.\n\nLe plan du canal pour l\u2019aviron n&rsquo;a \u00e9t\u00e9 approuv\u00e9 qu&rsquo;en novembre 2020. En plus du canal, un centre olympique sera construit avec un h\u00f4tel, une piste cyclable, une piscine, des hangars, des quais pour les kayaks, un \u00e9cran d\u2019affichage pour les spectateurs, des tribunes et un pont.\n\nLa holding a \u00e9galement particip\u00e9 \u00e0 la construction d&rsquo;installations de sant\u00e9. La filiale du groupe BI \u2013 KAZPACO a d\u00e9velopp\u00e9 un h\u00f4pital infectieux modulaire de 200 lits. La soci\u00e9t\u00e9 ATM Turkistan Hospital est devenue membre de la ZES Turkistan avec un projet de construction et d\u2019exploitation d&rsquo;un h\u00f4pital multidisciplinaire de 630 lits, o\u00f9 ont \u00e9t\u00e9 investis plus de 110 milliards de tengu\u00e9s (219 millions d\u2019euros).\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Bazis-A veut \u00ab&nbsp;construire l\u2019avenir&nbsp;\u00bb<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> Le promoteur immobilier Bazis-A, dont le slogan est <em>\u00ab Nous construisons l\u2019avenir ! \u00bb<\/em>, s&rsquo;est concentr\u00e9 sur les installations du centre historique et culturel et sur la cr\u00e9ation d&rsquo;infrastructures d&rsquo;ing\u00e9nierie. La soci\u00e9t\u00e9 a ainsi construit le parc du Premier pr\u00e9sident, d&rsquo;une valeur de 13,5 milliards de tengu\u00e9s (27,3 millions d\u2019euros). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/decryptage\/bouygues-au-turkmenistan-une-presence-a-toute-epreuve\/\">Bouygues au Turkm\u00e9nistan, une pr\u00e9sence \u00e0 toute \u00e9preuve<\/a><\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bazis-A a \u00e9galement la charge de construire la biblioth\u00e8que scientifique r\u00e9gionale, d\u2019am\u00e9nager le territoire du <a href=\"http:\/\/azretsultan.kz\/eng\/\">mus\u00e9e Azret Soultan<\/a> et de reconstruire le centre des artisans. La soci\u00e9t\u00e9 construit \u00e9galement le mus\u00e9e Khoja Ahmed Yasavi, pour laquelle la Fondation Samrouk-Kazyna a allou\u00e9 1,5 milliard de tengu\u00e9s (3 millions d\u2019euros). <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Un grand parc pour la ville<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nDans le centre administratif, le promoteur cr\u00e9e un parc urbain avec des attractions. Il s\u2019y trouve notamment trois \u0153uvres d&rsquo;architecture, un arc d\u2019entr\u00e9e et une \u00ab&nbsp;tente de la paix&nbsp;\u00bb.\n\nAu total, environ 8,5 milliards de tengu\u00e9s (17,2 millions d\u2019euros) ont \u00e9t\u00e9 allou\u00e9s \u00e0 la cr\u00e9ation du parc \u00e0 partir des budgets des r\u00e9gions de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oblys_de_Karaganda\">Karaganda<\/a>, d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oblys_d%27Aqmola\">Akmola<\/a> et d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oblys_d%27Almaty\">Almaty<\/a>&nbsp;: c&rsquo;\u00e9tait un cadeau \u00e0 Turkestan de leur part. Le client \u2013 l\u2019administration de la r\u00e9gion d&rsquo;Almaty \u2013 a signal\u00e9 l&rsquo;ach\u00e8vement des principaux travaux sur le site en d\u00e9cembre 2020.\n\nPour la cr\u00e9ation d&rsquo;infrastructures pour la chaleur, l&rsquo;eau, l&rsquo;assainissement et la construction de routes dans le centre administratif et d&rsquo;affaires, Bazis-A a conclu huit contrats d\u2019un montant total de 8,56 milliards de tengu\u00e9s (17,3 millions d\u2019euros).\n\nLe d\u00e9veloppeur construit des infrastructures d&rsquo;ing\u00e9nierie dans un nouveau quartier r\u00e9sidentiel sur la base de trois autres contrats. En outre, le d\u00e9veloppeur a remport\u00e9 un contrat pour la construction d&rsquo;infrastructures d&rsquo;ing\u00e9nierie dans le nouveau quartier de la ville de Turkestan, qui concerne 98 hectares aux alentours du complexe comm\u00e9moratif aux khans kazakhs. L\u2019infrastructure qui dessert le complexe comm\u00e9moratif n&rsquo;a pas \u00e9t\u00e9 pr\u00e9cis\u00e9e.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des investisseurs \u00e9trangers<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nLa projet <a href=\"https:\/\/www.karavansaray.com\/\">Karavan-Sara\u00ef<\/a> compte parmi les plus grands projets d&rsquo;investisseurs \u00e9trangers&nbsp;: c\u2019est un complexe de loisirs d\u2019une superficie de 12,5 hectares dans le centre historique de la ville avec des h\u00f4tels, des zones de restauration, des cin\u00e9mas, des centres commerciaux, un th\u00e9\u00e2tre suspendu et des bazars, o\u00f9 les visiteurs peuvent se d\u00e9placer le long des canaux en bateau. Il est construit par la soci\u00e9t\u00e9 turque Turkistan Silkway Harbor, qui fait partie de la holding Sembol Construction. Karavan-Sara\u00ef co\u00fbtera \u00e0 l&rsquo;investisseur 88,5 milliards de tengu\u00e9s (179 millions d\u2019euros).\n\nAu Kazakhstan, Sembol Construction n&rsquo;est pas un d\u00e9butant. Il a fait appara\u00eetre sur la carte de la R\u00e9publique l&rsquo;h\u00f4tel Rixos d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Aqtaw\">Aktaou<\/a> et de nombreux objets embl\u00e9matiques de la capitale <a href=\"https:\/\/www.novastan.org\/fr\/kazakhstan\/la-capitale-du-kazakhstan-renommee-nur-sultan\/\">Nur-Sultan<\/a> : le stade de hockey Astana Arena, le centre commercial <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Khan_Shatyr\">Khan-Chatyr<\/a>, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Palais_de_la_paix_et_de_la_r%C3%A9conciliation\">palais de la paix et de la r\u00e9conciliation<\/a> en forme de pyramide, le palais de l&rsquo;Ind\u00e9pendance et d\u2019autres encore.\n\nUne autre soci\u00e9t\u00e9 turque, YDA Holding, a investi plus de 68 milliards de tengu\u00e9s (137 millions d\u2019euros) dans l&rsquo;a\u00e9roport international Azret Soultan. YDA construit \u00e9galement la route d&rsquo;acc\u00e8s \u00e0 l&rsquo;a\u00e9roport, de 15 kilom\u00e8tres, la d\u00e9viation par l\u2019est de la ville de Turkestan, de 30 kilom\u00e8tres, ainsi que l&rsquo;h\u00f4pital multidisciplinaire d\u00e9j\u00e0 mentionn\u00e9.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des contrats dans tout le Kazakhstan<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nDans le portefeuille de cette soci\u00e9t\u00e9 au Kazakhstan, il y a l&rsquo;a\u00e9roport d\u2019Aktaou, le centre financier d&rsquo;Almaty, l&rsquo;usine pharmaceutique Nobel, la reconstruction du parc de la culture et des loisirs, les r\u00e9seaux d&rsquo;ing\u00e9nierie de l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Exposition_internationale_d%27Astana_de_2017\">Expo 2017<\/a> et d&rsquo;autres infrastructures.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nLa soci\u00e9t\u00e9 suisse Mabetex Group a construit une salle de concert multifonctionnelle pour 9,6 milliards de tengu\u00e9s (19,5 millions d\u2019euros) et un Palais du mariage pour 1,16 milliard de tengu\u00e9s (2,35 millions d\u2019euros).\n\nCette soci\u00e9t\u00e9 d&rsquo;ing\u00e9nierie et de construction a d\u00e9j\u00e0 construit dans la capitale du Kazakhstan la r\u00e9sidence du pr\u00e9sident, l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ak_Orda\">Ak orda<\/a>, une piste cyclable, la salle de cin\u00e9ma Kazakhstan et d&rsquo;autres installations.\n\nLes deux plus grands d\u00e9veloppeurs nationaux, BI Group et Bazis-A, ont remport\u00e9 \u00e0 Turkestan des contrats dont le montant total s\u2019\u00e9l\u00e8ve \u00e0 plus de 80 milliards de tengu\u00e9s (162 millions d\u2019euros) et 60 milliards de tengu\u00e9s (121,5 millions d\u2019euros) respectivement pour les ann\u00e9es 2019 et 2020. En comparaison, le montant des contrats publics sur cette m\u00eame p\u00e9riode remport\u00e9s par le troisi\u00e8me concurrent, Chymkent A.R.T \u2013 Kourylis, est d&rsquo;environ 10 milliards de tengu\u00e9s (20,3 millions d\u2019euros).\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Natalia Katchalova<\/strong><br><strong>Journaliste pour Kursiv<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Traduit du <a href=\"https:\/\/kz.kursiv.media\/2021-01-28\/kto-stroit-turkestan\/\">russe<\/a> par Anastasia Ture Caballero<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>\u00c9dit\u00e9 par Paulinon Vanack\u00e8re<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par V\u00e9ronique Tapponnier<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Merci d&rsquo;avoir lu cet article jusqu&rsquo;au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez&nbsp;<a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a>&nbsp;ou nous envoyer un email \u00e0&nbsp;<a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Turkestan, dans le sud du Kazakhstan, est r\u00e9put\u00e9e \u00eatre la capitale spirituelle du pays. La ville essaie d\u2019attirer les visiteurs en s\u2019am\u00e9nageant. Quelles entreprises construisent Turkestan, avec quels projets et quel argent&nbsp;? Novastan reprend et traduit ici un article publi\u00e9 le 28 janvier 2021 par le m\u00e9dia kazakh Kursiv. En 2020, Turkestan a obtenu un [&hellip;]<\/p>\n","protected":false},"author":1247,"featured_media":54022,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,3986],"tags":[571,473,879,470,4027,1956,999],"coauthors":[4697,4417],"class_list":["post-54020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kazakhstan","category-societe-et-culture","tag-economie","tag-histoire","tag-investissement","tag-kazakhstan","tag-societe-et-culture","tag-traduction","tag-turkestan"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1247"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=54020"}],"version-history":[{"count":2,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54020\/revisions"}],"predecessor-version":[{"id":61476,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/54020\/revisions\/61476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/54022"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=54020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=54020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=54020"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=54020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}