{"id":53968,"date":"2022-04-12T12:05:14","date_gmt":"2022-04-12T10:05:14","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=53968"},"modified":"2023-03-30T10:12:25","modified_gmt":"2023-03-30T08:12:25","slug":"premiers-echanges-universitaires-entre-linalco-et-le-tadjikistan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/tadjikistan\/premiers-echanges-universitaires-entre-linalco-et-le-tadjikistan\/","title":{"rendered":"Premiers \u00e9changes universitaires entre l\u2019Inalco et le Tadjikistan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Quatre \u00e9tudiants en langue persane \u00e0 l&rsquo;Inalco de Paris ont pu partir au Tadjikistan entre mars et juin 2022. Cet \u00e9change permet \u00e0 la Fondation Inalco de s&rsquo;impliquer davantage en Asie centrale.<\/strong>\n\n\u00c0 la suite de l\u2019obtention d\u2019une bourse de mobilit\u00e9 de la <a href=\"http:\/\/www.inalco.fr\/fondation-inalco\/fondation\">Fondation Inalco<\/a>, organisme charg\u00e9 du financement des projets des \u00ab Langues O\u2019 \u00bb, quatre \u00e9tudiants en langue persane \u00e0 l\u2019Institut national des langues et civilisations orientales (Inalco) ont pu partir \u00e9tudier \u00e0 Douchanb\u00e9, la capitale du Tadjikistan, entre mars et juin 2022.\n\n<\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nBien qu&rsquo;elle ait d\u00e9j\u00e0 organis\u00e9 quelques projets depuis trois ans sous la forme d&rsquo;une association, la Fondation Inalco n\u2019existe officiellement que depuis octobre 2021. Cet \u00e9change avec l\u2019<a href=\"https:\/\/tnu.tj\/index.php\/en\/main\/\">Universit\u00e9 de Douchanb\u00e9<\/a> lance donc ses activit\u00e9s. Il s&rsquo;agit de la premi\u00e8re \u00ab promotion \u00bb de laur\u00e9ats de ses bourses de mobilit\u00e9 internationale, mais \u00e9galement du premier \u00e9change entre l\u2019<a href=\"http:\/\/www.inalco.fr\/institut\/presentation-politique-institut\">Inalco<\/a> et l\u2019Universit\u00e9 de Douchanb\u00e9.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Le Tadjikistan, un choix \u00ab\u00a0naturel\u00a0\u00bb<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\n\u00ab<i>&nbsp;Le choix du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Tadjikistan\">Tadjikistan<\/a> s\u2019est fait naturellement\u00a0\u00bb<\/i>, explique \u00e0 Novastan Arnaud Gennevois, d\u00e9l\u00e9gu\u00e9 g\u00e9n\u00e9ral de la Fondation Inalco. \u00ab\u00a0<i>La Fondation a souhait\u00e9 prioriser le monde perse, le <\/i><i>p<\/i><i>ersan \u00e9tant l&rsquo;une des quatre langues originelles de l&rsquo;Inalco (aux c\u00f4t\u00e9s du <\/i><i>c<\/i><i>hinois, du <\/i><i>h<\/i><i>indi et du <\/i><i>t<\/i><i>urc), et l&rsquo;aire g\u00e9ographique concern\u00e9e pr\u00e9sentant des enjeux g\u00e9opolitiques, culturels et civilisationnels majeurs<\/i> \u00bb, ajoute-t-il.\n\nLe persan est parl\u00e9 par plus de cent vingt millions de locuteurs, majoritairement en Iran, en Afghanistan et au Tadjikistan. Les \u00e9changes avec l\u2019Iran et l\u2019Afghanistan \u00e9tant compliqu\u00e9s, l\u2019Institut a port\u00e9 son choix sur le Tadjikistan. En outre, l&rsquo;Institut a sign\u00e9 au d\u00e9but de l&rsquo;ann\u00e9e une convention avec l&rsquo;Universit\u00e9 nationale d\u2019\u00c9tat du Tadjikistan.\n\n<strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/societe-et-culture\/nous-investissons-dans-lavenir-du-tadjikistan\/\">\u00ab Nous investissons dans l&rsquo;avenir du Tadjikistan \u00bb<\/a><\/strong>\n\nPour ce qui est de la s\u00e9lection des \u00e9tudiants, les crit\u00e8res d\u2019obtention de cette bourse sont vari\u00e9s. Cette opportunit\u00e9 a \u00e9t\u00e9 offerte aux \u00e9tudiants en deuxi\u00e8me et troisi\u00e8me ann\u00e9e de Licence et en Master. La s\u00e9lection porte sur l\u2019excellence de leurs r\u00e9sultats, ou sur une progression et une r\u00e9ussite exceptionnelles. Enfin, les \u00e9tudiants ayant un projet professionnel, social ou humanitaire particuli\u00e8rement original ont \u00e9t\u00e9 soutenus.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des parcours divers<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nParmi les premiers \u00e9tudiants s\u00e9lectionn\u00e9s se trouvent Eve Garinat, \u00e9tudiante en Licence 3 Relations internationales, sp\u00e9cialis\u00e9e dans le monde iranien. \u00ab\u00a0<i>\u00c9tudier l&rsquo;Asie centrale, espace au carrefour des mondes turc, iranien et russe est apparu comme un prolongement naturel de mon cursus\u00a0\u00bb,<\/i> explique l&rsquo;\u00e9tudiante <a href=\"http:\/\/www.inalco.fr\/actualite\/mobilite-internationale-tadjikistan-premiers-laureats-bourse-fondation-inalco\">\u00e0 l&rsquo;Inalco.<\/a><i> \u00ab\u00a0En effet, si le Tadjikistan a vu son histoire li\u00e9e \u00e0 celle de l&rsquo;Iran sous les Ach\u00e9m\u00e9nides dans l&rsquo;Antiquit\u00e9 et sous les Samanides au Moyen-\u00c2ge, o\u00f9 il a vu na\u00eetre le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Roudaki\">po\u00e8te Roudaki<\/a>, il a \u00e9t\u00e9 transform\u00e9 par l&rsquo;influence russe, imp\u00e9riale puis communiste, cr\u00e9ant une histoire complexe et unique<\/i>\u00ab\u00a0, ajoute-t-elle.\n\nSephora Valloton, \u00e9tudiante en Master 2 Traduction litt\u00e9raire en langue persane, est pour sa part tr\u00e8s impliqu\u00e9e aupr\u00e8s des \u00e9tudiants exil\u00e9s iraniens et afghans accueillis par l\u2019Institut dans le cadre de l\u2019action \u00ab <a href=\"http:\/\/www.inalco.fr\/actualite\/campagne-urgence-afghanistan-institut-fondation-inalco\">Urgence Afghanistan<\/a> \u00bb men\u00e9e apr\u00e8s la chute de Kaboul en ao\u00fbt 2021. Contact\u00e9e par Novastan, elle voit dans cet \u00e9change une opportunit\u00e9 unique d\u2019approfondir sa compr\u00e9hension culturelle et linguistique, ce qui est n\u00e9cessaire pour la pratique de la traduction litt\u00e9raire. Elle pourra \u00e9galement \u00e9changer avec des \u00e9tudiants et des professeurs sp\u00e9cialis\u00e9s en litt\u00e9rature tadjike et profiter des ressources bibliographiques sur place.\n\n<strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/la-france-et-le-kazakhstan-devoilent-une-bourse-etudiante-abai-verne\/\">La France et le Kazakhstan d\u00e9voilent une bourse \u00e9tudiante \u00ab Aba\u00ef-Verne \u00bb<\/a><\/strong>\n\nEnfin, Alice Darb-Esfahani, \u00e9tudiante en Licence 3 de persan, parcours Relations internationales, explique \u00e0 Novastan que, outre un perfectionnement en persan, cet \u00e9change lui permettra de mieux comprendre un pays qui soul\u00e8ve en elle beaucoup d&rsquo;interrogations. Elle donne des cours de fran\u00e7ais tout au long de son s\u00e9jour en \u00e9change de son logement en dortoir, et se d\u00e9clare ravie de l&rsquo;accueil et des \u00e9changes avec les \u00e9tudiants tadjiks.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des projets en plein essor<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nL&rsquo;Inalco n&rsquo;a pas encore pu accueillir d&rsquo;\u00e9tudiants tadjiks, n&rsquo;ayant pas de parcours universitaire adapt\u00e9 \u00e0 leur proposer pour l&rsquo;instant. Les cours de Fran\u00e7ais langue \u00e9trang\u00e8re (FLE) existent mais \u00e0 un volume trop restreint pour de grands d\u00e9butants venus suivre un cursus en France, tandis que les cours de langue \u00e9trang\u00e8re se font tout de m\u00eame en grande partie \u00e0 partir du fran\u00e7ais.\n\n\u00ab <em>Nous travaillons sur deux chantiers pour pallier ces difficult\u00e9s : tout d&rsquo;abord, d\u00e9velopper l&rsquo;enseignement des langues \u00e0 partir d&rsquo;autres langues que le fran\u00e7ais, l&rsquo;anglais notamment, mais pas que\u00a0\u00bb,<\/em> explique Arnaud Gennevois. <em>\u00ab\u00a0Ensuite, d\u00e9velopper la philanthropie pour permettre \u00e0 nos \u00e9tudiants de partir dans une mobilit\u00e9 \u00ab \u00e0 sens unique \u00bb, c&rsquo;est-\u00e0-dire dans laquelle l&rsquo;Inalco n&rsquo;offre pas de r\u00e9ciprocit\u00e9 \u00e0 l&rsquo;\u00e9tablissement partenaire. Ou encore, partir avec une r\u00e9ciprocit\u00e9 diff\u00e9rente, par exemple accueillir des enseignants ou doctorants en \u00e9change d&rsquo;\u00e9tudiants<\/em> \u00bb, ajoute le d\u00e9l\u00e9gu\u00e9 g\u00e9n\u00e9ral de la Fondation Inalco.\n\nPlus largement, la Fondation a pour objectif de favoriser la mobilit\u00e9 des \u00e9tudiants, de leur permettre une immersion dans les pays de l\u2019aire g\u00e9ographique et culturelle \u00e9tudi\u00e9e, et d\u2019am\u00e9liorer leur acc\u00e8s \u00e0 la langue et \u00e0 l\u2019emploi. Dans la mesure o\u00f9 l\u2019Inalco accueille plus de neuf mille \u00e9tudiants et enseigne cent trois langues diff\u00e9rentes, un soutien financier tel qu\u2019apport\u00e9 par la Fondation est n\u00e9cessaire pour garantir un acc\u00e8s plus grand et plus \u00e9galitaire \u00e0 la mobilit\u00e9.\n\nSon objectif \u00e0 court terme, courant ann\u00e9e 2022, serait de cr\u00e9er une bourse de mobilit\u00e9 internationale similaire pour les mondes indien et berb\u00e8re. La Fondation se d\u00e9clare \u00e9galement vivement int\u00e9ress\u00e9e pour d\u00e9velopper des partenariats acad\u00e9miques, scientifiques, culturels et philanthropiques en Asie centrale.\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Annah Tiprez<\/strong>\n<strong>R\u00e9dactrice pour Novastan<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par \u00c9lise Piedfort<\/strong>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatre \u00e9tudiants en langue persane \u00e0 l&rsquo;Inalco de Paris ont pu partir au Tadjikistan entre mars et juin 2022. Cet \u00e9change permet \u00e0 la Fondation Inalco de s&rsquo;impliquer davantage en Asie centrale. \u00c0 la suite de l\u2019obtention d\u2019une bourse de mobilit\u00e9 de la Fondation Inalco, organisme charg\u00e9 du financement des projets des \u00ab Langues O\u2019 [&hellip;]<\/p>\n","protected":false},"author":1090,"featured_media":53969,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3986,6],"tags":[814,5148,5151,2794,5152,5153,5150,720,5149],"coauthors":[4364,5154],"class_list":["post-53968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-et-culture","category-tadjikistan","tag-douchanbe","tag-echanges-universitaires","tag-fondation-inalco","tag-inalco","tag-institut-national-des-langues-et-civilisations-orientales","tag-langues-o","tag-mobilite-internationale","tag-universite","tag-universite-nationale-detat-de-douchanbe"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1090"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=53968"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/53969"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=53968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=53968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=53968"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=53968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}