{"id":53943,"date":"2022-03-31T11:16:52","date_gmt":"2022-03-31T09:16:52","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=53943"},"modified":"2023-03-30T10:12:25","modified_gmt":"2023-03-30T08:12:25","slug":"guerre-en-ukraine-des-centrasiatiques-en-europe-se-mobilisent-pour-aider-les-refugies","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/societe-et-culture\/guerre-en-ukraine-des-centrasiatiques-en-europe-se-mobilisent-pour-aider-les-refugies\/","title":{"rendered":"Guerre en Ukraine\u00a0: des Centrasiatiques en Europe se mobilisent pour aider les r\u00e9fugi\u00e9s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>3,<\/b><b>7 <\/b><b>millions de personnes ont fui l\u2019Ukraine depuis l\u2019invasion par la Russie, le 24 f\u00e9vrier 2022. <\/b><b>Alors que les Europ\u00e9ens s\u2019organisent pour aider les r\u00e9fugi\u00e9s, <\/b><b>des immigr\u00e9s <\/b><b>centrasiatiques<\/b><b> se rassemblent pour aider \u00e0 leur \u00e9chelle.<\/b>\n\nFace \u00e0 l\u2019un des plus grands mouvements de population en Europe, les Centrasiatiques pr\u00e9sents sur le continent s\u2019organisent. <span style=\"color: #0563c1\"><span style=\"color: #000000\">Nigora Razykova<\/span><\/span> est une \u00e9tudiante en gestion des affaires internationales \u00e0 l\u2019universit\u00e9 Saint Vincent Paul \u00e0 Lublin, en Pologne. D\u00e8s le d\u00e9but de l\u2019invasion de l\u2019Ukraine par la Russie, la Tadjike de 23 ans a su qu\u2019elle ne pouvait pas rester \u00e0 l\u2019\u00e9cart du conflit, relate le m\u00e9dia tadjik <a href=\"https:\/\/your.tj\/volonter-nigora-kak-tadzhikistanka-v-polshe-pomogaet-bezhencam-iz-ukrainy\/\">Your.tj<\/a>. Depuis le 24 f\u00e9vrier, 3,7 millions d\u2019Ukrainiens ont fui leur pays, comme l\u2019a d\u00e9crit le 25 mars dernier <a href=\"https:\/\/www.unhcr.org\/news\/briefing\/2022\/3\/623da5894\/month-since-start-war-quarter-ukraines-population-displaced.html\">l\u2019Agence des nations unies pour les r\u00e9fugi\u00e9s<\/a> (UNHCR).\n\n<\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nAu d\u00e9but, Nigora Razykova a particip\u00e9 \u00e0 sa mani\u00e8re et <span style=\"color: #0563c1\"><span style=\"color: #000000\">milit<\/span><\/span><span style=\"color: #0563c1\"><span style=\"color: #000000\">\u00e9<\/span><\/span><span style=\"color: #0563c1\"><span style=\"color: #000000\"> dans des rassemblement<\/span><\/span> anti-guerres. <i>\u00ab D\u00e8s que j&rsquo;ai appris ce qui s&rsquo;\u00e9tait pass\u00e9, j&rsquo;ai eu peur et j&rsquo;ai eu mal pour ces malheureux.&nbsp;Je n&rsquo;aurais jamais pens\u00e9 que cela puisse arriver, et si pr\u00e8s de nous&nbsp;<\/i>\u00bb explique-t-elle \u00e0 Your.tj. Lublin est \u00e0 637 kilom\u00e8tres de l\u2019Ukraine.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>Des actions b\u00e9n\u00e9voles et polyvalentes<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nPetit \u00e0 petit, Nigora Razykova diversifie ses actions et participe \u00e0 <span style=\"color: #0563c1\"><span style=\"color: #000000\">des collectes<\/span><\/span> de dons pour les r\u00e9fugi\u00e9s ukrainiens. \u00ab&nbsp;<i>Je me sentais impuissante, incapable de faire quoi que ce soit face \u00e0 la situation&nbsp;\u00bb <\/i>avoue-t-elle. Elle r\u00e9cup\u00e8re tous les biens primaires, susceptibles d\u2019aider les r\u00e9fugi\u00e9s&nbsp;: argent, nourriture, v\u00eatements et m\u00e9dicaments.\n\n<strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/politique\/guerre-en-ukraine-lasie-centrale-affectee-par-ricochets\/\"><strong>Guerre en Ukraine : l\u2019Asie centrale affect\u00e9e par ricochets<\/strong><\/a>\n\nSelon Your.tj, Nigora Razykova s\u2019engage imm\u00e9diatement en tant que b\u00e9n\u00e9vole, d\u00e8s que la Pologne a commenc\u00e9 \u00e0 accueillir les premiers r\u00e9fugi\u00e9s. <span style=\"color: #0563c1\"><span style=\"color: #000000\">Elle traduit le russe<\/span><\/span> en polonais pour aider les Ukrainiens. Elle enregistre les nouveaux arrivants. \u00ab&nbsp;<i>C&rsquo;est calme dans le centre pendant un moment, puis, <\/i><i>d\u2019un coup, <\/i><i>ils am\u00e8nent tout un bus de personnes qu&rsquo;il faut rapidement enregistrer, \u00e9quiper, nourrir&nbsp;\u00bb <\/i>raconte-t-elle.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>Une Tadjike parmi les aidants<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nL\u2019\u00e9quipe de b\u00e9n\u00e9voles o\u00f9 travaille Nigora Razykova est majoritairement ukrainienne et polonaise. Lorsque la jeune fille propose son aide, <span style=\"color: #0563c1\"><span style=\"color: #000000\">le personnel l\u2019accueille avec surprise<\/span><\/span>, \u00e9tonn\u00e9 qu\u2019une \u00e9trang\u00e8re veuille s\u2019investir et apporter sa coop\u00e9ration. \u00ab&nbsp;<i>La plupart des volontaires sont des r\u00e9sidents locaux. [\u2026] Par cons\u00e9quent, pour eux, tout cela est un peu inhabituel<\/i>&nbsp;\u00bb confie-t-elle.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nLorsque les habitants locaux d\u00e9couvrent d\u2019o\u00f9 elle vient, leur r\u00e9action demeure unanime&nbsp;: \u00ab&nbsp;<i>Le <\/i><i>Ta<\/i><i>d<\/i><i>jikistan&nbsp;! Oh c\u2019est si loin&nbsp;<\/i>\u00bb relate Nigora Razykova. Mais elle pr\u00e9cise que tous la f\u00e9licitent pour son courage et sa r\u00e9activit\u00e9. \u00ab&nbsp;<i>Je pense que l&rsquo;entraide est inh\u00e9rente \u00e0 chacun de nous.&nbsp;Et la situation actuelle l&rsquo;a montr\u00e9&nbsp;<\/i>\u00bb rappelle-t-elle.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>Des Centrasiatiques r\u00e9partis dans plusieurs pays<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nUne entraide qui ne se limite pas aux fronti\u00e8res polonaises. De fait, d\u2019autres personnes originaires des pays de l\u2019ex-URSS apportent leur aide aux r\u00e9fugi\u00e9s, selon <a href=\"https:\/\/your.tj\/jeto-nash-otvet-na-vojnu-kak-russkojazychnye-vyhodcy-iz-byvshego-sssr-pomogajut-ukrainskim-bezhencam-v-evrope\/\">Your.tj<\/a>. C\u2019est notamment le cas d\u2019Olga, originaire du Kazakhstan, qui vit en Allemagne.\n\n\u00ab&nbsp;<i>C\u2019est maintenant une id\u00e9e si commune qui unit tout le monde. C\u2019est probablement notre r\u00e9ponse \u00e0 la guerre<\/i>&nbsp;\u00bb d\u00e9clare Olga. Au 28 mars, l\u2019Allemagne avait enregistr\u00e9 plus de 300 000 r\u00e9fugi\u00e9s ukrainiens, relaie le m\u00e9dia allemand <a href=\"https:\/\/www.dw.com\/en\/ukrainian-refugees-face-bureaucratic-hurdles-in-germany\/a-61261691\">Deutsche Welle<\/a>.\n\n<strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/economie\/limpact-de-la-guerre-en-ukraine-sur-lasie-centrale-vers-la-fin-dune-politique-multidirectionnelle\/\">L\u2019impact de la guerre en Ukraine sur l\u2019Asie centrale&nbsp;: vers la fin d\u2019une \u00ab&nbsp;politique multidirectionnelle&nbsp;\u00bb&nbsp;?<\/a><\/strong>\n\nUn peu plus \u00e0 l\u2019Est, en <span style=\"color: #0563c1\"><span style=\"color: #000000\">R\u00e9publique Tch\u00e8que, se trouve Madina, <\/span><\/span><span style=\"color: #0563c1\"><span style=\"color: #000000\">d\u00e9crit <a href=\"https:\/\/your.tj\/jeto-nash-otvet-na-vojnu-kak-russkojazychnye-vyhodcy-iz-byvshego-sssr-pomogajut-ukrainskim-bezhencam-v-evrope\/\">Your.tj<\/a><\/span><\/span>. D\u2019origine tadjike, la jeune femme vit \u00e0 Prague avec sa petite fille de 9 ans. Madina explique que l\u2019entraide ne conna\u00eet pas de barri\u00e8res. \u00ab&nbsp;<i>J\u2019ai beaucoup d\u2019amis de diff\u00e9rentes nationalit\u00e9s de l\u2019ex-URSS. Ils aident tous les r\u00e9fugi\u00e9s<\/i>&nbsp;\u00bb raconte Madina. Russes, Tadjiks, Bi\u00e9lorusses, Kazakhs, Ouzbeks&nbsp;: ils pr\u00eatent main forte aux immigr\u00e9s ukrainiens, selon Your.tj.\n\n\u00ab&nbsp;<i>Nous avons vraiment honte que cela se soit produit&nbsp;<\/i>\u00bb d\u00e9plore Madina. Apr\u00e8s le d\u00e9but de la guerre, la jeune m\u00e8re s\u2019est inqui\u00e9t\u00e9e pour ses enfants. \u00ab&nbsp;<i>J\u2019ai demand\u00e9 \u00e0 mes enfants s\u2019ils avaient des probl\u00e8mes parce qu\u2019ils parlaient russe. Dieu merci, non, la relation est rest\u00e9e la m\u00eame<\/i>&nbsp;\u00bb explique-t-elle. Dans la classe de la fille a\u00een\u00e9e de Madina, les <span style=\"color: #0563c1\"><span style=\"color: #000000\">enfants se rassemblent et protestent<\/span><\/span> \u00e0 leur mani\u00e8re contre la guerre. \u00ab&nbsp;<i>Ces enfants se sont assis ensemble, ont condamn\u00e9 ce qui s\u2019est pass\u00e9 et ont d\u00e9cid\u00e9 d\u2019organiser une action de protestation contre la guerre&nbsp;<\/i>\u00bb, relate Madina.\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><b>Valentine Briant\nR\u00e9dactrice pour Novastan<\/b><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Emma Jerome<\/strong>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>3,7 millions de personnes ont fui l\u2019Ukraine depuis l\u2019invasion par la Russie, le 24 f\u00e9vrier 2022. Alors que les Europ\u00e9ens s\u2019organisent pour aider les r\u00e9fugi\u00e9s, des immigr\u00e9s centrasiatiques se rassemblent pour aider \u00e0 leur \u00e9chelle. Face \u00e0 l\u2019un des plus grands mouvements de population en Europe, les Centrasiatiques pr\u00e9sents sur le continent s\u2019organisent. Nigora Razykova [&hellip;]<\/p>\n","protected":false},"author":1618,"featured_media":53945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3987,3986],"tags":[493,5147,1576,5129,1842,521],"coauthors":[5168,5049],"class_list":["post-53943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europe-et-asie-centrale","category-societe-et-culture","tag-asie-centrale","tag-entraide","tag-europe","tag-guerre-en-ukraine","tag-refugies","tag-societe"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1618"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=53943"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/53945"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=53943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=53943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=53943"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=53943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}