{"id":53540,"date":"2022-03-09T09:47:51","date_gmt":"2022-03-09T08:47:51","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=53540"},"modified":"2023-03-30T10:12:25","modified_gmt":"2023-03-30T08:12:25","slug":"paris-et-nur-sultan-signent-un-pacte-de-cooperation","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kazakhstan\/paris-et-nur-sultan-signent-un-pacte-de-cooperation\/","title":{"rendered":"Paris et Nur-Sultan signent un pacte de coop\u00e9ration"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Les capitales fran\u00e7aise et kazakhe ont sign\u00e9 un pacte de coop\u00e9ration en d\u00e9cembre dernier. Nur-Sultan est la premi\u00e8re capitale en Asie centrale \u00e0 obtenir un tel partenariat avec Paris.&nbsp;<\/strong>\n\nC&rsquo;est un accord pass\u00e9 presque inaper\u00e7u. Le 6 d\u00e9cembre dernier, Paris et <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/la-capitale-du-kazakhstan-renommee-nur-sultan\/\">Nur-Sultan<\/a>, la capitale du Kazakhstan, ont sign\u00e9 un pacte de coop\u00e9ration, comme l&rsquo;a d\u00e9crit le m\u00e9dia kazakh <a href=\"https:\/\/24.kz\/ru\/news\/policy\/item\/514551-kazakhstan-i-frantsiya-podpisali-pakt-o-sotrudnichestve\">Khabar24<\/a>. Dans l&rsquo;intervalle, ni la mairie de Paris, ni celle de Nur-Sultan n&rsquo;ont publi\u00e9 de communiqu\u00e9 en bonne et due forme.\n\n<\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab\u00a0Notre objectif \u00e9tait que Paris noue un partenariat avec un acteur important en Asie centrale, alors que nous ne comptions jusqu&rsquo;\u00e0 pr\u00e9sent pas de partenaires dans la r\u00e9gion\u00a0\u00bb<\/em>, d\u00e9crit \u00e0 Novastan <a href=\"https:\/\/www.paris.fr\/pages\/arnaud-ngatcha-7966\">Arnaud Ngatcha<\/a>, adjoint aux relations internationales et \u00e0 la francophonie \u00e0 la mairie de Paris. <em>\u00ab\u00a0Nous voulons accompagner le d\u00e9veloppement de ce pays qui est, pour de nombreux observateurs, un acteur majeur dans cette partie du monde\u00a0\u00bb,&nbsp;<\/em>ajoute-t-il.\n\n<strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/un-accord-damitie-signe-entre-kyzylorda-et-nogent-sur-marne\/\"><strong>Un accord d\u2019amiti\u00e9 sign\u00e9 entre Kyzylorda et Nogent-sur-Marne<\/strong><\/a>\n\nCet accord, qui n&rsquo;est pas un pacte d&rsquo;amiti\u00e9 ni un jumelage, reste le premier de ce type pour Paris avec une capitale en Asie centrale.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Des vues essentiellement culturelles<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nCe pacte de coop\u00e9ration devrait principalement \u00eatre la base d&rsquo;actions communes sur le plan culturel. <em>\u00ab\u00a0Les discussions sont en cours, nous r\u00e9fl\u00e9chissons \u00e0 organiser des expositions ou encore des ballets ou des spectacles. Le directeur culturel de Paris doit aussi rencontrer le monde culturel de Nur-Sultan\u00a0\u00bb<\/em>, d\u00e9crit Arnaud Ngatcha.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nL&rsquo;annonce de ce pacte a d&rsquo;ailleurs eu lieu apr\u00e8s l&rsquo;inauguration d&rsquo;un buste <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Aba%C3%AF_Kounanba%C3%AFouly\">d&rsquo;Aba\u00ef<\/a>, l&rsquo;un des po\u00e8tes les plus c\u00e9l\u00e8bres du Kazakhstan, dans le VI\u00e8me arrondissement de Paris, d\u00e9crit le m\u00e9dia kazakh <a href=\"https:\/\/astanatimes.com\/2021\/12\/monument-honoring-great-kazakh-poet-and-philosopher-abai-kunanbayev-unveiled-in-paris\/\">The Astana Times<\/a>. \u00ab\u00a0<em>Il s&rsquo;agit d&rsquo;un premier point concret.&nbsp;<\/em><em>Nur-Sultan rend aussi hommage dans sa capitale \u00e0 un grand personnage de l\u2019histoire de France, le g\u00e9n\u00e9ral de<\/em><em>Gaulle\u00a0\u00bb<\/em>, explique Arnaud Ngatcha.\n\n<strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/la-france-et-le-kazakhstan-devoilent-une-bourse-etudiante-abai-verne\/\"><strong>La France et le Kazakhstan d\u00e9voilent une bourse \u00e9tudiante \u00ab&nbsp;Aba\u00ef-Verne&nbsp;\u00bb<\/strong><\/a>\n\nDe son c\u00f4t\u00e9, la mairie de Nur-Sultan d\u00e9crit \u00e0 Novastan que ce pacte pourra aussi permettre de <em>\u00ab\u00a0renforcer et \u00e9tendre les relations bilat\u00e9rales dans l&rsquo;\u00e9ducation, les investissements et d&rsquo;autres secteurs\u00a0\u00bb<\/em>.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Une proposition kazakhe<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nDans le d\u00e9tail, ce pacte a \u00e9t\u00e9 propos\u00e9 par la partie kazakhe \u00e0 Paris en juillet 2020, par le biais de Jean Galiev, l&rsquo;ambassadeur du Kazakhstan en France. <em>\u00ab\u00a0Le Kazakhstan nous a donn\u00e9 beaucoup de preuves d\u2019amour et nous avons entendu leur d\u00e9sir de coop\u00e9ration\u00a0\u00bb<\/em>, d\u00e9crit Arnaud Ngatcha.<em> \u00ab\u00a0Sur la sc\u00e8ne internationale, le Kazakhstan est de plus en plus pr\u00e9sent avec l&rsquo;abolition de la peine de mort, une ouverture sur la question des droits humains et une volont\u00e9 de se tourner vers l\u2019Europe\u00a0\u00bb<\/em>, ajoute l&rsquo;adjoint \u00e0 la mairie de Paris.\n\n<strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/le-kazakhstan-abolit-la-peine-de-mort\/\"><strong>Le Kazakhstan abolit la peine de mort<\/strong><\/a>\n\nAvec cet accord, Paris esp\u00e8re \u00e9galement pouvoir s&rsquo;impliquer davantage en Asie centrale. Tachkent et Bichkek auraient ainsi d\u00e9j\u00e0 contact\u00e9 la ville, mais sans pouvoir convaincre \u00e0 l&rsquo;heure actuelle d&rsquo;une v\u00e9ritable n\u00e9cessit\u00e9 ou d&rsquo;un projet commun. <em>\u00ab\u00a0Pour le moment, on se concentre sur cet accord avec Nur-Sultan. Nous verrons si on \u00e9largit ensuite\u00a0\u00bb<\/em>, estime Arnaud Ngatcha.\n\n<strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/le-kazakhstan-inaugure-son-consulat-general-a-strasbourg-et-vise-lunion-europeenne\/\"><strong>Le Kazakhstan inaugure son consulat g\u00e9n\u00e9ral \u00e0 Strasbourg et vise l\u2019Union europ\u00e9enne<\/strong><\/a>\n\nC\u00f4t\u00e9 kazakh, le message a \u00e9t\u00e9 bien re\u00e7u. <em>\u00ab\u00a0Nous pensons que ce pacte donnera une nouvelle dynamique au d\u00e9veloppement des relations franco-kazakhes\u00a0\u00bb<\/em>, affirme la mairie de Nur-Sultan.\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Etienne Combier<\/strong>\n<strong>R\u00e9dacteur en chef de Novastan<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Baptiste Long\u00e8re<\/strong>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les capitales fran\u00e7aise et kazakhe ont sign\u00e9 un pacte de coop\u00e9ration en d\u00e9cembre dernier. Nur-Sultan est la premi\u00e8re capitale en Asie centrale \u00e0 obtenir un tel partenariat avec Paris.&nbsp; C&rsquo;est un accord pass\u00e9 presque inaper\u00e7u. Le 6 d\u00e9cembre dernier, Paris et Nur-Sultan, la capitale du Kazakhstan, ont sign\u00e9 un pacte de coop\u00e9ration, comme l&rsquo;a d\u00e9crit [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":53542,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[1714,1235,458,470,3080,5120,1927],"coauthors":[81,2497],"class_list":["post-53540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kazakhstan","tag-accord","tag-diplomatie","tag-france","tag-kazakhstan","tag-nur-sultan","tag-pacte-de-cooperation","tag-paris"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=53540"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/53542"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=53540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=53540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=53540"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=53540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}