{"id":53493,"date":"2022-03-01T08:34:02","date_gmt":"2022-03-01T07:34:02","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=53493"},"modified":"2023-05-13T12:37:10","modified_gmt":"2023-05-13T10:37:10","slug":"kirghizstan-huit-histoires-tres-mediatisees-de-mariage-par-enlevement","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kirghizstan\/kirghizstan-huit-histoires-tres-mediatisees-de-mariage-par-enlevement\/","title":{"rendered":"Kirghizstan : huit histoires tr\u00e8s m\u00e9diatis\u00e9es de mariage par enl\u00e8vement"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Au Kirghizstan, enlever une jeune fille pour l\u2019\u00e9pouser est une pratique encore r\u00e9pandue, malgr\u00e9 son interdiction. Cet enl\u00e8vement, que certains consid\u00e8rent comme traditionnel, porte le nom d\u2019ala-kachuu. Aziza Abdirassoulova, d\u00e9fenseuse des droits de l\u2019Homme, vient en aide aux victimes, pour les encourager \u00e0 porter plainte et faire \u00e9voluer la situation.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Novastan reprend et traduit ici un article publi\u00e9 le 15 ao\u00fbt 2020 par le m\u00e9dia kirghiz <\/strong><a href=\"https:\/\/24.kg\/obschestvo\/162372_jertvyi_ala_kachuu_vosem_gromkih_istoriy_umyikaniya_nevest\/\"><strong>24.kg<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que ce soit interdit par la loi kirghize, les victimes d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ala_Kachuu\">ala-kachuu<\/a> sont encore nombreuses. Cette pratique, qui consiste \u00e0 enlever une jeune fille pour l\u2019\u00e9pouser, est encore r\u00e9pandue car les ravisseurs ne sont que rarement punis. En effet, la plupart des familles pr\u00e9f\u00e8rent laisser le mariage avoir lieu plut\u00f4t que d\u2019aller \u00e0 l\u2019encontre des traditions. Le m\u00e9dia kirghiz 24.kg revient sur huit histoires tr\u00e8s m\u00e9diatis\u00e9es d\u2019ala-kachuu. <\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\">\n\nEn ao\u00fbt 2020, un homme responsable d\u2019une tentative d\u2019enl\u00e8vement manqu\u00e9e sur une jeune fille a \u00e9t\u00e9 condamn\u00e9 \u00e0 deux mois de d\u00e9tention. La victime de cette pratique a failli se suicider. <a href=\"https:\/\/www.frontlinedefenders.org\/fr\/profile\/aziza-abdirasulova\">Aziza Abdirassoulova<\/a>, responsable de la Fondation de d\u00e9fense des droits de l\u2019Homme <a href=\"https:\/\/notorture.kg\/en\/kylym-shamy-public-foundation\/\">Kylym Shamy<\/a>, a aid\u00e9 \u00e0 pr\u00e9venir la trag\u00e9die.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Le silence contre un b\u00e9lier<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> L\u2019homme de 38 ans, trois fois divorc\u00e9, avait d\u00e9cid\u00e9 d\u2019enlever la jeune fille de 21 ans. Il a \u00e9t\u00e9 aid\u00e9 dans sa tentative par la s\u0153ur et un proche parent de la jeune fille. La victime a \u00e9t\u00e9 emmen\u00e9e dans le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/District_de_T%C3%BCp\">district de T\u00fcp<\/a>, dans le nord-est du pays. Les proches de la victime ont commenc\u00e9 \u00e0 r\u00e9diger des messages en son nom, indiquant que la jeune fille acceptait de se marier et demandait leur b\u00e9n\u00e9diction. Les ravisseurs ont cach\u00e9 aux parents la localisation de leur fille. L\u2019agresseur a finalement \u00e9t\u00e9 arr\u00eat\u00e9, mais les parents de celui-ci se sont mis \u00e0 faire pression sur la jeune fille et ont <a href=\"https:\/\/24.kg\/proisshestvija\/162020_vbishkeke_devushku_pohitili_zamuj_roditeley_prosyat_napisat_vstrechnoe_zayavlenie\/\">propos\u00e9<\/a> \u00e0 la famille un b\u00e9lier en \u00e9change d\u2019une contre-d\u00e9claration de la victime. Le principal suspect a tout de m\u00eame \u00e9t\u00e9 <a href=\"https:\/\/24.kg\/obschestvo\/162164_kraja_nevestyi_vbishkeke_nesostoyavshegosya_jeniha_vodvorili_vsizo-1na_dva_mesyatsa\/\">plac\u00e9 en garde \u00e0 vue<\/a>, tandis que les deux complices ont \u00e9t\u00e9 assign\u00e9s \u00e0 r\u00e9sidence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/kirghizstan-le-meurtre-dune-jeune-femme-enlevee-suscite-la-colere\/\">Kirghizstan : le meurtre d\u2019une jeune femme enlev\u00e9e suscite la col\u00e8re<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jeune fille enlev\u00e9e et ses proches ont l\u2019intention d\u2019obtenir une d\u00e9cision de justice \u00e9quitable et sont aid\u00e9s par la Fondation Kylym Shamy. Selon les d\u00e9fenseurs des droits de l\u2019Homme, la justice est souvent indulgente \u00e0 l\u2019\u00e9gard des crimes li\u00e9s \u00e0 l\u2019enl\u00e8vement de jeunes filles pour les contraindre \u00e0 se marier. Les ravisseurs \u00e9chappent le plus souvent \u00e0 la responsabilit\u00e9 p\u00e9nale ou sont condamn\u00e9s \u00e0 une peine avec sursis. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des enl\u00e8vements qui aboutissent parfois \u00e0 des meurtres<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> M\u00eame la trag\u00e9die de <a href=\"https:\/\/www.currenttime.tv\/a\/29257312.html\">Bouroula\u00ef Tourdalieva<\/a> n\u2019a rien chang\u00e9. La jeune fille de 19 ans a \u00e9t\u00e9 assassin\u00e9e en mai\u00a02018. Le responsable du meurtre de la jeune fille, qui a eu lieu dans le b\u00e2timent m\u00eame du d\u00e9partement r\u00e9gional des Affaires int\u00e9rieures, a \u00e9cop\u00e9 de 20\u00a0ans de prison. En juin de la m\u00eame ann\u00e9e, une jeune fille de 18\u00a0ans a \u00e9t\u00e9 <a href=\"https:\/\/24.kg\/obschestvo\/87827_vtoraya_burulay_devushku_ukrali_iiznasilovali\/\">enlev\u00e9e<\/a> dans la capitale, Bichkek. La victime n\u2019avait jamais rencontr\u00e9 son ravisseur. Lorsque la police l\u2019a localis\u00e9e, \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Naryn_(ville)\">Naryn<\/a>, dans l\u2019est du pays, elle avait d\u00e9j\u00e0 \u00e9t\u00e9 viol\u00e9e. Au cours du proc\u00e8s, les parents de l\u2019accus\u00e9 ont <a href=\"https:\/\/24.kg\/obschestvo\/102784_vtoraya_burulay_rodstvenniki_podsudimogo_prinesli_postradavshim_400_tyisyach_somov\/\">offert<\/a> aux parents de la victime 400\u00a0000\u00a0soms (4\u00a0140 euros) pour qu\u2019ils r\u00e9digent une contre-d\u00e9claration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/une-visite-a-ak-talaa-le-mariage-par-enlevement-26\/\">Une visite \u00e0 Ak-Talaa\u00a0: Le mariage par enl\u00e8vement \u00a0(2\/6)<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le tribunal a alors acquitt\u00e9 le jeune homme pour le chef d\u2019accusation de viol, mais l\u2019a condamn\u00e9 \u00e0 une peine avec sursis pour enl\u00e8vement. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>La cl\u00e9mence des tribunaux<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> En avril\u00a02019, une jeune fille de 16\u00a0ans a <a href=\"https:\/\/24.kg\/proisshestvija\/115015_voshe_ukrali_16-letnyuyu_devushku_ona_zayavila_chto_sama_reshila_vyiyti_zamuj\/\">disparu<\/a> \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Och\">Och<\/a>, dans le sud du Kirghizstan. Les parents ont imm\u00e9diatement fait une d\u00e9claration \u00e0 la police. La jeune fille avait \u00e9t\u00e9 enlev\u00e9e par un gar\u00e7on de 20 ans. Cependant, une fois retrouv\u00e9e, la victime a d\u00e9clar\u00e9 aux policiers qu\u2019elle connaissait son fianc\u00e9, qu\u2019elle avait eu des relations sexuelles avec lui et qu\u2019elle avait d\u00e9lib\u00e9r\u00e9ment d\u00e9cid\u00e9 de l\u2019\u00e9pouser. Dans le district de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/District_de_Le%C3%AFlek\">Le\u00eflek<\/a>, dans le sud-ouest du pays, une autre mineure a \u00e9t\u00e9 victime d\u2019ala-kachuu, enlev\u00e9e par un homme de 22 ans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais en septembre 2019, le tribunal l\u2019a <a href=\"https:\/\/24.kg\/obschestvo\/129921_vleyleke_paren_ukral_nesovershennoletnyuyu_zamuj_sud_ego_otpustil\/\">rel\u00e2ch\u00e9<\/a> avec un an de contr\u00f4le judiciaire. Le tribunal a indiqu\u00e9 que la victime \u00e9tait elle-m\u00eame mont\u00e9e dans la voiture de l\u2019accus\u00e9 sans le conna\u00eetre. L\u2019homme avait consid\u00e9r\u00e9 cela comme un consentement et l\u2019avait emmen\u00e9e dans un village voisin. Les parents du ravisseur les attendaient d\u00e9j\u00e0 dans la maison. L&rsquo;accus\u00e9 a \u00e9t\u00e9 reconnu coupable, mais il a affirm\u00e9 avoir renvoy\u00e9 la victime chez elle car elle refusait de se marier avec lui. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Des enl\u00e8vements de mineures<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> En janvier\u00a02020, trois hommes ont \u00e9t\u00e9 <a href=\"https:\/\/24.kg\/proisshestvija\/139670_vbishkeke_troe_parney_ukrali_nesovershennoletnyuyu_imdali_podva_goda_kolonii\/\">condamn\u00e9s<\/a> \u00e0 Bichkek pour enl\u00e8vement sur mineure. Les accus\u00e9s ont \u00e9t\u00e9 condamn\u00e9s \u00e0 la peine minimale de deux ans et demi d\u2019emprisonnement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/mariage-par-enlevement-les-etudiants-de-bichkek-dans-la-rue\/\">Mariage par enl\u00e8vement\u00a0: les \u00e9tudiants de Bichkek dans la rue<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jeune fille travaillait dans un caf\u00e9 de restauration rapide. Elle ne connaissait pas son agresseur. Le jeune homme et ses amis l\u2019ont forc\u00e9e \u00e0 entrer dans une voiture et l\u2019ont emmen\u00e9e \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Talas_(ville)\">Talas<\/a>, dans l\u2019ouest du pays. En chemin, ils ont appris que la jeune fille n\u2019avait que 17\u00a0ans. De plus, ses parents avaient appel\u00e9 la police. Les ravisseurs l\u2019ont alors ramen\u00e9e chez elle. Au tribunal, l\u2019homme a plaid\u00e9 coupable, mais en expliquant que la jeune fille lui avait menti sur son \u00e2ge, en affirmant avoir 21\u00a0ans. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Exiger une punition<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"> \u00c0 Och, un \u00e9tudiant est en cours de proc\u00e8s apr\u00e8s avoir enlev\u00e9 et tent\u00e9 de forcer une jeune fille de 20 ans \u00e0 l&rsquo;\u00e9pouser . La victime a \u00e9t\u00e9 emmen\u00e9e de force dans une voiture dans le centre-ville, pr\u00e8s d\u2019un supermarch\u00e9. Selon les donn\u00e9es pr\u00e9liminaires, la victime connaissait son agresseur, mais ne souhaitait pas l\u2019\u00e9pouser. Sa m\u00e8re a adress\u00e9 une plainte \u00e0 la police. Par la suite, les forces de l\u2019ordre ont <a href=\"https:\/\/24.kg\/proisshestvija\/141427_kraja_nevest_voshe_zaderjanyi_pohititeli_20-letney_devushki\/\">arr\u00eat\u00e9<\/a> deux suspects. Le ravisseur a \u00e9t\u00e9 \u00e9crou\u00e9 dans un centre de d\u00e9tention. La d\u00e9fense de l\u2019accus\u00e9 a requis la relaxe en r\u00e9sidence surveill\u00e9e, motivant cela par le fait que l\u2019agresseur est toujours \u00e9tudiant. Cependant, la gravit\u00e9 du crime a pouss\u00e9 le tribunal \u00e0 garder le jeune homme en d\u00e9tention.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/deux-femmes-kirghizes-temoignent-apres-setre-echappees-dun-mariage-force\/\">Deux femmes kirghizes t\u00e9moignent apr\u00e8s s\u2019\u00eatre \u00e9chapp\u00e9es d\u2019un mariage forc\u00e9<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le proc\u00e8s des ravisseurs d\u2019une habitante de Bichkek, \u00e2g\u00e9e de 28\u00a0ans, se poursuit. La jeune fille avait \u00e9t\u00e9 invit\u00e9e par des amis au bord du lac <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Yssyk_Koul\">Issyk-Koul<\/a> pour des vacances, mais avait \u00e9t\u00e9 emmen\u00e9e \u00e0 la place dans la maison d\u2019un inconnu dans le village de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Jeti-%C3%96g%C3%BCz_village\">Djeti-Ogouz<\/a>, qui a voulu la contraindre \u00e0 se marier avec lui. Lorsque la victime a refus\u00e9, elle a \u00e9t\u00e9 brutalement battue. La victime \u00e9tait orpheline. Le crime avait \u00e9t\u00e9 facilit\u00e9 par des femmes de son entourage qui l\u2019avaient emmen\u00e9e \u00e0 Issyk-Koul. La jeune femme s\u2019est adress\u00e9e \u00e0 l\u2019Association des centres de crise, o\u00f9 elle a re\u00e7u une assistance juridique et psychologique. En raison du stress v\u00e9cu, elle est d\u00e9sormais victime de tremblements, et un traitement s\u00e9rieux est n\u00e9cessaire. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Les histoires derri\u00e8re les chiffres<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nEn 2019, les condamnations pour ala-kachuu ont \u00e9t\u00e9 renforc\u00e9es au Kirghizstan. Pourtant, la situation a peu chang\u00e9. Chaque ann\u00e9e, des centaines de jeunes filles sont enlev\u00e9es et forc\u00e9es \u00e0 se marier. Victimes d\u2019intimidations, de viols et le plus souvent rejet\u00e9es par leurs proches, elles sont souvent oblig\u00e9es de rester avec leur ravisseur. Peu d\u2019entre elles d\u00e9cident de demander de l\u2019aide aux forces de l\u2019ordre ou aux d\u00e9fenseurs des droits de l\u2019Homme.\n\n<\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"> Selon des donn\u00e9es r\u00e9centes, une Kirghize sur quatre \u00e2g\u00e9e de 15 \u00e0 49 ans a subi des violences physiques. 4\u00a0% des femmes ont \u00e9t\u00e9 victimes de violences sexuelles, 14\u00a0% de violences \u00e9motionnelles ou psychologiques. Toutes les affaires p\u00e9nales ne se retrouvent pas au tribunal, car des dizaines sont abandonn\u00e9es pour diverses raisons au cours de l\u2019enqu\u00eate : pression des parents et de la soci\u00e9t\u00e9, le qu\u2019en-dira-t-on, pour r\u00e9diger une contre-d\u00e9claration, compensations vers\u00e9es, etc. Les ravisseurs ne sont d\u00e8s lors que quelques-uns \u00e0 \u00eatre condamn\u00e9s \u00e0 la sanction qu\u2019ils m\u00e9ritent.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>A\u00efda Djoumachova<\/strong><br><strong>Journaliste pour 24.kg<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Traduit du <\/strong><a href=\"https:\/\/24.kg\/obschestvo\/162372_jertvyi_ala_kachuu_vosem_gromkih_istoriy_umyikaniya_nevest\/\"><strong>russe<\/strong><\/a><strong> par Pierre-Fran\u00e7ois Hubert<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>\u00c9dit\u00e9 par Paulinon Vanack\u00e8re<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Swann Herrenschneider<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Merci d&rsquo;avoir lu cet article jusqu&rsquo;au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez&nbsp;<a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a>&nbsp;ou nous envoyer un email \u00e0&nbsp;<a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au Kirghizstan, enlever une jeune fille pour l\u2019\u00e9pouser est une pratique encore r\u00e9pandue, malgr\u00e9 son interdiction. Cet enl\u00e8vement, que certains consid\u00e8rent comme traditionnel, porte le nom d\u2019ala-kachuu. Aziza Abdirassoulova, d\u00e9fenseuse des droits de l\u2019Homme, vient en aide aux victimes, pour les encourager \u00e0 porter plainte et faire \u00e9voluer la situation. Novastan reprend et traduit ici [&hellip;]<\/p>\n","protected":false},"author":392,"featured_media":53494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,3986],"tags":[2589,433,1574,484,466,881,4027,1956],"coauthors":[1621,4417],"class_list":["post-53493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kirghizstan","category-societe-et-culture","tag-ala-kachuu","tag-bichkek","tag-enlevement","tag-issyk-koul","tag-kirghizstan","tag-och","tag-societe-et-culture","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/392"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=53493"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/53493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/53494"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=53493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=53493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=53493"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=53493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}