{"id":52418,"date":"2021-12-20T09:12:33","date_gmt":"2021-12-20T08:12:33","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=52418"},"modified":"2025-03-12T14:22:15","modified_gmt":"2025-03-12T13:22:15","slug":"saikal-jounouchova-larchitecte-ecologiste-qui-deconstruit-les-stereotypes-de-genre-au-kirghizstan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kirghizstan\/saikal-jounouchova-larchitecte-ecologiste-qui-deconstruit-les-stereotypes-de-genre-au-kirghizstan\/","title":{"rendered":"Sa\u00efkal Jounouchova, l\u2019architecte \u00e9cologiste qui d\u00e9construit les st\u00e9r\u00e9otypes de genre au Kirghizstan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Comme les autres pays d\u2019Asie centrale, le Kirghizstan est en premi\u00e8re ligne face aux changements climatiques. L\u2019architecte Sa\u00efkal Jounouchova milite pour que son travail sur des maisons \u00e9conomes en \u00e9nergie soit reconnu dans ce milieu tr\u00e8s masculin et puisse aider \u00e0 am\u00e9liorer la qualit\u00e9 de l\u2019air.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Novastan reprend et traduit ici un article publi\u00e9 le 16<strong>\u00a0<\/strong>septembre 2021 par le m\u00e9dia kirghiz <\/b><a href=\"https:\/\/kloop.kg\/blog\/2021\/09\/16\/obyasnyaesh-chto-ty-ne-prosto-zhenshhina-a-spetsialist-kak-arhitektorka-sajkal-stroit-ekologichnye-doma\/?fbclid=IwAR2h29-tBZgDxNtTHSBObii5c87V7951QqGsCR-KlmzwpsUp4rwndngp4oA\"><b>Kloop.kg<\/b><\/a><b>.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Cet article a \u00e9t\u00e9 \u00e9crit dans le cadre du projet <a href=\"https:\/\/news.un.org\/fr\/story\/2021\/02\/1089202\">\u00ab Les femmes dans la science \u00bb<\/a> en partenariat avec le <a href=\"http:\/\/www.streetchild.ktnet.kg\/index.php\/en-us\/\">Centre pour la protection des enfants<\/a> et l\u2019UNICEF.La fin de l\u2019\u00e9t\u00e9 \u00e0 Bichkek annonce la p\u00e9riode des grands froids, et, corr\u00e9lativement, la saison du chauffage. \u00c0 l\u2019approche de l\u2019hiver, la capitale se couvre d\u00e9j\u00e0 de brume et on verra bient\u00f4t la fum\u00e9e sortir des chemin\u00e9es des habitations. Sa\u00efkal Jounouchova est architecte, et il y a six mois, elle a commenc\u00e9 \u00e0 construire une maison \u00e9cologique \u00e0 \u00e9conomie d&rsquo;\u00e9nergie pour sa famille.<\/span><\/p>\n\n\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">En ballerines et v\u00eatements blancs, Sa\u00efkal Jounouchova fait le tour de sa maison construite sur deux \u00e9tages et nous montre avec pr\u00e9cision les d\u00e9tails de la construction. Sa maison n\u2019a ni chauffage \u00e9lectrique ni chaudi\u00e8re. Elle est chauff\u00e9e gr\u00e2ce au soleil.<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>Des maisons \u00e9cologiques pour r\u00e9duire les d\u00e9penses \u00e9nerg\u00e9tiques<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><i><span style=\"font-weight: 400\">\u00ab Une maison \u00e9conome en \u00e9nergie, c\u2019est une maison qui ne requiert pas de consommation de ressources pour se chauffer, ou pour la climatisation en \u00e9t\u00e9\u00a0\u00bb<\/span><\/i><span style=\"font-weight: 400\">, explique l\u2019architecte.<\/span><i><span style=\"font-weight: 400\"> \u00ab Il n\u2019y a pas de chauffages muraux standards ou de radiateurs. L\u2019id\u00e9e d\u2019origine dans cette maison est de n\u2019utiliser que l\u2019\u00e9nergie solaire. \u00bb<\/span><\/i><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Lire aussi sur Novastan: <\/b><a href=\"https:\/\/novastan.org\/fr\/decryptage\/lenergie-solaire-en-plein-boom-en-asie-centrale\/\"><b>L\u2019\u00e9nergie solaire en plein boom en Asie centrale<\/b><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Dans sa maison, la sp\u00e9cialiste a tout fait pour exploiter au maximum le soleil. Les trois \u00e9tages du c\u00f4t\u00e9 sud sont tous \u00e9quip\u00e9s de fen\u00eatres panoramiques. En hiver, quand le soleil sera bas, il entrera enti\u00e8rement dans la maison. En \u00e9t\u00e9, quand il sera haut, il fera frais, gr\u00e2ce \u00e0 l\u2019angle droit de l\u2019auvent et aux balcons blancs. Sur le toit sont install\u00e9s trois panneaux solaires, qui servent \u00e0 chauffer l\u2019eau et le sol de la maison.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/lair-que-lon-respire-au-kirghizstan\/\">L\u2019air que l\u2019on respire au Kirghizstan<\/a><\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">L\u2019id\u00e9e de construire cette maison est venue \u00e0 Sa\u00efkal Jounouchova en Suisse, o\u00f9 elle a \u00e9tudi\u00e9 et travaille depuis 12 ans. Elle explique que le soleil y est souvent utilis\u00e9 pour chauffer les maisons \u2013 c\u2019est plus \u00e9cologique et plus \u00e9conomique.Mais la cr\u00e9atrice est all\u00e9e plus loin encore dans la r\u00e9ponse \u00e9cologique. Elle a install\u00e9 dans sa maison un syst\u00e8me de recyclage des d\u00e9chets alimentaires, gr\u00e2ce auquel sa famille pourra produire du compost \u00e0 partir de pelures de pomme de terre ou de restes de past\u00e8que.<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Devenir architecte, un r\u00eave d\u2019enfant<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Pour Sa\u00efkal Jounouchova, construire des b\u00e2timents est un r\u00eave d\u2019enfant n\u00e9 du temps elle vivait dans le village de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Vinogradnoe\">Vinogradnoye<\/a>, au nord de Bichkek. L\u2019architecte se souvient de l\u2019inconfort de leur petite maison, o\u00f9 il faisait toujours tr\u00e8s froid. Elle devait parfois s\u2019habiller chaudement m\u00eame en \u00e9t\u00e9.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i><span style=\"font-weight: 400\">\u00ab Les probl\u00e8mes de logement m\u2019ont toujours int\u00e9ress\u00e9e. Je voulais trouver comment les r\u00e9soudre. Mon p\u00e8re aussi \u00e9tait architecte, mais il est mort jeune. Ses journaux et ses ouvrages, que j\u2019ai d\u00e9couverts par la suite, ont \u00e9t\u00e9 pour moi une source d\u2019inspiration. Comme je dessinais bien, j\u2019\u00e9tais faite pour devenir architecte ou designer \u00bb<\/span><\/i><span style=\"font-weight: 400\">, raconte-t-elle.<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>L\u2019architecture, un domaine tr\u00e8s masculin au Kirghizstan<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Sa\u00efkal Jounouchova est partie \u00e9tudier en Suisse en 2009. Elle y a ouvert un <\/span><a href=\"https:\/\/www.oekofacta.com\/\"><span style=\"font-weight: 400\">cabinet d\u2019architecture<\/span><\/a><span style=\"font-weight: 400\"> et construit des b\u00e2timents pour les habitants et les entrepreneurs locaux. Au Kirghizstan, elle donne des cours pour les apprentis architectes et leur parle de construction \u00e9cologique et r\u00e9fl\u00e9chie.<\/span><span style=\"font-weight: 400\">Malgr\u00e9 cela, Sa\u00efkal Jounouchova se heurte aux st\u00e9r\u00e9otypes sur son r\u00f4le dans la profession. Selon elle, elle doit souvent d\u00e9montrer son utilit\u00e9 et son professionnalisme, et il lui arrive r\u00e9guli\u00e8rement d\u2019\u00eatre confront\u00e9e au <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Mansplaining\"><span style=\"font-weight: 400\">mansplaining<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Du fait des st\u00e9r\u00e9otypes et <\/span><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/le-sexisme-au-kirghizstan\/\"><span style=\"font-weight: 400\">in\u00e9galit\u00e9s de genre<\/span><\/a><span style=\"font-weight: 400\"> au Kirghizstan, les femmes s\u2019orientent rarement vers les sciences techniques. En 2020, il y avait 79 % d\u2019\u00e9tudiants hommes en architecture, contre seulement 21 % de femmes. La plupart des architectes dans le pays sont des hommes.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/asie-centrale-2030-legalite-hommes-femmes-jusque-dans-le-travail\/\"><b>Asie centrale 2030 : l\u2019\u00e9galit\u00e9 hommes-femmes jusque dans le travail ?<\/b><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i><span style=\"font-weight: 400\">\u00ab Au d\u00e9but, tu dois expliquer que tu n\u2019es pas seulement une femme, mais une sp\u00e9cialiste dans ton domaine, que tu es l\u2019auteure du projet, et que tu fais tout pour une raison. Que tu n\u2019es pas l\u00e0 que pour regarder, mais aussi pour discuter avec eux des probl\u00e8mes concrets. Tu dois le faire au d\u00e9part, puis ils se rendent compte que tu as des arguments pertinents, que tu es forte, et ils ne peuvent plus se passer de toi \u00bb<\/span><\/i><span style=\"font-weight: 400\">, explique Sa\u00efkal Jounouchova.<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Une solution pour am\u00e9liorer la qualit\u00e9 de l\u2019air<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">L\u2019architecte pense que gr\u00e2ce aux maisons \u00e0 haute performance \u00e9nerg\u00e9tique, le Kirghizstan pourra trouver des solutions significatives au probl\u00e8me de la qualit\u00e9 de l\u2019air. Sa\u00efkal ne veut pas travailler qu\u2019en Suisse, mais \u00e9galement au Kirghizstan, pour construire des b\u00e2timents plus \u00e9cologiques.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/decryptage\/la-pollution-de-lair-de-bichkek-un-probleme-insoluble\/\">La pollution de l\u2019air de Bichkek, un probl\u00e8me insoluble ?<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i><span style=\"font-weight: 400\">\u00ab L\u2019environnement au Kirghizstan se d\u00e9t\u00e9riore. Chaque ann\u00e9e Bichkek perd des espaces verts et des arbres. Nous avons beaucoup de soleil au Kirghizstan. M\u00eame en hiver, quand il fait froid et qu\u2019il neige, nous avons tout le temps du soleil. D\u2019o\u00f9 cette id\u00e9e\u2026 Pourquoi ne pas exploiter cet atout ? \u00bb<\/span><\/i><span style=\"font-weight: 400\">, conclut Sa\u00efkal Jounouchova.<\/span><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>A\u00efzirek Imanalieva<\/strong><strong>&nbsp;pour Kloop.kg<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Vid\u00e9o par Alexandre Alexandrov&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Traduit du <a href=\"https:\/\/kloop.kg\/blog\/2021\/09\/16\/obyasnyaesh-chto-ty-ne-prosto-zhenshhina-a-spetsialist-kak-arhitektorka-sajkal-stroit-ekologichnye-doma\/?fbclid=IwAR2h29-tBZgDxNtTHSBObii5c87V7951QqGsCR-KlmzwpsUp4rwndngp4oA\">russe<\/a> par Juliette Amiranoff<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>\u00c9dit\u00e9 par Fr\u00e9d\u00e9rique Faucher <\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Anne Marvau<\/strong><\/p>\n\n\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme les autres pays d\u2019Asie centrale, le Kirghizstan est en premi\u00e8re ligne face aux changements climatiques. L\u2019architecte Sa\u00efkal Jounouchova milite pour que son travail sur des maisons \u00e9conomes en \u00e9nergie soit reconnu dans ce milieu tr\u00e8s masculin et puisse aider \u00e0 am\u00e9liorer la qualit\u00e9 de l\u2019air. Novastan reprend et traduit ici un article publi\u00e9 le [&hellip;]<\/p>\n","protected":false},"author":917,"featured_media":52422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3981,3],"tags":[1027,428,4278,466,521,1956],"coauthors":[4242,3595,3584],"class_list":["post-52418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-environnement","category-kirghizstan","tag-architecture","tag-environnement","tag-genre","tag-kirghizstan","tag-societe","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/52418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/917"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=52418"}],"version-history":[{"count":2,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/52418\/revisions"}],"predecessor-version":[{"id":69483,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/52418\/revisions\/69483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/52422"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=52418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=52418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=52418"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=52418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}