{"id":50776,"date":"2021-10-11T09:13:09","date_gmt":"2021-10-11T07:13:09","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=50776"},"modified":"2023-03-30T10:29:07","modified_gmt":"2023-03-30T08:29:07","slug":"renault-en-ouzbekistan-lhistoire-continue","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/economie\/renault-en-ouzbekistan-lhistoire-continue\/","title":{"rendered":"Renault en Ouzb\u00e9kistan : l\u2019histoire continue"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\"><b>Renault tente une nouvelle implantation en Ouzb\u00e9kistan, par l\u2019interm\u00e9diaire du distributeur Roodell Motor Vehicle. Le constructeur fran\u00e7ais avait d\u00e9j\u00e0 annonc\u00e9 la vente de ses v\u00e9hicules dans le pays en 2019, sans que cela ne soit effectif.&nbsp;<\/b>\nLes Ouzbeks devraient bient\u00f4t pouvoir rouler en Renault. Le 10 septembre dernier,&nbsp;<a href=\"https:\/\/roodell.uz\"><span style=\"font-weight: 400;\">Roodell<\/span><\/a><span style=\"font-weight: 400;\">, distributeur des v\u00e9hicules Renault en Russie et des v\u00e9hicules Lada et Kia en Ouzb\u00e9kistan, a annonc\u00e9 aupr\u00e8s <a href=\"https:\/\/www.gazeta.uz\/ru\/2021\/09\/10\/renault\/\">du m\u00e9dia ouzbek Gazeta.uz<\/a> qu&rsquo;il pr\u00e9voyait d\u2019\u00e9largir son offre dans le pays en produisant directement sur place des v\u00e9hicules Renault.&nbsp;<\/span><span style=\"font-weight: 400;\">Contact\u00e9 par Novastan, le distibuteur Roodell pr\u00e9cise que la vente des deux Crossovers <\/span><a href=\"https:\/\/www.renault.fr\/vehicules-particuliers\/arkana.html\"><span style=\"font-weight: 400;\">Arkana<\/span><\/a><span style=\"font-weight: 400;\"> et <\/span><a href=\"https:\/\/www.renaultgroup.com\/news-onair\/actualites\/nouveau-kaptur-un-crossover-renault-pense-pour-la-russie\/\"><span style=\"font-weight: 400;\">Captur<\/span><\/a><span style=\"font-weight: 400;\"> commencera \u201c<\/span><i><span style=\"font-weight: 400;\">dans un avenir proche<\/span><\/i><span style=\"font-weight: 400;\">\u201d et celle du SUV <\/span><a href=\"https:\/\/renault-ci.com\/cars\/DusterHjdPh1Helios\/overview.html\"><span style=\"font-weight: 400;\">Duster<\/span><\/a><span style=\"font-weight: 400;\">, \u201c<\/span><i><span style=\"font-weight: 400;\">sera lanc\u00e9e plus tard<\/span><\/i><span style=\"font-weight: 400;\">\u201d.&nbsp;<\/span><\/p>\n\n\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Roodell estime ainsi qu&rsquo;il existe une opportunit\u00e9 \u00e9conomique nouvelle.<\/span><span style=\"font-weight: 400;\">&nbsp;\u201c<\/span><i><span style=\"font-weight: 400;\">Le secteur des SUV est tr\u00e8s prometteur en Ouzb\u00e9kistan, il y a peu d\u2019offres et la demande est \u00e9lev\u00e9e\u201d, <\/span><\/i><span style=\"font-weight: 400;\">explique <\/span><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.linkedin.com\/in\/mariya-savatyugina-21177b143\/?trk=public_profile_browsemap_profile-result-card_result-card_full-click\">Mariya Savatyougina<\/a><\/span><span style=\"font-weight: 400;\">, cheffe marketing chez Roodell. &nbsp;<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><b>Une production locale&nbsp;&nbsp;<\/b><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Concr\u00e8tement, les voitures seront produites en Ouzb\u00e9kistan, dans la zone industrielle de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Djizak\">Djizak<\/a>, situ\u00e9e au nord-est de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Samarcande\">Samarcande<\/a>. L&rsquo;usine est <a href=\"https:\/\/www.gazeta.uz\/ru\/2020\/12\/31\/lada-renault\/\">d\u00e9j\u00e0 utilis\u00e9e<\/a> par Roodell pour produire ses Lada et Kia.<\/span><span style=\"font-weight: 400;\"> Mariya Savatyouhina a confirm\u00e9 la localisation de l\u2019usine de fabrication et sa r\u00e9cente ouverture en 2021.<\/span><span style=\"font-weight: 400;\">La capacit\u00e9 de production devrait atteindre 100 000 v\u00e9hicules par an et le projet devrait co\u00fbter quelque 60 millions de dollars (51,8 millions d&rsquo;euros) d&rsquo;ici \u00e0 2023, dont un peu plus de la moiti\u00e9 pour la seule ann\u00e9e 2021, <\/span><a href=\"https:\/\/www.gazeta.uz\/ru\/2021\/09\/10\/renault\/\"><span style=\"font-weight: 400;\">selon Gazeta.uz<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Un premier \u00ab\u00a0lancement\u00a0\u00bb en 2019<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nCette arriv\u00e9e prochaine en Ouzb\u00e9kistan via Roodell est la deuxi\u00e8me tentative de Renault de s&rsquo;implanter sur le march\u00e9 ouzbek. <span style=\"font-weight: 400;\">En 2019 en effet, Maximilian Missan, directeur g\u00e9n\u00e9ral export de Renault pour la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Communaut%C3%A9_des_%C3%89tats_ind%C3%A9pendants\">Communaut\u00e9 des Etats ind\u00e9pendants<\/a> (CEI), avait d\u00e9clar\u00e9 <\/span><a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/renault-bientot-present-dans-les-rues-de-tachkent\/\"><span style=\"font-weight: 400;\">l\u2019intention de Renault de vendre la marque phare du groupe en Ouzb\u00e9kistan<\/span><\/a><span style=\"font-weight: 400;\">, mais cela \u00e9tait rest\u00e9 sans suite. <\/span>Contact\u00e9 par Novastan, Renault n\u2019a pas souhait\u00e9 communiquer sur le sujet \u201c<i>pour le moment<\/i>\u201d.\n\n<span style=\"font-weight: 400;\">Plus largement, les pr\u00e9cautions prises par le groupe fran\u00e7ais sont influenc\u00e9es par l&rsquo;\u00e9chec de PSA qui, en mai 2017 <\/span><span style=\"font-weight: 400;\">avait sign\u00e9 <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/psa-simplante-en-ouzbekistan\/\">un accord<\/a> avec l\u2019entreprise ouzb\u00e8ke<\/span><span style=\"font-weight: 400;\">&nbsp;Uzavtosanoat <\/span><span style=\"font-weight: 400;\">pour la production de v\u00e9hicules utilitaires<\/span><span style=\"font-weight: 400;\">, avant de se retirer en janvier 2020, <\/span><span style=\"font-weight: 400;\">remettant en question la \u201c<\/span><i><span style=\"font-weight: 400;\">pertinence \u00e9conomique<\/span><\/i><span style=\"font-weight: 400;\">\u201d du projet<\/span><span style=\"font-weight: 400;\">. <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/psa-quitte-louzbekistan-sans-avoir-produit-le-moindre-vehicule\/\">Aucun v\u00e9hicule<\/a> n\u2019avait alors \u00e9t\u00e9 produit.&nbsp;<\/span><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Un vent nouveau sur le march\u00e9 de l&rsquo;automobile<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nAujourd&rsquo;hui pourtant, le march\u00e9 de l&rsquo;automobile s&rsquo;ouvre en Ouzb\u00e9kistan. En juin 2020, le gouvernement ouzbek a supprim\u00e9 la taxe d&rsquo;importation sur les voitures, qui s&rsquo;\u00e9levait \u00e0 70 %, pr\u00e9cise <a href=\"https:\/\/www.gazeta.uz\/ru\/2020\/06\/03\/auto\/\">Gazeta.uz<\/a>. Au regard de ce geste, le gouvernement ouzbek semblerait vouloir susciter de nouvelles opportunit\u00e9s \u00e9conomiques dans le pays.\n\nDe plus, si jusqu&rsquo;\u00e0 pr\u00e9sent l&rsquo;entreprise Uzavtsanoat \u00e9tait en situation de monopole dans le pays, Roodell par son assise croissante semble <a href=\"https:\/\/www.gazeta.uz\/ru\/2020\/10\/05\/kia-roodell\/\">remettre en question<\/a> le leader de l&rsquo;automobile. Effectivement, d\u00e8s mars dernier, le cor\u00e9en KIA annon\u00e7ait <a href=\"https:\/\/www.kia.ru\/press\/news\/259\/\">son arriv\u00e9e<\/a> sur le march\u00e9 ouzbek par l&rsquo;interm\u00e9diaire de Roodell.\n<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Une pr\u00e9sence de plus en plus importante en Asie centrale<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">\nAvec Roodell, Renault tente de dupliquer un mod\u00e8le qui lui a r\u00e9ussi au Kazakhstan et au Kirghizstan. En effet, lors de son arriv\u00e9e sur le march\u00e9 kazakh en 2010, Renault s&rsquo;\u00e9tait li\u00e9 avec Orion distribution, qui g\u00e8re actuellement son r\u00e9seau de concessionnaires, note <a href=\"https:\/\/tengrinews.kz\/news\/renault-v-kazahstane-predstavit-5-novyih-modeley-444375\/\">le m\u00e9dia kazakh Tengrinews.<\/a> Le succ\u00e8s sur ce march\u00e9 resterait limit\u00e9, avec 3 % des parts de march\u00e9 et une septi\u00e8me place, ajoute Tengrinews.\n\nAu Kirghizstan, o\u00f9 le groupe <a href=\"https:\/\/renault.kg\/Aboutcompany\/RenaultinKyrgyzstan.html\">se pr\u00e9sente<\/a>&nbsp;comme \u00ab\u00a0<em>l&rsquo;un des leaders du march\u00e9 selon les r\u00e9sultats de 2019<\/em>\u00ab\u00a0, Renault avait choisi de s&rsquo;appuyer sur Asiamotors pour vendre \u00e0 la fois des Renault et des Lada, indique <a href=\"http:\/\/www.tazabek.kg\/news:1584860\">le m\u00e9dia kirghiz Tazabek<\/a>. L&rsquo;implantation date <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/renault-debarque-officiellement-au-kirghizstan\/\">de 2016.<\/a><strong>Lire aussi : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/renault-debarque-officiellement-au-kirghizstan\/\">Renault d\u00e9barque officiellement au Kirghizstan <\/a><\/strong>\n\n\u00ab\u00a0<em>L&rsquo;Asie centrale est une r\u00e9gion immense dont l&rsquo;\u00e9conomie est en pleine croissance, et Renault consid\u00e8re qu&rsquo;elle a un grand potentiel <\/em>\u00a0\u00bb <a href=\"https:\/\/www.lagazetteaz.fr\/news\/international\/7273.html\">rapporte Lagazetteaz.fr<\/a> citant un repr\u00e9sentant du groupe. Le groupe fran\u00e7ais Renault semble donc bien int\u00e9ress\u00e9 par l&rsquo;Asie centrale.\n<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Adeline Chaverot<\/strong>\n<strong>R\u00e9dactrice et tr\u00e9sori\u00e8re adjointe de Novastan<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Relu par Jacqueline Ripart<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renault tente une nouvelle implantation en Ouzb\u00e9kistan, par l\u2019interm\u00e9diaire du distributeur Roodell Motor Vehicle. Le constructeur fran\u00e7ais avait d\u00e9j\u00e0 annonc\u00e9 la vente de ses v\u00e9hicules dans le pays en 2019, sans que cela ne soit effectif.&nbsp; Les Ouzbeks devraient bient\u00f4t pouvoir rouler en Renault. Le 10 septembre dernier,&nbsp;Roodell, distributeur des v\u00e9hicules Renault en Russie et [&hellip;]<\/p>\n","protected":false},"author":1275,"featured_media":50778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3985,5],"tags":[],"coauthors":[4840,4513],"class_list":["post-50776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-ouzbekistan"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/50776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/1275"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=50776"}],"version-history":[{"count":1,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/50776\/revisions"}],"predecessor-version":[{"id":61943,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/50776\/revisions\/61943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/50778"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=50776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=50776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=50776"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=50776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}