{"id":33678,"date":"2020-06-24T17:09:29","date_gmt":"2020-06-24T15:09:29","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=33678"},"modified":"2021-04-08T16:51:01","modified_gmt":"2021-04-08T14:51:01","slug":"incident-de-beryozovka-cinq-ans-apres-un-village-deserte-des-enfants-intoxiques-le-silence-des-autorites","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kazakhstan\/incident-de-beryozovka-cinq-ans-apres-un-village-deserte-des-enfants-intoxiques-le-silence-des-autorites\/","title":{"rendered":"Incident de Beryozovka : cinq ans apr\u00e8s, un village d\u00e9sert\u00e9, des enfants intoxiqu\u00e9s, le silence des autorit\u00e9s"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Le 28 novembre 2014, dans le village de Beryozovka, dans l\u2019ouest du Kazakhstan, 25 enfants et 4 instituteurs perdent conscience pendant les cours et sont hospitalis\u00e9s. L\u2019entreprise p\u00e9troli\u00e8re Karachaganak Petroleum Operating B.V (KPO), qui poss\u00e8de un site \u00e0 la bordure du village, est point\u00e9e du doigt par les parents et les \u00e9cologistes. L\u2019implication du consortium dans l\u2019intoxication massive n\u2019a pas \u00e9t\u00e9 prouv\u00e9e. R\u00e9sultat\u00a0: affaire class\u00e9e sans suite. Cinq ans apr\u00e8s, la photographe Nata Li propose une exposition de photos qui met l\u2019accent sur ce drame et pose \u00e0 nouveau la question de la responsabilit\u00e9 de KPO. <\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Novastan reprend et traduit ici un article initialement publi\u00e9 le 15 janvier 2020 par le m\u00e9dia kazakh <\/strong><a href=\"https:\/\/www.the-village.kz\/village\/city\/situation\/8767-neft-ili-deti-vinovat-li-neftegazovyy-gigant-v-massovom-otravlenii-detey-v-berezovke?fbclid=IwAR1JaDw02Qa0c9BOfiTSgrx9a8nqqjvdLQRHzHYQpd-Eo5S8hKjeZ2Jr_KM\"><strong>The Village<\/strong><\/a><strong>. <\/strong><\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/mapcarta.com\/fr\/15396566\">Beryozovka<\/a> est un village de 1\u00a0357 personnes au Kazakhstan occidental, \u00e0 la fronti\u00e8re de la zone de s\u00e9curit\u00e9 qui s\u00e9pare les villages de la soci\u00e9t\u00e9 gazop\u00e9troli\u00e8re Karachaganak Petroleum Operating B.V (KPO). Non loin, l\u2019entreprise exploite une grande quantit\u00e9 de sulfure d\u2019hydrog\u00e8ne en tant que mati\u00e8re premi\u00e8re.<\/p>\n<p style=\"text-align: justify\">Cinq soci\u00e9t\u00e9s font partie de la Karachaganak Petroleum Operating\u00a0: la kazakhe KazMunaiGaz, l\u2019italienne Eni, la germano-britannique Shell, l\u2019am\u00e9ricaine Chevron Corporation et la russe Lukoil. La soci\u00e9t\u00e9 kazakhe poss\u00e8de 10 % des actions.<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p style=\"text-align: justify\">La proximit\u00e9 du village de KPO a inqui\u00e9t\u00e9 durant de longues ann\u00e9es les habitants du village et les \u00e9cologistes. En novembre 2014, c\u2019est le drame\u00a0: les \u00e9l\u00e8ves de l\u2019\u00e9cole du village et leurs instituteurs sont pris de malaises. Ils sont hospitalis\u00e9s. Une enqu\u00eate est ouverte par la police, puis arr\u00eat\u00e9e, \u00e0 plusieurs reprises. La responsabilit\u00e9 de KPO n\u2019est pas prouv\u00e9e. L\u2019entreprise accepte cependant de d\u00e9dommager financi\u00e8rement les familles. Les habitants du village sont finalement transf\u00e9r\u00e9s, mais les probl\u00e8mes de sant\u00e9 des enfants persistent.<\/p>\n<p style=\"text-align: justify\">En 2019, une exposition de la photographe kazakhe Nata Li, <em>Post face<\/em>, \u00ab\u00a0relance\u00a0\u00bb l\u2019affaire en retra\u00e7ant l\u2019histoire d\u2019une jeune fille du village qui souffre toujours des suites de cette intoxication. La photographe pose le probl\u00e8me de la responsabilit\u00e9 de KPO et du co\u00fbt du r\u00eave p\u00e9trolier au Kazakhstan.<\/p>\n<p style=\"text-align: justify\"><strong>Des inqui\u00e9tudes depuis 2002<\/strong><\/p>\n<p style=\"text-align: justify\">D\u2019apr\u00e8s <a href=\"http:\/\/www.greensalvation.org\/index.php?page=berezovka\">l\u2019association \u00e9cologique \u00ab\u00a0Salut vert\u00a0\u00bb<\/a>, une partie du village s\u2019est retrouv\u00e9e \u00e0 cinq kilom\u00e8tres de la zone de s\u00e9curit\u00e9 en 2002, ce qui est contraire \u00e0 la l\u00e9gislation du Kazakhstan. Les habitants devaient \u00eatre transf\u00e9r\u00e9s, mais au lieu d\u2019ex\u00e9cuter cette mesure, la zone fronti\u00e8re a \u00e9t\u00e9 r\u00e9duite \u00e0 trois kilom\u00e8tres des installations p\u00e9troli\u00e8res en 2003.<\/p>\n<p style=\"text-align: justify\">La m\u00eame ann\u00e9e, l\u2019organisation \u00e9cologique internationale Crude Accountability <a href=\"http:\/\/crudeaccountability.org\/wp-content\/uploads\/2012\/06\/health_survey_results_2003.pdf\">a publi\u00e9<\/a> les r\u00e9sultats d\u2019une enqu\u00eate men\u00e9e aupr\u00e8s des habitants de Beryozovka par les activistes locaux, suivant la m\u00e9thodologie de Crude Accountability et Environmental Health Network. 886 adultes et 180 enfants et adolescents ont particip\u00e9 \u00e0 cette enqu\u00eate. Les r\u00e9sultats ont d\u00e9montr\u00e9 que 45 % des habitants du village souffraient de maladies chroniques. Les adultes se plaignaient de perte de m\u00e9moire, de chute des dents et des cheveux, de douleurs musculaires et osseuses, de probl\u00e8mes de c\u0153ur, de vue, du syst\u00e8me digestif et de peau. Les \u00e9coliers ont cit\u00e9 parmi les sympt\u00f4mes des pertes de connaissance.<\/p>\n<p style=\"text-align: justify\">Selon les \u00e9cologistes, les probl\u00e8mes de sant\u00e9 de la population de Beryozovka \u00e9taient d\u00e9j\u00e0 alors li\u00e9s aux effets des toxines, du sulfure d\u2019hydrog\u00e8ne et d\u2019autres produits d\u00e9riv\u00e9s de l\u2019extraction du p\u00e9trole. En 2007 et 2008, les habitants locaux ont d\u00e9pos\u00e9 deux plaintes et demand\u00e9 un transfert de la population du village \u00e0 cause des rejets nocifs dans l\u2019atmosph\u00e8re, mais l\u2019affaire est rest\u00e9e au stade de l\u2019\u00e9tude.<\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi dans Novastan\u00a0: <\/strong><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kazakhstan-les-autorites-locales-veulent-du-petrole-les-villageois-de-leau\/\"><strong>Kazakhstan : les autorit\u00e9s locales veulent du p\u00e9trole, les villageois de l&rsquo;eau<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">En 2009, les organisations \u00ab\u00a0Salut vert\u00a0\u00bb, \u00ab\u00a0Bureau pour les droits de l\u2019Homme\u00a0\u00bb et \u00ab\u00a0Chanyrak\u00a0\u00bb <a href=\"http:\/\/www.greensalvation.org\/uploads\/Berezovka\/20091223-374-VS_berezovka.pdf\">ont port\u00e9 plainte<\/a> contre le gouvernement du Kazakhstan et le minist\u00e8re de la Protection de l\u2019environnement. En 2010, comme l\u2019a rapport\u00e9 <a href=\"https:\/\/365info.kz\/2014\/12\/eshhe-shestero-shkolnikov-iz-berezovki-popali-v-bolnicu-s-priznakami-otravleniya-neizvestnym-gazom\">le m\u00e9dia kazakh 365info.kz<\/a>, la zone de s\u00e9curit\u00e9 a \u00e9t\u00e9 restitu\u00e9e \u00e0 cinq kilom\u00e8tres, mais les habitants sont rest\u00e9s sur place.<\/p>\n<p style=\"text-align: justify\"><strong>Une intoxication massive<\/strong><\/p>\n<p style=\"text-align: justify\">Le 28 novembre 2014, pendant les cours dans la seule \u00e9cole du village, 25 \u00e9l\u00e8ves et quatre instituteurs se sont \u00e9vanouis et ont \u00e9t\u00e9 pris de convulsions, <a href=\"https:\/\/rus.azattyq.org\/a\/kazakhstan-otravlenie-berezovka\/28267456.html\">a d\u00e9crit Radio Azattyk<\/a>, la branche kazakhe du m\u00e9dia am\u00e9ricain Radio Free Europe. \u00a0Des malaises du m\u00eame ordre avaient eu lieu auparavant, comme <a href=\"https:\/\/crudeaccountability.org\/two-years-tragedy-berezovka\/\">l\u2019a fait remarquer \u00ab\u00a0Salut vert\u00a0\u00bb<\/a>, mais cet incident \u00e9tait le premier cas massif.<\/p>\n<p style=\"text-align: justify\">Dans la foul\u00e9e, l\u2019entreprise a publi\u00e9 <a href=\"https:\/\/www.kpo.kz\/ru\/novosti\/novosti-kompanii\/novosti-kompanii\/article\/soobshchenie-kpo-kasatelno-incidenta-v-srednei-shkole-po.html\">un communiqu\u00e9 officiel<\/a> en affirmant que le contr\u00f4le n\u2019avait pas d\u00e9voil\u00e9 de d\u00e9passement de la concentration maximale autoris\u00e9e des \u00e9l\u00e9ments nocifs. <em>\u00ab\u00a0Alors que la raison de cet incident n\u2019a pas \u00e9t\u00e9 confirm\u00e9e, la compagnie KPO participe activement \u00e0 l\u2019enqu\u00eate, en collaborant \u00e9troitement avec des structures \u00e9tatiques du Kazakhstan et la direction de la r\u00e9gion du Kazakhstan occidental\u00a0\u00bb<\/em>, affirmait alors le consortium<em>.<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi dans Novastan\u00a0: <\/strong><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kazakhstan-il-y-a-35-ans-un-tchernobyl-petrolier-a-tengiz\/\"><strong>Kazakhstan : il y a 35 ans, un Tchernobyl p\u00e9trolier \u00e0 Tengiz<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">En d\u00e9cembre 2014, le KPO a publi\u00e9 <a href=\"https:\/\/www.kpo.kz\/ru\/novosti\/novosti-kompanii\/novosti-kompanii\/archive\/2014\/december\/article\/pojasnenija-kompanii-karachaganak-petrolium-opereiting.html\">une autre annonce<\/a> affirmant qu\u2019ils consid\u00e9raient comme fausses les suppositions sur les rejets ou la fuite du gaz contenant l\u2019hydrog\u00e8ne sulfur\u00e9. Il s\u2019est av\u00e9r\u00e9 ult\u00e9rieurement que juste avant l\u2019intoxication massive, il y a eu un rejet de sulfure d\u2019hydrog\u00e8ne.<\/p>\n<p style=\"text-align: justify\"><strong>Les \u00ab\u00a0enfants de l\u2019\u00e9cole tombaient\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: justify\">Un t\u00e9moin de l\u2019\u00e9v\u00e9nement, Lidiya Samara, se souvient. <em>\u00ab\u00a0Lorsqu\u2019on passait pr\u00e8s de l\u2019\u00e9cole, on voyait les gens sortir les enfants de l\u2019\u00e9cole\u00a0: ils tombaient, certains avaient l\u2019\u00e9cume \u00e0 la bouche et tremblaient\u00a0\u00bb, <\/em>d\u00e9crit-elle<em>. <\/em><\/p>\n<p style=\"text-align: justify\">Juste apr\u00e8s ces malaises, une enqu\u00eate a \u00e9t\u00e9 ouverte sur la base de l\u2019article de loi \u00ab\u00a0Infraction des r\u00e8gles de rejet des mati\u00e8res polluantes dans l\u2019atmosph\u00e8re ayant entra\u00een\u00e9 des pr\u00e9judices de sant\u00e9 de deux personnes ou plus\u00a0\u00bb. L\u2019affaire a abouti \u00e0 un non-lieu. Selon la version officielle, <a href=\"https:\/\/rus.azattyq.org\/a\/kazakhstan-otravlenie-berezovka\/28267456.html\">d\u00e9crite par Radio Azattyk<\/a>, l\u2019intoxication massive est due aux \u00e9missions de la chaudi\u00e8re \u00e0 gaz dans le r\u00e9fectoire de l\u2019\u00e9cole.<\/p>\n<p style=\"text-align: justify\">En 2015, la direction du KPO a tout de m\u00eame re\u00e7u une amende de 9,5 milliards de tengu\u00e9s (46,5 millions d\u2019euros), <a href=\"https:\/\/rus.azattyq.org\/a\/kazakhstan-berezovka-children-poisoned-by-toxic-emissions\/30295740.html\">rapporte Radio Azattyk<\/a>. Plus tard, les repr\u00e9sentants du parquet r\u00e9gional ont confirm\u00e9 qu\u2019en 2014, le KPO a rejet\u00e9 des \u00e9missions de sulfure d\u2019hydrog\u00e8ne exc\u00e9dant les normes \u00e0 quatre reprises.<\/p>\n<p style=\"text-align: justify\"><strong>Des probl\u00e8mes de sant\u00e9 persistants<\/strong><\/p>\n<p style=\"text-align: justify\">Apr\u00e8s l\u2019hospitalisation, les enfants se sont sentis mieux pendant un court moment, puis les sympt\u00f4mes ont repris\u00a0: \u00e9vanouissements, convulsons, migraines. Les m\u00e9decins kazakhs ont \u00e9tabli les diagnostics qui n\u2019\u00e9taient pas li\u00e9s \u00e0 l\u2019intoxication par sulfure d\u2019hydrog\u00e8ne, par exemple la dystonie neurov\u00e9g\u00e9tative. Mais les parents continuaient \u00e0 \u00e9tablir le lien entre la d\u00e9gradation de l\u2019\u00e9tat physique de leurs enfants et les rejets du sulfure d\u2019hydrog\u00e8ne \u00e9manant du gisement de <a href=\"https:\/\/fr.m.wikipedia.org\/wiki\/Karachaganak\">Karachaganak<\/a>.<\/p>\n<p style=\"text-align: justify\">Les \u00e9cologistes et les habitants du village ont continu\u00e9 d\u2019accuser KPO. Comme solution, l\u2019entreprise a propos\u00e9 de d\u00e9m\u00e9nager les villageois dans un endroit \u00e9cologiquement propre, \u00e9tudier la situation et d\u00e9dommager les enfants qui avaient subi des effets n\u00e9fastes sur leur sant\u00e9.<\/p>\n<figure id=\"attachment_33680\" aria-describedby=\"caption-attachment-33680\" style=\"width: 1050px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33680\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/UMOQPbqrq6ln-6N_ffl9g.jpg\" alt=\"Beryozovka Kazakhstan Incident KPO\" width=\"1050\" height=\"700\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/UMOQPbqrq6ln-6N_ffl9g.jpg 1050w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/UMOQPbqrq6ln-6N_ffl9g-300x200.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/UMOQPbqrq6ln-6N_ffl9g-768x512.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/UMOQPbqrq6ln-6N_ffl9g-1024x683.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/UMOQPbqrq6ln-6N_ffl9g-128x86.jpg 128w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><figcaption id=\"caption-attachment-33680\" class=\"wp-caption-text\">L&rsquo;entreprise Karachaganak Petroleum Operating est point\u00e9e du doigt par les familles et les \u00e9cologistes.<\/figcaption><\/figure>\n<p style=\"text-align: justify\">En avril 2015, Crude Accountability a produit <a href=\"https:\/\/www.youtube.com\/watch?v=JSEuVWTfTgk\">un documentaire<\/a> sur les enfants de Beryozovka\u00a0intitul\u00e9 \u00ab\u00a0Karachaganak\u00a0: les enfants en \u00e9change du p\u00e9trole\u00a0\u00bb. Le film a \u00e9t\u00e9 prim\u00e9 second au Festival international des films documentaires de court-m\u00e9trage au Venezuela.<\/p>\n<p style=\"text-align: justify\">En d\u00e9cembre 2015, 82 familles ont \u00e9t\u00e9 relog\u00e9es \u00e0 <a href=\"https:\/\/fr.m.wikipedia.org\/wiki\/Aksay_(Kazakhstan)\">Aqsa\u00ef<\/a>, mais les enfants ont continu\u00e9 \u00e0 tomber malades. <em>\u00ab\u00a0De temps \u00e0 autre, elle perd connaissance, ses jambes se paralysent. Il y a une semaine, elle est tomb\u00e9e \u00e0 l\u2019\u00e9cole, elle a eu un malaise. Elle est rest\u00e9e au lit toute la journ\u00e9e et a mis 20-25 minutes pour retrouver ses esprits. Les c\u00e9phal\u00e9es sont constantes\u00a0\u00bb<\/em>, d\u00e9crit <a href=\"https:\/\/rus.azattyq.org\/a\/kazakhstan-otravlenie-berezovka\/28267456.html\">\u00e0 Radio Azattyk<\/a> une ancienne habitante du village \u00e0 propos de sa fille, Svetlana Voskobo\u00ef.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0J\u2019ai eu peur. Sur les r\u00e9seaux sociaux, des vid\u00e9os discr\u00e9ditent les parents et se moquent d\u2019eux, en disant qu\u2019ils extorquent de l\u2019argent en prenant les enfants pour pr\u00e9texte. Apr\u00e8s cet incident, je ne suis all\u00e9e nulle part pour demander de l\u2019aide \u00bb<\/em>, a-t-elle ajout\u00e9.<\/p>\n<p style=\"text-align: justify\"><strong>Les familles d\u00e9dommag\u00e9es et d\u00e9plac\u00e9es<\/strong><\/p>\n<p style=\"text-align: justify\">En 2016, le consortium a accept\u00e9 de payer 1\u00a0000 dollars (890 euros) \u00e0 chaque famille du village et 200 dollars (178 euros) \u00e0 chaque membre de la famille. De plus, KPO a d\u00fb verser une amende de plus de 526 millions de tengu\u00e9s (environ un million d\u2019euros) au titre de l\u2019indemnisation du dommage \u00e9cologique.<\/p>\n<p style=\"text-align: justify\">La m\u00eame ann\u00e9e, les repr\u00e9sentants de la coalition <em>\u00ab\u00a0Les enfants ou le p\u00e9trole\u00a0\u00bb<\/em> ont adress\u00e9 aux compagnies faisant partie du KPO une p\u00e9tition,\u00a0<a href=\"https:\/\/rus.azattyq.org\/a\/27843349.html\">a d\u00e9crit Radio Azattyk<\/a>. Elle a \u00e9t\u00e9 sign\u00e9e par 11 parents et 77 organisations des droits de l\u2019Homme kazakhes et internationales. Ils soulignaient que KPO avait la responsabilit\u00e9 de fournir aux parents des enfants malades les moyens financiers n\u00e9cessaires pour un examen m\u00e9dical s\u00e9rieux et ind\u00e9pendant, l\u2019obtention d&rsquo;un diagnostic et d&rsquo;un traitement et qu&rsquo;ils exigeaient en cons\u00e9quence un financement ad\u00e9quat.<\/p>\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n<p style=\"text-align: justify\">La r\u00e9ponse est arriv\u00e9e l\u2019ann\u00e9e suivante du minist\u00e8re de la Sant\u00e9, <a href=\"https:\/\/rus.azattyq.org\/a\/28393580.html\">a rapport\u00e9 Radio Azattyk<\/a>. Elle affirmait que des soins \u00e0 l\u2019\u00e9tranger et des consultations avec des sp\u00e9cialistes internationaux n\u2019\u00e9taient pas n\u00e9cessaires, alors que les activistes de la coalition avaient insist\u00e9 sur le fait qu\u2019il n\u2019y avait pas, au niveau local, de traitement adapt\u00e9 pour les enfants.<\/p>\n<p style=\"text-align: justify\">En 2017, 100 maisons ont \u00e9t\u00e9 construites dans le village d\u2019<a href=\"https:\/\/fr.m.wikipedia.org\/wiki\/Aralsk\">Aral<\/a> et deux immeubles de neuf \u00e9tages dans la ville <a href=\"https:\/\/fr.m.wikipedia.org\/wiki\/Aksay_(Kazakhstan)\">Aksa\u00ef<\/a> \u00a0par KPO, <a href=\"https:\/\/rus.azattyq.org\/a\/28743671.html\">d\u00e9crit Radio Azattyk<\/a>. En 2018, le relogement des habitants de Beryozovka s\u2019est termin\u00e9, a rapport\u00e9 <a href=\"https:\/\/inbusiness.kz\/ru\/last\/zavershilos-pereselenie-zhitelej-problemnoj-berezovki-v-zko\">le m\u00e9dia kazakh inbusiness.kz<\/a>. Le service de presse de l\u2019administration r\u00e9gionale a \u00e9t\u00e9 soulign\u00e9 que les habitants de Beryozovka et <a href=\"https:\/\/maps.app.goo.gl\/ZexixVDUXdnsiJEQ7\">Bestaou<\/a> avaient re\u00e7u un d\u00e9dommagement entre un et 15 millions de tengu\u00e9s (entre 2 800 et 42\u00a0000 euros).<\/p>\n<p style=\"text-align: justify\">La m\u00eame ann\u00e9e, une expertise ind\u00e9pendante a confirm\u00e9 que l\u2019intoxication \u00e9tait due aux \u00e9missions d\u2019hydrocarbures, a d\u00e9crit <a href=\"https:\/\/www.currenttime.tv\/a\/29189560.html\">le m\u00e9dia am\u00e9ricain CurrentTimes<\/a>. D\u2019apr\u00e8s Sergue\u00ef Solyanik, qui dirigeait l\u2019enqu\u00eate, les m\u00e9decins russes ont insist\u00e9 sur la n\u00e9cessit\u00e9 d\u2019une r\u00e9habilitation pluriannuelle pour les victimes. Un diagnostic d\u2019enc\u00e9phalopathie toxique a \u00e9t\u00e9 \u00e9tabli. Les demandes, avec la conclusion des experts moscovites, ont \u00e9t\u00e9 envoy\u00e9es au Parquet g\u00e9n\u00e9ral du Kazakhstan et \u00e0 l\u2019ONU.<\/p>\n<p style=\"text-align: justify\"><strong>Une exposition relance l\u2019affaire<\/strong><\/p>\n<p style=\"text-align: justify\">Au point de d\u00e9part du renouveau de l\u2019int\u00e9r\u00eat m\u00e9diatique autour de l\u2019affaire, on trouve l\u2019exposition \u00ab\u00a0<em>Post<\/em>&#8211;<em>face<\/em>\u00a0\u00bb, organis\u00e9e par la photographe kazakhe Nata Li. Selon elle, cette exposition tente de traiter d&rsquo;un probl\u00e8me grave avec la langue vivante de la photo, sans relater des faits secs et des informations relevant d\u2019un journal t\u00e9l\u00e9vis\u00e9.<\/p>\n<p style=\"text-align: justify\">La protagoniste de l\u2019exposition s\u2019appelle Albina. Au moment de l\u2019intoxication de masse dans le village, elle avait 14 ans, les m\u00e9decins moscovites lui ont diagnostiqu\u00e9 \u00ab\u00a0une intoxication du cerveau\u00a0\u00bb. Son histoire est un portrait vif non seulement de sa vie, mais aussi d\u2019autres enfants qui ont souffert. Aujourd\u2019hui elle a 19 ans, habite \u00e0 <a href=\"https:\/\/fr.m.wikipedia.org\/wiki\/Oural_(Kazakhstan)\">Oural<\/a> et \u00e9crit des po\u00e8mes sur Beryozovka.<\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi dans Novastan\u00a0: <\/strong><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/lasie-centrale-sinquiete-des-consequences-economiques-de-la-chute-des-cours-du-petrole\/\"><strong>L&rsquo;Asie centrale s&rsquo;inqui\u00e8te des cons\u00e9quences \u00e9conomiques de la chute des cours du p\u00e9trole<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">L\u2019exposition r\u00e9unit les essais audio et photos consacr\u00e9s \u00e0 ce sujet. Elle a \u00e9t\u00e9 organis\u00e9e \u00e0 New York, Varsovie et en 2020 \u00e0 Almaty. Pour toutes les questions li\u00e9es au drame, c\u2019est l\u2019\u00e9quipe de Crude Accountability qui a consult\u00e9 les habitants. N-Map (New Media Advocacy Project) a aid\u00e9 \u00e0 organiser l\u2019exposition dans le coll\u00e8ge La Guardia \u00e0 New York. Living Asia a aid\u00e9 son organisation \u00e0 Almaty.<\/p>\n<p style=\"text-align: justify\">Les tournages ont eu lieu \u00e0 Oural et dans le village de Beryozovka en mai 2019.\u00a0\u00c0 Oural, la photographe a longuement interview\u00e9 Albina. Elle pr\u00e9cise que c\u2019\u00e9tait une t\u00e2che difficile de r\u00e9v\u00e9ler l\u2019h\u00e9ro\u00efne et de la montrer comme une personnalit\u00e9 forte et non comme une victime.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0La situation a \u00e9t\u00e9 compl\u00e8tement diff\u00e9rente lors du tournage \u00e0 Beryozovka. Rien qu\u2019\u00e0 l\u2019arriv\u00e9e \u00e0 Oural, j\u2019ai compris qu\u2019en dehors d\u2019Almaty les gens vivent autrement. Au d\u00e9but cela semble curieux, mais ensuite vient le sentiment de terreur, surtout quand j\u2019ai film\u00e9 une \u00e9cole d\u00e9truite, les affaires abandonn\u00e9es \u00e0 l\u2019emplacement des maisons. Je me suis dit que cela fait partie de mon pays et de moi-m\u00eame\u00a0\u00bb<\/em>, ajoute Nata Li.<\/p>\n<p style=\"text-align: justify\"><strong>\u00ab\u00a0De quel futur peut-on parler si de telles choses se passent dans le pays\u00a0?\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: justify\">La photographe explique les difficult\u00e9s qu\u2019elle a rencontr\u00e9es pendant le tournage\u00a0: apr\u00e8s avoir film\u00e9 pendant quinze minutes ce qui restait du village apr\u00e8s le relogement de ses habitants, l\u2019\u00e9quipe a \u00e9t\u00e9 arr\u00eat\u00e9e par la police. Les images de l\u2019\u00e9cole ont \u00e9t\u00e9 r\u00e9alis\u00e9es en toute h\u00e2te, quelques minutes avant l\u2019arrestation.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0D\u2019apr\u00e8s la police, je me trouvais dans une zone \u00e9cologique o\u00f9 le tournage est interdit, alors que selon la l\u00e9gislation cela n\u2019est pas le cas, les juristes me l\u2019ont expliqu\u00e9 plus tard. Au lieu du travail planifi\u00e9, j\u2019ai pass\u00e9 trois heures au commissariat de police de la ville <a href=\"https:\/\/fr.m.wikipedia.org\/wiki\/Aksay_(Kazakhstan)\">Aksa\u00ef<\/a><\/em><em>. On me posait des questions du type \u00ab\u00a0qui es-tu\u00a0? Et pourquoi es-tu ici\u00a0? \u00bb. Apr\u00e8s l\u2019interrogatoire, j\u2019ai \u00e9t\u00e9 rel\u00e2ch\u00e9e\u00a0\u00bb<\/em>, d\u00e9crit Nata Li.<\/p>\n<p style=\"text-align: justify\">Elle ajoute que le but de l\u2019exposition \u00e9tait de montrer le co\u00fbt r\u00e9el du r\u00eave p\u00e9trolier au Kazakhstan. <em>\u00ab De quel futur peut-on parler si de telles choses se passent dans le pays\u00a0? Cette ann\u00e9e est le cinqui\u00e8me anniversaire de la trag\u00e9die et les enfants continuent \u00e0 souffrir. Les enfants de Beryozovka sont un v\u00e9ritable barom\u00e8tre pour tout le Kazakhstan car cela concerne tout le monde\u00a0\u00bb<\/em>, affirme la photographe kazakhe.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Un probl\u00e8me principal de la soci\u00e9t\u00e9 transpara\u00eet\u00a0: le non-respect de la vie de l\u2019homme et l\u2019irresponsabilit\u00e9 des autorit\u00e9s qui ferment les yeux face \u00e0 de tels probl\u00e8mes. Rien de tel que le silence et l\u2019indiff\u00e9rence pour que les autorit\u00e9s se croient dans l\u2019impunit\u00e9\u00a0\u00bb<\/em>, conclut la photographe.<\/p>\n<p style=\"text-align: right\"><strong>Damina Moukitanova<br \/>\nJournaliste pour The Village <\/strong><\/p>\n<p style=\"text-align: right\"><strong>Photographies\u00a0par Nata Li<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Traduit <a href=\"https:\/\/www.the-village.kz\/village\/city\/situation\/8767-neft-ili-deti-vinovat-li-neftegazovyy-gigant-v-massovom-otravlenii-detey-v-berezovke?fbclid=IwAR1JaDw02Qa0c9BOfiTSgrx9a8nqqjvdLQRHzHYQpd-Eo5S8hKjeZ2Jr_KM\">du russe<\/a> par Talgat Abdrakhmanov<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u00c9dit\u00e9 par Christine Wystup<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Relu par Aline Cordier Simonneau<\/strong><\/p>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 28 novembre 2014, dans le village de Beryozovka, dans l\u2019ouest du Kazakhstan, 25 enfants et 4 instituteurs perdent conscience pendant les cours et sont hospitalis\u00e9s. L\u2019entreprise p\u00e9troli\u00e8re Karachaganak Petroleum Operating B.V (KPO), qui poss\u00e8de un site \u00e0 la bordure du village, est point\u00e9e du doigt par les parents et les \u00e9cologistes. L\u2019implication du consortium [&hellip;]<\/p>\n","protected":false},"author":807,"featured_media":33679,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[3916,428,773,3321,3915,470,3914,799,1956],"coauthors":[3919,3556,3353],"class_list":["post-33678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kazakhstan","tag-beryozovka","tag-environnement","tag-hydrocarbures","tag-incident","tag-karachaganak-petroleum-operating","tag-kazakhstan","tag-kpo","tag-sante","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/33678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/807"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=33678"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/33678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/33679"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=33678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=33678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=33678"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=33678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}