{"id":32902,"date":"2020-06-02T08:05:49","date_gmt":"2020-06-02T06:05:49","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=32902"},"modified":"2020-06-03T08:12:45","modified_gmt":"2020-06-03T06:12:45","slug":"newsletter-la-mer-caspienne-a-son-plus-bas-niveau-depuis-30-ans","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/newsletter\/newsletter-la-mer-caspienne-a-son-plus-bas-niveau-depuis-30-ans\/","title":{"rendered":"[Newsletter] La mer Caspienne \u00e0 son plus bas niveau depuis 30 ans"},"content":{"rendered":"<p>Vous trouverez ci-dessous une reproduction de notre newsletter hebdomadaire du 1er juin 2020, envoy\u00e9e gratuitement tous les lundis. Si vous souhaitez la recevoir directement dans votre bo\u00eete mail,\u00a0<a href=\"http:\/\/eepurl.com\/O0Qub\" data-versionurl=\"https:\/\/novastan.org\/fr\/amber\/cache\/09330c9f239fb0be84150e4e7dedc0db\/\" data-versiondate=\"2019-02-11T19:03:52+00:00\" data-amber-behavior=\"\">inscrivez-vous ici<\/a>. En attendant, bonne lecture !<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p><em>Cette newsletter est d\u00e9di\u00e9e \u00e0 l\u2019Asie centrale.\u00a0Chaque semaine, nous vous r\u00e9sumons les diff\u00e9rentes actualit\u00e9s de la r\u00e9gion, tout en vous proposant les articles \u00e9crits par la r\u00e9daction. Une question, une remarque, une envie ? Envoyez-nous un\u00a0mail \u00e0 novastan.france@novastan.org<\/em><\/p>\n<h1 class=\"null\">Les 3 infos \u00e0 ne pas manquer<\/h1>\n<p class=\"null\"><strong>La mer Caspienne a perdu 13 centim\u00e8tres de hauteur entre 2018 et 2019.\u00a0<\/strong>Une baisse continue depuis plusieurs ann\u00e9es, qui fait craindre\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/la-mer-caspienne-a-atteint-son-niveau-le-plus-bas-depuis-30-ans\/\" target=\"_blank\" rel=\"noopener\">le m\u00eame sort que la tristement c\u00e9l\u00e8bre mer d\u2019Aral<\/a>, distante de quelques centaines de kilom\u00e8tres.<\/p>\n<p><strong>L\u2019h\u00f4tel \u00ab\u00a0Ouzb\u00e9kistan\u00a0\u00bb rachet\u00e9 par une myst\u00e9rieuse holding singapourienne.<\/strong>\u00a0Ce symbole de Tachkent, la capitale ouzb\u00e8ke, a \u00e9t\u00e9 rachet\u00e9 pour 20 millions d&rsquo;euros. L&rsquo;identit\u00e9 de l&rsquo;acheteur\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/lhotel-ouzbekistan-rachete-par-une-mysterieuse-holding-singapourienne\/\" target=\"_blank\" rel=\"noopener\">reste tr\u00e8s floue<\/a>\u00a0et pourrait cacher un homme d&rsquo;affaires centrasiatique.<\/p>\n<p><strong>Les heurts \u00e0 la fronti\u00e8re tadjiko-kirghize continuent.<\/strong>\u00a0Le 24 mai, un soldat tadjik\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">a \u00e9t\u00e9 bless\u00e9 \u00e0 la jambe<\/a>\u00a0apr\u00e8s des \u00e9changes de tirs avec les gardes-fronti\u00e8res kirghiz. Une situation qui a pouss\u00e9 la Russie\u00a0<a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/moscou-propose-de-jouer-les-mediateurs-dans-le-conflit-frontalier-opposant-le-tadjikistan-au-kirghizstan\/\" target=\"_blank\" rel=\"noopener\">\u00e0 se proposer comme m\u00e9diateur<\/a>. Moscou a essuy\u00e9 un refus c\u00f4t\u00e9 tadjik et un silence c\u00f4t\u00e9 kirghiz.<\/p>\n<h1 class=\"null\">Le d\u00e9cryptage de Novastan<\/h1>\n<p><strong>Uranium : la suspension du d\u00e9veloppement des nouveaux gisements au Kazakhstan, un risque pour la France ?<\/strong><\/p>\n<p>Alors que les mesures de confinement li\u00e9 \u00e0 l\u2019\u00e9pid\u00e9mie de Covid-19 au Kazakhstan ont amen\u00e9 la production d\u2019uranium dans le pays au plus bas, c\u2019est au tour de la prospection de nouveaux gisements d\u2019\u00eatre affect\u00e9e. Le premier producteur mondial, avec en t\u00eate de proue la co-entreprise Katco entre Kazatomprom et le fran\u00e7ais Orano, voit le d\u00e9veloppement de nouveaux gisements s\u2019arr\u00eater. Ce qui risque de poser des probl\u00e8mes pour l\u2019approvisionnement en uranium sur le moyen long terme \u00e0 cause des retards pris qui s\u2019accumulent pour le premier fournisseur d\u2019uranium \u00e0 la France.<\/p>\n<p><strong>Suite aux probl\u00e8mes li\u00e9s \u00e0 la destruction d\u2019une for\u00eat prot\u00e9g\u00e9e que Novastan avait r\u00e9v\u00e9l\u00e9 en ao\u00fbt dernier, la pand\u00e9mie pourrait bien mettre sous pression une des entreprises les plus impliqu\u00e9e dans les relations entre la France et le Kazakhstan. Novastan\u00a0<a href=\"https:\/\/novastan.org\/fr\/decryptage\/uranium-la-suspension-du-developpement-des-nouveaux-gisements-au-kazakhstan-un-risque-pour-la-france\/\" target=\"_blank\" rel=\"noopener\">tente de d\u00e9crypter<\/a>\u00a0l\u2019importance de Katco pour cette relation et sa situation au jour de la pand\u00e9mie et de la crise \u00e9conomique.<\/strong><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><em>Ces deux paragraphes ne sont que le d\u00e9but de notre d\u00e9cryptage hebdomadaire r\u00e9serv\u00e9 \u00e0 nos soutiens, envoy\u00e9 tous les mardis matins directement dans leur bo\u00eete mail. Pour le recevoir dans votre bo\u00eete, vous pouvez nous soutenir\u00a0<a href=\"https:\/\/www.okpal.com\/soutenez-novastan-seul-media-francais-sur-l-asie\/#\/\" data-amber-behavior=\"down hover:2\" data-versiondate=\"2020-01-22T17:09:21+00:00\" data-versionurl=\"https:\/\/novastan.org\/fr\/amber\/cache\/cbdd60866d44a75348adc83d1a3cd2c0\/\">\u00e0 partir de 2 euros par mois<\/a>. Pour en savoir plus sur notre philosophie, nous vous avons\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/devenez-membre-devenez-novastan\/\">tout expliqu\u00e9 par ici.<\/a>\u00a0Une question, une demande ? Notre email :\u00a0<a href=\"mailto:novastan.france@novastan.org\" target=\"_blank\" rel=\"noopener\">novastan.france@novastan.org<\/a><\/em><\/p>\n<p><strong>Nos d\u00e9cryptages des semaines pr\u00e9c\u00e9dentes :\u00a0<\/strong><\/p>\n<p><strong><a href=\"http:\" target=\"_blank\" rel=\"noopener\">Le Kazakhstan critique \u201cl\u2019\u00e9volution inappropri\u00e9e\u201d de l\u2019int\u00e9gration eurasiatique : le d\u00e9but de la fin de l\u2019UEE ?<\/a>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/novastan.org\/fr\/decryptage\/rechauffement-climatique-lasie-centrale-touchee-par-des-pluies-et-vents-violents\/\" target=\"_blank\" rel=\"noopener\">R\u00e9chauffement climatique : l\u2019Asie centrale touch\u00e9e par des pluies et vents violents<\/a><\/strong><\/p>\n<p class=\"entry-title mkd-post-title\"><a href=\"https:\/\/novastan.org\/fr\/decryptage\/la-catastrophe-de-sardoba-pourrait-elle-menacer-louverture-ouzbeke\/\"><strong>La catastrophe de Sardoba pourrait-elle menacer l\u2019ouverture ouzb\u00e8ke ?<\/strong><\/a><\/p>\n<p>[mkd_separator class_name=\u00a0\u00bb\u00a0\u00bb type=\u00a0\u00bbfull-width\u00a0\u00bb position=\u00a0\u00bbcenter\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb\u00a0\u00bb thickness=\u00a0\u00bb5&Prime; top_margin=\u00a0\u00bb\u00a0\u00bb bottom_margin=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h1 class=\"null\">Notre photo de la semaine<\/h1>\n<figure id=\"attachment_32596\" aria-describedby=\"caption-attachment-32596\" style=\"width: 6000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32596\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1.jpg\" alt=\"Afghanistan Tadjikistan Fronti\u00e8re Montagne\" width=\"6000\" height=\"4000\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1.jpg 6000w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1-300x200.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1-768x512.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1-1024x683.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1-1300x867.jpg 1300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/46058257525_7ac04fcaaf_6k-min-2-1-128x86.jpg 128w\" sizes=\"auto, (max-width: 6000px) 100vw, 6000px\" \/><figcaption id=\"caption-attachment-32596\" class=\"wp-caption-text\">Une vall\u00e9e dans la r\u00e9gion frontali\u00e8re entre le Tadjikistan et l\u2019Afghanistan en automne.<\/figcaption><\/figure>\n<p><em>Une vall\u00e9e dans la r\u00e9gion frontali\u00e8re entre le Tadjikistan et l\u2019Afghanistan en automne. <a href=\"https:\/\/novastan.org\/fr\/photo-du-jour\/une-vallee-en-automne\/\">Plus d&rsquo;infos par ici.<\/a><\/em><\/p>\n<p>[mkd_separator class_name=\u00a0\u00bb\u00a0\u00bb type=\u00a0\u00bbfull-width\u00a0\u00bb position=\u00a0\u00bbcenter\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb\u00a0\u00bb thickness=\u00a0\u00bb5&Prime; top_margin=\u00a0\u00bb\u00a0\u00bb bottom_margin=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h1 class=\"null\">Dans le reste de l&rsquo;actu<\/h1>\n<p class=\"null\"><strong>L\u2019Allemagne cesse son aide au d\u00e9veloppement dans trois pays centrasiatiques.<\/strong>\u00a0En Asie centrale, seul l\u2019Ouzb\u00e9kistan restera un partenaire\u00a0de l\u2019Allemagne. Dans la r\u00e9gion, cette \u00e9volution ne suscite toutefois\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">des discussions qu\u2019au Kirghizstan.<\/a><\/p>\n<p><strong>La gestion d\u2019Uzbekistan Airways pourrait \u00eatre transf\u00e9r\u00e9e \u00e0 une entreprise \u00e9trang\u00e8re.\u00a0<\/strong>Le pr\u00e9sident ouzbek a indiqu\u00e9 le 25 mai dernier que l&rsquo;entreprise publique pourrait \u00eatre g\u00e9r\u00e9e par\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/la-gestion-duzbekistan-airways-pourrait-etre-transferee-a-une-entreprise-etrangere\/\" target=\"_blank\" rel=\"noopener\">une\u00a0\u00ab\u00a0prestigieuse entreprise \u00e9trang\u00e8re\u00a0\u00bb<\/a>. Une privatisation reste cependant exclue.<\/p>\n<p><strong>La construction de la centrale hydro\u00e9lectrique de Rogun au Tadjikistan se poursuit, malgr\u00e9 le coronavirus.<\/strong>\u00a0Pand\u00e9mie ou non, ce qui deviendra le plus haut barrage du monde se doit de continuer \u00e0 \u00eatre construit, a jug\u00e9 le pr\u00e9sident tadjik. Pour autant, les probl\u00e8mes de financements\u00a0<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-la-construction-de-la-centrale-hydroelectrique-de-rogun-se-poursuit-malgre-le-coronavirus\/\" target=\"_blank\" rel=\"noopener\">n&rsquo;ont pas miraculeusement disparus.<\/a><\/p>\n<p><strong>Le Kazakhstan investit davantage dans les \u00e9nergies renouvelables.<\/strong>\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">19 nouveau projets<\/a>\u00a0ont \u00e9t\u00e9 approuv\u00e9s le 25 mai dernier. Le Kazakhstan veut\u00a0r\u00e9duire ses \u00e9missions de gaz \u00e0 effet de serre tout en diversifiant son approvisionnement \u00e9nerg\u00e9tique, aujourd\u2019hui largement domin\u00e9 par les \u00e9nergies fossiles.<\/p>\n<p><strong>Le Haut-Badakhchan \u00e0 nouveau victime de troubles.<\/strong>\u00a0Des manifestants se sont rassembl\u00e9s \u00e0 Rushan, dans la r\u00e9gion autonome tadjike, pour protester contre l\u2019arrestation de trois r\u00e9sidents locaux, dont l\u2019un est accus\u00e9 de trafic de drogue. Une illustration du combat encore actuel\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">entre le gouvernement et les \u00ab\u00a0Autorit\u00e9s\u00a0\u00bb.\u00a0<\/a><\/p>\n<p><strong>Les archives de l\u2019historienne de l\u2019art Galina Pougatchenkova sauv\u00e9es et mises en ligne.<\/strong>\u00a0Les archives de la c\u00e9l\u00e8bre arch\u00e9ologue et historienne de l\u2019art ouzb\u00e8ke, d\u00e9c\u00e9d\u00e9e en 2007, ont \u00e9t\u00e9 num\u00e9ris\u00e9es et mise en ligne dans une base de donn\u00e9es ouverte \u00e0 tous. Novastan\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">a rencontr\u00e9 la co-responsable de ce projet titanesque<\/a>, Svetlana Gorshenina.<\/p>\n<p><strong>L\u2019Iran veut renforcer sa coop\u00e9ration bilat\u00e9rale avec le Kazakhstan.\u00a0<\/strong>Le pr\u00e9sident iranien Hassan Rohani a fait savoir \u00e0 son homologue kazakh Kassym-Jomart Toka\u00efev la volont\u00e9 de l\u2019Iran d\u2019approfondir les relations bilat\u00e9rales entre les deux pays,<a href=\"http:\" target=\"_blank\" rel=\"noopener\">\u00a0notamment dans le domaine \u00e9conomique.\u00a0<\/a><\/p>\n<p><strong>La place de la langue russe dans l\u2019administration ouzb\u00e8ke\u00a0vivement\u00a0d\u00e9battue.<\/strong>\u00a0Apr\u00e8s la publication d&rsquo;un projet de loi en avril visant \u00e0 n&rsquo;utiliser que l&rsquo;ouzbek dans l&rsquo;administration, un communiqu\u00e9 du minist\u00e8re des Affaires \u00e9trang\u00e8res russe\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/ouzbekistan-la-place-de-la-langue-russe-dans-ladministration-vivement-debattue\/\" target=\"_blank\" rel=\"noopener\">a mis le feu aux poudres.<\/a><\/p>\n<p><strong>L\u2019Ouzb\u00e9kistan en marche pour d\u00e9velopper l\u2019agriculture biologique.\u00a0<\/strong>Tachkent pr\u00e9voit des mesures politiques \u00e0 mettre en place\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">au plus tard en janvier 2021<\/a>\u00a0et pourrait se voir attribuer une certification sanitaire d\u2019ici \u00e0 2025.<\/p>\n<p><strong>Vous n&rsquo;avez pas suivi l&rsquo;actualit\u00e9 de l&rsquo;Asie centrale en avril ?<\/strong>\u00a0En voici un r\u00e9sum\u00e9, r\u00e9alis\u00e9 par la journaliste ind\u00e9pendante allemande Othmara Glas,\u00a0<a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/droits-civils-et-liberte-dexpression-avril-en-asie-centrale\/\" target=\"_blank\" rel=\"noopener\">traduit en fran\u00e7ais pour Novastan.<\/a><\/p>\n<p><strong>Avec les tensions entre Etats-Unis et Chine, la politique multi-vectorielle de l&rsquo;Asie centrale est \u00ab\u00a0mise \u00e0 l&rsquo;\u00e9preuve\u00a0\u00bb.\u00a0<\/strong>C&rsquo;est l&rsquo;avis du politologue kazakh\u00a0Sanat Kouchkoumba\u00efev, qui dresse un portrait des perspectives de la r\u00e9gion, \u00e0 l\u2019heure o\u00f9 les tensions entre \u00c9tats-Unis et Chine\u00a0<a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/tensions-etats-unis-chine-la-diplomatie-multi-vectorielle-des-pays-dasie-centrale-est-mise-a-lepreuve\/\" target=\"_blank\" rel=\"noopener\">semblent dessiner un nouvel environnement.<\/a><\/p>\n<p><strong>Les victimes des inondations du barrage de Sardoba recevront de nouveaux logements.\u00a0<\/strong>Des milliers d\u2019habitants de la province de Syr-Daria, dans l\u2019est de l\u2019Ouzb\u00e9kistan, ont vu leurs habitations d\u00e9vast\u00e9es suite aux inondations provoqu\u00e9es par la destruction du barrage de Sardoba. Cependant, le choix des partenaires\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">s&rsquo;est pass\u00e9 d&rsquo;un appel d&rsquo;offres.<\/a><\/p>\n<h1 class=\"null\">&#8230;chez Novastan France<\/h1>\n<p><strong>Novastan lance son projet de refonte de son site Web.<\/strong>\u00a0Au programme : un site plus rapide, plus clair, plus s\u00e9curis\u00e9. Pour y parvenir, nous avons besoin de votre soutien ! Les d\u00e9tails du projet\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan\/un-plan-de-refonte-pour-le-site-web-de-novastan\/\" target=\"_blank\" rel=\"noopener\">se trouvent par ici.<\/a><\/p>\n<p><strong>Novastan officiellement reconnu comme m\u00e9dia en France.\u00a0<\/strong>Durant sa s\u00e9ance de mars 2020, la Commission paritaire des publications et agences de presse (CPPAP) a reconnu Novastan France comme\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/novastan-officiellement-reconnu-comme-media-en-ligne\/\" target=\"_blank\" rel=\"noopener\">un\u00a0<\/a><a href=\"https:\/\/novastan.org\/fr\/novastan-france\/novastan-officiellement-reconnu-comme-media-en-ligne\/\">service de presse en ligne<\/a>, au titre de l\u2019information politique et g\u00e9n\u00e9rale. Une nouvelle \u00e9tape pour notre projet !<\/p>\n<p><strong>Envie de nous aider ?\u00a0Novastan recherche des traducteurs, des r\u00e9dacteurs et des \u00e9diteurs.\u00a0<\/strong>Tous les moyens de contribuer \u00e0 notre projet c\u00f4t\u00e9 r\u00e9daction\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/contribuer-a-la-redaction-de-novastan\/\" target=\"_blank\" rel=\"noopener\">sont expliqu\u00e9s par ici.<\/a>\u00a0Si vous souhaitez nous aider sur le c\u00f4t\u00e9 associatif, nous essayons d&rsquo;organiser des \u00e9v\u00e8nements, festifs ou non. <a href=\"https:\/\/novastan.org\/fr\/novastan-france\/devenez-membre-devenez-novastan\/\">Les d\u00e9tails par ici<\/a>.<\/p>\n<p><strong>Novastan est le seul m\u00e9dia franco-allemand sur l\u2019Asie centrale.\u00a0<\/strong>Pour soutenir notre ind\u00e9pendance, devenez membre de la communaut\u00e9\u00a0Novastan !\u00a0Vous pouvez nous soutenir\u00a0<a href=\"https:\/\/www.okpal.com\/soutenez-novastan-seul-media-francais-sur-l-asie\/#\/\" target=\"_blank\" rel=\"noopener\">\u00e0 partir de 2 euros par mois<\/a>. Cela permet \u00e0\u00a0Novastan\u00a0de se professionnaliser tout en renfor\u00e7ant une communaut\u00e9 autour de l\u2019Asie centrale en France et en Europe.\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/devenez-membre-devenez-novastan\/\" target=\"_blank\" rel=\"noopener\">Tous les d\u00e9tails se trouvent ici<\/a>.<\/p>\n<p><strong>La r\u00e9daction<\/strong><\/p>\n<p>Merci de nous avoir lu jusqu&rsquo;au bout ! Rendez-vous d\u00e8s la semaine prochaine pour plus d&rsquo;informations sur l&rsquo;Asie centrale. Pour plus d&rsquo;infos au quotidien,\u00a0n&rsquo;h\u00e9sitez pas \u00e0 nous suivre sur\u00a0<a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=43466d9d21&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=9b56fd2518&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Twitter<\/a>, <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=1c21104214&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=dcc599a9fc&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Instagram<\/a> ou <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=c94d32b198&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Telegram<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ci-dessous une reproduction de notre newsletter hebdomadaire du 1er juin 2020, envoy\u00e9e gratuitement tous les lundis. Si vous souhaitez la recevoir directement dans votre bo\u00eete mail,\u00a0inscrivez-vous ici. En attendant, bonne lecture ! Cette newsletter est d\u00e9di\u00e9e \u00e0 l\u2019Asie centrale.\u00a0Chaque semaine, nous vous r\u00e9sumons les diff\u00e9rentes actualit\u00e9s de la r\u00e9gion, tout en vous proposant [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":32584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2469],"tags":[1379],"coauthors":[108],"class_list":["post-32902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","tag-newsletter"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/32902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=32902"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/32902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/32584"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=32902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=32902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=32902"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=32902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}