{"id":32758,"date":"2020-06-24T09:47:16","date_gmt":"2020-06-24T07:47:16","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=32758"},"modified":"2021-04-08T16:51:22","modified_gmt":"2021-04-08T14:51:22","slug":"on-nous-a-dit-que-nous-allions-en-russie-pour-construire-des-maisons-lhistoire-des-liquidateurs-tadjiks","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/tadjikistan\/on-nous-a-dit-que-nous-allions-en-russie-pour-construire-des-maisons-lhistoire-des-liquidateurs-tadjiks\/","title":{"rendered":"\u00ab On nous a dit que nous allions en Russie pour construire des maisons \u00bb, l\u2019histoire des liquidateurs tadjiks"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Pendant de nombreuses ann\u00e9es des centaines de milliers de personnes ont particip\u00e9 \u00e0 l&rsquo;\u00e9limination des cons\u00e9quences de l&rsquo;accident de la centrale nucl\u00e9aire de Tchernobyl, dont environ 6 000 Tadjiks. On les a surnomm\u00e9s \u00ab\u00a0les liquidateurs\u00a0\u00bb. Aujourd&rsquo;hui on compte plus de 1 800 liquidateurs au Tadjikistan, dont 1 450 sont handicap\u00e9s. Certains d\u2019entre eux se rem\u00e9morent le temps de leur travail sur la zone de l\u2019accident.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Nova<\/strong><strong>stan reprend et traduit ici un article publi\u00e9 le 24 avril 2020 par le m\u00e9dia russe sp\u00e9cialis\u00e9 sur l&rsquo;Asie centrale,\u00a0<\/strong><a href=\"https:\/\/fergana.ru\/articles\/117133\/\"><strong>Fergana News<\/strong><\/a>.<\/p>\n<p style=\"text-align: justify\">Le 26 avril dernier a eu lieu la Journ\u00e9e internationale de m\u00e9moire aux victimes d&rsquo;accidents et de catastrophes dus aux radiations nucl\u00e9aires. C&rsquo;est en ce jour de 1986 que s&rsquo;est produite la plus grande catastrophe industrielle du XX\u00e8me si\u00e8cle, \u00e0 la centrale de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Tchernobyl\">Tchernobyl<\/a>, en Ukraine. Apr\u00e8s l\u2019accident, les autorit\u00e9s envoyaient sur place principalement les hommes qui avaient servi dans l&rsquo;arm\u00e9e sovi\u00e9tique, dont de nombreux Tadjiks. On ne leur communiquait ni la destination ni les raisons de leur d\u00e9placement. De jeunes hommes en bonne sant\u00e9 partaient travailler dans la zone de radiation \u00e9lev\u00e9e, souvent en violation des normes de s\u00e9curit\u00e9. Ce n&rsquo;est que des mois, voire des ann\u00e9es apr\u00e8s leur retour qu&rsquo;ils ont connu la raison pour laquelle ils d\u00e9veloppaient diverses maladies graves. Les <em>\u00ab\u00a0liquidateurs\u00a0\u00bb<\/em> tadjiks ont donn\u00e9 naissance \u00e0 plus de 1 300 enfants atteints de pathologies ou de maladies chroniques.<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p style=\"text-align: justify\">Kibrio Gan\u00efeva, la pr\u00e9sidente de l\u2019ONG Union des victimes de Tchernobyl \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Khodjent\">Khodjent<\/a>, se souvient tr\u00e8s bien de la soir\u00e9e du 7 avril 1989. Il faisait d\u00e9j\u00e0 nuit quand des gens en uniforme militaire ont toqu\u00e9 \u00e0 sa porte. Les officiers se sont pr\u00e9sent\u00e9s\u00a0comme des employ\u00e9s du commissariat militaire de Leninabad, l&rsquo;ancien nom de Khodjent. Ils ont dit \u00e0 son mari, Nozir Gan\u00efev, \u00e2g\u00e9 alors de 35 ans : <em>\u00ab\u00a0Demain vous devez vous pr\u00e9senter au commissariat. \u00c9quipez-vous de l\u2019essentiel, vous serez envoy\u00e9 \u00e0 une formation militaire. \u00bb<\/em><\/p>\n<p style=\"text-align: justify\">Kibrio Gan\u00efeva se rem\u00e9more\u00a0: <em>\u00ab\u00a0Nozir \u00e9tait un chef de cuisine r\u00e9put\u00e9. Il travaillait \u00e0 \u00ab\u00a0Panchshanbe\u00a0\u00bb, un restaurant prestigieux connu non seulement \u00e0 Khodjent, mais dans toute la R\u00e9publique. Des gens venaient de tous les coins du Tadjikistan sp\u00e9cialement pour go\u00fbter les plats pr\u00e9par\u00e9s par mon mari. Il \u00e9tait souvent invit\u00e9 \u00e0 de grands \u00e9v\u00e8nements avec des centaines de personnes. Sa sp\u00e9cialit\u00e9 \u00e9tait le pilaf.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0\u00ab\u00a0Il ne tenait pas debout \u00e0 cause des douleurs\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Il est parti le 8 avril. Il nous a dit qu&rsquo;il \u00e9tait envoy\u00e9 en Ukraine, mais pourquoi\u00a0? Ni lui ni nous ne le savions. Il s&rsquo;est av\u00e9r\u00e9 ensuite qu&rsquo;il avait \u00e9t\u00e9 envoy\u00e9 \u00e0 Tchernobyl pour \u00e9liminer les cons\u00e9quences de l&rsquo;accident survenu dans la centrale nucl\u00e9aire. Il est revenu le 2 octobre, six mois plus tard \u00bb,<\/em> raconte Kibrio Gan\u00efeva. Elle explique qu\u2019avant Tchernobyl, Nozir Gan\u00efev \u00e9tait en parfaite sant\u00e9. \u00c0 son retour il a repris le travail, il faisait ce qu&rsquo;il aimait faire le plus. Mais son exposition aux radiations s&rsquo;est vite fait sentir. <em>\u00ab\u00a0Nozir a commenc\u00e9 \u00e0 avoir des douleurs tr\u00e8s fortes<strong>. <\/strong>Il ne tenait plus debout \u00e0 cause des douleurs. \u00bb<\/em><\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Les m\u00e9decins ont diagnostiqu\u00e9 chez Nozir\u00a0la leuc\u00e9mie, le cancer du sang. Il a \u00e9t\u00e9 clou\u00e9 au lit pendant une longue p\u00e9riode. Il a courageusement endur\u00e9 la douleur et ne s&rsquo;est jamais plaint \u00e0 personne. J\u2019\u00e9tais la seule \u00e0 savoir quelle souffrance il \u00e9prouvait\u00a0\u00bb,<\/em> raconte Kibrio Gan\u00efeva.<em>\u00a0\u00ab\u00a0Nozir est d\u00e9c\u00e9d\u00e9 sept ans apr\u00e8s son retour de Tchernobyl. Les amis de mon mari m&rsquo;ont demand\u00e9 de m\u2019occuper de l&rsquo;Union de victimes de Tchernobyl \u00e0 Khodjent. J\u2019ai accept\u00e9 parce que je voulais consoler les victimes de Tchernobyl, les aider \u00e0 obtenir une assistance juridique et des aides financi\u00e8res. Actuellement nous pr\u00e9parons une proposition au gouvernement sur l&rsquo;exemption totale ou au moins partielle des charges d&rsquo;\u00e9lectricit\u00e9 pour ceux qui ont \u00e9t\u00e9 envoy\u00e9s \u00e0 Tchernobyl. \u00bb<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/istiklol-entre-fabrication-de-chaussures-et-de-missiles-atomiques\/\"><strong>Istiklol, entre fabrication de chaussures et de missiles atomiques<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">Les cons\u00e9quences de Tchernobyl ont affect\u00e9 la plus jeune des filles des Gan\u00efev. Contrairement \u00e0 ses s\u0153urs, elle est n\u00e9e apr\u00e8s que Nozir est rentr\u00e9 de la zone contamin\u00e9e. Kibrio Gan\u00efeva raconte : \u00ab\u00a0<em>Notre fille de 24 ans est an\u00e9mique. Comme elle, de nombreux enfants de liquidateurs souffrent de maladies chroniques et ont r\u00e9guli\u00e8rement besoin d&rsquo;un traitement. Les effets de la radiation peuvent affecter la sant\u00e9 de plusieurs g\u00e9n\u00e9rations. \u00bb<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Une journ\u00e9e de travail de 20 minutes<\/strong><\/p>\n<p style=\"text-align: justify\">Khomijon Obidjonov est un habitant de Khodjent. Apr\u00e8s son service \u00e0 l&rsquo;arm\u00e9e il travaillait \u00e0 l&rsquo;usine d\u2019ing\u00e9nierie de b\u00e2timents r\u00e9sidentiels. Le 16 mai 1989 il est rentr\u00e9 tard. Il faisait d\u00e9j\u00e0 noir quand il s&rsquo;approcha de sa maison. Des employ\u00e9s du commissariat militaire attendaient Khomijon Obidjonov \u00e0 sa porte. Ils lui ont demand\u00e9 de se pr\u00e9senter le lendemain au commissariat avec des v\u00eatements de rechange. La conversation a \u00e9t\u00e9 br\u00e8ve. Les officiers ont dit qu\u2019il allait \u00eatre envoy\u00e9 en Russie pour construire de nouveaux b\u00e2timents r\u00e9sidentiels.<\/p>\n<p style=\"text-align: justify\">Le lendemain matin, Khomijon Obidjonov a vu une foule de jeunes hommes au commissariat. Il y en avait beaucoup comme lui. Ils ont \u00e9t\u00e9 plac\u00e9s dans des wagons. Tout le monde pensait qu&rsquo;ils allaient en Russie. On leur a cach\u00e9 la v\u00e9rit\u00e9 jusqu&rsquo;au dernier moment.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Les officiers nous ont menti. Ils nous ont amen\u00e9s \u00e0 Tchernobyl, pas en Russie. On nous a plac\u00e9s dans l&rsquo;unit\u00e9 militaire, \u00e0 18 kilom\u00e8tres du lieu de l&rsquo;accident. On nous a distribu\u00e9 des combinaisons. Quand on allait au travail, on se changeait dans les vestiaires, on mettait des masques \u00e0 gaz. J&rsquo;ai travaill\u00e9 dans la 4\u00e8me unit\u00e9 de la centrale. Nous faisions ce qu\u2019on nous demandait de faire. Par exemple, on nous ordonnait de d\u00e9placer divers mat\u00e9riaux de construction. Notre journ\u00e9e de travail ne durait que 20 minutes. Apr\u00e8s on nous examinait avec un appareil sp\u00e9cial. Apr\u00e8s un traitement chimique nos v\u00eatements \u00e9taient jet\u00e9s dans une urne sp\u00e9ciale et enterr\u00e9s ensuite. Chaque jour on avait un nouvel uniforme. Les ouvriers avaient des placards personnels sur lesquels il y avait leurs nom, pr\u00e9nom et patronyme. Le 3 septembre 1989 j\u2019ai \u00e9t\u00e9 renvoy\u00e9 chez moi \u00bb<\/em>, se rem\u00e9more Khomijon Obidjonov.<\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/quand-le-rock-and-roll-sovietique-faisait-danser-douchanbe\/\">Quand le rock-and-roll sovi\u00e9tique faisait danser Douchanb\u00e9<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">Aujourd\u2019hui Khomijon Obidjonov a 66 ans. Il est handicap\u00e9 du troisi\u00e8me groupe. Il per\u00e7oit une retraite de 800 somonis (70 euros). Une grande partie de cet argent lui sert \u00e0 payer le traitement des maladies qu\u2019il a d\u00e9velopp\u00e9es suite \u00e0 l&rsquo;exposition aux radiations.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Avant d&rsquo;\u00eatre envoy\u00e9 \u00e0 Tchernobyl j&rsquo;avais d\u00e9j\u00e0 deux enfants et on voulait en avoir d\u2019autres. Mais apr\u00e8s mon retour ce n\u2019\u00e9tait plus possible. Rapidement mes cheveux ont blanchi, et j\u2019ai perdu toutes mes dents. Ma m\u00e9moire est devenue tr\u00e8s mauvaise, mes articulations ont commenc\u00e9 \u00e0 me faire mal. Je suis parti jeune, en bonne sant\u00e9 et je suis revenu invalide \u00bb<\/em>, explique Khomijon Obidjonov.<\/p>\n<p style=\"text-align: justify\"><strong>\u00ab\u00a0Nous avons \u00e9t\u00e9 forc\u00e9s de travailler au-del\u00e0 de la norme\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: justify\">Quand Agzam Khodj\u00efev a \u00e9t\u00e9 envoy\u00e9 \u00e0 Tchernobyl, les autorit\u00e9s lui ont menti comme \u00e0 tous les autres liquidateurs. Il vient du village <a href=\"https:\/\/en.wikipedia.org\/wiki\/Poshkent\">Pochkent<\/a>, dans la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Istaravshan_District\">r\u00e9gion d\u2019Istaravchan<\/a>. Apr\u00e8s avoir obtenu un dipl\u00f4me \u00e0 l\u2019Institut des m\u00e9tiers du b\u00e2timent de Zafarabadski\u00ef, il a travaill\u00e9 comme pl\u00e2trier et peintre dans la r\u00e9gion de Khodjent. Un soir tardif de septembre 1988 alors qu\u2019Agzam Khodj\u00efev se reposait apr\u00e8s le travail, il a re\u00e7u une convocation. Le lendemain il devait se pr\u00e9senter au commissariat militaire, bagage \u00e0 la main, soi-disant pour une formation militaire de dix jours.<\/p>\n<p style=\"text-align: justify\">Mais les hommes pr\u00e9sents au commissariat ont d&rsquo;abord \u00e9t\u00e9 envoy\u00e9s \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Volgograd\">Volgograd<\/a>, le lendemain \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kiev\">Kiev<\/a>, ensuite ils ont \u00e9t\u00e9 transf\u00e9r\u00e9s au village Zelenyi Mis, \u00e0 30 kilom\u00e8tres de Tchernobyl et plac\u00e9s dans une unit\u00e9 militaire.<\/p>\n<figure id=\"attachment_33425\" aria-describedby=\"caption-attachment-33425\" style=\"width: 1300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33425\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1522px-IAEA_02790037_5612537827-1300x922.jpg\" alt=\"Tadjikistan Tchernobyl D\u00e9contamination Catastrophe\" width=\"1300\" height=\"922\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1522px-IAEA_02790037_5612537827-1300x922.jpg 1300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1522px-IAEA_02790037_5612537827-1300x922-300x213.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1522px-IAEA_02790037_5612537827-1300x922-768x545.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1522px-IAEA_02790037_5612537827-1300x922-1024x726.jpg 1024w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/><figcaption id=\"caption-attachment-33425\" class=\"wp-caption-text\">Les liquidateurs de Tchernobyl re\u00e7oivent des rations alimentaires suppl\u00e9mentaires: du lait condens\u00e9 et du poisson en conserve. &#8211; Image d&rsquo;archive de la Soci\u00e9t\u00e9 ukrainienne pour l&rsquo;amiti\u00e9 et les relations culturelles avec les autres \u00c9tats (USFCRFC).<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Ce n&rsquo;est qu\u2019\u00e0 ce moment-l\u00e0 que j&rsquo;ai d\u00e9couvert que nous avions \u00e9t\u00e9 appel\u00e9s pour \u00ab\u00a0liquider\u00a0\u00bb les cons\u00e9quences de l&rsquo;accident de Tchernobyl. Cela a \u00e9t\u00e9 le d\u00e9but d\u2019un quotidien tr\u00e8s strict et r\u00e9glement\u00e9\u00a0\u00bb,<\/em> explique Agzam Khodj\u00efev. <em>\u00ab\u00a0Chaque matin apr\u00e8s le petit-d\u00e9jeuner on nous envoyait au travail. On prenait un bus, on passait trois postes de contr\u00f4le avant d\u2019arriver sur le lieu de l\u2019accident. Il y avait beaucoup de monde et tous \u00e9tait press\u00e9s, comme si on accomplissait une mission d\u2019une tr\u00e8s grande importance. Selon nos savoir-faire on \u00e9tait divis\u00e9s par groupes de dix. On se changeait dans un vestiaire sp\u00e9cial. Il y avait des v\u00eatements de travail de trois couleurs : rouge \u2013 pour travailler \u00e0 l&rsquo;int\u00e9rieur du bloc, jaune \u2013 \u00e0 c\u00f4t\u00e9 du bloc et bleu \u2013 loin du bloc. Le travail le plus dangereux \u00e9tait \u00e0 l&rsquo;int\u00e9rieur du bloc. Notre t\u00e2che consistait \u00e0 collecter des fragments de m\u00e9tal et des d\u00e9bris de construction rest\u00e9s \u00e0 l&rsquo;int\u00e9rieur et \u00e0 les jeter dans une bo\u00eete sp\u00e9ciale. La bo\u00eete \u00e9tait ensuite transmise \u00e0 un autre groupe.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-la-construction-de-la-centrale-hydroelectrique-de-rogun-se-poursuit-malgre-le-coronavirus\/\">Tadjikistan : la construction de la centrale hydro\u00e9lectrique de Rogun se poursuit malgr\u00e9 le coronavirus<\/a><\/strong><\/p>\n<p style=\"text-align: justify\"><em>\u00a0\u00ab\u00a0Parfois on travaillait dans des installations adjacentes. Par exemple on pompait l&rsquo;eau du sous-sol d&rsquo;une maison inond\u00e9e pr\u00e8s de la centrale nucl\u00e9aire. Nous n&rsquo;avions pas le choix\u00a0: on faisait ce qu\u2019on nous demandait de faire. Il se trouve qu\u2019alors il y avait un document secret relatif aux conditions de travail. Mais les officiers ne nous le montraient pas. Le document identifiait les normes autoris\u00e9es pour chaque t\u00e2che sp\u00e9cifique. Lorsque nous avons finalement r\u00e9ussi \u00e0 obtenir ce document, il s&rsquo;est av\u00e9r\u00e9 que nous avions travaill\u00e9 bien au-del\u00e0 de la norme d\u00e9finie. Si selon la r\u00e9glementation 15 minutes \u00e9taient allou\u00e9es pour effectuer une t\u00e2che, nous travaillions pendant 30 minutes, et au lieu de 30 minutes on travaillait 45. Malheureusement nous avons appris \u00e7a trop tard. \u00c7a n\u2019avait plus de sens de d\u00e9poser une plainte. Le reste du temps on se reposait dans l&rsquo;unit\u00e9 militaire.<\/em><\/p>\n<p style=\"text-align: justify\"><em>Chacun de nous a re\u00e7u un dosim\u00e8tre en forme de badge pour mesurer le niveau de radiation. Nous devions porter ce badge tout le temps : au travail, dans la rue ou dans une unit\u00e9 militaire. Une fois par semaine on nous retirait les badges pour les envoyer \u00e0 Kiev et on nous en distribuait de nouveaux. Personne ne nous expliquait rien. Et puis \u00e0 ce moment-l\u00e0 nous ne connaissions rien sur la radiation, combien on \u00e9tait expos\u00e9s, et on ne se rendait pas compte du danger.<\/em><\/p>\n<figure id=\"attachment_33424\" aria-describedby=\"caption-attachment-33424\" style=\"width: 1300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33424\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1528px-IAEA_02790036_5613126700-1300x919.jpg\" alt=\"Tadjikistan Tchernobyl D\u00e9contamination Catastrophe\" width=\"1300\" height=\"919\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1528px-IAEA_02790036_5613126700-1300x919.jpg 1300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1528px-IAEA_02790036_5613126700-1300x919-300x212.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1528px-IAEA_02790036_5613126700-1300x919-768x543.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/06\/1528px-IAEA_02790036_5613126700-1300x919-1024x724.jpg 1024w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/><figcaption id=\"caption-attachment-33424\" class=\"wp-caption-text\">Vue depuis un h\u00e9licopt\u00e8re de la zone autour du r\u00e9acteur accident\u00e9 de Tchernobyl. &#8211; Image d&rsquo;archive de la Soci\u00e9t\u00e9 ukrainienne pour l&rsquo;amiti\u00e9 et les relations culturelles avec les autres \u00c9tats (USFCRFC).<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><em>J&rsquo;\u00e9tais \u00e0 Tchernobyl avec un autre Tadjik, Solidjon Khakimov. Nous sommes arriv\u00e9s l\u00e0-bas en m\u00eame temps. J\u2019ai pass\u00e9 80 jours dans la zone de l&rsquo;accident et je suis rentr\u00e9 le 20 d\u00e9cembre. Solidjon y a pass\u00e9 exactement trois mois, jusqu&rsquo;au 30 d\u00e9cembre 1988. Au fil du temps il a compl\u00e8tement perdu la vue. Quant \u00e0 moi je suis devenu faible, j\u2019ai commenc\u00e9 \u00e0 avoir des vertiges, puis j\u2019ai d\u00e9velopp\u00e9 un ost\u00e9ochondrose et des maladies des organes internes. Une autre de mes connaissances de Tchernobyl, Ourazkoul, n&rsquo;a pas v\u00e9cu longtemps apr\u00e8s son retour. Beaucoup de mes coll\u00e8gues n&rsquo;ont pas eu la chance d\u2019\u00eatre en vie aujourd\u2019hui, ils \u00e9taient pourtant encore jeunes \u00bb<\/em>, conclut Agzam Khodjiev.<\/p>\n<p style=\"text-align: justify\"><strong>Une aide d\u2019\u00c9tat insuffisante<\/strong><\/p>\n<p style=\"text-align: justify\">En 2007, le Tadjikistan a adopt\u00e9 une loi sur <em>\u00ab la protection sociale des citoyens victimes de la catastrophe de la centrale nucl\u00e9aire de Tchernobyl\u00a0\u00bb<\/em>. En vertu de cette loi les participants \u00e0 la liquidation de l&rsquo;accident et leurs enfants ont droit \u00e0 une aide financi\u00e8re. Les liquidateurs sont exon\u00e9r\u00e9s d\u2019imp\u00f4ts (sur le revenu, foncier, sur l&rsquo;immobilier et autres). Les soins m\u00e9dicaux et les m\u00e9dicaments doivent leur \u00eatre fournis gratuitement. Cependant, les liquidateurs disent qu\u2019ils doivent acheter de nombreux m\u00e9dicaments co\u00fbteux \u00e0 leurs frais.<\/p>\n<p style=\"text-align: justify\"><em>\u00ab\u00a0Chaque ann\u00e9e il nous est recommand\u00e9 de suivre un traitement de 24 jours dans les centres de sant\u00e9. Pour cela l&rsquo;\u00c9tat alloue 2 930 somonis (257 euros) \u00e0 chaque travailleur de Tchernobyl. Mais ce montant ne couvre pas le traitement. Un s\u00e9jour de 24 jours co\u00fbte entre 4\u00a0500 et 5 000 somonis (entre 394 et 438 euros). Par cons\u00e9quent on est oblig\u00e9s soit de r\u00e9duire la dur\u00e9e du s\u00e9jour, soit de payer un suppl\u00e9ment de notre poche. Ce serait bien si, en tant que victime de Tchernobyl, on pouvait avoir une remise de 50 % dans les centres de sant\u00e9. De plus, ces derni\u00e8res ann\u00e9es les aides ont \u00e9t\u00e9 r\u00e9duites. Jusqu&rsquo;en 2007 nous ne payions pas l&rsquo;\u00e9lectricit\u00e9, l&rsquo;eau, l\u2019entretien du b\u00e2timent, mais nous avons \u00e9t\u00e9 priv\u00e9s de ce privil\u00e8ge. Maintenant l&rsquo;\u00e9lectricit\u00e9 est enti\u00e8rement \u00e0 notre charge, et nous payons la moiti\u00e9 pour l&rsquo;eau et l\u2019entretien du b\u00e2timent <\/em>\u00bb, se plaint le liquidateur Abdouvakhob Khodjibo\u00efev.<\/p>\n<p style=\"background-color: #d4d4d4;\"><span style=\"color: #000000;\">Envie d'Asie centrale dans votre bo\u00eete mail ? Inscrivez-vous gratuitement \u00e0 notre newsletter hebdomadaire <strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/2ff41361.sibforms.com\/serve\/MUIFAEUtgQP8Waps-GeAAxU6xgHAdCwla_phFOCNHYUG2N5pyugc_FC9NR3XbOOigQxU5CuQ4V0IZJcq6LjCU6Hx9fBECllNbyvRpMFItJi2WzECxpflAKA-cS-isERi5gQRcgrqND1R6toUU-9w6b_7bd4-Ty-GtfBQfXNFFjMIK0bYtfXjv8bCS5qFaXUgi00yBrR5vK187H2N\">en cliquant ici.<\/a><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify\">Apr\u00e8s leur retour au Tadjikistan, la plupart des liquidateurs n\u2019ont pas pu, pour des raisons de sant\u00e9, reprendre leur travail. Ils vivent de leur retraite\u00a0: 800 somonis par mois (70 euros). Cet argent ne suffit ni pour une bonne nutrition ni pour un bon traitement.<\/p>\n<p style=\"text-align: justify\">Lorsqu\u2019on leur demande ce qu\u2019il leur manque, la r\u00e9ponse est inattendue<em>\u00a0: \u00ab\u00a0Je voudrais visiter Tchernobyl \u00e0 nouveau. Je voudrais voir de mes propres yeux comment c\u2019est maintenant l\u00e0-bas. Tchernobyl a chang\u00e9 toute ma vie. Oh, si seulement le gouvernement de l&rsquo;Ukraine nous faisait un tel cadeau, d\u2019inviter les liquidateurs de l&rsquo;accident du Tadjikistan \u00e0 une excursion dans la zone de l\u2019exclusion&#8230;\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: right\"><strong>Tilava Rassoul-Zad\u00e9<br \/>\n<\/strong><strong>Journaliste pour Fergana News<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Traduit <\/strong><a href=\"https:\/\/fergana.ru\/articles\/117133\/\"><strong>du russe<\/strong><\/a><strong> par Jelena Dzekseneva<br \/>\n<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Edit\u00e9 par Anthony Vial <\/strong><\/p>\n<p style=\"text-align: right\"><strong>Relu par Anne Marvau<br \/>\n<\/strong><\/p>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendant de nombreuses ann\u00e9es des centaines de milliers de personnes ont particip\u00e9 \u00e0 l&rsquo;\u00e9limination des cons\u00e9quences de l&rsquo;accident de la centrale nucl\u00e9aire de Tchernobyl, dont environ 6 000 Tadjiks. On les a surnomm\u00e9s \u00ab\u00a0les liquidateurs\u00a0\u00bb. Aujourd&rsquo;hui on compte plus de 1 800 liquidateurs au Tadjikistan, dont 1 450 sont handicap\u00e9s. Certains d\u2019entre eux se rem\u00e9morent [&hellip;]<\/p>\n","protected":false},"author":755,"featured_media":33426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[428,473,3913,799,523,3567,1956,446],"coauthors":[3709,3688,3584],"class_list":["post-32758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tadjikistan","tag-environnement","tag-histoire","tag-liquidateur","tag-sante","tag-tadjikistan","tag-tchernobyl","tag-traduction","tag-urss"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/32758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/755"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=32758"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/32758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/33426"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=32758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=32758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=32758"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=32758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}