{"id":32069,"date":"2020-05-13T14:00:57","date_gmt":"2020-05-13T12:00:57","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=32069"},"modified":"2020-05-16T09:37:24","modified_gmt":"2020-05-16T07:37:24","slug":"le-coronavirus-en-perte-de-vitesse-en-asie-centrale","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kirghizstan\/le-coronavirus-en-perte-de-vitesse-en-asie-centrale\/","title":{"rendered":"Le coronavirus en perte de vitesse en Asie centrale"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>L\u2019Asie centrale approche les 10 000 cas de coronavirus, dont une bonne moiti\u00e9 se concentre au Kazakhstan. Toutefois, la propagation de l\u2019\u00e9pid\u00e9mie d\u00e9c\u00e9l\u00e8re dans trois des quatre pays officiellement touch\u00e9s, qui sont entr\u00e9s en phase de reprise \u00e9conomique.\u00a0<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Comme dans de nombreuses r\u00e9gions du monde, l\u2019heure est \u00e0 la sortie du confinement en Asie centrale. Alors que la situation \u00e9pid\u00e9miologique semble stabilis\u00e9e au Kazakhstan, au Kirghizstan et en Ouzb\u00e9kistan, les gouvernements ont abaiss\u00e9 le niveau d\u2019alerte et enclench\u00e9 la reprise d\u2019activit\u00e9s \u00e9conomiques par \u00e9tapes. Reprise fragile toutefois, alors que de nombreux foyers ont \u00e9t\u00e9 touch\u00e9s durement par la crise.\u00a0<\/span><\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Seul le Tadjikistan, qui a reconnu la pr\u00e9sence du virus <\/span><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-tadjikistan-declare-ses-premiers-cas-de-coronavirus\/\"><span style=\"font-weight: 400;\">tr\u00e8s tardivement<\/span><\/a><span style=\"font-weight: 400;\">, se retrouve en pleine crise sanitaire, tandis que le Turkm\u00e9nistan n\u2019enregistre toujours aucun cas. Notre point, pays par pays.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Le Kazakhstan sort de deux mois d\u2019\u00e9tat d\u2019urgence\u00a0<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le Kazakhstan enregistre de loin le plus de cas de coronavirus en Asie centrale, avec <\/span><a href=\"https:\/\/www.coronavirus2020.kz\/\"><span style=\"font-weight: 400;\">5 417 infections<\/span><\/a><span style=\"font-weight: 400;\">, pour 32 d\u00e9c\u00e8s au 13 mai. Deux tiers des cas environ se concentrent dans les trois principales villes du pays, <\/span><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/almaty-la-ville-aux-1000-couleurs-et-aux-1001-annees\/\"><span style=\"font-weight: 400;\">Almaty<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/la-capitale-du-kazakhstan-renommee-nur-sultan\/\"><span style=\"font-weight: 400;\">Nur-Sultan<\/span><\/a><span style=\"font-weight: 400;\"> et <\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Shymkent\"><span style=\"font-weight: 400;\">Chimkent<\/span><\/a><span style=\"font-weight: 400;\">. Toutefois, la courbe des infections commence \u00e0 ralentir alors que le nombre de gu\u00e9risons augmente, menant \u00e0 une baisse des cas de Covid-19 actifs.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u201c<\/span><i><span style=\"font-weight: 400;\">Le respect des conditions de quarantaine nous a permis de stabiliser la situation \u00e9pid\u00e9miologique. Tout en tenant compte de celle-ci, les mesures de quarantaine doivent aujourd\u2019hui \u00eatre adoucies par \u00e9tapes. Petit \u00e0 petit, nous devons retourner \u00e0 une vie normale et tranquille<\/span><\/i><span style=\"font-weight: 400;\">\u201d, expliquait le principal m\u00e9decin \u00e9pid\u00e9miologique du pays, Aijan Esmagambetova, cit\u00e9e <\/span><a href=\"https:\/\/vlast.kz\/novosti\/39316-epidemiologiceskaa-situacia-v-kazahstane-stabilizirovalas-esmagambetova.html\"><span style=\"font-weight: 400;\">par le m\u00e9dia kzaakh Vlast.kz<\/span><\/a><span style=\"font-weight: 400;\"> d\u00e9but mai. C\u2019est ainsi que le 11 mai dernier, le pr\u00e9sident kazakh <\/span><a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kassym-jomart-tokaiev-le-diplomate-devenu-president\/\"><span style=\"font-weight: 400;\">Kassym-Jomart Toka\u00efev<\/span><\/a><span style=\"font-weight: 400;\"> a lev\u00e9 l\u2019\u00e9tat d\u2019urgence introduit le 16 mars et prolong\u00e9 deux fois, <\/span><a href=\"https:\/\/vlast.kz\/novosti\/39459-v-kazahstane-zaversilos-dejstvie-rezima-cp.html?utm_source=popular_pages&amp;utm_medium=novosti\"><span style=\"font-weight: 400;\">rapporte Vlast.kz<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Comme le pr\u00e9sident l\u2019a indiqu\u00e9 <\/span><a href=\"http:\/\/www.akorda.kz\/ru\/speeches\/internal_political_affairs\/in_speeches_and_addresses\/vystuplenie-glavy-gosudarstva-na-zaklyuchitelnom-zasedanii-gosudarstvennoi-komissii-po-chrezvychainomu-polozheniyu\"><span style=\"font-weight: 400;\">dans son discours<\/span><\/a><span style=\"font-weight: 400;\"> sur la lev\u00e9e de l\u2019\u00e9tat d\u2019urgence, plus d\u2019un million de Kazakhstanais peuvent ainsi retourner travailler, alors que certains magasins, salons de beaut\u00e9 et centres \u00e9ducatifs reprennent leur activit\u00e9. Par ailleurs, certaines <\/span><a href=\"https:\/\/tengrinews.kz\/kazakhstan_news\/nazvanyi-goroda-kazahstana-kuda-vnov-nachnut-letat-samoletyi-401776\/\"><span style=\"font-weight: 400;\">lignes a\u00e9riennes internes<\/span><\/a><span style=\"font-weight: 400;\"> sont de nouveau desservies. \u201c<\/span><i><span style=\"font-weight: 400;\">Dans la vie quotidienne il est indispensable de strictement respecter les r\u00e8gles de pr\u00e9caution. [&#8230;] La distanciation sociale et le port de masque dans les lieux publics doivent devenir la norme <\/span><\/i><span style=\"font-weight: 400;\">\u201d<\/span><i><span style=\"font-weight: 400;\">, <\/span><\/i><span style=\"font-weight: 400;\">a cependant pr\u00e9venu Kassym-Jomart Toka\u00efev.\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Alors que l\u2019\u00e9pid\u00e9mie est loin d\u2019\u00eatre achev\u00e9e, des mesures de quarantaine <\/span><a href=\"https:\/\/tengrinews.kz\/kazakhstan_news\/rejim-chp-zavershilsya-v-kazahstane-no-karantin-ne-snyali-401699\/\"><span style=\"font-weight: 400;\">continuent d\u2019\u00eatre appliqu\u00e9es<\/span><\/a><span style=\"font-weight: 400;\">, notamment \u00e0 Almaty et la capitale Nur-Sultan. Ainsi, la mobilit\u00e9 entre les r\u00e9gions reste r\u00e9duite, les transports en commun ne fonctionnent qu\u2019\u00e0 une capacit\u00e9 de 50 % des passagers et les citoyens peuvent sortir par groupe de trois maximum, toujours selon les <\/span><a href=\"http:\/\/www.akorda.kz\/ru\/speeches\/internal_political_affairs\/in_speeches_and_addresses\/vystuplenie-glavy-gosudarstva-na-zaklyuchitelnom-zasedanii-gosudarstvennoi-komissii-po-chrezvychainomu-polozheniyu\"><span style=\"font-weight: 400;\">annonces<\/span><\/a><span style=\"font-weight: 400;\"> du pr\u00e9sident kazakh. Selon la docteure en chef du Kazakhstan Aijan Esmagambetova <\/span><a href=\"https:\/\/tengrinews.kz\/kazakhstan_news\/usloviya-oslableniya-karantina-nazvala-glavnyiy-sanvrach-401928\/\"><span style=\"font-weight: 400;\">cit\u00e9e par le m\u00e9dia kazakh Tengrinews<\/span><\/a><span style=\"font-weight: 400;\">, une lev\u00e9e progressive des mesures de quarantaine d\u00e9pendra du ralentissement des nouvelles infections.\u00a0<\/span><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/selfcontrol.carto.com\/viz\/6bece7c2-efcd-446e-af85-f8102b299ab9\/embed_map\" width=\"100%\" height=\"520\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pour de nombreuses familles, les effets \u00e9conomiques de la crise ont \u00e9t\u00e9 d\u00e9vastateurs. Comme l\u2019illustre <\/span><a href=\"https:\/\/rus.azattyq.org\/a\/kazakhstan-coronavirus-quarantine-socium\/30607037.html\"><span style=\"font-weight: 400;\">Radio Azattyq<\/span><\/a><span style=\"font-weight: 400;\">, la branche kazakhe du m\u00e9dia am\u00e9ricain Radio Free Europe, beaucoup n\u2019ont plus de quoi payer leur loyer ou l\u2019\u00e9ducation de leurs enfants. Selon la sociologue Ayman Jousoupova, cit\u00e9e par Azattyq, seulement 15 % de la population a pu faire des \u00e9conomies. \u201c<\/span><i><span style=\"font-weight: 400;\">Dans notre pays, la majeure partie de la population paye ses d\u00e9penses quotidiennes avec ses revenus. Les salaires sont tellement bas que les gens n\u2019ont rien \u00e0 \u00e9pargner pour demain<\/span><\/i><span style=\"font-weight: 400;\">\u201d, d\u00e9crit Ayman Jousoupova. C\u2019est ainsi que, <\/span><a href=\"https:\/\/www.gov.kz\/memleket\/entities\/enbek\/press\/news\/details\/bolee-2-mln-chelovek-poluchili-vtoruyu-vyplatu-42-500-tenge?lang=ru\"><span style=\"font-weight: 400;\">selon le minist\u00e8re du Travail et de la Protection sociale<\/span><\/a><span style=\"font-weight: 400;\">, 4,5 millions de personnes, soit un quart de la population, ont obtenu les 42 500 tengu\u00e9s (environ 92 euros) d\u2019aide sociale mensuelle allou\u00e9e par le gouvernement lors de la crise.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/decryptage\/le-kazakhstan-vient-en-aide-a-ses-citoyens-touches-par-le-coronavirus\/\"><b>Le Kazakhstan vient en aide \u00e0 ses citoyens touch\u00e9s par le coronavirus<\/b><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La crise est ainsi loin d\u2019\u00eatre termin\u00e9e, d\u2019autant que, selon le directeur du centre national de la sant\u00e9 Damir Kobjassarov <\/span><a href=\"https:\/\/vlast.kz\/novosti\/39423-kazahstan-ozidaet-vtoroj-volny-koronavirusa-osenu.html\"><span style=\"font-weight: 400;\">cit\u00e9 par Vlast.kz<\/span><\/a><span style=\"font-weight: 400;\">, le Kazakhstan attend une deuxi\u00e8me vague de l\u2019\u00e9pid\u00e9mie en automne, en m\u00eame temps que l\u2019\u00e9pid\u00e9mie de grippe habituelle. \u201c<\/span><i><span style=\"font-weight: 400;\">Il ne faut pas trop se d\u00e9contracter. Toute la population doit se rappeler que le virus est l\u00e0, il n\u2019est pas \u00e9limin\u00e9<\/span><\/i><span style=\"font-weight: 400;\">\u201d, a averti Damir Kobjassarov.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Sortie de quarantaine par petites \u00e9tapes au Kirghizstan<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Alors que le Kirghizstan avait rapidement introduit <\/span><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/coronavirus-lasie-centrale-entre-dans-le-dur\/\"><span style=\"font-weight: 400;\">des mesures de quarantaine particuli\u00e8rement strictes<\/span><\/a><span style=\"font-weight: 400;\">, le nombre d\u2019infections enregistr\u00e9es a \u00e9volu\u00e9 de fa\u00e7on assez mod\u00e9r\u00e9e. Pr\u00e8s de deux mois apr\u00e8s les premiers cas, le pays en compte <\/span><a href=\"https:\/\/covid.kg\/\"><span style=\"font-weight: 400;\">1 044<\/span><\/a><span style=\"font-weight: 400;\"> au 13 mai, dont 12 d\u00e9c\u00e8s. Alors que le nombre de gu\u00e9risons s\u2019accro\u00eet, le nombre d\u2019infections actives est en l\u00e9g\u00e8re baisse apr\u00e8s avoir atteint un pic le 16 avril, soit une bonne semaine plus t\u00f4t que pr\u00e9vu, <\/span><a href=\"https:\/\/kloop.kg\/blog\/2020\/05\/12\/nablyudaetsya-tendentsiya-k-snizheniyu-zabolevaemosti-koronavirusnoj-infektsiej-minzdrav\/\"><span style=\"font-weight: 400;\">remarque le vice-ministre de la Sant\u00e9 Nourbolot Ousenba\u00efev, cit\u00e9 par le m\u00e9dia kirghiz Kloop.kg<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Chiffre inqui\u00e9tant toutefois, pr\u00e8s d\u2019un quart des infections concernent des membres du personnel m\u00e9dical, un indicateur des faiblesses du syst\u00e8me de sant\u00e9, qui atteindrait vite ses limites en cas d\u2019une \u00e9pid\u00e9mie accrue. Ce chiffre est en augmentation par rapport \u00e0 la mi-avril, o\u00f9 un cinqui\u00e8me des personnels soignants <\/span><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/coronavirus-au-kirghizstan-une-personne-infectee-sur-cinq-fait-partie-du-personnel-soignant\/\"><span style=\"font-weight: 400;\">\u00e9taient affect\u00e9s<\/span><\/a><span style=\"font-weight: 400;\">. Diff\u00e9rents experts cit\u00e9 <\/span><a href=\"https:\/\/kaktus.media\/doc\/412761_pochemy_v_infekcionnoy_bolnice_lish_odin_zarajennyy_medik_a_v_drygih_massa._mneniia.html\"><span style=\"font-weight: 400;\">par le m\u00e9dia kirghiz Kaktus.kg<\/span><\/a><span style=\"font-weight: 400;\"> pointent un manque d\u2019\u00e9quipement, de pr\u00e9paration du personnel et certains h\u00f4pitaux mal adapt\u00e9s au contr\u00f4le \u00e9pid\u00e9miologique.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Depuis d\u00e9but mai, le Kirghizstan a par ailleurs enclench\u00e9 une sortie progressive de la quarantaine dans les zones particuli\u00e8rement touch\u00e9es, notamment la capitale Bichkek et <\/span><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/och-ville-frontiere-du-kirghizstan\/\"><span style=\"font-weight: 400;\">Och<\/span><\/a><span style=\"font-weight: 400;\">, la deuxi\u00e8me ville du pays. Depuis le 1er mai, certains secteurs \u00e9conomiques ont repris leurs activit\u00e9s, notamment le secteur de la construction, les services automobiles, et les services de taxis <\/span><a href=\"https:\/\/rus.azattyk.org\/a\/30587909.html\"><span style=\"font-weight: 400;\">d\u00e9crit Radio Azattyk<\/span><\/a><span style=\"font-weight: 400;\">, la branche kirghize du m\u00e9dia am\u00e9ricain Radio Free Europe. Tous les postes de contr\u00f4le \u00e0 l\u2019int\u00e9rieur des villes ont \u00e9t\u00e9 retir\u00e9s. \u00c0 Bichkek, 120 000 personnes ont ainsi pu reprendre le travail.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La deuxi\u00e8me \u00e9tape a \u00e9t\u00e9 enclench\u00e9e le 11 mai avec la <\/span><a href=\"https:\/\/www.gov.kg\/ru\/post\/s\/premer-ministr-mukhammedkalyy-abylgaziev-soblyudenie-rezhima-chrezvychaynoy-situatsii-trebuet-osoboy-otvetstvennosti-ot-kazhdogo-kyrgyzstantsa\"><span style=\"font-weight: 400;\">lev\u00e9e de l\u2019\u00e9tat d\u2019urgence<\/span><\/a><span style=\"font-weight: 400;\"> dans toutes les zones affect\u00e9es et la reprise du travail dans de nouveaux secteurs, notamment du domaine de services. Le pays descend d\u2019un niveau d\u2019alerte et reste en situation d\u2019urgence, de nombreuses r\u00e8gles de quarantaine demeurent donc en place. Ainsi, la mobilit\u00e9 entre les r\u00e9gions reste limit\u00e9e par les postes de contr\u00f4le, tandis que les citoyens dans les zones sous quarantaine ne peuvent se d\u00e9placer que sous pr\u00e9sentation d\u2019une \u201cfiche de route\u201d ou d\u2019une d\u00e9claration de l\u2019employeur, <\/span><a href=\"https:\/\/kloop.kg\/blog\/2020\/05\/10\/rezhim-chp-i-komendantskij-chas-snimut-rezhim-chs-i-karantin-ostanutsya\/\"><span style=\"font-weight: 400;\">rapporte Kloop.kg<\/span><\/a><span style=\"font-weight: 400;\">. La mise en service des transports en commun a \u00e9galement \u00e9t\u00e9 repouss\u00e9e par crainte d\u2019une nouvelle vague d\u2019infections.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En th\u00e9orie, peu d\u2019\u00e9l\u00e9ments changent pour les citoyens en zone de quarantaine, mais la vie publique y a nettement gagn\u00e9 en activit\u00e9 depuis le d\u00e9but du mois. Par ailleurs, les critiques se multiplient \u00e0 l\u2019encontre des autorit\u00e9s, accus\u00e9es de communication erratique et d\u2019introduire des difficult\u00e9s administratives inutiles, notamment pour obtenir le droit de se d\u00e9placer au travail. La d\u00e9put\u00e9e d\u2019opposition Natalya Nikitenko, <\/span><a href=\"https:\/\/kaktus.media\/doc\/412804_natalia_nikitenko:_vlasti_igraut_v_igry_kak_maksimalno_yslojnit_jizn_ludey.html\"><span style=\"font-weight: 400;\">interrog\u00e9e par le m\u00e9dia en ligne Kaktus<\/span><\/a><span style=\"font-weight: 400;\">, ironise : \u201c<\/span><i><span style=\"font-weight: 400;\">Parfois il semble que le gouvernement du pays et le comit\u00e9 national [de lutte contre le Coronavirus] participent \u00e0 un jeu nomm\u00e9 \u2018Comment rendre la vie la plus difficile possible et tourner les gens en d\u00e9rision ?\u2019 Je me demande quel est le prix \u00e0 gagner dans ce jeu ? Un bon poste ? <\/span><\/i><span style=\"font-weight: 400;\">\u201d.\u00a0\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Alors que la possibilit\u00e9 de limiter certains droits en cas de quarantaine a \u00e9t\u00e9 <\/span><a href=\"http:\/\/www.president.kg\/ru\/sobytiya\/16624_vneseni_izmeneniya_vzakoni_krobobshestvennom_zdravoohranenii_iograghdanskoy_zashite\"><span style=\"font-weight: 400;\">fix\u00e9e dans la loi<\/span><\/a><span style=\"font-weight: 400;\"> et dans un contexte de difficult\u00e9s \u00e9conomiques, une \u201cmanifestation pacifique pour les droits des citoyens\u201d <\/span><a href=\"https:\/\/www.facebook.com\/events\/892549817837144\/\"><span style=\"font-weight: 400;\">est annonc\u00e9e<\/span><\/a><span style=\"font-weight: 400;\"> pour le 16 mai prochain. La description de l\u2019\u00e9v\u00e8nement sur Facebook, organis\u00e9 par un compte anonyme nomm\u00e9 \u201cSoke Kamalsyn\u201d (Soke [surnom du Pr\u00e9sident Sooronbay Jeenbekov] en prison!), annonce : \u201c<\/span><i><span style=\"font-weight: 400;\">Respectons la distance et toutes les mesures de pr\u00e9caution, sortons et exprimons-nous ! Nous, le peuple du Kirghizstan, sommes le pouvoir dans notre pays !<\/span><\/i><span style=\"font-weight: 400;\">\u201d<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Le Tadjikistan continue \u00e0 minimiser l\u2019ampleur de la crise sanitaire<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le Tadjikistan n\u2019a officiellement<\/span><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-tadjikistan-declare-ses-premiers-cas-de-coronavirus\/\"> <span style=\"font-weight: 400;\">d\u00e9clar\u00e9 ses 15 premiers cas<\/span><\/a><span style=\"font-weight: 400;\"> de coronavirus que le 30 avril dernier. Depuis, ce chiffre augmente r\u00e9guli\u00e8rement : le dernier bilan, communiqu\u00e9 par le<\/span><a href=\"http:\/\/moh.tj\/729-%d2%b3%d0%be%d0%bb%d0%b0%d1%82%d0%b8-%d1%81%d0%b8%d1%80%d0%be%d1%8f%d1%82%d0%b8-%d0%ba%d0%be%d1%80%d0%be%d0%bd%d0%b0%d0%b2%d0%b8%d1%80%d1%83%d1%81%d0%b8-%d0%bd%d0%b0%d0%b2%d0%b8-covid-19-%d0%b1\/\"> <span style=\"font-weight: 400;\">minist\u00e8re de la Sant\u00e9<\/span><\/a><span style=\"font-weight: 400;\"> le 12 mai, faisait \u00e9tat <\/span><a href=\"https:\/\/covid.tj\/\"><span style=\"font-weight: 400;\">de 729 cas et 23 d\u00e9c\u00e8s<\/span><\/a><span style=\"font-weight: 400;\">. Selon<\/span><a href=\"https:\/\/rus.ozodi.org\/a\/30606122.html\"> <span style=\"font-weight: 400;\">Radio Ozodi<\/span><\/a><span style=\"font-weight: 400;\">, la branche tadjike du m\u00e9dia am\u00e9ricain Radio Free Europe, environ 5 000 personnes sont \u00e9galement plac\u00e9es sous surveillance m\u00e9dicale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pourtant, ces donn\u00e9es officielles semblent sous-estimer l\u2019ampleur de l\u2019\u00e9pid\u00e9mie dans le pays. Des citoyens ont ainsi cr\u00e9\u00e9 le site internet<\/span><a href=\"https:\/\/kvtj.info\/\"> <span style=\"font-weight: 400;\">Kvtj.info<\/span><\/a><span style=\"font-weight: 400;\"> qui recense tous les cas de mort suspecte, notamment celles attribu\u00e9es \u00e0 des <\/span><i><span style=\"font-weight: 400;\">\u00ab pneumonies \u00bb<\/span><\/i><span style=\"font-weight: 400;\">. Le 12 mai, plus de 150 d\u00e9c\u00e8s \u00e9taient d\u00e9j\u00e0 r\u00e9pertori\u00e9s sur ce site. Celui-ci a d\u2019ailleurs \u00e9t\u00e9 bloqu\u00e9 par les autorit\u00e9s et n\u2019est d\u00e9sormais plus accessible au Tadjikistan, comme l\u2019a rapport\u00e9 le m\u00e9dia russe<\/span><a href=\"https:\/\/fergana.agency\/news\/117985\/\"> <span style=\"font-weight: 400;\">Fergana News<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le gouvernement, qui n\u2019a pris aucune mesure de confinement et n\u2019a initialement pas<\/span><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-tadjikistan-est-il-vraiment-epargne-par-le-coronavirus\/\"> <span style=\"font-weight: 400;\">limit\u00e9 la tenue d\u2019\u00e9v\u00e8nements publics<\/span><\/a><span style=\"font-weight: 400;\">, cherche \u00e0 faire oublier sa gestion d\u00e9sastreuse au d\u00e9but de la crise sanitaire. Le 5 mai dernier, le ministre de la Sant\u00e9,<\/span><a href=\"http:\/\/moh.tj\/leadership\/?lang=en\"> <span style=\"font-weight: 400;\">Nasim Olimzoda<\/span><\/a><span style=\"font-weight: 400;\">, a donc fait les frais de ce revirement<\/span><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-ministre-de-la-sante-du-tadjikistan-limoge-en-pleine-pandemie-de-coronavirus\/\"> <span style=\"font-weight: 400;\">et a \u00e9t\u00e9 limog\u00e9<\/span><\/a><span style=\"font-weight: 400;\">. En outre, les autorit\u00e9s ont repens\u00e9 leur communication et mis en sc\u00e8ne leur d\u00e9vouement \u00e0 la population. L\u2019agence de presse officielle<\/span><a href=\"http:\/\/khovar.tj\/rus\/2020\/05\/rustami-emomali-oznakomilsya-v-dushanbe-s-hodom-razvyortyvaniya-bolnits-dlya-infitsirovannyh-koronavirusom\/\"> <span style=\"font-weight: 400;\">Khovar<\/span><\/a><span style=\"font-weight: 400;\"> a ainsi abondamment relay\u00e9 la visite du maire de la capitale Douchanb\u00e9 et fils du pr\u00e9sident,<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Rustam_Emomalii\"> <span style=\"font-weight: 400;\">Rustam Emomali<\/span><\/a><span style=\"font-weight: 400;\">, dans un h\u00f4pital en construction, le 4 mai.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Lire aussi sur Novastan :<\/b><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-ministre-de-la-sante-du-tadjikistan-limoge-en-pleine-pandemie-de-coronavirus\/\"> <b>Le ministre de la Sant\u00e9 du Tadjikistan limog\u00e9 en pleine pand\u00e9mie de coronavirus<\/b><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Quelques mesures de distanciation sociale ont \u00e9galement \u00e9t\u00e9 prises dans la capitale. Ainsi, le 12 mai, d\u2019apr\u00e8s le m\u00e9dia russe<\/span><a href=\"https:\/\/sputnik-tj.com\/Tajikistan\/20200512\/1031221977\/Makomoti-Dushanbe-faoliyati-tamomi-koshonahoi-husn-sartaroshkhonahoro-man-kard.html\"> <span style=\"font-weight: 400;\">Sputnik<\/span><\/a><span style=\"font-weight: 400;\">, la mairie de Douchanb\u00e9 a annonc\u00e9 la fermeture des salons de beaut\u00e9, des coiffeurs et des boutiques de t\u00e9l\u00e9phonie jusqu\u2019au 31 mai prochain. Les march\u00e9s aux v\u00eatements de la ville, ferm\u00e9s depuis le 30 avril, le resteront \u00e9galement jusqu\u2019\u00e0 fin mai, comme l\u2019a annonc\u00e9 le m\u00e9dia tadjik<\/span><a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/society\/20200508\/v-dushanbe-vetshevie-rinki-budut-zakriti-do-kontsa-maya\"> <span style=\"font-weight: 400;\">Asia-Plus<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<div style=\"padding: 8px 0; font-family: Arial!important; font-size: 13px!important; line-height: 15px!important; text-align: center; border-top: 1px solid #dadada; margin: 0 30px; width: 490px;\"><a style=\"color: #989898!important; text-decoration: none!important;\" href=\"https:\/\/infogram.com\/19262695-dd18-4642-b4e3-38c10db84c81\" target=\"_blank\" rel=\"noopener\">Number of cases Coronavirus<\/a><br \/>\n<a style=\"color: #989898!important; text-decoration: none!important;\" href=\"https:\/\/infogram.com\" target=\"_blank\" rel=\"nofollow noopener\">Infogram<\/a><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le syst\u00e8me de sant\u00e9 tadjik ne semble actuellement pas \u00eatre en mesure de faire face \u00e0 l\u2019afflux de malades. Des m\u00e9decins, cit\u00e9s sous condition d\u2019anonymat par<\/span><a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/society\/20200507\/na-12-vrachei-4-kostyuma-i-plavatelnie-ochki-vmesto-zatshitnih\"> <span style=\"font-weight: 400;\">Asia-Plus<\/span><\/a><span style=\"font-weight: 400;\">, d\u00e9crivent des conditions pr\u00e9caires. <\/span><i><span style=\"font-weight: 400;\">\u201cNous avons 4 combinaisons de protection pour 12 m\u00e9decins, que nous avons achet\u00e9es nous-m\u00eames \u00bb<\/span><\/i><span style=\"font-weight: 400;\">, affirme l\u2019un d\u2019entre eux, qui ajoute : <\/span><i><span style=\"font-weight: 400;\">\u00ab Ni aide ni tests ne nous parviennent\u201d<\/span><\/i><span style=\"font-weight: 400;\">. La mairie de Douchanb\u00e9 a n\u00e9anmoins<\/span><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-ministre-de-la-sante-du-tadjikistan-limoge-en-pleine-pandemie-de-coronavirus\/\"> <span style=\"font-weight: 400;\">promis la construction d\u2019h\u00f4pitaux temporaires<\/span><\/a><span style=\"font-weight: 400;\">, d\u2019une capacit\u00e9 de 3 000 lits.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Lire aussi sur Novastan :<\/b><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-tadjikistan-declare-ses-premiers-cas-de-coronavirus\/\"> <b>Le Tadjikistan d\u00e9clare ses premiers cas de coronavirus<\/b><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Face \u00e0 cette situation, l\u2019aide internationale s\u2019organise. Le 8 mai dernier, L\u2019Ouzb\u00e9kistan a envoy\u00e9 par avion du mat\u00e9riel m\u00e9dical, comprenant des respirateurs, des m\u00e9dicaments et du mat\u00e9riel de protection. Selon<\/span><a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/politics\/20200508\/shavkat-mirziyoev-napravil-v-tadzhikistan-mobilnie-meditsinskie-konteineri\"> <span style=\"font-weight: 400;\">Asia-Plus<\/span><\/a><span style=\"font-weight: 400;\">, 8 virologues et \u00e9pid\u00e9miologistes ouzbeks ont \u00e9galement \u00e9t\u00e9 d\u00e9p\u00each\u00e9s au Tadjikistan. Le 7 mai, un train ouzbek comprenant 144 conteneurs m\u00e9dicalis\u00e9s, servant d\u2019h\u00f4pitaux mobiles, \u00e9tait d\u00e9j\u00e0 parvenu \u00e0 Douchanb\u00e9.<\/span><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none;\" title=\"Number of cases Coronavirus\" src=\"https:\/\/e.infogram.com\/19262695-dd18-4642-b4e3-38c10db84c81?src=embed\" width=\"550\" height=\"706\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<div style=\"padding: 8px 0; font-family: Arial!important; font-size: 13px!important; line-height: 15px!important; text-align: center; border-top: 1px solid #dadada; margin: 0 30px; width: 490px;\"><a style=\"color: #989898!important; text-decoration: none!important;\" href=\"https:\/\/infogram.com\/19262695-dd18-4642-b4e3-38c10db84c81\" target=\"_blank\" rel=\"noopener\">Number of cases Coronavirus<\/a><br \/>\n<a style=\"color: #989898!important; text-decoration: none!important;\" href=\"https:\/\/infogram.com\" target=\"_blank\" rel=\"nofollow noopener\">Infogram<\/a><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Enfin, le 1<\/span><span style=\"font-weight: 400;\">er<\/span><span style=\"font-weight: 400;\"> mai, au lendemain de l\u2019annonce des premiers cas de coronavirus dans le pays, une \u00e9quipe de<\/span><a href=\"http:\/\/www.euro.who.int\/en\/media-centre\/sections\/press-releases\/2020\/whoeurope-covid-19-mission-arrives-in-tajikistan-international-experts-to-support-countrys-response-to-the-pandemic\"> <span style=\"font-weight: 400;\">l\u2019Organisation mondiale de la sant\u00e9<\/span><\/a><span style=\"font-weight: 400;\"> (OMS) est arriv\u00e9e dans la capitale. Toutefois, l\u2019organisation n\u2019a qu\u2019un r\u00f4le consultatif, et l\u2019efficacit\u00e9 de son travail d\u00e9pendra en grande partie de la coop\u00e9ration des autorit\u00e9s locales, qui semblent \u00e0 l\u2019heure actuelle ne pas vouloir transmettre de donn\u00e9es fiables.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Le Turkm\u00e9nistan s\u2019enferre dans le d\u00e9ni<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Depuis que le Tadjikistan a d\u00e9clar\u00e9 ses premiers cas le 30 avril dernier, le Turkm\u00e9nistan est le seul pays d\u2019Asie centrale \u00e0 \u00eatre officiellement \u00e9pargn\u00e9 par le coronavirus. Premier pays de la r\u00e9gion \u00e0 avoir<\/span><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/coronavirus-lasie-centrale-entre-dans-le-dur\/\"> <span style=\"font-weight: 400;\">ferm\u00e9 ses fronti\u00e8res<\/span><\/a><span style=\"font-weight: 400;\"> au d\u00e9but du mois de mars, le tr\u00e8s secret Turkm\u00e9nistan continue \u00e0 ne rapporter aucun cas de contamination, sans qu\u2019aucune organisation internationale ne soit autoris\u00e9e \u00e0 venir v\u00e9rifier.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cependant, les signes montrant que les autorit\u00e9s cherchent \u00e0 dissimuler la r\u00e9alit\u00e9 commencent \u00e0 s\u2019accumuler. En effet, le 12 mai,<\/span><a href=\"https:\/\/rus.azathabar.com\/a\/30607418.html\"> <span style=\"font-weight: 400;\">Radio Azatlyk<\/span><\/a><span style=\"font-weight: 400;\">, branche turkm\u00e8ne du m\u00e9dia am\u00e9ricain Radio Free Europe, a affirm\u00e9 que des personnes pr\u00e9sentant les sympt\u00f4mes du Covid-19 en provenance de plusieurs provinces turkm\u00e8nes avaient \u00e9t\u00e9 hospitalis\u00e9es dans la capitale Achgabat. De plus, Radio Azatlyk a rapport\u00e9 une hausse des d\u00e9c\u00e8s dans la capitale, rendue visible par l\u2019augmentation du nombre de c\u00e9r\u00e9monies fun\u00e9raires et de tombes dans les cimeti\u00e8res, au cours des cinq derni\u00e8res semaines. Dans la majorit\u00e9 des cas, une bien myst\u00e9rieuse <\/span><i><span style=\"font-weight: 400;\">\u00ab maladie pulmonaire \u00bb<\/span><\/i><span style=\"font-weight: 400;\"> serait officiellement la cause de la mort.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pour lutter contre une \u00e9pid\u00e9mie pour l\u2019instant inexistante \u00e0 leurs yeux, les autorit\u00e9s ont pris plusieurs mesures. Selon<\/span><a href=\"https:\/\/www.rferl.org\/a\/analysis-turkmenistan-says-it-s-coronavirus-free-but-doesn-t-want-who-to-check\/30600762.html\"> <span style=\"font-weight: 400;\">Radio Free Europe<\/span><\/a><span style=\"font-weight: 400;\">, le gouvernement turkm\u00e8ne a mis en place des camps de quarantaine dans la province orientale de<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lebap\"> <span style=\"font-weight: 400;\">Lebap<\/span><\/a><span style=\"font-weight: 400;\">, o\u00f9 les rares personnes arrivant depuis l\u2019\u00e9tranger doivent s\u00e9journer en isolement. De plus, comme l\u2019a not\u00e9 le m\u00e9dia turkm\u00e8ne<\/span><a href=\"http:\/\/gundogar.org\/?02330519279000000000000011000000\"> <span style=\"font-weight: 400;\">G\u00fcndogar<\/span><\/a><span style=\"font-weight: 400;\">, les d\u00e9placements entre les provinces ont \u00e9t\u00e9 restreints et des barrages routiers ont \u00e9t\u00e9 dress\u00e9s \u00e0 l\u2019entr\u00e9e des villes. Les transports publics et les march\u00e9s sont r\u00e9guli\u00e8rement d\u00e9sinfect\u00e9s, m\u00eame si, le 8 mai,<\/span><a href=\"https:\/\/rus.azathabar.com\/a\/30600913.html\"> <span style=\"font-weight: 400;\">Radio Azatlyk<\/span><\/a><span style=\"font-weight: 400;\"> a rapport\u00e9 le rel\u00e2chement des mesures de d\u00e9sinfection \u00e0 Achgabat, ainsi que la rar\u00e9faction des gels hydroalcooliques dans le pays.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Lire aussi sur Novastan :<\/b><a href=\"https:\/\/novastan.org\/fr\/turkmenistan\/le-turkmenistan-organise-un-defile-militaire-pour-celebrer-la-fin-de-la-seconde-guerre-mondiale-une-premiere-depuis-1991\/\"> <b>Le Turkm\u00e9nistan organise un d\u00e9fil\u00e9 militaire pour c\u00e9l\u00e9brer la fin de la Seconde Guerre mondiale, une premi\u00e8re depuis 1991<\/b><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Toutefois, les autorit\u00e9s turkm\u00e8nes n\u2019imposent pas le respect des mesures de distanciation sociale et n\u2019encouragent pas le port du masque. En outre, le 9 mai dernier, le r\u00e9gime a organis\u00e9 une<\/span><a href=\"https:\/\/novastan.org\/fr\/turkmenistan\/le-turkmenistan-organise-un-defile-militaire-pour-celebrer-la-fin-de-la-seconde-guerre-mondiale-une-premiere-depuis-1991\/\"> <span style=\"font-weight: 400;\">parade militaire grandiose<\/span><\/a><span style=\"font-weight: 400;\"> pour c\u00e9l\u00e9brer les 75 ans de la victoire de 1945, faisant fi des pr\u00e9occupations sanitaires. Le pr\u00e9sident turkm\u00e8ne,<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Gurbanguly_Berdimuhamedow\"> <span style=\"font-weight: 400;\">Gourbangouly Berdimouhamedov<\/span><\/a><span style=\"font-weight: 400;\">, para\u00eet ainsi s\u00fbr de sa capacit\u00e9 \u00e0 emp\u00eacher le coronavirus de se propager dans le pays, et n\u2019a d\u2019ailleurs pas h\u00e9sit\u00e9 \u00e0 proposer de<\/span><a href=\"https:\/\/rus.azathabar.com\/a\/30600913.html\"> <span style=\"font-weight: 400;\">partager son exp\u00e9rience<\/span><\/a><span style=\"font-weight: 400;\"> avec d\u2019autres \u00c9tats.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En revanche, malgr\u00e9 cette \u00e9clatante r\u00e9ussite officielle, le Turkm\u00e9nistan n\u2019a toujours pas invit\u00e9 de mission de l\u2019OMS \u00e0 venir \u00e9valuer la situation. D\u2019apr\u00e8s le m\u00e9dia am\u00e9ricain<\/span><a href=\"https:\/\/eurasianet.org\/turkmenistan-more-lean-times-looming\"> <span style=\"font-weight: 400;\">Eurasianet<\/span><\/a><span style=\"font-weight: 400;\">, le 8 mai, le ministre des Affaires \u00e9trang\u00e8res turkm\u00e8ne,<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ra%C5%9Fit_Meredow\"> <span style=\"font-weight: 400;\">Rachid Meredov<\/span><\/a><span style=\"font-weight: 400;\">, a affirm\u00e9 que le pays \u00e9tait pr\u00eat \u00e0 accueillir une mission de l\u2019OMS, puisque selon ses termes, <\/span><i><span style=\"font-weight: 400;\">\u00ab il n\u2019y a absolument aucun probl\u00e8me \u00bb<\/span><\/i><span style=\"font-weight: 400;\"> dans le pays. Pourtant aucune invitation officielle, sans laquelle l\u2019OMS ne peut intervenir, n\u2019a \u00e9t\u00e9 remise \u00e0 l\u2019organisation. Celle-ci tente d\u2019envoyer une \u00e9quipe au Turkm\u00e9nistan depuis le mois d\u2019avril, pour l\u2019instant sans succ\u00e8s. Seule une invitation orale aurait \u00e9t\u00e9 faite le 5 mai dernier, comme l&rsquo;a affirm\u00e9 sur Twitter le responsable Europe de l&rsquo;OMS.\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">VC with the \ud83c\uddf9\ud83c\uddf2 Minister of Health. I welcome Turkmenistan Government\u2018s invitation for <a href=\"https:\/\/twitter.com\/WHO_Europe?ref_src=twsrc%5Etfw\">@WHO_Europe<\/a> to undertake a technical <a href=\"https:\/\/twitter.com\/hashtag\/COVID19?src=hash&amp;ref_src=twsrc%5Etfw\">#COVID19<\/a> mission. <a href=\"https:\/\/twitter.com\/WHO?ref_src=twsrc%5Etfw\">@WHO<\/a> ready to deploy experts as soon as possible. Minister expressed gratitude to \ud83c\uddf7\ud83c\uddfa \ud83c\uddf9\ud83c\uddf7 \ud83c\udde9\ud83c\uddea\ud83c\uddfa\ud83c\uddf3for solidarity <a href=\"https:\/\/twitter.com\/hashtag\/UnitedActionforBetterHealth?src=hash&amp;ref_src=twsrc%5Etfw\">#UnitedActionforBetterHealth<\/a><\/p>\n<p>&mdash; Hans Kluge (@hans_kluge) <a href=\"https:\/\/twitter.com\/hans_kluge\/status\/1257751363217473537?ref_src=twsrc%5Etfw\">May 5, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><b>L\u2019Ouzb\u00e9kistan prend la pand\u00e9mie tr\u00e8s au s\u00e9rieux<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pr\u00e8s de deux mois apr\u00e8s <\/span><a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/premier-cas-de-coronavirus-en-ouzbekistan-en-provenance-de-france\/\"><span style=\"font-weight: 400;\">le premier cas de Covid-19<\/span><\/a><span style=\"font-weight: 400;\">, l\u2019Ouzb\u00e9kistan compte au 13 mai, <\/span><a href=\"https:\/\/coronavirus.uz\/uz\"><span style=\"font-weight: 400;\">2 568 personnes<\/span><\/a><span style=\"font-weight: 400;\"> touch\u00e9es par le virus. Parmi elles, 2 046 se sont r\u00e9tablies et 10 sont d\u00e9c\u00e9d\u00e9es.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cette \u00e9volution mod\u00e9r\u00e9e, s\u2019explique par l\u2019extr\u00eame r\u00e9activit\u00e9 de l\u2019Ouzb\u00e9kistan. D\u00e8s le 16 mars dernier, le pays a ferm\u00e9 toutes ses fronti\u00e8res. Ceci s\u2019est accompagn\u00e9 d\u2019un confinement maximal impos\u00e9 sur l\u2019ensemble territoire, mettant les \u00e9coles et la majorit\u00e9 des entreprises \u00e0 l&rsquo;arr\u00eat. Cette mesure a \u00e9t\u00e9 suivie d\u2019une hausse du t\u00e9l\u00e9travail dont les r\u00e9sultats ne sont cependant pas toujours pleinement satisfaisants selon le rapport du m\u00e9dia ouzbek <\/span><a href=\"https:\/\/podrobno.uz\/cat\/obchestvo\/v-mininfokome-obyasnili-prichiny-snizheniya-skorosti-mobilnogo-interneta-v-selskikh-rayonakh\/\"><span style=\"font-weight: 400;\">Podrobno.uz.<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/le-coronavirus-ralentit-internet-en-ouzbekistan\/\"><b>Le coronavirus ralentit Internet en Ouzb\u00e9kistan<\/b><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Un syst\u00e8me de confinement par couleur a \u00e9galement \u00e9t\u00e9 instaur\u00e9 le 8 mai dernier, rapporte le m\u00e9dia russe <\/span><a href=\"https:\/\/uz.sputniknews.ru\/society\/20200510\/14103901\/Koronavirus-v-Uzbekistane-glavnoe-na-10-maya.html\"><span style=\"font-weight: 400;\">Sputnik<\/span><\/a><span style=\"font-weight: 400;\">. Les autorit\u00e9s ont d\u00e9cid\u00e9 d&rsquo;attribuer \u00e0 chaque quartier et ville du pays une couleur : vert, orange ou rouge. La couleur attribu\u00e9e indique le niveau de danger de contamination et l\u2019importance des restrictions appliqu\u00e9es sur le territoire concern\u00e9.\u00a0<\/span><\/p>\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ce confinement se double d\u2019un syst\u00e8me de sant\u00e9 efficace. L\u2019Ouzb\u00e9kistan parvient \u00e0 produire plus de 10 000 tests de laboratoire par jour. Le 5 mai, le pays avait ainsi produit plus de 335 000 tests rapporte <\/span><a href=\"https:\/\/uz.sputniknews.ru\/Uzbekistan\/20200505\/14060652\/Koronavirus-v-Uzbekistane-glavnoe-na-5-maya.html\"><span style=\"font-weight: 400;\">Sputnik<\/span><\/a><span style=\"font-weight: 400;\">. Ces \u00e9l\u00e9ments peuvent expliquer en partie la faible proportion de contamination dans le pays par rapport \u00e0 la taille de sa population.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Sur la sc\u00e8ne internationale, l&rsquo;Ouzb\u00e9kistan s&rsquo;affiche comme une figure de proue dans la lutte contre le virus, multipliant les aides humanitaires \u00e0 l&rsquo;\u00e9tranger par l&rsquo;envoi de mat\u00e9riels sanitaires. Au d\u00e9but du mois pass\u00e9, le gouvernement ouzbek a aid\u00e9 ses pays voisins le <\/span><a href=\"http:\/\/uza.uz\/en\/society\/humanitarian-aid-to-tajikistan-09-04-2020\"><span style=\"font-weight: 400;\">Tadjikistan<\/span><\/a><span style=\"font-weight: 400;\"> et le <\/span><a href=\"http:\/\/uza.uz\/en\/society\/humanitarian-aid-to-kyrgyzstan-01-04-2020\"><span style=\"font-weight: 400;\">Kirghizstan<\/span><\/a><span style=\"font-weight: 400;\"> mais aussi l&rsquo;<\/span><a href=\"http:\/\/uza.uz\/en\/politics\/presidents-of-uzbekistan-and-afghanistan-speak-over-the-phon-26-03-2020\"><span style=\"font-weight: 400;\">Afghanistan<\/span><\/a><span style=\"font-weight: 400;\">, comme le rapporte l\u2019agence nationale d\u2019information d\u2019Ouzb\u00e9kistan.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Lire aussi sur Novastan : <\/b><a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/coronavirus-les-pays-dasie-centrale-sentraident-mutuellement\/\"><b>Coronavirus : les pays d\u2019Asie centrale s\u2019entraident\u00a0<\/b><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En parall\u00e8le, l\u2019Ouzb\u00e9kistan a re\u00e7u l\u2019aide de la part de la communaut\u00e9 internationale. Comme le rapporte le m\u00e9dia ouzbek <\/span><a href=\"https:\/\/www.gazeta.uz\/ru\/2020\/05\/01\/wb\/\"><span style=\"font-weight: 400;\">Gazeta.uz<\/span><\/a><span style=\"font-weight: 400;\"> le 30 avril dernier, la Banque mondiale a accord\u00e9 200 millions de dollars (184 millions d\u2019euros) \u00e0 l\u2019Ouzb\u00e9kistan afin d&rsquo;att\u00e9nuer les effets du coronavirus sur le d\u00e9veloppement de l\u2019\u00e9conomie du pays.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le pays cherche d\u00e9sormais \u00e0 relancer progressivement son activit\u00e9. Selon <\/span><a href=\"https:\/\/uz.sputniknews.ru\/society\/20200505\/14057527\/Khokim-Andizhanskoy-oblasti-poruchil-vozobnovit-rabotu-salonov-krasoty.html\"><span style=\"font-weight: 400;\">Sputnik<\/span><\/a><span style=\"font-weight: 400;\">, le chef de la r\u00e9gion d\u2019<\/span><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Province_d%27Andijan\"><span style=\"font-weight: 400;\">Andijan<\/span><\/a><span style=\"font-weight: 400;\">, Shouhratbek Abdourahmonov, a d\u00e9j\u00e0 autoris\u00e9 le 4 mai dernier la reprise du travail pour plus de 3 700 entreprises bien que des cas de contamination restent constat\u00e9s dans la r\u00e9gion. Dans la m\u00eame logique, <\/span><a href=\"https:\/\/www.gazeta.uz\/ru\/2020\/05\/12\/charter-flights\/\"><span style=\"font-weight: 400;\">Gazeta.uz<\/span><\/a><span style=\"font-weight: 400;\"> rapporte que le minist\u00e8re des Transports a annonc\u00e9 le 11 mai un programme de vols charters afin que les citoyens, bloqu\u00e9s \u00e0 l\u2019\u00e9tranger, puissent \u00eatre rapatri\u00e9s. Ces vols sont principalement destin\u00e9s aux personnes les plus vuln\u00e9rables, les personnes \u00e2g\u00e9es, les femmes enceintes et les enfants.\u00a0<\/span><\/p>\n<p style=\"text-align: right;\"><b>Florian Coppenrath<\/b><b><br \/>\n<\/b><b>R\u00e9dacteur en chef de Novastan<\/b><\/p>\n<p style=\"text-align: right;\"><b>Quentin Couvreur<\/b><b><br \/>\n<\/b><b>Journaliste pour Novastan<\/b><\/p>\n<p style=\"text-align: right;\"><b>Tanguy Martignolles<\/b><b><br \/>\n<\/b><b>Journaliste pour Novastan<\/b><\/p>\n<p style=\"text-align: right;\"><strong>Relu par Anne Marvau<\/strong><\/p>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Asie centrale approche les 10 000 cas de coronavirus, dont une bonne moiti\u00e9 se concentre au Kazakhstan. Toutefois, la propagation de l\u2019\u00e9pid\u00e9mie d\u00e9c\u00e9l\u00e8re dans trois des quatre pays officiellement touch\u00e9s, qui sont entr\u00e9s en phase de reprise \u00e9conomique.\u00a0 Comme dans de nombreuses r\u00e9gions du monde, l\u2019heure est \u00e0 la sortie du confinement en Asie centrale. [&hellip;]<\/p>\n","protected":false},"author":88,"featured_media":32071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,3,5,6,7],"tags":[493,3736,3544,3610,470,466,548,799,523,467],"coauthors":[88,3609,3749,3584],"class_list":["post-32069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kazakhstan","category-kirghizstan","category-ouzbekistan","category-tadjikistan","category-turkmenistan","tag-asie-centrale","tag-confinement","tag-coronavirus","tag-covid-19","tag-kazakhstan","tag-kirghizstan","tag-ouzbekistan","tag-sante","tag-tadjikistan","tag-turkmenistan"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/32069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=32069"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/32069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/32071"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=32069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=32069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=32069"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=32069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}