{"id":31943,"date":"2020-05-12T05:43:15","date_gmt":"2020-05-12T03:43:15","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=31943"},"modified":"2020-05-11T11:44:21","modified_gmt":"2020-05-11T09:44:21","slug":"newsletter-adp-rachete-le-plus-grand-aeroport-dasie-centrale","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/newsletter\/newsletter-adp-rachete-le-plus-grand-aeroport-dasie-centrale\/","title":{"rendered":"[Newsletter] ADP rach\u00e8te le plus grand a\u00e9roport d&rsquo;Asie centrale"},"content":{"rendered":"<p>Vous trouverez ci-dessous une reproduction de notre newsletter hebdomadaire du 11 mai 2020, envoy\u00e9e gratuitement tous les lundis. Si vous souhaitez la recevoir directement dans votre bo\u00eete mail,\u00a0<a href=\"http:\/\/eepurl.com\/O0Qub\" data-versionurl=\"https:\/\/novastan.org\/fr\/amber\/cache\/09330c9f239fb0be84150e4e7dedc0db\/\" data-versiondate=\"2019-02-11T19:03:52+00:00\" data-amber-behavior=\"\">inscrivez-vous ici<\/a>. En attendant, bonne lecture !<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p><em>Cette newsletter est d\u00e9di\u00e9e \u00e0 l\u2019Asie centrale.\u00a0Chaque semaine, nous vous r\u00e9sumons les diff\u00e9rentes actualit\u00e9s de la r\u00e9gion, tout en vous proposant les articles \u00e9crits par la r\u00e9daction. Une question, une remarque, une envie ? Envoyez-nous un\u00a0mail \u00e0 novastan.france@novastan.org<\/em><\/p>\n<h1 class=\"null\">Les 3 infos \u00e0 ne pas manquer<\/h1>\n<p class=\"null\"><strong>ADP rach\u00e8te l&rsquo;a\u00e9roport d&rsquo;Almaty pour 415 millions de dollars.<\/strong>\u00a0Le groupe fran\u00e7ais, en n\u00e9gociations exclusives depuis novembre,\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">a clos la transaction le 8 mai dernier.\u00a0<\/a><\/p>\n<p><strong>Deux nouveaux incidents dans le sud du Kirghizstan autour des fronti\u00e8res.<\/strong>\u00a0Le 1er mai, des villageois ouzbeks s&rsquo;en sont pris \u00e0 des garde-fronti\u00e8res kirghiz\u00a0<a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/des-villageois-ouzbeks-lancent-des-pierres-sur-des-garde-frontieres-kirghiz\/\" target=\"_blank\" rel=\"noopener\">\u00e0 coups de pierres<\/a>. Le 8 mai, c&rsquo;est entre des garde-fronti\u00e8res tadjiks et kirghiz qu&rsquo;un affrontement a eu lieu, impliquant notamment\u00a0<a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/plusieurs-blesses-dans-de-violents-affrontements-a-la-frontiere-tadjiko-kirghize\/\" target=\"_blank\" rel=\"noopener\">des tirs de mortier<\/a>.<\/p>\n<p><strong>La collaboration \u00e9conomique franco-ouzb\u00e8ke survit \u00e0 la pand\u00e9mie.\u00a0<\/strong>Le 20 avril dernier, les groupes fran\u00e7ais membres du Medef international ont annonc\u00e9 le maintien des projets en cours dans le pays,\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/la-collaboration-economique-franco-ouzbeke-survit-a-la-pandemie\/\" target=\"_blank\" rel=\"noopener\">en d\u00e9pit du report de la construction d\u2019une centrale solaire en 2021.<\/a><\/p>\n<h1 class=\"null\">Le d\u00e9cryptage de Novastan<\/h1>\n<p><strong>La catastrophe de Sardoba pourrait-elle menacer l\u2019ouverture ouzb\u00e8ke ?<\/strong><\/p>\n<p>L\u2019effondrement du barrage de Sardoba, qui a entra\u00een\u00e9 la mort de quatre personnes, 100 000 d\u00e9plac\u00e9s et des dizaines de millions de dollars de dommages \u00e9conomiques, n\u2019est que la derni\u00e8re des catastrophes caus\u00e9es par une fr\u00e9n\u00e9sie de d\u00e9pouillement et d\u2019enrichissement rapide sans foi ni loi des \u00e9lites ouzb\u00e8kes dans le secteur de la construction. Corruption, n\u00e9potisme et vol ont \u00e9t\u00e9 point\u00e9s du doigt par le pr\u00e9sident ouzbek Chavkat Mirzio\u00efev ainsi que de nombreux journalistes ouzbeks, comme les vraies raisons de la catastrophe de Sardoba et de celles qui l\u2019ont pr\u00e9c\u00e9d\u00e9e. Les pr\u00e9c\u00e9dents cas, comme la mort de six ouvriers dans l\u2019effondrement du chantier du m\u00e9tro de Tachkent en d\u00e9cembre dernier, n\u2019ont cependant abouti \u00e0 aucune accusation ni aucun changement dans ce secteur, au c\u0153ur du miracle de l\u2019ouverture \u00e9conomique et politique ouzb\u00e8ke depuis l\u2019arriv\u00e9e \u00e0 la pr\u00e9sidence de Chavkat Mirzio\u00efev fin 2016.<b>\u00a0<\/b><\/p>\n<p><b>Alors que l\u2019ampleur de Sardoba et sa visibilit\u00e9 sont historiques, les financeurs et investisseurs internationaux qui ont soutenu l\u2019Ouzb\u00e9kistan et sa strat\u00e9gie d\u2019ouverture pourraient \u00eatre fortement refroidis si des mesures radicales et profondes ne sont pas prises par les autorit\u00e9s pour mettre fin \u00e0 des pratiques d\u00e9l\u00e9t\u00e8res et dangereuses. L\u2019Ouzb\u00e9kistan pourrait bien \u00eatre en train de jouer sa r\u00e9ussite \u00e9conomique et son ouverture dans la fa\u00e7on dont les autorit\u00e9s vont r\u00e9gler les probl\u00e8mes soulev\u00e9s par l\u2019effondrement de Sardoba.<\/b><b>\u00a0<\/b><\/p>\n<p><b>D\u00e9cryptage de <a href=\"https:\/\/novastan.org\/fr\/decryptage\/la-catastrophe-de-sardoba-pourrait-elle-menacer-louverture-ouzbeke\/\">l\u2019importance politique et \u00e9conomique<\/a> de ce qui est en train de se jouer autour du secteur de la construction en Ouzb\u00e9kistan apr\u00e8s Sardoba.<\/b><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><em>Ces deux paragraphes ne sont que le d\u00e9but de notre d\u00e9cryptage hebdomadaire r\u00e9serv\u00e9 \u00e0 nos soutiens, envoy\u00e9 tous les mardis matins directement dans leur bo\u00eete mail. Pour le recevoir dans votre bo\u00eete, vous pouvez nous soutenir\u00a0<a href=\"https:\/\/www.okpal.com\/soutenez-novastan-seul-media-francais-sur-l-asie\/#\/\" data-amber-behavior=\"down hover:2\" data-versiondate=\"2020-01-22T17:09:21+00:00\" data-versionurl=\"https:\/\/novastan.org\/fr\/amber\/cache\/cbdd60866d44a75348adc83d1a3cd2c0\/\">\u00e0 partir de 2 euros par mois<\/a>. Pour en savoir plus sur notre philosophie, nous vous avons\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/devenez-membre-devenez-novastan\/\">tout expliqu\u00e9 par ici.<\/a>\u00a0Une question, une demande ? Notre email :\u00a0<a href=\"mailto:novastan.france@novastan.org\" target=\"_blank\" rel=\"noopener\">novastan.france@novastan.org<\/a><\/em><\/p>\n<p><strong>Nos d\u00e9cryptages des semaines pr\u00e9c\u00e9dentes :\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/novastan.org\/fr\/decryptage\/le-statut-de-membre-observateur-de-lunion-economique-eurasiatique-seme-la-discorde-en-ouzbekistan\/\" target=\"_blank\" rel=\"noopener\">Le statut de membre observateur de l\u2019Union \u00e9conomique eurasiatique s\u00e8me la discorde en Ouzb\u00e9kistan<\/a>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/novastan.org\/fr\/decryptage\/des-dizaines-de-milliards-pour-lasie-centrale-les-institutions-financieres-internationales-mettent-le-paquet-face-a-la-crise\/\" target=\"_blank\" rel=\"noopener\">Des dizaines de milliards pour l\u2019Asie centrale : les institutions financi\u00e8res internationales mettent le paquet face \u00e0 la crise<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/novastan.org\/fr\/decryptage\/le-kazakhstan-vient-en-aide-a-ses-citoyens-touches-par-le-coronavirus\/\" target=\"_blank\" rel=\"noopener\">Le Kazakhstan vient en aide \u00e0 ses citoyens touch\u00e9s par le coronavirus<\/a><\/strong><\/p>\n<p>[mkd_separator class_name=\u00a0\u00bb\u00a0\u00bb type=\u00a0\u00bbfull-width\u00a0\u00bb position=\u00a0\u00bbcenter\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb\u00a0\u00bb thickness=\u00a0\u00bb5&Prime; top_margin=\u00a0\u00bb\u00a0\u00bb bottom_margin=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h1 class=\"null\">Notre photo de la semaine<\/h1>\n<figure id=\"attachment_31809\" aria-describedby=\"caption-attachment-31809\" style=\"width: 1333px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31809\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/493.-Karimkols-plant-nursery-farm-Ala-Buka.jpg\" alt=\"\" width=\"1333\" height=\"2000\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/493.-Karimkols-plant-nursery-farm-Ala-Buka.jpg 1333w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/493.-Karimkols-plant-nursery-farm-Ala-Buka-200x300.jpg 200w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/493.-Karimkols-plant-nursery-farm-Ala-Buka-768x1152.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/493.-Karimkols-plant-nursery-farm-Ala-Buka-682x1024.jpg 682w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/05\/493.-Karimkols-plant-nursery-farm-Ala-Buka-1300x1950.jpg 1300w\" sizes=\"auto, (max-width: 1333px) 100vw, 1333px\" \/><figcaption id=\"caption-attachment-31809\" class=\"wp-caption-text\">L&rsquo;agriculteur Karimkol au travail dans sa ferme d&rsquo;Ala-Buka au Kirghizistan.<\/figcaption><\/figure>\n<p><em>L\u2019agriculteur Karimkol au travail dans sa ferme d\u2019Ala-Buka au Kirghizstan.<\/em><em>\u00a0<\/em><em><a href=\"https:\/\/novastan.org\/fr\/photo-du-jour\/karimkol\/\">Plus d&rsquo;infos par ici.<\/a><\/em><\/p>\n<p>[mkd_separator class_name=\u00a0\u00bb\u00a0\u00bb type=\u00a0\u00bbfull-width\u00a0\u00bb position=\u00a0\u00bbcenter\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb\u00a0\u00bb thickness=\u00a0\u00bb5&Prime; top_margin=\u00a0\u00bb\u00a0\u00bb bottom_margin=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h1 class=\"null\">Dans le reste de l&rsquo;actu<\/h1>\n<p class=\"null\"><strong>Le ministre de la Sant\u00e9 du Tadjikistan limog\u00e9 en pleine pand\u00e9mie de coronavirus.<\/strong>\u00a0Le 5 mai dernier, le ministre de la Sant\u00e9 tadjik Nasim Olimzoda a \u00e9t\u00e9 limog\u00e9\u00a0<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/le-ministre-de-la-sante-du-tadjikistan-limoge-en-pleine-pandemie-de-coronavirus\/\" target=\"_blank\" rel=\"noopener\">par d\u00e9cret pr\u00e9sidentiel.\u00a0<\/a>Apr\u00e8s des semaines de d\u00e9n\u00e9gations, les autorit\u00e9s doivent faire face \u00e0 une forte hausse des cas de coronavirus et ont d\u00fb repenser leur communication.<\/p>\n<p><strong>Le Turkm\u00e9nistan devient membre observateur de l\u2019OMC.<\/strong>\u00a0Le pays<a href=\"https:\/\/novastan.org\/fr\/turkmenistan\/le-turkmenistan-devient-membre-observateur-de-lomc\/\" target=\"_blank\" rel=\"noopener\">\u00a0rejoint ses voisins centrasiatiques<\/a>, d\u00e9j\u00e0 tous membres ou observateurs de l\u2019organisation.<\/p>\n<p><strong>Un Panth\u00e9on national pour les \u00e9lites du Kazakhstan.\u00a0<\/strong>Initiative controvers\u00e9e depuis ses d\u00e9buts, la construction d\u2019un tel \u00e9difice\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/un-pantheon-national-pour-les-elites-du-kazakhstan\/\" target=\"_blank\" rel=\"noopener\">risque de co\u00fbter cher au Kazakhstan<\/a>, touch\u00e9 de plein fouet par la crise du Covid-19.<\/p>\n<p><strong>L\u2019Est du Turkm\u00e9nistan ravag\u00e9 par une temp\u00eate.\u00a0<\/strong>De nombreux d\u00e9g\u00e2ts mat\u00e9riels et humains sont \u00e0 d\u00e9plorer dans la r\u00e9gion de Lebap. La situation\u00a0<a href=\"https:\/\/novastan.org\/fr\/turkmenistan\/lest-du-turkmenistan-ravage-par-une-tempete\/\" target=\"_blank\" rel=\"noopener\">est encore difficilement \u00e9valuable.<\/a>\u00a0La r\u00e9action du gouvernement semble quant \u00e0 elle indigner une grande partie de la population.<\/p>\n<p><strong>Malgr\u00e9 la pand\u00e9mie, Carrefour maintient ses objectifs en Ouzb\u00e9kistan.<\/strong>\u00a0Le g\u00e9ant fran\u00e7ais de la distribution a confirm\u00e9, par la voix de son partenaire \u00e9mirati Majid Al Futtaim, que quatre magasins ouvriraient<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/malgre-la-pandemie-carrefour-maintient-ses-objectifs-en-ouzbekistan\/\" target=\"_blank\" rel=\"noopener\">\u00a0bien d\u2019ici fin 2020 \u00e0 Tachkent.<\/a><\/p>\n<p><strong>L\u2019Ouzb\u00e9kistan cr\u00e9e une division de \u00ab\u00a0blogueurs patriotiques\u00a0\u00bb.<\/strong>\u00a0Cette strat\u00e9gie alimente de nombreux d\u00e9bats sur les potentiels d\u00e9rives\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/louzbekistan-cree-une-division-de-blogueurs-patriotiques\/\" target=\"_blank\" rel=\"noopener\">d\u2019une politique d\u2019influence num\u00e9rique<\/a>\u00a0qui n\u2019est pas sans rappeler les \u00ab\u00a0fermes \u00e0 trolls\u00a0\u00bb russes.<\/p>\n<p><strong>Capitalisme, mythe et folklore : dans les coulisses d\u2019un documentaire sp\u00e9cial sur le Kazakhstan.\u00a0<\/strong>Le festival suisse Visions du R\u00e9el propose sur son site un nouveau documentaire sur le Kazakhstan,\u00a0<em>On a Clear Day You Can See the Revolution from\u00a0Here<\/em>. \u00c0 cette occasion, Novastan\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/capitalisme-mythe-et-folklore-dans-les-coulisses-dun-documentaire-special-sur-le-kazakhstan\/\" target=\"_blank\" rel=\"noopener\">a rencontr\u00e9 les r\u00e9alisateurs<\/a>\u00a0pour en savoir plus sur leur projet.<\/p>\n<p><strong>La tombe d\u2019un aristocrate kouchan d\u00e9couverte lors de fouilles au Tadjikistan.<\/strong>\u00a0De la monnaie et des objets ont \u00e9galement \u00e9t\u00e9 mis au jour. A son apog\u00e9e au II\u00e8me si\u00e8cle de notre \u00e8re, l\u2019Empire kouchan\u00a0<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/la-tombe-dun-aristocrate-kouchan-decouverte-lors-de-fouilles-au-tadjikistan\/\" target=\"_blank\" rel=\"noopener\">s\u2019\u00e9tendait de l\u2019Asie centrale jusqu\u2019\u00e0 l\u2019Inde.<\/a><\/p>\n<p><strong>Quand le rock and roll sovi\u00e9tique faisait danser Douchanb\u00e9.<\/strong>\u00a0Bien que dans le Douchanb\u00e9 de l\u2019\u00e9poque ce genre de musique soit appel\u00e9 \u00ab\u00a0Ensemble Vocalo-Instrumental\u00a0\u00bb (EVI), la ville a toujours\u00a0<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/quand-le-rock-and-roll-sovietique-faisait-danser-douchanbe\/\" target=\"_blank\" rel=\"noopener\">abrit\u00e9 des personnes fans de rock.<\/a><\/p>\n<p><strong>Kassym-Jomart Toka\u00efev proc\u00e8de \u00e0 des nominations en s\u00e9rie.<\/strong>\u00a0Le pr\u00e9sident kazakh a nomm\u00e9 certains de ses proches\u00a0aux plus hauts \u00e9chelons de l\u2019\u00c9tat, suite au limogeage\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/dariga-nazarbaieva-demise-de-ses-fonctions-de-numero-2-de-letat-kazakh\/\" target=\"_blank\" rel=\"noopener\">de Dariga Nazarba\u00efeva<\/a>. Des changements qui pourraient laisser entendre que le pr\u00e9sident Kassym-Jomart Toka\u00efev\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/nouvelles-nominations-au-kazakhstan-vers-un-renforcement-des-pouvoirs-du-president\/\" target=\"_blank\" rel=\"noopener\">chercherait \u00e0 renforcer son influence.<\/a><\/p>\n<p><strong>Une entreprise ouzb\u00e8ke exclue des projets de la Banque mondiale pour fraude.\u00a0<\/strong>La Banque mondiale a radi\u00e9 la soci\u00e9t\u00e9 ouzb\u00e8ke Mega-Mebiko JV LLC de ses projets pour une dur\u00e9e de 30 mois. La compagnie a\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/une-entreprise-ouzbeke-exclue-des-projets-de-la-banque-mondiale-pour-fraude\/\" target=\"_blank\" rel=\"noopener\">reconnu avoir fraud\u00e9<\/a>\u00a0dans le cadre d\u2019un projet financ\u00e9 par l\u2019institution.<\/p>\n<p><strong>Un p\u00eacheur az\u00e9ri tu\u00e9 par les garde-c\u00f4tes kazakhs en mer Caspienne.<\/strong>\u00a0Le 30 avril, les garde-c\u00f4tes kazakhs ont tu\u00e9\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/un-pecheur-azeri-tue-par-les-garde-cotes-kazakhs-en-mer-caspienne\/\" target=\"_blank\" rel=\"noopener\">un membre d\u2019\u00e9quipage d\u2019un navire de p\u00eache az\u00e9ri<\/a>, entr\u00e9 ill\u00e9galement dans les eaux territoriales du pays sur la mer Caspienne.<\/p>\n<p><strong>Le d\u00e9veloppement du num\u00e9rique s\u2019acc\u00e9l\u00e8re en Ouzb\u00e9kistan.\u00a0<\/strong>Un d\u00e9cret du pr\u00e9sident Chavkat Mirizio\u00efev a pour vocation d\u2019int\u00e9grer le num\u00e9rique dans une large majorit\u00e9 des administrations et des activit\u00e9s \u00e9conomiques\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/le-developpement-du-numerique-saccelere-en-ouzbekistan\/\" target=\"_blank\" rel=\"noopener\">dans les trois prochaines ann\u00e9es.<\/a><\/p>\n<p><strong>Un pan de l&rsquo;histoire d&rsquo;Achgabat, la capitale turkm\u00e8ne au million d&rsquo;habitants<\/strong>.\u00a0Connue pour son architecture ostentatoire et son marbre blanc immacul\u00e9, la capitale turkm\u00e8ne a franchi le seuil du million d\u2019habitants durant l\u2019\u00e9t\u00e9 2018.\u00a0<a href=\"http:\" target=\"_blank\" rel=\"noopener\">Retour sur une histoire mouvement\u00e9e.<\/a><\/p>\n<p><strong>L\u2019opposition en Ouzb\u00e9kistan\u00a0: \u00eatre ou ne pas \u00eatre.<\/strong>\u00a0Avec le changement de pr\u00e9sident en 2016, on observe\u00a0<a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/lopposition-en-ouzbekistan-etre-ou-ne-pas-etre\/\" target=\"_blank\" rel=\"noopener\">une diminution de la crainte parmi la population<\/a>. Pour autant, la frustration est grande chez de nombreux Ouzbeks, car le pays ne change pas assez vite.<\/p>\n<p><strong>La Chine partout pr\u00e9sente au Tadjikistan.<\/strong>\u00a0L\u2019influence de la Chine au Tadjikistan se renforce chaque ann\u00e9e, au point que P\u00e9kin a aujourd\u2019hui un pied dans pratiquement toutes les activit\u00e9s du pays, depuis les investissements\u00a0<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/la-chine-partout-presente-au-tadjikistan\/\" target=\"_blank\" rel=\"noopener\">jusqu\u2019au soutien militaire.<\/a><\/p>\n<p><strong>Un lac \u00e0 proximit\u00e9 d\u2019un ancien gisement d\u2019uranium se r\u00e9v\u00e8le pollu\u00e9 au Kazakhstan.<\/strong>\u00a0Si la qualit\u00e9 de l\u2019air de la zone \u00e9tudi\u00e9e est aux normes, ce n\u2019est en revanche pas le cas pour celle de l\u2019eau. Ce lac\u00a0<a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/kazakhstan-un-lac-a-proximite-dun-ancien-gisement-duranium-se-revele-pollue\/\" target=\"_blank\" rel=\"noopener\">est pourtant fr\u00e9quent\u00e9 par les habitants de la r\u00e9gion<\/a>\u00a0qui viennent s\u2019y reposer et s\u2019y baigner.<\/p>\n<h1 class=\"null\">&#8230;chez Novastan France<\/h1>\n<p><strong>Novastan lance son projet de refonte de son site Web.<\/strong>\u00a0Au programme : un site plus rapide, plus clair, plus s\u00e9curis\u00e9. Pour y parvenir, nous avons besoin de votre soutien ! Les d\u00e9tails du projet\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan\/un-plan-de-refonte-pour-le-site-web-de-novastan\/\" target=\"_blank\" rel=\"noopener\">se trouvent par ici.<\/a><\/p>\n<p><strong>Novastan officiellement reconnu comme m\u00e9dia en France.\u00a0<\/strong>Durant sa s\u00e9ance de mars 2020, la Commission paritaire des publications et agences de presse (CPPAP) a reconnu Novastan France comme\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/novastan-officiellement-reconnu-comme-media-en-ligne\/\" target=\"_blank\" rel=\"noopener\">un\u00a0<\/a><a href=\"https:\/\/novastan.org\/fr\/novastan-france\/novastan-officiellement-reconnu-comme-media-en-ligne\/\">service de presse en ligne<\/a>, au titre de l\u2019information politique et g\u00e9n\u00e9rale. Une nouvelle \u00e9tape pour notre projet !<\/p>\n<p><strong>Envie de nous aider ?\u00a0Novastan recherche des traducteurs, des r\u00e9dacteurs et des \u00e9diteurs.\u00a0<\/strong>Tous les moyens de contribuer \u00e0 notre projet c\u00f4t\u00e9 r\u00e9daction\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/contribuer-a-la-redaction-de-novastan\/\" target=\"_blank\" rel=\"noopener\">sont expliqu\u00e9s par ici.<\/a>\u00a0Si vous souhaitez nous aider sur le c\u00f4t\u00e9 associatif, nous essayons d&rsquo;organiser des \u00e9v\u00e8nements, festifs ou non. <a href=\"https:\/\/novastan.org\/fr\/novastan-france\/devenez-membre-devenez-novastan\/\">Les d\u00e9tails par ici<\/a>.<\/p>\n<p><strong>Novastan est le seul m\u00e9dia franco-allemand sur l\u2019Asie centrale.\u00a0<\/strong>Pour soutenir notre ind\u00e9pendance, devenez membre de la communaut\u00e9\u00a0Novastan !\u00a0Vous pouvez nous soutenir\u00a0<a href=\"https:\/\/www.okpal.com\/soutenez-novastan-seul-media-francais-sur-l-asie\/#\/\" target=\"_blank\" rel=\"noopener\">\u00e0 partir de 2 euros par mois<\/a>. Cela permet \u00e0\u00a0Novastan\u00a0de se professionnaliser tout en renfor\u00e7ant une communaut\u00e9 autour de l\u2019Asie centrale en France et en Europe.\u00a0<a href=\"https:\/\/novastan.org\/fr\/novastan-france\/devenez-membre-devenez-novastan\/\" target=\"_blank\" rel=\"noopener\">Tous les d\u00e9tails se trouvent ici<\/a>.<\/p>\n<p><strong>La r\u00e9daction<\/strong><\/p>\n<p>Merci de nous avoir lu jusqu&rsquo;au bout ! Rendez-vous d\u00e8s la semaine prochaine pour plus d&rsquo;informations sur l&rsquo;Asie centrale. Pour plus d&rsquo;infos au quotidien,\u00a0n&rsquo;h\u00e9sitez pas \u00e0 nous suivre sur\u00a0<a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=43466d9d21&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=9b56fd2518&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Twitter<\/a>, <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=1c21104214&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=dcc599a9fc&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Instagram<\/a> ou <a href=\"https:\/\/novastan.us4.list-manage.com\/track\/click?u=6a15a2256d412b041fdec39e8&amp;id=c94d32b198&amp;e=cf79850cee\" target=\"_blank\" rel=\"noopener\">Telegram<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ci-dessous une reproduction de notre newsletter hebdomadaire du 11 mai 2020, envoy\u00e9e gratuitement tous les lundis. Si vous souhaitez la recevoir directement dans votre bo\u00eete mail,\u00a0inscrivez-vous ici. En attendant, bonne lecture ! Cette newsletter est d\u00e9di\u00e9e \u00e0 l\u2019Asie centrale.\u00a0Chaque semaine, nous vous r\u00e9sumons les diff\u00e9rentes actualit\u00e9s de la r\u00e9gion, tout en vous proposant [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":31873,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2469],"tags":[1379],"coauthors":[108],"class_list":["post-31943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","tag-newsletter"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/31943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=31943"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/31943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/31873"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=31943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=31943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=31943"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=31943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}