{"id":29872,"date":"2020-03-27T10:29:02","date_gmt":"2020-03-27T09:29:02","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=29872"},"modified":"2021-04-07T18:11:06","modified_gmt":"2021-04-07T16:11:06","slug":"dans-les-coulisses-de-la-construction-tourmentee-du-barrage-de-toktogoul","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/kirghizstan\/dans-les-coulisses-de-la-construction-tourmentee-du-barrage-de-toktogoul\/","title":{"rendered":"Dans les coulisses de la construction tourment\u00e9e du barrage de Toktogoul"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>La centrale hydro\u00e9lectrique de Toktogoul, dans le centre du Kirghizstan, est l\u2019une des principales sources d\u2019\u00e9lectricit\u00e9 du pays, tout en repr\u00e9sentant son plus grand lac de retenue. Achev\u00e9e en 1976 apr\u00e8s une quinzaine d\u2019ann\u00e9es de travaux, sa construction n\u2019a pas \u00e9t\u00e9 de tout repos.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Novastan reprend et traduit ici un article publi\u00e9 le 26 avril 2019 par <a href=\"https:\/\/fergana.agency\/articles\/106757\/\">le m\u00e9dia russe Fergana News.<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">Quelle importance a pu avoir la centrale hydro\u00e9lectrique de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Barrage_de_Toktogul\">Toktogoul<\/a> et d\u2019autres grands chantiers du socialisme pour les anciennes R\u00e9publiques sovi\u00e9tiques d\u2019Asie centrale\u00a0? Comment ces projets, cens\u00e9s apporter la modernit\u00e9, fournir l\u2019\u00e9lectricit\u00e9 et la civilisation aux confins de l\u2019Union sovi\u00e9tique et servir de tremplin vers le socialisme, sont-ils devenus sources de conflits\u00a0? Pourquoi les R\u00e9publiques socialistes sovi\u00e9tiques (RSS) ouzb\u00e8ke et kirghize, derri\u00e8re leurs grands discours sur la solidarit\u00e9 fraternelle, se sont-elles finalement \u00e9charp\u00e9es dans la lutte pour les ressources\u00a0?<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p style=\"text-align: justify\">Toutes ces questions sont abord\u00e9es dans <a href=\"https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/02634937.2019.1584604?journalCode=ccas20\">un article<\/a> de <a href=\"https:\/\/www.osteuropa.phil.fau.de\/person\/dr-moritz-florin\/\">Moritz Florin<\/a>, professeur \u00e0 l\u2019Universit\u00e9 d\u2019Erlangen-Nuremberg et auteur d\u2019une histoire politique de la centrale hydro\u00e9lectrique de Toktogoul. Le sp\u00e9cialiste a \u00e9pluch\u00e9 les articles de presse sovi\u00e9tiques des ann\u00e9es 1960-1970, la litt\u00e9rature scientifique consacr\u00e9e au projet, les m\u00e9moires en plusieurs volumes de l\u2019ancien Premier secr\u00e9taire du Parti communiste de la RSS du Kirghizstan, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Tourdakoun_Oussoubaliev\">Tourdakoun Oussoubaliev<\/a>, ainsi que des documents d\u2019archives provenant <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/och-ville-frontiere-du-kirghizstan\/\">d\u2019Och<\/a> et de Bichkek. Il livre ses conclusions dans un article intitul\u00e9 <em>\u00ab\u00a0Emptying lakes, filling up seas: hydroelectric dams and the ambivalences of development in late Soviet central Asia\u00a0\u00bb<\/em>, publi\u00e9 par la revue <em>Central Asian Survey <\/em>le 20 mars 2019.<\/p>\n<p style=\"text-align: justify\"><strong>Un chantier du socialisme et un pas en avant<\/strong><\/p>\n<p style=\"text-align: justify\">Au cours du mandat de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nikita_Khrouchtchev\">Nikita Khrouchtchev<\/a> (1953-1964) en URSS, les mouvements de lib\u00e9ration nationale dirig\u00e9s contre les puissances coloniales se sont multipli\u00e9s en Asie et en Afrique. Moscou y a jou\u00e9 un r\u00f4le actif pour tenter d\u2019attirer les pays du tiers monde dans le camp du socialisme. Pour les historiens, les dirigeants des R\u00e9publiques centrasiatiques ont profit\u00e9 d\u2019une conjoncture de politique ext\u00e9rieure favorable pour augmenter les investissements dans leur \u00e9conomie. Sur ce plan, les R\u00e9publiques du sud du pays servaient de vitrine pour les \u00c9tats d\u2019Asie et d\u2019Afrique dans la strat\u00e9gie du \u00ab\u00a0Socialisme \u00e0 l\u2019Est\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify\">L\u2019id\u00e9e de construire une centrale hydro\u00e9lectrique sur la rivi\u00e8re <a href=\"https:\/\/en.wikipedia.org\/wiki\/Naryn_River\">Naryn<\/a>, reliant les monts du <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/la-fonte-des-glaciers-du-tian-chan-un-danger-de-long-terme-en-asie-centrale\/\">Tian Chan<\/a> \u00e0 l\u2019Ouzb\u00e9kistan, a \u00e9t\u00e9 propos\u00e9e pour la premi\u00e8re fois en 1960 par les Premiers secr\u00e9taires du Parti communiste des RSS d\u2019Ouzb\u00e9kistan <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sharof_Rashidov\">Charaf Rachidov<\/a>, et du Kirghizstan <a href=\"https:\/\/ru.wikipedia.org\/wiki\/%D0%A0%D0%B0%D0%B7%D0%B7%D0%B0%D0%BA%D0%BE%D0%B2,_%D0%98%D1%81%D1%85%D0%B0%D0%BA_%D0%A0%D0%B0%D0%B7%D0%B7%D0%B0%D0%BA%D0%BE%D0%B2%D0%B8%D1%87\">Ichak Razzakov<\/a>. Les autorit\u00e9s kirghizes souhaitaient augmenter l\u2019approvisionnement en \u00e9lectricit\u00e9 pour <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/pichpek-frounze-bichkek-la-ville-dont-il-est-impossible-de-ne-pas-tomber-amoureux\/\">Frounz\u00e9<\/a>, le nom port\u00e9 par la capitale Bichkek entre 1926 et 1992, et Och, tandis que Tachkent voulait assurer des fournitures d\u2019eau r\u00e9guli\u00e8res dans <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Vall%C3%A9e_de_Ferghana\">la vall\u00e9e de Ferghana<\/a>. Le journal officiel <em>Pravda<\/em>\u00a0se faisait le reflet de la m\u00e9galomanie sovi\u00e9tique en \u00e9crivant que la centrale devait permettre aux cultivateurs de coton de Ferghana de gagner des centaines de milliers, voire deux \u00e0 quatre millions d\u2019hectares de terres irrigu\u00e9es. Les autorit\u00e9s voulaient m\u00eame construire sur les rives de ce lac artificiel des stations baln\u00e9aires qui n\u2019auraient rien \u00e0 envier \u00e0 celles de la mer Noire.<\/p>\n<p style=\"text-align: justify\">La d\u00e9cision de construire la centrale de Toktogoul, symbole d\u2019amiti\u00e9 entre les peuples, n\u2019a toutefois \u00e9t\u00e9 prise qu\u2019en juin 1962, apr\u00e8s la d\u00e9mission d\u2019Ichak Razzakov. Son successeur \u00e0 la t\u00eate du Kirghizstan, Tourdakoun Oussoubaliev, note dans ses m\u00e9moires qu\u2019il n\u2019\u00e9tait pas un ardent d\u00e9fenseur d\u2019un projet de centrale hydro\u00e9lectrique et qu\u2019il lui pr\u00e9f\u00e9rait celui, plus modeste mais plus utile, d\u2019une s\u00e9rie de petites centrales thermiques autour de Frounz\u00e9 et ses industries. Le barrage ayant \u00e9t\u00e9 inclus dans les grands projets de construction du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Komsomol\">Komsomol<\/a>, la jeunesse communiste, des milliers de travailleurs de toute l\u2019URSS ont particip\u00e9 \u00e0 son \u00e9rection et la presse n\u2019a pas manqu\u00e9 de souligner l\u2019aide apport\u00e9e par les R\u00e9publiques plus d\u00e9velopp\u00e9es aux industries de l\u2019arri\u00e8re-pays de l\u2019ancienne Russie tsariste.<\/p>\n<figure id=\"attachment_29876\" aria-describedby=\"caption-attachment-29876\" style=\"width: 496px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29876\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/ddf56ed0-5893-45eb-b35a-e4f0be0d98c1.jpeg\" alt=\"Naryn Rivi\u00e8re Toktogoul Barrage Kirghizstan Eau Lac Electricit\u00e9 Histoire\" width=\"496\" height=\"308\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/ddf56ed0-5893-45eb-b35a-e4f0be0d98c1.jpeg 496w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/ddf56ed0-5893-45eb-b35a-e4f0be0d98c1-300x186.jpeg 300w\" sizes=\"auto, (max-width: 496px) 100vw, 496px\" \/><figcaption id=\"caption-attachment-29876\" class=\"wp-caption-text\">Construction du barrage sur la rivi\u00e8re Naryn.<\/figcaption><\/figure>\n<p style=\"text-align: justify\">En outre, \u00e0 l\u2019instar des centrales hydro\u00e9lectriques du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Dniepr\">Dniepr<\/a> et de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Barrage_de_Bratsk\">Bratsk<\/a>, le projet a \u00e9t\u00e9 pr\u00e9sent\u00e9 comme un symbole de la victoire \u00e9clatante sur la nature\u00a0: l\u2019escalade h\u00e9ro\u00efque des ouvriers arpentant les falaises escarp\u00e9es et hissant m\u00eame des bulldozers, la participation de 523 alpinistes provenant de toute l\u2019Union sovi\u00e9tique, acc\u00e9dant \u00e0 des endroits o\u00f9 seuls les l\u00e9opards des neiges avaient jusqu\u2019alors mis le pied, l\u2019apprivoisement, gr\u00e2ce \u00e0 la force collective, de la tumultueuse rivi\u00e8re Naryn.<\/p>\n<p style=\"text-align: justify\">Mais ce projet est avant tout la r\u00e9ussite du peuple kirghiz, comme en atteste son nom, inspir\u00e9 par le c\u00e9l\u00e8bre po\u00e8te et barde traditionnel (<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Akyn\">akyn<\/a><\/em>) local <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Toktogul_Satilganov\">Toktogoul Satilganov<\/a>, dont le village a \u00e9t\u00e9 noy\u00e9 par les eaux du barrage. Tous louaient alors la magnificence de la construction : le po\u00e8te sovi\u00e9tique et h\u00e9ros kirghiz <a href=\"https:\/\/ru.wikipedia.org\/wiki\/%D0%AD%D1%80%D0%B0%D0%BB%D0%B8%D0%B5%D0%B2,_%D0%A1%D1%83%D1%8E%D0%BD%D0%B1%D0%B0%D0%B9\">Sou\u00efounba\u00ef Eraliev<\/a> la comparait \u00e0 la domestication de chevaux sauvages, tandis que le journaliste <a href=\"https:\/\/ky.wikipedia.org\/wiki\/%D0%9A%D0%BE%D0%B6%D0%BE%D0%BC%D0%B1%D0%B5%D1%80%D0%B4%D0%B8%D0%B5%D0%B2_%D0%A2%D1%83%D1%80%D0%B0%D1%80\">Tourar Kojomberdiev<\/a> assurait ses lecteurs qu\u2019une fois le projet achev\u00e9, plus aucune force naturelle ne pourrait plus mettre en danger les bergers et leurs troupeaux.<\/p>\n<p style=\"text-align: justify\"><strong>De l\u2019eau contre des investissements<\/strong><\/p>\n<p style=\"text-align: justify\">Selon les autorit\u00e9s, la centrale hydro\u00e9lectrique devait b\u00e9n\u00e9ficier \u00e0 tous\u00a0: davantage d\u2019\u00e9lectricit\u00e9 c\u00f4t\u00e9 kirghiz, un approvisionnement constant en eau pour les exploitations de coton ouzb\u00e8kes et une union de tous les peuples de la grande famille sovi\u00e9tique pour le r\u00e9aliser. Cependant, nombre de probl\u00e8mes surgirent avant m\u00eame le d\u00e9but des travaux\u00a0: l\u2019irrigation des terres ouzb\u00e8kes, par exemple, d\u00e9pendait de la bonne volont\u00e9 de Frounz\u00e9 et, <em>in fine<\/em>, de Moscou.<\/p>\n<p style=\"text-align: justify\">En avril\u00a01962, alors que le barrage n\u2019\u00e9tait encore qu\u2019un projet, la vall\u00e9e de Fergana est touch\u00e9e par une grave s\u00e9cheresse. Le chef du d\u00e9partement de l\u2019Agriculture du Comit\u00e9 central du Parti communiste de l\u2019Union sovi\u00e9tique, <a href=\"https:\/\/ru.wikipedia.org\/wiki\/%D0%9F%D0%BE%D0%BB%D1%8F%D0%BA%D0%BE%D0%B2,_%D0%92%D0%B0%D1%81%D0%B8%D0%BB%D0%B8%D0%B9_%D0%98%D0%B2%D0%B0%D0%BD%D0%BE%D0%B2%D0%B8%D1%87_(%D0%BF%D0%B0%D1%80%D1%82%D0%B8%D0%B9%D0%BD%D1%8B%D0%B9_%D0%B4%D0%B5%D1%8F%D1%82%D0%B5%D0%BB%D1%8C)\">Vassily Poliakov<\/a>, soumet alors \u00e0 Tourdakoun Oussoubaliev l\u2019id\u00e9e de proc\u00e9der \u00e0 des explosions dans le lac <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lac_Son_Koul\">Son Koul<\/a> afin d\u2019en augmenter le d\u00e9bit vers la rivi\u00e8re Naryn, son affluent. De son propre aveu, le Premier secr\u00e9taire \u00e9tait sous le choc. Le lac Son Koul se distingue en effet par ses conditions naturelles et ses paysages uniques. En outre, les experts inform\u00e8rent le Premier secr\u00e9taire que si cette id\u00e9e \u00e9tait appliqu\u00e9e, le lac s\u2019\u00e9puiserait en dix \u00e0 quinze jours \u00e0 peine. Tourdakoun Oussoubaliev s\u2019adressa alors personnellement \u00e0 Nikita Khrouchtchev et parvint, non sans mal, \u00e0 le convaincre d\u2019arr\u00eater le projet et mettre de c\u00f4t\u00e9 les int\u00e9r\u00eats personnels pour pr\u00e9server le lac.<\/p>\n<p style=\"text-align: justify\">Le d\u00e9but de la construction a \u00e9t\u00e9 marqu\u00e9 par une multiplication des conflits, \u00e0 commencer par celui concernant le lieu d\u2019installation de la centrale. Les autorit\u00e9s kirghizes souhaitaient choisir un endroit en amont de la rivi\u00e8re Naryn pour inonder moins de terre, tandis que Douchanb\u00e9 pr\u00e9f\u00e9rait un lieu en aval, qui permettrait de b\u00e9n\u00e9ficier d\u2019un r\u00e9servoir d\u2019eau plus vaste pour l\u2019irrigation des terres. De violentes disputes \u00e9clat\u00e8rent par ailleurs aux emplacements futurs des lignes \u00e0 haute tension. D\u00e8s\u00a01962, les Kirghiz demand\u00e8rent au minist\u00e8re de l\u2019\u00c9nergie sovi\u00e9tique que Frounz\u00e9 soit rapidement aliment\u00e9e en \u00e9lectricit\u00e9. Or, la capitale n\u2019a \u00e9t\u00e9 int\u00e9gr\u00e9e au r\u00e9seau qu\u2019en 1979, bien apr\u00e8s la ville ouzb\u00e8ke <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Andijan\">d\u2019Andijan<\/a>, situ\u00e9e dans la vall\u00e9e de Ferghana.<\/p>\n<p style=\"text-align: justify\">Les autorit\u00e9s ouzb\u00e8kes sont \u00e0 nouveau avantag\u00e9es en 1974, lorsqu\u2019une nouvelle vague de s\u00e9cheresse touche la vall\u00e9e de Ferghana. Elles demandent en effet que l\u2019eau du barrage soit d\u00e9vers\u00e9e dans les champs, ce \u00e0 quoi s\u2019oppos\u00e8rent en vain les ing\u00e9nieurs kirghiz, car cette mesure signifiait un retard d\u2019un an pour le lancement des turbines de la centrale. Une nouvelle fois, le coton l\u2019emportait.<\/p>\n<figure id=\"attachment_29875\" aria-describedby=\"caption-attachment-29875\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29875\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k.jpg\" alt=\"Toktogoul Barrage Kirghizstan Eau Lac Electricit\u00e9 Histoire\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k.jpg 2048w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k-300x200.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k-768x512.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k-1024x683.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k-1300x866.jpg 1300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/8534425182_d26f7a5ae4_k-128x86.jpg 128w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><figcaption id=\"caption-attachment-29875\" class=\"wp-caption-text\">Le lac de retenue, aussi appel\u00e9 r\u00e9servoir de Toktogoul, a cr\u00e9\u00e9 de nouveaux paysages.<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Les dirigeants kirghiz n\u2019ont pourtant pas toujours \u00e9t\u00e9 en reste. Lorsqu\u2019en 1962, un projet de centrale hydro\u00e9lectrique a vu le jour \u00e0 Andijan, sur la rivi\u00e8re <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kara-Daria\">Kara-Daria<\/a>, soit juste \u00e0 c\u00f4t\u00e9 de la rivi\u00e8re Naryn, la majeure partie de son r\u00e9servoir devait \u00eatre situ\u00e9e sur le territoire de la RSS du Kirghizstan. Le Comit\u00e9 central du d\u00e9partement kirghiz du Parti communiste de l\u2019Union sovi\u00e9tique a accept\u00e9, sous certaines conditions, de participer \u00e0 cette <em>\u00ab\u00a0construction \u00e0 la gloire des peuples\u00a0\u00bb<\/em>. Les autorit\u00e9s kirghizes, voyant que le r\u00e9servoir allait inonder quelque 5\u00a0000\u00a0hectares de leurs terres agricoles, propos\u00e8rent qu\u2019une partie du territoire de la RSS d\u2019Ouzb\u00e9kistan leur soit c\u00e9d\u00e9e afin d\u2019y d\u00e9placer les habitants des territoires prochainement inond\u00e9s par les barrages d\u2019Andijan et de Toktogoul. Leurs exigences furent entendues\u00a0: ils re\u00e7urent 4\u00a0127 hectares et la promesse de Tachkent d\u2019allouer des indemnit\u00e9s aux personnes d\u00e9plac\u00e9es et de financer la construction de deux canaux.<\/p>\n<p style=\"text-align: justify\"><strong>Un co\u00fbt de relogement \u00e0 plusieurs millions<\/strong><\/p>\n<p style=\"text-align: justify\">Pour le barrage de Toktogoul, le relogement des habitants des territoires inond\u00e9s, en particulier de la vall\u00e9e de Ketmen-Tioube, a longtemps repr\u00e9sent\u00e9 un v\u00e9ritable casse-t\u00eate pour les autorit\u00e9s. Une partie du co\u00fbt de r\u00e9installation et de construction de maisons a \u00e9t\u00e9 assum\u00e9e par le minist\u00e8re de l\u2019\u00c9nergie sovi\u00e9tique, une autre partie par le Conseil des ministres de la RSS du Kirghizstan. Le Comit\u00e9 de parti de la ville d\u2019Och examina d\u00e8s 1968 la situation sur le terrain et demanda d\u2019urgence des fonds suppl\u00e9mentaires car la vall\u00e9e \u00e9tait habit\u00e9e principalement par d\u2019anciens nomades, transf\u00e9r\u00e9s de force \u00e0 un mode de vie s\u00e9dentaire entre 1946 et 1952 et qui s\u2019\u00e9taient endett\u00e9s pour financer leurs nouvelles maisons.<\/p>\n<p style=\"text-align: justify\">En 1971, rien n\u2019avait encore \u00e9t\u00e9 propos\u00e9 pour reloger les personnes d\u00e9plac\u00e9es. Toktogoul, ville cr\u00e9\u00e9e sur les rives du barrage pour les accueillir, n\u2019\u00e9tait pourvue d\u2019aucun approvisionnement en \u00e9lectricit\u00e9. Tourdakoun Oussoubaliev a \u00e9t\u00e9 alors oblig\u00e9 de s\u2019adresser personnellement au pr\u00e9sident du Conseil des ministres d\u2019URSS, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alexis_Kossyguine\">Alexe\u00ef Kossyguine<\/a>, en soulignant que la RSS du Kirghizstan avait d\u00e9j\u00e0 d\u00e9pens\u00e9 1,6\u00a0fois plus que pr\u00e9vu pour le relogement, mais que cette somme ne suffisait pas. Le seul transfert des \u00e9coles, pour lequel 1,4\u00a0milliard de roubles \u00e9tait pr\u00e9vu, d\u00e9passa de 11 millions de roubles le budget.<\/p>\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n<p style=\"text-align: justify\">Mais le probl\u00e8me le plus \u00e9pineux demeurait la m\u00e9diocrit\u00e9 des terres nouvellement attribu\u00e9es. Les colons durent repasser de l\u2019industrie \u00e0 l\u2019\u00e9levage. D\u00e8s les ann\u00e9es 1970, faute de place, certains \u00e9migr\u00e8rent vers la <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/vallee-de-chatkal\/\">vall\u00e9e de Chatkal<\/a>, plus \u00e0 l\u2019ouest. Par ailleurs, les r\u00eaves de voir Toktogoul devenir un haut lieu du tourisme s\u2019\u00e9vanouirent car les fluctuations du niveau d\u2019eau selon les saisons emp\u00eachaient tout projet de station baln\u00e9aire. Le Conseil des ministres de l\u2019URSS a d\u00e8s lors \u00e9t\u00e9 contraint de poursuivre jusqu\u2019en 1987 les octrois d\u2019indemnit\u00e9s aux personnes d\u00e9plac\u00e9es, soit des dizaines de millions de roubles.<\/p>\n<p style=\"text-align: justify\"><strong>L\u2019\u00e9cologie avant tout\u00a0?<\/strong><\/p>\n<p style=\"text-align: justify\">L\u2019histoire de la centrale hydro\u00e9lectrique de Toktogoul et des conflits qui l\u2019accompagnent montrent clairement l\u2019\u00e9volution de l\u2019Asie centrale sovi\u00e9tique entre les mandats de Nikita Khrouchtchev et de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Mikha%C3%AFl_Gorbatchev\">Mikha\u00efl Gorbatchev<\/a> (1985-1991). L\u2019ampleur des projets d\u00e9passait \u00e0 l\u2019origine les R\u00e9publiques et m\u00eame l\u2019URSS\u00a0: modernisation du concept de \u00ab\u00a0Socialisme \u00e0 l\u2019Est\u00a0\u00bb, d\u00e9veloppement de l\u2019irrigation et de la production de coton, etc. Mais au fil du temps, les int\u00e9r\u00eats et exigences propres des R\u00e9publiques ont pris le pas. Le r\u00f4le de Moscou n\u2019\u00e9tait plus de fixer les objectifs \u00e9conomiques g\u00e9n\u00e9raux, mais de concilier les ambitions personnelles des lobbyistes de Tachkent et de Frounz\u00e9.<\/p>\n<figure id=\"attachment_29874\" aria-describedby=\"caption-attachment-29874\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29874\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k.jpg\" alt=\"Toktogoul Barrage Kirghizstan Eau Lac Electricit\u00e9 Histoire\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k.jpg 2048w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k-300x200.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k-768x512.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k-1024x683.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k-1300x866.jpg 1300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/03\/29473089117_6533a1abf7_k-128x86.jpg 128w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><figcaption id=\"caption-attachment-29874\" class=\"wp-caption-text\">Le barrage a \u00e9t\u00e9 termin\u00e9 en 1976.<\/figcaption><\/figure>\n<p style=\"text-align: justify\">En parall\u00e8le, des voix s\u2019\u00e9lev\u00e8rent pour critiquer les centrales hydro\u00e9lectriques, les barrages, les lignes \u00e0 haute tension et autres infrastructures modernes. L\u2019intelligentsia kirghize des ann\u00e9es 1970 s\u2019insurgea contre les dommages caus\u00e9s \u00e0 l\u2019environnement et aux cultures traditionnelles. Une vague \u00e9cologiste d\u00e9ferla sur l\u2019Union sovi\u00e9tique (comme l\u2019illustre \u00ab\u00a0<em>L\u2019adieu \u00e0 l\u2019\u00eele<\/em>\u00a0\u00bb de Valentin Raspoutine) et s\u2019intensifia jusqu\u2019\u00e0 son effondrement.<\/p>\n<p style=\"text-align: justify\">Et voil\u00e0 que paradoxalement, apr\u00e8s la chute du r\u00e9gime sovi\u00e9tique et la fin du r\u00f4le de Moscou comme arbitre des revendications, cette critique s\u2019est apais\u00e9e. Les centrales hydro\u00e9lectriques sont aujourd\u2019hui devenues une source de fiert\u00e9 nationale, un pilier de l\u2019\u00e9conomie, voire un outil de pression politique sur les voisins. Citons ainsi l\u2019exemple du <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-la-deuxieme-turbine-du-barrage-de-rogun-operationnelle\/\">barrage de Rogun<\/a>, au Tadjikistan, qui pourrait priver l\u2019agriculture ouzb\u00e8ke d\u2019une partie pr\u00e9cieuse de son irrigation. Pour autant, alors que le barrage \u00e9tait une pomme de discorde entre Tadjikistan et Ouzb\u00e9kistan, les deux voisins ont apais\u00e9 leur relation depuis 2018. L\u2019Ouzb\u00e9kistan a ainsi particip\u00e9 <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/barrage-de-rogun-louzbekistan-et-le-tadjikistan-enquetent-ensemble-sur-les-risques-du-projet\/\">\u00e0 l\u2019enqu\u00eate sur les risques du projet<\/a>.<\/p>\n<p style=\"text-align: right\"><strong>Artiom Kosmarsky<br \/>\nR\u00e9dacteur pour Fergana News<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Traduit <a href=\"https:\/\/fergana.agency\/articles\/106757\/\">du russe<\/a> par Pierre-Fran\u00e7ois Hubert<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Edit\u00e9 par Etienne Combier<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Corrig\u00e9 par Aline Simonneau<\/strong><\/p>\n<p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La centrale hydro\u00e9lectrique de Toktogoul, dans le centre du Kirghizstan, est l\u2019une des principales sources d\u2019\u00e9lectricit\u00e9 du pays, tout en repr\u00e9sentant son plus grand lac de retenue. Achev\u00e9e en 1976 apr\u00e8s une quinzaine d\u2019ann\u00e9es de travaux, sa construction n\u2019a pas \u00e9t\u00e9 de tout repos. Novastan reprend et traduit ici un article publi\u00e9 le 26 avril [&hellip;]<\/p>\n","protected":false},"author":392,"featured_media":29873,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[1010,1009,473,466,1359,1012,1956,446],"coauthors":[1621,81,3353],"class_list":["post-29872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kirghizstan","tag-barrage","tag-centrale-hydroelectrique","tag-histoire","tag-kirghizstan","tag-patrimoine","tag-toktogoul","tag-traduction","tag-urss"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/29872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/392"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=29872"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/29872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/29873"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=29872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=29872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=29872"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=29872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}