{"id":28279,"date":"2020-01-27T06:00:53","date_gmt":"2020-01-27T05:00:53","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=28279"},"modified":"2020-12-03T20:02:50","modified_gmt":"2020-12-03T19:02:50","slug":"daech-menace-t-il-le-tadjikistan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/tadjikistan\/daech-menace-t-il-le-tadjikistan\/","title":{"rendered":"Daech menace-t-il le Tadjikistan ?"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Au Tadjikistan, un certain nombre d&rsquo;habitants soutiennent, m\u00eame partiellement, les vues de l\u2019\u00c9tat islamique. Les r\u00e9cents attentats dans le pays montrent que la guerre contre Daech est loin d&rsquo;\u00eatre gagn\u00e9e, estime le politologue tadjik Parviz Mullodjanov.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Novastan reprend et traduit un article initialement publi\u00e9 le 21 novembre 2019 <a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/security\/20191121\/igil-ugrozhaet-tadzhikistanu?tg_rhash=4ad06923c19fc6\">par le m\u00e9dia tadjik Asia-Plus.<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">Le 6 novembre dernier, un avant-poste fronti\u00e8re entre le Tadjikistan et l&rsquo;Ouzb\u00e9kistan situ\u00e9 \u00e0 Ichkobod&nbsp;<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-daech-revendique-lattaque-terroriste-de-lavant-poste-frontiere\/\">a \u00e9t\u00e9 attaqu\u00e9<\/a>. Cet attentat a \u00e9t\u00e9 le premier revendiqu\u00e9 par le groupe \u00c9tat islamique apr\u00e8s la mort de son ancien chef Abu-Bakar Al-Baghdadi.<\/p>\n<p style=\"text-align: justify\">Le politologue tadjik Parviz Mullodjanov explique ce \u00e0 quoi les pays d\u2019Asie centrale doivent encore s\u2019attendre de la part de l\u2019\u00c9tat Islamique.<\/p>\n<p style=\"text-align: justify\"><strong>Asia-Plus : L\u2019Etat islamique a revendiqu\u00e9 l\u2019organisation de l\u2019attentat de Danghara et les r\u00e9bellions dans les prisons de Khodjent et Vakhdat. Peut-on dire que l\u2019\u00c9tat islamique a pris racine au Tadjikistan&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Parviz Mullodjanov :<\/strong> Nous ne disposons pas de toutes les informations, dans la mesure o\u00f9 ce sont les forces de l\u2019ordre qui les d\u00e9tiennent. Cependant, la majorit\u00e9 des experts estime que Daech en a la capacit\u00e9. Ce groupe poss\u00e8de aujourd&rsquo;hui suffisamment de membres et de ramifications dans tout l\u2019espace post-sovi\u00e9tique, notamment dans les r\u00e9gions musulmanes. Dans le nord du Caucase, par exemple, on a vu une part consid\u00e9rable des subdivisions de l\u2019ancien \u00c9mirat du Caucase pr\u00eater all\u00e9geance \u00e0 Daech.<\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-daech-revendique-lattaque-terroriste-de-lavant-poste-frontiere\/\">Daech revendique l\u2019attaque terroriste de l\u2019avant-poste fronti\u00e8re au Tadjikistan<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">L\u2019autre fait est qu\u2019aujourd\u2019hui, la sp\u00e9cificit\u00e9 organisationnelle de Daech ne r\u00e9side pas tant dans des filiales et des cellules bien structur\u00e9es que dans la cr\u00e9ation de diff\u00e9rents groupes de partisans en r\u00e9seau. Il s\u2019av\u00e8re que ces groupes ne font pas partie de Daech d\u2019un point de vue organisationnel, mais ils partagent leurs id\u00e9es et se trouvent sous l\u2019emprise de ses propagandistes et des <em>\u00ab&nbsp;managers de r\u00e9seau \u00bb<\/em>.<\/p>\n<p style=\"text-align: justify\">\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<\/p>\n<p style=\"text-align: justify\">Une telle approche permet \u00e0 Daech de s\u2019adresser au plus large public possible, \u00e0 la diff\u00e9rence des structures traditionnelles en cellules et filiales clandestines. Plus le r\u00e9seau de soutiens id\u00e9ologiques est amorphe, plus il est difficile de le surveiller. Un tel groupe d\u2019adeptes peut ne pas appartenir formellement \u00e0 la structure de Daech, mais partager l\u2019id\u00e9ologie extr\u00e9miste. Ils communiquent alors par Internet et re\u00e7oivent des sortes d\u2019instructions g\u00e9n\u00e9rales. Ils peuvent planifier en autonomie des actions sur place.<\/p>\n<figure id=\"attachment_28356\" aria-describedby=\"caption-attachment-28356\" style=\"width: 945px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28356\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/Photo-ISIS_Tadjikistan-2.png\" alt=\"Photo ISIS Tadjikistan 2\" width=\"945\" height=\"715\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/Photo-ISIS_Tadjikistan-2.png 945w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/Photo-ISIS_Tadjikistan-2-300x227.png 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/Photo-ISIS_Tadjikistan-2-768x581.png 768w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><figcaption id=\"caption-attachment-28356\" class=\"wp-caption-text\">Une attaque \u00e0 un poste-fronti\u00e8re tadjik a fait 17 morts, dont un garde-fronti\u00e8re et un policier tadjiks.<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><strong>\u00c0&nbsp;quel point peut-on croire les d\u00e9clarations de Daech revendiquant la paternit\u00e9 de tel ou tel attentat ayant eu lieu au Tadjikistan&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">Daech revendique souvent tout ce qu\u2019il peut \u2013 cela fait partie de sa strat\u00e9gie d\u2019agence de relations publiques. Et toutes les organisations radicales proc\u00e8dent de la sorte. Le fait est qu\u2019on ne peut pas toujours les croire. Mais chez Daech, la fa\u00e7on de mener le djihad a chang\u00e9. Aujourd\u2019hui ils donnent de grandes lignes \u00e0 des gens qui partagent leurs id\u00e9es et sont pr\u00eats \u00e0 agir individuellement.<\/p>\n<p style=\"text-align: justify\">Par exemple, la direction de Daech appelle ses partisans par Internet \u00e0 faire le djihad avec tous les moyens \u00e0 disposition&nbsp;: prenez un couteau, allez dans la rue, tuez des chr\u00e9tiens, des mauvais musulmans ou les hypocrites. Faites le djihad sur place, comme vous le voulez et comme vous le pouvez. Simplement, tuez, agissez, faites exploser. Pour de tels attentats, on n\u2019a besoin de rien, a fortiori d\u2019aucune pr\u00e9paration sp\u00e9ciale. Tout \u00e7a, c\u2019est dur \u00e0 surveiller. Et bien que d\u2019un point de vue organisationnel, l\u2019attentat peut ne pas \u00eatre li\u00e9 \u00e0 lui, Daech peut se porter garant de personnes, auxquelles il a donn\u00e9 des consignes g\u00e9n\u00e9rales.<\/p>\n<p style=\"text-align: justify\">Il en va de m\u00eame dans le cas de l\u2019<a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-quatre-touristes-a-velo-tues-par-un-groupe-dhommes-armes\/\">attentat<\/a> de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Danghara\">Danghara<\/a>, lors de l\u2019attaque sur des touristes. Il y a une vid\u00e9o dans laquelle les jeunes gens font un serment d\u2019all\u00e9geance. Mais il est tout \u00e0 fait possible qu\u2019ils aient choisi eux-m\u00eames la cible et aient d\u00e9fini le plan d\u2019action, en suivant des instructions g\u00e9n\u00e9rales.<\/p>\n<p><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/tadjikistan-quatre-touristes-a-velo-tues-par-un-groupe-dhommes-armes\/\">Tadjikistan : quatre touristes \u00e0 v\u00e9lo tu\u00e9s par un groupe d\u2019hommes arm\u00e9s<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">Il y a pas mal de cas o\u00f9 les personnes qui commettent des attentats font au pr\u00e9alable une vid\u00e9o, dans laquelle il est question de lien avec Daech. Mais le plus souvent, ils partagent certes les id\u00e9es du califat, mais personne ne les pr\u00e9pare sur le plan organisationnel.<\/p>\n<p style=\"text-align: justify\"><strong>Est-ce que l\u2019attaque dans le ra\u00efon de Rukad porte la marque de Daech&nbsp;?&nbsp;\u00c0 ce sujet, l\u2019organisation a reconnu son implication.<\/strong><\/p>\n<p style=\"text-align: justify\">L\u2019incident s\u2019y apparente en effet par son absurdit\u00e9 et sa brutalit\u00e9 \u2013 c\u2019est un signe distinctif des djihadistes, et particuli\u00e8rement de Daech. Mais en m\u00eame temps, la version officielle a tant de contradictions, et est si mal pr\u00e9sent\u00e9e, qu\u2019il y a encore beaucoup de zones d\u2019ombre.<\/p>\n<p style=\"text-align: justify\"><strong>Ne consid\u00e9rez-vous pas que les autorit\u00e9s tadjikes tendent d\u2019autant plus la situation, cr\u00e9ent une atmosph\u00e8re de d\u00e9fiance, en dissimulant ou en ne donnant au public qu\u2019au compte-goutte l\u2019information au sujet des attentats (ou du moins des attentats qui en \u00e9taient vraiment) ?<\/strong><\/p>\n<p style=\"text-align: justify\">Une information incompl\u00e8te conduit \u00e0 l\u2019apparition de diverses versions alternatives, ce qui n\u2019est pas dans l\u2019int\u00e9r\u00eat du gouvernement. Dans de tels cas, plus l\u2019information est d\u00e9taill\u00e9e, mieux c\u2019est pour la version officielle.<\/p>\n<p style=\"text-align: justify\"><strong>Que cherche Daech au Tadjikistan&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">L\u2019objectif principal de Daech est la formation d\u2019un califat islamique, qui doit dans les faits unifier tous les pays de population musulmane, et \u00e0 l\u2019avenir, c\u2019est la cr\u00e9ation d\u2019un califat universel, qui dominerait le monde entier. Ils ne cherchent pas l\u2019argent, mais le statut.<\/p>\n<p style=\"text-align: justify\"><strong>Quand le Tadjikistan, les autorit\u00e9s, la soci\u00e9t\u00e9 et nous tous avons-nous rat\u00e9 l\u2019instant, o\u00f9 nos compatriotes partisans de l\u2019\u00c9tat islamique ont commenc\u00e9 \u00e0 faire davantage confiance \u00e0 Daech qu\u2019aux autorit\u00e9s la\u00efques&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">Au d\u00e9but des ann\u00e9es 2000, la r\u00e9gion a vu la prolif\u00e9ration de groupuscules salafistes. Ils ont commenc\u00e9 \u00e0 s\u2019organiser, et, sans repr\u00e9sailles, \u00e0 diffuser leurs id\u00e9es. C\u2019est alors que le fondement id\u00e9ologique a \u00e9t\u00e9 pos\u00e9, parce que toute la diff\u00e9rence entre les salafistes \u00ab&nbsp;pacifiques&nbsp;\u00bb et les \u00ab&nbsp;takfiristes&nbsp;\u00bb r\u00e9side dans la strat\u00e9gie et la tactique. La base de l\u2019id\u00e9ologie est la m\u00eame \u2013 simplement le premier groupe dit que ce n\u2019est pas le bon moment pour appliquer la contrainte, alors que les autres ne veulent pas attendre. La m\u00eame distinction vaut pour le niveau et l\u2019\u00e9tendue de violence permis.<\/p>\n<p style=\"text-align: justify\">Les id\u00e9ologues de Daech consid\u00e8rent que la violence \u00e0 l\u2019encontre d\u2019opposants politiques, et simplement de personnes ne partageant pas leurs opinions, ne doit conna\u00eetre aucune limite. Les autres organisations djihadistes estiment qu\u2019il faut d\u2019abord une certaine limitation de la violence, sinon cela effraierait leurs potentiels soutiens parmi les simples musulmans.<\/p>\n<p style=\"text-align: justify\">Mais les deux rejettent la soci\u00e9t\u00e9 moderne et tout ce qui a \u00e9t\u00e9 cr\u00e9\u00e9 par l\u2019humanit\u00e9 apr\u00e8s le VII\u00e8me si\u00e8cle&nbsp;: les institutions d\u00e9mocratiques, les \u00e9lections, le droit des peuples, y compris des Tadjiks, \u00e0 un gouvernement national, le droit \u00e0 une \u00e9ducation moderne, \u00e0 l\u2019art et ainsi de suite, la musique et la danse \u00e9tant interdites d\u2019office. C\u2019est une id\u00e9ologie de n\u00e9gation.<\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/pourquoi-autant-de-citoyens-tadjiks-ont-rejoint-daech\/\">Pourquoi autant de citoyens tadjiks ont rejoint Daech ?<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">C\u2019est au moment o\u00f9 nous avons laiss\u00e9 une telle base id\u00e9ologique s\u2019installer que nous avons enclench\u00e9 le m\u00e9canisme m\u00eame de radicalisation id\u00e9ologique.<\/p>\n<p style=\"text-align: justify\">Le probl\u00e8me, c\u2019est que les \u00e9l\u00e9ments de cette id\u00e9ologie s\u2019infiltrent dans la soci\u00e9t\u00e9 tadjike sous l\u2019apparence du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Hanafisme\">hanafisme.<\/a> Les personnes qui en font la propagande refusent souvent de se qualifier de salafistes. Ils se d\u00e9crivent comme de vrais musulmans. Mais l\u2019interpr\u00e9tation du Coran et de la Sunna contredisent l\u2019interpr\u00e9tation admise dans les cadres d&rsquo;\u00e9coles juridiques hanafites traditionnelles et mod\u00e9r\u00e9es. M\u00eame les gens qui rejettent la violence mais adh\u00e8rent aux id\u00e9es salafistes constituent une base sociale pour les futurs djihadistes.<\/p>\n<p style=\"text-align: justify\">La propagande m\u00eame de Daech cherche \u00e0 isoler ses cibles de la soci\u00e9t\u00e9&nbsp;: toutes les personnes autour qui ne partagent pas tes id\u00e9es, ce sont des kouffars, c\u2019est une soci\u00e9t\u00e9 d\u2019incroyants et ainsi de suite. C\u2019est l\u2019approche de toutes les sectes religieuses totalitaires. Les t\u00e9moins de J\u00e9hovah proc\u00e8dent de la m\u00eame fa\u00e7on, affirmant aux gens que ce qui compte ce ne sont pas les parents, les amis, la nation ou la communaut\u00e9. Le plus important, c\u2019est la relation \u00e0 Dieu.<\/p>\n<p style=\"text-align: justify\">Mais cela d\u00e9note aussi que de nombreux probl\u00e8mes existent dans la soci\u00e9t\u00e9. Les gens ne peuvent pas se r\u00e9aliser, il n\u2019y a pas d\u2019ascenseurs sociaux, ils ne peuvent pas travailler et r\u00e9sister face \u00e0 la corruption et \u00e0 l\u2019anarchie. Les propagandes religieuses trouvent dans de telles conditions un terreau favorable pour la r\u00e9alisation de leurs id\u00e9es.<\/p>\n<p style=\"text-align: justify\"><strong>Malgr\u00e9 tout, quelle est la cause principale poussant nos compatriotes \u00e0 rejoindre les rangs de l\u2019\u00c9tat islamique&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">Il y a beaucoup de raisons pour lesquelles des gens rejoignent des organisations terroristes. Au Tadjikistan, il n\u2019y a rien qu\u2019on ne trouverait ailleurs dans les autres pays. Les facteurs sont tr\u00e8s similaires&nbsp;: absence d\u2019ascenseurs sociaux, injustice sociale, grand foss\u00e9 entre les pauvres et les riches, des d\u00e9fauts qui existent dans la soci\u00e9t\u00e9 et qui contribuent \u00e0 la radicalisation sociale de la population.<\/p>\n<p style=\"text-align: justify\">\u00c0 cela s\u2019ajoute, aujourd\u2019hui, une influence ext\u00e9rieure, sous la forme d\u2019un message id\u00e9ologique, de propagande, qui se propage par Internet, les groupuscules et les cellules sur place.<\/p>\n<p style=\"text-align: justify\">On ne peut pas dire que les gens rejoignent l\u2019\u00c9tat islamique pour des int\u00e9r\u00eats purement financiers. Pour beaucoup, c\u2019est simplement une perspective de r\u00e9alisation de soi, d\u2019am\u00e9lioration du statut social. Le fait est que la propagande des organisations djihadistes se base sur l\u2019offre de nouvelles possibilit\u00e9s&nbsp;faite \u00e0 ses partisans : am\u00e9liorer le statut social, sortir de sa mis\u00e8re sociale, recevoir de nouvelles opportunit\u00e9s.<\/p>\n<p style=\"text-align: justify\">Dans les vid\u00e9os que les djihadistes tadjiks de Syrie ont diffus\u00e9es, ils montrent comment ils se d\u00e9placent dans telle ville, ils montrent telles maisons en construction. En fait, ces maisons sont en construction depuis le temps de Hafez El-Assad (ex-pr\u00e9sident de la Syrie). Mais les djihadistes affirmaient \u00e0 de potentiels moudjahidines qu\u2019\u00e0 leur arriv\u00e9e, l\u2019\u00c9tat islamique leur donnerait 2 ou 3 appartements o\u00f9 ils pourraient vivre.<\/p>\n<p style=\"text-align: justify\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/13-enfants-seraient-impliques-dans-lattaque-terroriste-du-poste-frontiere-au-tadjikistan\/\">13 enfants seraient impliqu\u00e9s dans l\u2019attaque terroriste du poste-fronti\u00e8re au Tadjikistan<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">Ils montrent des ruines d\u2019usines, et disent qu\u2019ils construisent des usines o\u00f9 les nouveaux arrivants musulmans peuvent trouver du travail. En m\u00eame temps, ils insistent sur le fait qu\u2019\u00e0 l\u2019int\u00e9rieur des fronti\u00e8res du Califat il n\u2019y aurait pas de corruption, que tout serait organis\u00e9 comme au temps du Proph\u00e8te.<\/p>\n<p style=\"text-align: justify\">Une telle propagande agit sur des personnes qui se sentent perdues dans leur mis\u00e8re sociale, ils ont l\u2019impression qu\u2019\u00e0 cause de la corruption et du r\u00e9gionalisme, ou de n\u2019importe quel autre obstacle, ils ne peuvent trouver un bon travail chez eux et garantir une bonne \u00e9ducation \u00e0 leurs enfants. C\u2019est un stimulus compl\u00e9mentaire, qui les pousse \u00e0 devenir djihadistes.<\/p>\n<figure id=\"attachment_28361\" aria-describedby=\"caption-attachment-28361\" style=\"width: 861px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28361 size-full\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/terroriste-tadjik-SITE.jpg\" alt=\"terroriste-tadjik SITE\" width=\"861\" height=\"480\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/terroriste-tadjik-SITE.jpg 861w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/terroriste-tadjik-SITE-300x167.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/terroriste-tadjik-SITE-768x428.jpg 768w\" sizes=\"auto, (max-width: 861px) 100vw, 861px\" \/><figcaption id=\"caption-attachment-28361\" class=\"wp-caption-text\">De nombreux Tadjiks ont rejoint l\u2019\u00c9tat islamique en Syrie et en Irak.<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><strong>Vous avez personnellement rencontr\u00e9 des citoyens du Tadjikistan qui soutiendraient \u00e0 un certain degr\u00e9 leur vision. Qui sont ces personnes ?<\/strong><\/p>\n<p style=\"text-align: justify\">N\u2019importe quel citoyen tadjik peut rencontrer ces gens, il y en a assez. De loin, on ne peut pas tous les consid\u00e9rer comme salafistes, mais une certaine partie de la population se trouve sous l\u2019emprise de leurs id\u00e9es \u2013 ou plut\u00f4t de quelques \u00e9l\u00e9ments de cette id\u00e9ologie qui se r\u00e9pand aujourd\u2019hui en ligne, par les ressources disponibles sur Internet.<\/p>\n<p style=\"text-align: justify\">Il y a des crit\u00e8res selon lesquels il est possible de d\u00e9terminer si cet homme-ci ou cet homme-l\u00e0 est influenc\u00e9 par l\u2019id\u00e9ologie. C\u2019est une id\u00e9ologie de n\u00e9gation. Elle rejette tout ce qui a \u00e9t\u00e9 fait apr\u00e8s le VII\u00e8me si\u00e8cle, elle rejette toute culture extra-islamique.<\/p>\n<p style=\"text-align: justify\">Ce sont des points que respectent les salafistes et les djihadistes&nbsp;: la haine des chiites, la haine des soufis, des musulmans suivant une interpr\u00e9tation large du Coran.<\/p>\n<p style=\"text-align: justify\">Il y aussi la haine contre l\u2019intelligentsia, la haine et la d\u00e9fiance envers les institutions d\u00e9mocratiques, de la haine contre tout ce qui rel\u00e8ve de la nation, l\u2019appellation tadjike, par exemple.<\/p>\n<p><strong>Lire aussi sur Novastan : <\/strong><a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/17-morts-apres-une-attaque-terroriste-au-tadjikistan-pres-de-la-frontiere-ouzbeke\/\"><strong>17 morts apr\u00e8s une attaque terroriste au Tadjikistan, pr\u00e8s de la fronti\u00e8re ouzb\u00e8ke<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">\u00c0&nbsp;la mosqu\u00e9e, ils peuvent dire qu\u2019il est interdit de mettre une st\u00e8le sur la tombe, qu\u2019en g\u00e9n\u00e9ral il est interdit de se recueillir sur les tombes. Ce sont des id\u00e9es salafistes, et elles sont maintenant tr\u00e8s populaires. J\u2019ai moi-m\u00eame particip\u00e9 \u00e0 quelques \u00e9v\u00e8nements religieux conduits par de pr\u00e9tendus hanafites mais avec une id\u00e9ologie purement salafiste.<\/p>\n<p style=\"text-align: justify\">De telles personnes peuvent d\u00e9clarer quelqu\u2019un \u00ab&nbsp;takfir&nbsp;\u00bb (accusation d\u2019incroyance), car n\u2019importe quelle preuve fait de vous un non-musulman \u00e0 leurs yeux. De telles personnes commencent \u00e0 consid\u00e9rer tous les gens autour d&rsquo;elles comme non-musulmans, parce qu\u2019ils ne partagent pas leurs id\u00e9es, ils ne prient pas ou ne suivent pas un des piliers de l\u2019islam.<\/p>\n<p style=\"text-align: justify\"><strong>L\u2019influence de Daech a consid\u00e9rablement cr\u00fb dans les lieux de privation de libert\u00e9. En t\u00e9moignent deux soul\u00e8vements dans des prisons au Tadjikistan que Daech a revendiqu\u00e9s. Une diff\u00e9rence est apparue entre les religieux et les profanes.&nbsp;\u00c0 quoi est-ce d\u00fb ?<\/strong><\/p>\n<p style=\"text-align: justify\">C\u2019est li\u00e9 \u00e0 la strat\u00e9gie globale de Daech et des organisations djihadistes. Ils agissent, comme les Sovi\u00e9tiques \u00e0 leur \u00e9poque, \u00e0 travers les prisons. Vladimir Illich L\u00e9nine en son temps, disait que <em>\u00ab&nbsp;la prison est une universit\u00e9 populaire \u00bb<\/em>. Ainsi les djihadistes estiment que les prisons sont leur universit\u00e9. Ils envoient en reconnaissance leurs leaders et leurs \u00e9missaires en prison, non seulement au Tadjikistan mais aussi dans le monde entier.<\/p>\n<p style=\"text-align: justify\">Ils tentent d\u2019entrer en prison pour des faits non-religieux, pour ne pas attirer l\u2019attention. Ils cr\u00e9ent l\u00e0-bas des djamoats (communaut\u00e9s), ils ont des soutiens dehors \u2013 quand tu as une aide financi\u00e8re, tu peux acheter l\u2019administration, t\u2019assurer de meilleures conditions, ce dans toutes les prisons. Gr\u00e2ce \u00e0 \u00e7a, ils obtiennent une influence consid\u00e9rable dans les prisons. Ils y font r\u00e9gner leur loi.<\/p>\n<p style=\"text-align: justify\">C\u2019est une strat\u00e9gie globale, mais le Tadjikistan s\u2019av\u00e8re \u00eatre seulement une partie de leur strat\u00e9gie. R\u00e9cemment, un concept est apparu en Russie, celui de <em>\u00ab&nbsp;zone verte \u00bb<\/em>. Auparavant on parlait seulement de <em>\u00ab&nbsp;zones rouges&nbsp;\u00bb<\/em>, l\u00e0 o\u00f9 l\u2019administration est aux commandes et des <em>\u00ab&nbsp;zones noires&nbsp;\u00bb<\/em>, l\u00e0 o\u00f9, dans les colonies p\u00e9nitentiaires, les criminels dominent. Mais dans les zones vertes, ce sont les djamoats salafistes qui ont la main haute.<\/p>\n<p style=\"text-align: justify\"><strong>Dans cette configuration, que doit-on changer dans le syst\u00e8me p\u00e9nitentiaire du pays&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">Il faut r\u00e9tablir l\u2019ordre et combattre la corruption. Je proposerais de r\u00e9former de nouveau l\u2019administration, renvoyer les employ\u00e9s en place et prendre de nouveaux travailleurs.<\/p>\n<p style=\"text-align: justify\">Faire passer tout le monde au d\u00e9tecteur de mensonges, pour qu\u2019il n\u2019y ait plus de trace de corruption, de torture et d\u2019anarchie, parce que les djihadistes utilisent l\u2019anarchie \u00e0 leur avantage. Parce que plus grand est le d\u00e9sordre, plus les gens cherchent une alternative. Les nouveaux ont besoin de soutien, d\u2019un c\u00f4t\u00e9 il y a l\u2019administration, d\u2019un autre des criminels. Dans les prisons, les lois sont assez diff\u00e9rentes, et pour beaucoup, fricoter avec les organisations radicales, c\u2019est une \u00e9chappatoire.<\/p>\n<p style=\"text-align: justify\">En m\u00eame temps, je proposerais de mettre des personnes \u00e0 l\u2019\u00e9cart &#8211; les leaders et les \u00e9missaires des djihadistes. Et garder s\u00e9par\u00e9s les r\u00e9cidivistes et les personnes jug\u00e9es pour des faits \u00ab&nbsp;l\u00e9gers&nbsp;\u00bb. \u00c7a s\u2019appelle l\u2019approche diff\u00e9rentielle du syst\u00e8me p\u00e9nitentiaire.<br \/>\n<strong><br \/>\n<\/strong><\/p>\n<figure id=\"attachment_28366\" aria-describedby=\"caption-attachment-28366\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28366 size-full\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/01\/Tadjikistan-Attentat-Daesh-poste-fronti\u00e8re.jpg\" alt=\"Tadjikistan Attentat Daesh poste-fronti\u00e8re\" width=\"600\" height=\"338\"><figcaption id=\"caption-attachment-28366\" class=\"wp-caption-text\">L\u2019\u00c9tat islamique a revendiqu\u00e9 l\u2019attentat du poste-fronti\u00e8re d\u2019Ishkobod, entre le Tadjikistan et l\u2019Ouzb\u00e9kistan.<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><strong><br \/>\nCes derni\u00e8res ann\u00e9es, les autorit\u00e9s ont graci\u00e9 les personnes de retour de points chauds \u2013 la Syrie et l\u2019Irak, s&rsquo;ils reconnaissent leur faute et se repentent de ce qu\u2019ils ont fait. Qu\u2019est-ce que \u00e7a apporte \u00e0 la s\u00e9curit\u00e9 nationale&nbsp;? Quel cr\u00e9dit accorder \u00e0 leur repentir&nbsp;? Et, surtout, est-ce possible de contr\u00f4ler ces groupes&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">\u00c0 cet \u00e9gard, les autorit\u00e9s tadjikes agissent correctement, parce qu\u2019une grande partie de ces gens ne s\u2019av\u00e8rent pas \u00eatre des djihadistes convaincus. Beaucoup d\u2019entre eux ont \u00e9t\u00e9 d\u00e9\u00e7us, cela concerne particuli\u00e8rement les femmes et les adolescents. En fait, beaucoup d\u2019entre eux ont suivi un membre plus \u00e2g\u00e9 de leur famille.<\/p>\n<p style=\"text-align: justify\">On leur avait promis une chose, et, \u00e0 leur arriv\u00e9e, ils ont vu quelque chose d\u2019assez diff\u00e9rent. On disait que c\u2019\u00e9tait une soci\u00e9t\u00e9 id\u00e9ale, qu\u2019il n\u2019y avait pas de corruption, de r\u00e9gionalisme, d\u2019impunit\u00e9. Et dans les faits, quand ils sont arriv\u00e9s, ils ont vu que, de nouveau, l\u2019argent se trouvait dans les mains des chefs et que les gens simples se contentaient du minimum.<\/p>\n<p style=\"text-align: justify\">Ils voyaient qu\u2019il y avait des musulmans meilleurs que d\u2019autres. Les Arabes occupaient toutes les fonctions supr\u00eames, et, de plus, des Arabes de certains pays bien sp\u00e9cifiques.<\/p>\n<p style=\"text-align: justify\">Bien s\u00fbr, une certaine partie de ces personnes ne se sont pas repenties, et beaucoup d\u2019entre elles peuvent \u00eatre sous l\u2019influence de djihadistes. Mais en g\u00e9n\u00e9ral, c\u2019est une mesure plut\u00f4t juste. Elle donne la possibilit\u00e9 aux gens de se r\u00e9habiliter.<\/p>\n<p style=\"text-align: justify\">D\u2019autre part, l\u2019amnistie \u00e0 elle seule ne suffit pas. Il faut une r\u00e9habilitation sociale, psychologique et id\u00e9ologique. Cela doit \u00eatre un cheminement complexe. Si la personne est arriv\u00e9e et a \u00e9t\u00e9 amnisti\u00e9e, elle doit avoir la possibilit\u00e9 de changer sa vie, il faut un programme sp\u00e9cial qui la soutiendrait, pour qu\u2019elle se r\u00e9int\u00e8gre.<\/p>\n<p style=\"text-align: justify\">Chez nous, malheureusement, ce n\u2019est pas d\u00e9velopp\u00e9. L\u2019approche en elle-m\u00eame est louable, mais cela n\u00e9cessite un travail approfondi, pour que les gens ne se radicalisent pas de nouveau.<\/p>\n<p style=\"text-align: justify\"><strong>Qu&rsquo;en est-il des radicalis\u00e9s en Asie centrale&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">C\u2019est une tendance globale dans l\u2019espace post-sovi\u00e9tique, il y a un ph\u00e9nom\u00e8ne de radicalisation religieuse et sociale. Dans beaucoup de pays, on voit un retour de l\u2019Islam, de plus en plus de gens se mettent \u00e0 prier, de plus en plus de gens recherchent des informations sur la religion.<\/p>\n<p style=\"text-align: justify\">Mais le probl\u00e8me est que cette r\u00e9islamisation se fait sous l\u2019influence des salafistes ou des djihadistes. Dans cette configuration, nous avons un groupe de gens, qui retournent \u00e0 l\u2019Islam via les missionnaires, et ils suivent une id\u00e9ologie radicale.<\/p>\n<p style=\"text-align: justify\">C\u2019est visible principalement dans les soci\u00e9t\u00e9s enti\u00e8rement la\u00efques que sont le Kirghizstan et le Kazakhstan. L\u00e0-bas il n\u2019y pas un clerg\u00e9 puissant install\u00e9 localement, comme au Tadjikistan et en Ouzb\u00e9kistan. Et, l\u00e0-bas, on observe une croissance tr\u00e8s importante des communaut\u00e9s salafistes.<\/p>\n<p style=\"text-align: justify\">En g\u00e9n\u00e9ral, l\u00e0 o\u00f9 il y a un clerg\u00e9 traditionnel bien implant\u00e9 et des soufis, les salafistes n\u2019ont pas le champ libre pour faire la propagande de leur id\u00e9ologie.<\/p>\n<p style=\"text-align: justify\"><strong>La g\u00e9ographie des activit\u00e9s de Daech peut-elle changer&nbsp;? Ce groupuscule peut-il d\u2019une mani\u00e8re ou d\u2019une autre tenter de renforcer son emprise dans notre r\u00e9gion&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify\">Daech a renforc\u00e9 ses positions en Afghanistan avant le retournement de situation en Irak et en Syrie. L\u2019influence de l\u2019organisation grandit dans l\u2019espace post-sovi\u00e9tique.<\/p>\n<p style=\"text-align: justify\">\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t<\/p>\n<p style=\"text-align: justify\">La d\u00e9b\u00e2cle de Daech a seulement renforc\u00e9 le processus de diffusion de ces id\u00e9ologies dans tout le monde islamique. Pour sa revanche, ils peuvent choisir n\u2019importe quel pays arabe, avant tout l\u2019Alg\u00e9rie et la Libye.<\/p>\n<p style=\"text-align: justify\">La majorit\u00e9 des experts pense que l\u2019activation de Daech et d\u2019autres organisations est tout \u00e0 fait probable en Asie centrale. Dans les prochaines ann\u00e9es, ils peuvent se manifester aussi par des attentats, des attaques, que nous avons pu voir ces derniers mois au Tadjikistan. Ils tenteront de d\u00e9stabiliser la r\u00e9gion.<\/p>\n<p style=\"text-align: right\"><strong>Mekhrangez Tursunzoda<\/strong><br \/>\n<strong> Journaliste pour Asia-Plus<\/strong><\/p>\n<p style=\"text-align: right\"><strong>Traduit du <a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/security\/20191121\/igil-ugrozhaet-tadzhikistanu?tg_rhash=4ad06923c19fc6\">russe<\/a> par Arnaud Behr<\/strong><\/p>\n<p style=\"text-align: justify\"><p><em>Merci d'avoir lu cet article jusqu'au bout ! Si vous avez un peu de temps, nous aimerions avoir votre avis pour nous am\u00e9liorer. Pour ce faire, vous pouvez <a href=\"https:\/\/forms.gle\/3M7U3fyMRXAiaZmJA\">r\u00e9pondre anonymement \u00e0 ce questionnaire<\/a> ou nous envoyer un email \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>. Merci beaucoup !<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au Tadjikistan, un certain nombre d&rsquo;habitants soutiennent, m\u00eame partiellement, les vues de l\u2019\u00c9tat islamique. Les r\u00e9cents attentats dans le pays montrent que la guerre contre Daech est loin d&rsquo;\u00eatre gagn\u00e9e, estime le politologue tadjik Parviz Mullodjanov. Novastan reprend et traduit un article initialement publi\u00e9 le 21 novembre 2019 par le m\u00e9dia tadjik Asia-Plus. Le 6 [&hellip;]<\/p>\n","protected":false},"author":458,"featured_media":28358,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[2711,1252,523,576,1956],"coauthors":[2156,2765],"class_list":["post-28279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tadjikistan","tag-daech","tag-etat-islamique","tag-tadjikistan","tag-terrorisme","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/28279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/458"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=28279"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/28279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/28358"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=28279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=28279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=28279"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=28279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}