{"id":26280,"date":"2019-10-07T08:15:07","date_gmt":"2019-10-07T06:15:07","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=26280"},"modified":"2021-01-27T11:02:15","modified_gmt":"2021-01-27T10:02:15","slug":"pres-de-13-000-enfants-seraient-sans-nationalite-au-tadjikistan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/tadjikistan\/pres-de-13-000-enfants-seraient-sans-nationalite-au-tadjikistan\/","title":{"rendered":"Pr\u00e8s de 13 000 enfants seraient sans nationalit\u00e9 au Tadjikistan"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Selon le Haut commissariat des Nations unies pour les r\u00e9fugi\u00e9s, seulement 96,7 % des naissances sont enregistr\u00e9es au Tadjikistan. Cons\u00e9quence : plus de 13 000 enfants du pays sont menac\u00e9s d&rsquo;apatridie en raison de l&rsquo;absence d&rsquo;enregistrement de leur naissance.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Novastan reprend et traduit ici un article publi\u00e9 le 6 septembre 2019 par le m\u00e9dia tadjik&nbsp;<a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/society\/20190906\/mezhdu-nebom-i-zemlei-v-tadzhikistane-bolee-13-tis-detei-ne-imeyut-grazhdanstva?tg_rhash=59df260525b319\">Asia-Plus<\/a>.<\/strong><\/p>\n<p style=\"text-align: justify;\">Lors d&rsquo;une conf\u00e9rence organis\u00e9e le 5 septembre dernier dans la capitale kazakhe <a href=\"https:\/\/novastan.org\/fr\/kazakhstan\/la-capitale-du-kazakhstan-renommee-nur-sultan\/\">Nur-Sultan<\/a>, les repr\u00e9sentants des pays d&rsquo;Asie centrale ont d\u00e9battu de l&rsquo;\u00e9volution des processus d&rsquo;enregistrement des nouveau-n\u00e9s et de la pr\u00e9vention de cas d&rsquo;enfants apatrides. L&rsquo;\u00e9v\u00e8nement a \u00e9t\u00e9 organis\u00e9 par le Haut commissariat des Nations unies pour les r\u00e9fugi\u00e9s (HCR) en partenariat avec l&rsquo;UNICEF et l&rsquo;ONU, selon le m\u00e9dia kazakh&nbsp;<a href=\"https:\/\/informburo.kz\/novosti\/v-kazahstane-vyyavili-okolo-5000-lic-s-neopredelyonnym-grazhdanstvom.html\">Informburo<\/a>.<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p style=\"text-align: justify;\">\u00ab <em>Bien que le taux d&rsquo;enregistrement des naissances en Asie centrale soit relativement \u00e9lev\u00e9 \u2013 100 % pour le Kazakhstan, l&rsquo;Ouzb\u00e9kistan et le Turkm\u00e9nistan, 98,6 % pour le Kirghizstan et 96,7 % pour le Tadjikistan \u2013, l&rsquo;absence d&rsquo;immatriculation persiste dans certains endroits de la r\u00e9gion<\/em> \u00bb, a d\u00e9clar\u00e9 Carol Batchelor, conseill\u00e8re du HCR sur ce sujet. Malgr\u00e9 les 100 % kazakhs,&nbsp;<a href=\"https:\/\/informburo.kz\/novosti\/v-kazahstane-vyyavili-okolo-5000-lic-s-neopredelyonnym-grazhdanstvom.html\">Informburo<\/a>&nbsp;estime qu&rsquo;il y aurait aussi des milliers d&rsquo;enfants apatrides au Kazakhstan.<\/p>\n<p style=\"text-align: justify;\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/fact\/plus-de-130-000-personnes-sont-apatrides-en-asie-centrale\/\">Plus de 130 000 personnes sont apatrides en Asie centrale<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Au cours de la p\u00e9riode 2014-2018, les organisations partenaires du HCR ont identifi\u00e9 au Tadjikistan 13 500 enfants dont la naissance n&rsquo;a pas \u00e9t\u00e9 enregistr\u00e9e et qui risquent de se retrouver apatrides.<\/p>\n<p style=\"text-align: justify;\"><strong>Une question \u00e0 l&rsquo;\u00e9chelle mondiale<\/strong><\/p>\n<p style=\"text-align: justify;\">Selon le HCR, plus de 10 millions de personnes dans le monde n&rsquo;ont pas de nationalit\u00e9 \u00e0 l&rsquo;heure actuelle, c&rsquo;est-\u00e0-dire qu&rsquo;elles ne sont pas consid\u00e9r\u00e9es comme citoyens par la loi d&rsquo;un \u00c9tat.<\/p>\n<p style=\"text-align: justify;\"><strong>Lire aussi sur Novastan : <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/un-avocat-kirghiz-recompense-par-lonu-pour-son-combat-contre-lapatridie\/\">Un avocat kirghiz r\u00e9compens\u00e9 par l&rsquo;ONU pour son combat contre l&rsquo;apatridie<\/a><\/strong><\/p>\n<p style=\"background-color: #d4d4d4;\"><span style=\"color: #000000;\">Envie d'Asie centrale dans votre bo\u00eete mail ? Inscrivez-vous gratuitement \u00e0 notre newsletter hebdomadaire <strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/2ff41361.sibforms.com\/serve\/MUIFAEUtgQP8Waps-GeAAxU6xgHAdCwla_phFOCNHYUG2N5pyugc_FC9NR3XbOOigQxU5CuQ4V0IZJcq6LjCU6Hx9fBECllNbyvRpMFItJi2WzECxpflAKA-cS-isERi5gQRcgrqND1R6toUU-9w6b_7bd4-Ty-GtfBQfXNFFjMIK0bYtfXjv8bCS5qFaXUgi00yBrR5vK187H2N\">en cliquant ici.<\/a><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Carol Batchelor souligne que cette situation se produit dans le cas d&rsquo;enfants n\u00e9s de parents migrants sans papiers, ainsi que de personnes dont la nationalit\u00e9 est ind\u00e9termin\u00e9e. \u00ab <em>On suppose que le nombre r\u00e9el d&rsquo;enfants non enregistr\u00e9s \u00e0 la naissance est sous-estim\u00e9, car ils ne le sont pas en raison de certaines dispositions de la l\u00e9gislation nationale\u00a0\u00bb,<\/em>&nbsp;estime la sp\u00e9cialiste.<em>&nbsp;\u00ab\u00a0Les lacunes cette l\u00e9gislation peuvent conduire \u00e0 des situations o\u00f9 l&rsquo;existence m\u00eame d&rsquo;enfants n\u00e9s sur le territoire de ces pays restera ignor\u00e9e et o\u00f9, par cons\u00e9quent, ceux-ci ne pourront pas exercer leur droit \u00e0 la citoyennet\u00e9 ou tout autre droit humain fondamental tant que le statut juridique de leurs parents n&rsquo;aura pas \u00e9t\u00e9 r\u00e9gl\u00e9<\/em> \u00bb, a ajout\u00e9 Carol Batchelor.<\/p>\n<p style=\"text-align: right;\"><strong>Traduit du <a href=\"https:\/\/asiaplustj.info\/ru\/news\/tajikistan\/society\/20190906\/mezhdu-nebom-i-zemlei-v-tadzhikistane-bolee-13-tis-detei-ne-imeyut-grazhdanstva?tg_rhash=59df260525b319\">russe<\/a> par Baptiste Long\u00e8re<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>\u00c9dit\u00e9 par Aline Simonneau<\/strong><\/p>\n<p style=\"text-align: justify;\"><p style=\"text-align: left;\"><i><span style=\"font-weight: 400;\">Si vous avez aim\u00e9 cet article, n'h\u00e9sitez pas \u00e0 nous suivre sur <\/span><\/i><a href=\"https:\/\/twitter.com\/novastan_fr\"><i><span style=\"font-weight: 400;\">Twitter<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/www.facebook.com\/Novastan.org\/\"><i><span style=\"font-weight: 400;\">Facebook<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/telegram.me\/novastan\"><i><span style=\"font-weight: 400;\">Telegram<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/www.linkedin.com\/company\/fondation-novastan\/\"><i><span style=\"font-weight: 400;\">Linkedin<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ou <\/span><\/i><a href=\"https:\/\/www.instagram.com\/novastanorg\/\"><i><span style=\"font-weight: 400;\">Instagram<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ! Vous pouvez \u00e9galement vous inscrire pour recevoir<\/span><\/i><a href=\"http:\/\/eepurl.com\/O0Qub\"> <i><span style=\"font-weight: 400;\">notre newsletter hebdomadaire<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ou nous soutenir en devenant <\/span><\/i><a href=\"https:\/\/novastan.org\/fr\/novastan\/soutenir-novastan-mode-demploi\/\"><i><span style=\"font-weight: 400;\">membre de la communaut\u00e9 Novastan<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon le Haut commissariat des Nations unies pour les r\u00e9fugi\u00e9s, seulement 96,7 % des naissances sont enregistr\u00e9es au Tadjikistan. Cons\u00e9quence : plus de 13 000 enfants du pays sont menac\u00e9s d&rsquo;apatridie en raison de l&rsquo;absence d&rsquo;enregistrement de leur naissance. Novastan reprend et traduit ici un article publi\u00e9 le 6 septembre 2019 par le m\u00e9dia tadjik&nbsp;Asia-Plus. [&hellip;]<\/p>\n","protected":false},"author":504,"featured_media":26305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3986,6],"tags":[1803,808,809,521,523,1956],"coauthors":[2497,3353],"class_list":["post-26280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-et-culture","category-tadjikistan","tag-apatrides","tag-citoyennete","tag-nationalite","tag-societe","tag-tadjikistan","tag-traduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/26280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/504"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=26280"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/26280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/26305"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=26280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=26280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=26280"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=26280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}