{"id":25795,"date":"2019-09-17T11:28:36","date_gmt":"2019-09-17T09:28:36","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=25795"},"modified":"2023-03-31T08:43:34","modified_gmt":"2023-03-31T06:43:34","slug":"la-renaissance-du-bazar-dichkachim","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/tadjikistan\/la-renaissance-du-bazar-dichkachim\/","title":{"rendered":"La renaissance du bazar d\u2019Ichkachim"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>UN LIEU EN ASIE CENTRALE. Apr\u00e8s trois ans de fermeture, le bazar d\u2019Ichkachim a rouvert ses portes fin juillet. Chaque samedi le poste frontalier Ichkachim entre Tadjikistan et Afghanistan accueille un des plus grands march\u00e9s de la r\u00e9gion. Marchands tadjiks et afghans s\u2019affairent \u00e0 leurs \u00e9tals hauts en couleurs, regorgeant de tissus, griottes et pewarkas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ishkashim_(Tadjikistan)\">Ichkachim<\/a> est le chef-lieu de la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Corridor_du_Wakhan\">vall\u00e9e du Wakhan<\/a> et accueille un des quatre points de passage transfrontaliers entre le Tadjikistan et l\u2019Afghanistan. A 100 kilom\u00e8tres au sud de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Khorog\">Khorog<\/a>, la capitale de la r\u00e9gion du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Haut-Badakhchan\">Haut-Badakhchan<\/a>, cette commune est connue pour son march\u00e9, qui se situe dans le no man\u2019s land sur le fleuve <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Piandj\">Piandj<\/a>, \u00e0 trois kilom\u00e8tres \u00e0 l\u2019ouest de la ville.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors qu\u2019il \u00e9tait ferm\u00e9 depuis 2016, le march\u00e9 aura d\u00e9sormais lieu chaque samedi entre 8h et 14h, jusqu\u2019\u00e0 nouvel ordre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un signe de l\u2019abaissement des tensions dans la r\u00e9gion<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par sa position strat\u00e9gique, le bazar est un barom\u00e8tre des tensions g\u00e9opolitiques dans la r\u00e9gion. <a href=\"http:\/\/central.asia-news.com\/en_GB\/articles\/cnmi_ca\/features\/2016\/11\/03\/feature-01\">Ferm\u00e9 en 2014<\/a> apr\u00e8s les incursions des forces talibanes au nord de l\u2019Afghanistan et dans le massif de l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Hindou_Kouch\">Hindou Kouch<\/a>, il avait \u00e9t\u00e9 rouvert bri\u00e8vement en 2016 avant d\u2019\u00eatre ferm\u00e9 \u00e0 nouveau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan&nbsp;: <a href=\"https:\/\/novastan.org\/fr\/kirghizstan\/les-enjeux-de-lafghanistan-pour-lasie-centrale\/\">Les enjeux de l&rsquo;Afghanistan pour l&rsquo;Asie Centrale<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son ouverture fin juillet est un des signes tr\u00e8s encourageants de l\u2019abaissement des tensions dans le corridor&nbsp;du Wakhan. Longtemps probl\u00e9matique et expos\u00e9e aux trafics, la fronti\u00e8re a \u00e9t\u00e9 s\u00e9curis\u00e9e ces derni\u00e8res ann\u00e9es, avec le concours de l\u2019arm\u00e9e russe. <a href=\"https:\/\/www.eurasia.undp.org\/content\/rbec\/en\/home\/presscenter\/pressreleases\/2015\/3\/3\/undp--government-of-japan-support-to-promote-cross-border-cooper.html\">Quatre millions de dollars ont \u00e9galement \u00e9t\u00e9 investis<\/a> par le Programme des Nations Unies pour le D\u00e9veloppement (PNUD) et l\u2019Agence japonaise de coop\u00e9ration internationale (JICA) pour moderniser plusieurs points de passage \u00e0 la fronti\u00e8re et am\u00e9nager le march\u00e9 d\u2019Ichkachim.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-25799\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/2.jpg\" alt=\"Ichkachim Tadjikistan March\u00e9 Afghanistan Ouverture Japon\" class=\"wp-image-25799\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/2.jpg 1200w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/2-225x300.jpg 225w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/2-768x1024.jpg 768w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/2-600x800.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">L\u2019ONU et la JICA ont \u00e9t\u00e9 \u00e0 l\u2019\u0153uvre pour l\u2019am\u00e9nagement du march\u00e9.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lire aussi sur Novastan&nbsp;: <a href=\"https:\/\/novastan.org\/fr\/tadjikistan\/un-pont-supplementaire-pour-relier-le-tadjikistan-a-lafghanistan\/\">Un pont suppl\u00e9mentaire pour relier le Tadjikistan \u00e0 l\u2019Afghanistan<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Talibans ne sont plus signal\u00e9s dans une r\u00e9gion d\u00e9sormais plus ouverte, pour le bonheur des visiteurs tadjiks, afghans ou \u00e9trangers qui se pressent sous les grandes halles grises du bazar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le temps des retrouvailles<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On trouve sur le march\u00e9 toutes sortes de produits de la vie quotidienne&nbsp;: savon, v\u00eatements et objets pour la maison. Le march\u00e9 regorge de sp\u00e9cialit\u00e9s culinaires afghanes et tadjikes. Fruits, kompots et kefir c\u00f4toient des sacs de riz d\u00e9tourn\u00e9s du World Food Program. On trouve enfin quelques \u00e9l\u00e9ments d\u2019artisanat, comme des tapis, des foulards ou des pakol, ces bonnets plats en laine afghans<strong>. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-25800\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"772\" src=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/3.jpg\" alt=\"Ichkachim Tadjikistan March\u00e9 Afghanistan Ouverture\" class=\"wp-image-25800\" srcset=\"https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/3.jpg 1024w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/3-300x226.jpg 300w, https:\/\/novastan.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/3-768x579.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Un marchand afghan dans la halle sud du bazar.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cot\u00e9 tadjik, deux garde-fronti\u00e8res gardent l\u2019entr\u00e9e du no man\u2019s land et une pr\u00e9sentation du passeport suffit pour les ressortissants \u00e9trangers. Les citoyens tadjiks peuvent passer librement. Cot\u00e9 afghan, l\u2019attente est plus longue et les contr\u00f4les plus pouss\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ambiance du bazar est aux retrouvailles. Les clients rencontr\u00e9s le 10 ao\u00fbt dernier \u00e9taient principalement afghans et se r\u00e9jouissaient de sa r\u00e9ouverture. Celui-ci constitue pour eux une opportunit\u00e9 de trouver vivres et mat\u00e9riel \u00e0 moindre cout qu\u2019en Afghanistan. Plusieurs ont \u00e9galement \u00e9voqu\u00e9 la reprise du lien avec leurs voisins tadjiks. <em>\u00ab&nbsp;Cette ouverture est une bonne nouvelle. Je retrouve aujourd\u2019hui de bons amis du Tadjikistan&nbsp;\u00bb<\/em> t\u00e9moigne Zulmay, un jeune Afghan, tout sourire. Aux dires d\u2019un guide local, le tourisme dans le Wakhan se d\u00e9veloppe des deux c\u00f4t\u00e9s de la fronti\u00e8re. <em>\u00ab Rien que la semaine derni\u00e8re, j\u2019ai accompagn\u00e9 depuis Ichkachim dix touristes fran\u00e7ais en Afghanistan&nbsp;\u00bb, <\/em>affirme le guide<em>.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afghanis et somonis changent de main au milieu des rires et des accolades. On peine \u00e0 imaginer que le march\u00e9 \u00e9tait encore interdit quelques jours plus t\u00f4t.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Clara Cohade<br><\/strong><strong>Etienne Marsot<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab\u00a0Un lieu en Asie centrale\u00a0\u00bb est une collection d&rsquo;articles autour de lieux embl\u00e9matiques ou in\u00e9dits de la r\u00e9gion. D\u00e9couvrez-en davantage <a href=\"https:\/\/novastan.org\/fr\/tag\/un-lieu-en-asie-centrale\/\">en cliquant ici<\/a>. Envie de participer? Envoyez-nous vos id\u00e9es de lieu \u00e0 <a href=\"mailto:redaction@novastan.org\">redaction@novastan.org<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"text-align: left;\"><i><span style=\"font-weight: 400;\">Si vous avez aim\u00e9 cet article, n'h\u00e9sitez pas \u00e0 nous suivre sur <\/span><\/i><a href=\"https:\/\/twitter.com\/novastan_fr\"><i><span style=\"font-weight: 400;\">Twitter<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/www.facebook.com\/Novastan.org\/\"><i><span style=\"font-weight: 400;\">Facebook<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/telegram.me\/novastan\"><i><span style=\"font-weight: 400;\">Telegram<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/www.linkedin.com\/company\/fondation-novastan\/\"><i><span style=\"font-weight: 400;\">Linkedin<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ou <\/span><\/i><a href=\"https:\/\/www.instagram.com\/novastanorg\/\"><i><span style=\"font-weight: 400;\">Instagram<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ! Vous pouvez \u00e9galement vous inscrire pour recevoir<\/span><\/i><a href=\"http:\/\/eepurl.com\/O0Qub\"> <i><span style=\"font-weight: 400;\">notre newsletter hebdomadaire<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ou nous soutenir en devenant <\/span><\/i><a href=\"https:\/\/novastan.org\/fr\/novastan\/soutenir-novastan-mode-demploi\/\"><i><span style=\"font-weight: 400;\">membre de la communaut\u00e9 Novastan<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN LIEU EN ASIE CENTRALE. Apr\u00e8s trois ans de fermeture, le bazar d\u2019Ichkachim a rouvert ses portes fin juillet. Chaque samedi le poste frontalier Ichkachim entre Tadjikistan et Afghanistan accueille un des plus grands march\u00e9s de la r\u00e9gion. Marchands tadjiks et afghans s\u2019affairent \u00e0 leurs \u00e9tals hauts en couleurs, regorgeant de tissus, griottes et pewarkas. [&hellip;]<\/p>\n","protected":false},"author":660,"featured_media":25798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,3982],"tags":[406,2925,571,1335,1535,521,523,3339],"coauthors":[3343,3344],"class_list":["post-25795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tadjikistan","category-lieu-en-asie-centrale","tag-afghanistan","tag-echanges","tag-economie","tag-ichkachim","tag-marche","tag-societe","tag-tadjikistan","tag-un-lieu-en-asie-centrale"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/25795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/660"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=25795"}],"version-history":[{"count":1,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/25795\/revisions"}],"predecessor-version":[{"id":62864,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/25795\/revisions\/62864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/25798"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=25795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=25795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=25795"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=25795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}