{"id":23948,"date":"2019-05-31T11:26:37","date_gmt":"2019-05-31T09:26:37","guid":{"rendered":"https:\/\/novastan.org\/fr\/?p=23948"},"modified":"2020-12-03T19:40:35","modified_gmt":"2020-12-03T18:40:35","slug":"le-president-allemand-en-visite-officielle-en-ouzbekistan","status":"publish","type":"post","link":"https:\/\/novastan.org\/fr\/ouzbekistan\/le-president-allemand-en-visite-officielle-en-ouzbekistan\/","title":{"rendered":"Le pr\u00e9sident allemand en visite officielle en Ouzb\u00e9kistan"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Le pr\u00e9sident de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne, Frank-Walter Steinmeier, et son \u00e9pouse, Elke B\u00fcdenbender, se sont rendus en Ouzb\u00e9kistan du 27 au 29 mai. Ce voyage est consid\u00e9r\u00e9 comme un signe de soutien aux r\u00e9formes engag\u00e9es par le pr\u00e9sident ouzbek, Chavkat Mirzio\u00efev.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Novastan reprend et traduit un article initialement publi\u00e9 par notre version allemande. Pour y acc\u00e9der, vous pouvez cliquer <a href=\"https:\/\/novastan.org\/de\/usbekistan\/bundespraesident-steinmeier-besucht-usbekistan\/\">sur ce lien<\/a> ou bien sur le drapeau allemand en haut de notre site.<\/strong><\/p>\n<p style=\"text-align: justify;\">C\u2019est une visite rare. Du 27 au 29 mai dernier, le pr\u00e9sident allemand Frank-Walter Steinmeier a r\u00e9alis\u00e9 une visite officielle en Ouzb\u00e9kistan. A Tachkent, la capitale, le chef d\u2019Etat a \u00e9t\u00e9 re\u00e7u avec les honneurs militaires par son homologue ouzbek <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/qui-est-le-nouveau-president-de-louzbekistan\/\">Chavkat Mirzio\u00efev<\/a>. Apr\u00e8s une premi\u00e8re rencontre entre les deux chefs d&rsquo;\u00c9tat, Frank-Walter Steinmeier a d\u00e9pos\u00e9 une gerbe de fleurs au pied du monument comm\u00e9morant l&rsquo;ind\u00e9pendance de l&rsquo;Ouzb\u00e9kistan.<\/p>\n<p style=\"text-align: justify;\">Cette visite a aussi et surtout \u00e9t\u00e9 l\u2019occasion pour le chef d\u2019Etat allemand, qui n\u2019a qu\u2019une fonction de repr\u00e9sentation, de signer quelques contrats avec Tachkent. Le pr\u00e9sident allemand a notamment assist\u00e9 \u00e0 un forum \u00e9conomique entre les deux pays, qui a conduit \u00e0 la signature d\u2019un projet de co-entreprise entre Volkswagen et Uzavtosanoat, un constructeur automobile ouzbek.<\/p>\n<p style=\"text-align: justify;\"><strong>Des contrats sign\u00e9s dans l\u2019automobile\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.gazeta.uz\/ru\/2019\/05\/28\/volkswagen\/\">Selon le m\u00e9dia ouzbek Gazeta.uz<\/a>, des v\u00e9hicules Volkswagen pourraient \u00eatre vendus d\u2019ici 2021 dans le pays, si Uzavtosanoat dispose effectivement des capacit\u00e9s techniques. Un investissement de 40 millions d\u2019euros est d\u2019ores et d\u00e9j\u00e0 sur la table c\u00f4t\u00e9 Volkswagen.<\/p>\n\n\t\t<div class=\"flex flex-col md:flex-row justify-evenly items-center bg-yellow-100 my-20 p-10 space-y-10 subscribe\">\n\t\t\t<div class=\"container flex flex-row justify-between\">\n\t\t\t\t<div class=\"flex flex-col w-3\/5\">\n\t\t\t\t\t<h2 class=\"text-3xl text-secondary font-bold mb-4 text-[#749D02]\">\n\t\t\t\t\t\tSoutenez Novastan, le media associatif d\u2019Asie\u00a0centrale <\/h2>\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span>En vous abonnant \u00e0 Novastan, vous soutenez le seul m\u00e9dia en anglais, fran\u00e7ais et allemand sp\u00e9cialis\u00e9 sur l\u2019Asie\u00a0centrale.<\/span> Nous sommes ind\u00e9pendants et pour le rester, nous avons besoin de votre aide !<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"flex flex-col w-2\/5 flex flex-col justify-items-center justify-center\">\n\t\t\t\t\t<div class=\"rounded-md bg-accent-500 px-10 py-5 text-center w-72 mx-auto\">\n\t\t\t\t\t\t<p class=\"pricing text-2xl font-bold text-center\">3\u20ac\/mois<\/p>\n\t\t\t\t\t\t<p class=\"\">Toute l\u2019actualit\u00e9 d\u2019Asie centrale<\/p>\n\t\t\t\t\t\t<a class=\"block rounded bg-white p-2 mt-4 font-bold\" href=\"https:\/\/novastan.org\/fr\/sabonner\">Abonnez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n<p style=\"text-align: justify;\">Cette co-entreprise n\u2019est pas la premi\u00e8re pour Berlin dans l\u2019automobile. Depuis 2009, les poids lourds et camionnettes de la marque MAN sont produits en Ouzb\u00e9kistan, mais \u00e0 un rythme relativement al\u00e9atoire. <a href=\"https:\/\/caa-network.org\/archives\/16253?fbclid=IwAR1HPpjdqUP6fqBoA5uQ49JhX-HDlnMP5vxkHeGIac2XRms91kxmY5ZXBC4\">Comme le pr\u00e9cise le Central Asian Analytical Network<\/a> (CAAN), cette co-entreprise est la plus importante entre les deux pays.<\/p>\n<p style=\"text-align: justify;\"><strong>\u2026 et dans la sant\u00e9<\/strong><\/p>\n<p style=\"text-align: justify;\">Au-del\u00e0 de l\u2019automobile, l\u2019Allemagne devrait participer \u00e0 la cr\u00e9ation d\u2019un centre de m\u00e9decine nucl\u00e9aire et de radioth\u00e9rapie \u00e0 Tachkent. Berlin s\u2019est \u00e9galement engag\u00e9 \u00e0 participer \u00e0 la construction de deux cliniques contre le cancer, \u00e0 Tachkent et dans sa r\u00e9gion. Epsilon et l\u2019universit\u00e9 de Manheim devraient \u00eatre impliqu\u00e9s dans l\u2019une et l\u2019autre des cliniques.<\/p>\n<p style=\"text-align: justify;\">Durant sa visite, Frank-Walter Steinmeier s\u2019est \u00e9galement rendu avec des artistes ouzbeks \u00e0 l&rsquo;Institut Goethe de Tachkent, <a href=\"https:\/\/www.gazeta.uz\/ru\/2019\/05\/28\/goethe\/\">rapporte Gazeta.uz<\/a>. Une statue en l\u2019honneur de l\u2019\u00e9crivain allemand a \u00e9t\u00e9 \u00e9rig\u00e9e. Selon le CAAN, plus de 4&nbsp;000 Ouzbeks ont appris l\u2019allemand dans ce centre depuis sa cr\u00e9ation en 2014.<\/p>\n<p style=\"text-align: justify;\"><strong>Lire aussi sur Novastan&nbsp;:<\/strong> <strong><a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/lallemagne-conserve-ses-troupes-a-la-frontiere-ouzbeke-un-an-de-plus\/\">L\u2019Allemagne conserve ses troupes \u00e0 la fronti\u00e8re ouzb\u00e8ke un an de plus<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Pour terminer sa visite, Frank-Walter&nbsp;Steinmeier a visit\u00e9 la ville historique de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Khiva\">Khiva<\/a>, \u00e0 la fronti\u00e8re avec le Turkm\u00e9nistan, dans l\u2019ouest du pays.<\/p>\n<p style=\"text-align: justify;\"><strong>Une symbolique forte<\/strong><\/p>\n<p style=\"text-align: justify;\">La visite du pr\u00e9sident allemand fait suite \u00e0 celle de Chavkat Mirzio\u00efev en Allemagne en janvier dernier, o\u00f9 il avait \u00e9t\u00e9 re\u00e7u \u00e0 Berlin par la chanceli\u00e8re Angela Merkel. L&rsquo;Allemagne et l&rsquo;Ouzb\u00e9kistan souhaitent renforcer leur coop\u00e9ration \u00e9conomique et culturelle dans le cadre de la politique d&rsquo;ouverture du pr\u00e9sident ouzbek, au moyen notamment du programme de <a href=\"https:\/\/www.oaoev.de\/de\/wirtschaftsdelegation-mit-steinmeier-usbekistan\">stages lanc\u00e9 en 2019 par l\u2019association d\u2019entreprises d\u2019Allemagne orientale<\/a> (Ost-Auschuss &#8211; Osteuropaverein der Deutschen Wirtschaft), qui encourage la mobilit\u00e9 des dipl\u00f4m\u00e9s universitaires ouzbeks en Allemagne. La visite de Frank-Walter Steinmeier a constitu\u00e9 un soutien \u00e0 ces r\u00e9formes.<\/p>\n<p style=\"text-align: justify;\"><strong>Lire aussi sur Novastan&nbsp;: <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/les-compagnies-allemandes-a-lassaut-du-marche-ouzbek\/\">Les compagnies allemandes \u00e0 l\u2019assaut du march\u00e9 ouzbek<\/a><\/strong><\/p>\n\t\t\t<div class=\"hp-newsletter col-span-3 lg:col-span-1 flex flex-col bg-primary-100 border-t-8 border-secondary-500 rounded-lg justify-center items-center lg:items-stretch px-6 py-6 gap-4 box-border\">\n\t\t\t<div class=\"flex\">\n\t\t\t\t<div class=\"enveloppe\">\n\t\t\t\t\t<i class=\"far fa-envelope text-5xl text-secondary-300\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"formulaire_nl\">\n\t\t\t\t\t<p>\n\t\t\t\t\t\t<span class=\"font-bold text-xl block\">Toute l\u2019Asie centrale dans votre boite mails<\/span>\n\t\t\t\t\t\tAbonnez-vous \u00e0 notre newsletter hebdomadaire gratuite\t\t\t\t\t<\/p>\n\t\t\t\t\t<form class=\"flex w-3\/4 lg:w-full\" action=\"https:\/\/us4.list-manage.com\/subscribe?u=6a15a2256d412b041fdec39e8&id=d479236523\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\" novalidate=\"\">\n\t\t\t\t\t\t<input class=\"flex-grow py-2 px-3 border border-primary-300 rounded-l\" type=\"email\" placeholder=\"Email\" name=\"EMAIL\" id=\"mce-EMAIL\">\n\t\t\t\t\t\t<button class=\"bg-secondary-500 py-2 px-3 text-white rounded-r-md border border-secondary-500\" type=\"submit\" value=\"\" name=\"subscribe\">S\u2019inscrire<\/button>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<a href=\"#\" class=\"underline text-secondary-700\">D\u00e9couvrez la derni\u00e8re \u00e9dition<\/a>\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div><!-- newsletter -->\n\t\t\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 ouzbek, la venue du pr\u00e9sident allemand a \u00e9galement permis \u00e0 Chavkat Mirzio\u00efev de faire passer un message d\u2019ouverture \u00e0 la d\u00e9l\u00e9gation d\u2019entreprises allemandes. <em>\u00ab&nbsp;J\u2019ai discut\u00e9 avec des hommes d\u2019affaires en Allemagne, je sais qu\u2019ils sont nombreux \u00e0 vouloir s\u2019installer en Ouzb\u00e9kistan mais doutent encore. En tant que pr\u00e9sident, je peux vous le dire \u00e0 nouveau aujourd\u2019hui&nbsp;: il n\u2019y a pas besoin de douter, il n\u2019y a pas de retour en arri\u00e8re&nbsp;\u00bb<\/em>, a affirm\u00e9 le pr\u00e9sident ouzbek, <a href=\"https:\/\/uz.sputniknews.ru\/radio\/20190528\/11625040\/Mirziev--nemetskim-biznesmenam-somnevatsya-uzhe-ne-nado--nazad-dorogi-net.html?fbclid=IwAR18V5VqqJ47WUO9aekTrKW4WAxBs9JP94Kxr1BFf9kt6me4H-E_1w0zPkw\">rapporte Spoutnik<\/a>. Une mani\u00e8re de rappeler son engagement pour une ouverture \u00e9conomique du pays le plus peupl\u00e9 d\u2019Asie centrale, <a href=\"https:\/\/novastan.org\/fr\/ouzbekistan\/ouzbekistan-une-ouverture-mais-avec-certaines-lignes-rouges\/\">sans pour autant s\u2019engager sur une ouverture politique<\/a>.<\/p>\n<p style=\"text-align: right;\"><strong>Arnaud Enderlin<br \/>\nR\u00e9dacteur pour Novastan<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>Traduit <a href=\"https:\/\/novastan.org\/de\/usbekistan\/bundespraesident-steinmeier-besucht-usbekistan\/\">de l\u2019allemand<\/a> par Pierre-Fran\u00e7ois Hubert<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>Edit\u00e9 et enrichi par Etienne Combier<\/strong><\/p>\n<p style=\"text-align: justify;\"><p style=\"text-align: left;\"><i><span style=\"font-weight: 400;\">Si vous avez aim\u00e9 cet article, n'h\u00e9sitez pas \u00e0 nous suivre sur <\/span><\/i><a href=\"https:\/\/twitter.com\/novastan_fr\"><i><span style=\"font-weight: 400;\">Twitter<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/www.facebook.com\/Novastan.org\/\"><i><span style=\"font-weight: 400;\">Facebook<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/telegram.me\/novastan\"><i><span style=\"font-weight: 400;\">Telegram<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><a href=\"https:\/\/www.linkedin.com\/company\/fondation-novastan\/\"><i><span style=\"font-weight: 400;\">Linkedin<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ou <\/span><\/i><a href=\"https:\/\/www.instagram.com\/novastanorg\/\"><i><span style=\"font-weight: 400;\">Instagram<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ! Vous pouvez \u00e9galement vous inscrire pour recevoir<\/span><\/i><a href=\"http:\/\/eepurl.com\/O0Qub\"> <i><span style=\"font-weight: 400;\">notre newsletter hebdomadaire<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> ou nous soutenir en devenant <\/span><\/i><a href=\"https:\/\/novastan.org\/fr\/novastan\/soutenir-novastan-mode-demploi\/\"><i><span style=\"font-weight: 400;\">membre de la communaut\u00e9 Novastan<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne, Frank-Walter Steinmeier, et son \u00e9pouse, Elke B\u00fcdenbender, se sont rendus en Ouzb\u00e9kistan du 27 au 29 mai. Ce voyage est consid\u00e9r\u00e9 comme un signe de soutien aux r\u00e9formes engag\u00e9es par le pr\u00e9sident ouzbek, Chavkat Mirzio\u00efev. Novastan reprend et traduit un article initialement publi\u00e9 par notre version allemande. Pour [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":23950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[1013,3641,571,3184,548,488,1778,1956,1577,3185],"coauthors":[2634,1621,81],"class_list":["post-23948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ouzbekistan","tag-allemagne","tag-contrat","tag-economie","tag-frank-walter-steinmeier","tag-ouzbekistan","tag-politique","tag-sc-uzavtosanoat","tag-traduction","tag-visite","tag-volkswagen"],"acf":[],"_links":{"self":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/23948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/comments?post=23948"}],"version-history":[{"count":0,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/posts\/23948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media\/23950"}],"wp:attachment":[{"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/media?parent=23948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/categories?post=23948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/tags?post=23948"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/novastan.org\/fr\/wp-json\/wp\/v2\/coauthors?post=23948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}