{"id":1125,"name":"Enora M","url":"","description":"","link":"https:\/\/novastan.org\/de\/author\/emornal\/","slug":"emornal","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4e3f7412be548179d079ed97d0d1d40dfce9af31698cc0ee149eb8602a9c02d8?s=24&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4e3f7412be548179d079ed97d0d1d40dfce9af31698cc0ee149eb8602a9c02d8?s=48&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4e3f7412be548179d079ed97d0d1d40dfce9af31698cc0ee149eb8602a9c02d8?s=96&r=g"},"meta":{"lw_harbor_dismissed_notices":[]},"acf":[],"user_switching_url":null,"_links":{"self":[{"href":"https:\/\/novastan.org\/de\/wp-json\/wp\/v2\/users\/1125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novastan.org\/de\/wp-json\/wp\/v2\/users"}]}}